{"text_format":"1","workbook":"xlsx","n_sheets":13,"sheets":["Cover","Version Control","Inputs","Data Sources","Pre Op RAV","Finance","Op Rav","Allowances Cap","Allowances Floor","Tax Deductions","Tax Cap","Tax Floor","Cap Floor Levels"],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":2,"defined_names":88,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Cover","index":0,"n_rows":43,"n_cols":7,"rows_kept":43,"cut":false,"hidden":false,"merged":[[4,2,4,6]]}
[]
["Cap and Floor Financial Model 1 (CFFM1) - Actual Cost of Debt (ACOD)"]
[null,"Regime design model"]
[null,null,{"$f":"MID(CELL(\"filename\"),SEARCH(\"[\",CELL(\"filename\"))+1,SEARCH(\"]\",CELL(\"filename\"))-SEARCH(\"[\",CELL(\"filename\"))-1)","v":"Greenlink_Cap_and_Floor_Financial_Model_GCFFM1 for publication.xlsm"}]
[null,null,"DISCLAIMER: In the event of any inconsistency between this model and a project's licence, the licence conditions take precedence."]
[null,null,"For guidance on the use of the CFFM1 - ACOD, please refer to the CFFM1 Handbook - ACOD (CFFM1H - ACOD)"]
[]
[null,"Model key"]
[]
[null,null,null,null,"Sample",null,"Calculated value"]
[null,null,null,null,"Sample",null,"Formula changes in cells to the right"]
[null,null,null,null,"Sample",null,"Import from other sheet"]
[null,null,null,null,"Sample",null,"Export to other sheet"]
[null,null,null,null,"Sample",null,"Import from & export to other sheet"]
[null,null,null,null,"Sample",null,"Initial input"]
[null,null,null,null,"Sample",null,"Initial input for non-GB indexed portion (to be left empty if GB-indexed only)"]
[null,null,null,null,"Sample",null,"Updated input"]
[null,null,null,null,"Sample",null,"Notes and instructions"]
[null,null,null,null,"Sample",null,"Cell intentionally blank"]
[null,null,null,null,null,null,"Rows added to accommodate project-finance related inputs and calculations"]
[]
[null,"Contents"]
[]
[null,null,null,null,"Cover",null,"Model key and content directory"]
[null,null,null,null,"Version Control",null,"Version control and log of changes"]
[null,null,null,null,"Inputs",null,"Input data"]
[null,null,null,null,"Data Sources",null,"Sources of input data"]
[null,null,null,null,"Pre Op RAV",null,"Pre-operational RAV balances and project-finance eligible costs"]
[null,null,null,null,"Finance",null,"Interest during construction, transaction costs, project-finance debt service"]
[null,null,null,null,"Op RAV",null,"Operational RAV balances, return on RAV and RAV depreciation"]
[null,null,null,null,"Allowances Cap",null,"Cap allowances (excluding tax) and annuitisation"]
[null,null,null,null,"Allowances Floor",null,"Floor allowances (excluding tax) and annuitisation"]
[null,null,null,null,"Tax Deductions",null,"Tax calculations"]
[null,null,null,null,"Tax Cap",null,"Tax allowances at cap and annuitisation"]
[null,null,null,null,"Tax Floor",null,"Tax allowances at floor and annuitisation"]
[null,null,null,null,"Cap Floor Levels",null,"Cap and Floor values"]
[]
[null,"Checks"]
[]
[null,null,null,null,"Depreciation",null,{"$f":"'Op Rav'!I27","v":"TRUE"}]
[null,null,null,null,"Debt tenor",null,{"$f":"Inputs!I157","v":false}]
[]
[null,"End of sheet"]

{"sheet":"Version Control","index":1,"n_rows":10,"n_cols":12,"rows_kept":10,"cut":false,"hidden":false,"merged":[]}
["Version control"]
[null,"Version number","File pathname","Based on version","Author or editor","Date","Description of changes","Rationale for changes","Location of changes","Impact of changes on outputs","Quality assurance performed? By?","Comments on QA performed"]
[]
[null,1.1000000000000001,"link","N/a","Andrew Stone & Neill Aitken (NGV)","2017-01-31","N/a","N/a","N/a","N/a","Internal (ORE) and external (BDO)","Comments reflected in version 1.1"]
[null,2.1,"link",1.1000000000000001,"Martin Namor","2019-03-20","CFFM split into CFFM1 (up to PCR) & CFFM2 (operations)","Simplification and standardisation","Throughout the model","No impact","Internal (ORE - Svitlana Voronkova)","Comments reflected in version 2.2"]
[null,2.2000000000000002,null,2.1,"Martin Namor","2019-09-05","Minor changes","Reflecting comments from QA and tidying up","Throughout the model","No impact","Internal (ORE - Svitlana Voronkova)","Further comments reflected in version 2.2"]
[null,3.1,null,2.2000000000000002,"Martin Namor & Greenlink & NeuConnect","2020-12-11","Inclusion of additional inputs and calculations relevant to project financing","Allowing determination of actual floor level (AFL) in addition to notional floor level (NFL)","Throughout the model","Additional output (actual floor);\nOriginal outputs (notional cap and floor) unchanged","Internal (ORE - Svitlana Voronkova)","Comments reflected in version 3.1"]
[null,3.2,null,3.1,"Martin Namor","2021-02-05","Changes required to remove post-tail AFL","Allowing for AFL only during debt tenor and tail period","Throughout the model","Removal of post-tail AFL","Internal (IC - Riccardo Rosselli; ORE - Svitlana Voronkova)","Comments reflected in version 3.2"]
[null,3.3,null,3.2,"Greenlink & NeuConnect","2021-05-14","Inclusion of additional dates and flags","Correcting errors and allowing separate profiling for NFL and ACL","Throughout the model","No impact","Internal (RF - Martin Namor; ORE - Svitlana Voronkova)","Comments reflected in version 3.3"]
[null,3.4,null,3.3,"Magdalena Rut","2022-08-08","Placeholder parameters replaced with Greenlink input parameters to generate C+F levels for the Greenlink project.","Implementing the regime for Greenlink","Throughout the model","Medium","Internal (ORE - Rahmatullah Kawsary) and External (Greenlink)","Comments reflected in version 3.4"]

{"sheet":"Inputs","index":2,"n_rows":201,"n_cols":50,"rows_kept":201,"cut":false,"hidden":false,"merged":[]}
["Inputs",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[]
[null,"Indexation, currency and base year price term"]
[]
[null,null,null,null,"GB indexed portion of interconnector",null,"choice %",null,1]
[null,null,null,null,"Non-GB indexed portion of interconnector",null,"%",null,{"$f":"100%-I6","v":0}]
[]
[null,null,null,null,"Currency of cost inputs",null,"choice",null,"£"]
[]
[null,null,null,null,"Base year price term",null,"choice",null,"£m 20/21 prices"]
[]
[null,"Variables set after financial close"]
[]
[null,null,"Actual values"]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"$I$148","v":"2013-01-01"},{"$f":"+K18+1","v":"2014-01-01"},{"$f":"+L18+1","v":"2015-01-01"},{"$f":"+M18+1","v":"2016-01-01"},{"$f":"+N18+1","v":"2017-01-01"},{"$f":"+O18+1","v":"2018-01-01"},{"$f":"+P18+1","v":"2019-01-01"},{"$f":"+Q18+1","v":"2020-01-01"},{"$f":"+R18+1","v":"2021-01-01"},{"$f":"+S18+1","v":"2022-01-01"},{"$f":"+T18+1","v":"2023-01-01"},{"$f":"+U18+1","v":"2024-01-01"},{"$f":"+V18+1","v":"2025-01-01"},{"$f":"+W18+1","v":"2026-01-01"},{"$f":"+X18+1","v":"2027-01-01"},{"$f":"+Y18+1","v":"2028-01-01"},{"$f":"+Z18+1","v":"2029-01-01"},{"$f":"+AA18+1","v":"2030-01-01"},{"$f":"+AB18+1","v":"2031-01-01"},{"$f":"+AC18+1","v":"2032-01-01"},{"$f":"+AD18+1","v":"2033-01-01"},{"$f":"+AE18+1","v":"2034-01-01"},{"$f":"+AF18+1","v":"2035-01-01"},{"$f":"+AG18+1","v":"2036-01-01"},{"$f":"+AH18+1","v":"2037-01-01"},{"$f":"+AI18+1","v":"2038-01-01"},{"$f":"+AJ18+1","v":"2039-01-01"},{"$f":"+AK18+1","v":"2040-01-01"},{"$f":"+AL18+1","v":"2041-01-01"},{"$f":"+AM18+1","v":"2042-01-01"},{"$f":"+AN18+1","v":"2043-01-01"},{"$f":"+AO18+1","v":"2044-01-01"},{"$f":"+AP18+1","v":"2045-01-01"},{"$f":"+AQ18+1","v":"2046-01-01"},{"$f":"+AR18+1","v":"2047-01-01"},{"$f":"+AS18+1","v":"2048-01-01"},{"$f":"+AT18+1","v":"2049-01-01"},{"$f":"+AU18+1","v":"2050-01-01"},{"$f":"+AV18+1","v":"2051-01-01"},{"$f":"+AW18+1","v":"2052-01-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"EOMONTH(K17,11)","v":"2013-12-31"},{"$f":"DATE(YEAR(K18) + 1, MONTH(K18), DAY(K18))","v":"2014-12-31"},{"$f":"DATE(YEAR(L18) + 1, MONTH(L18), DAY(L18))","v":"2015-12-31"},{"$f":"DATE(YEAR(M18) + 1, MONTH(M18), DAY(M18))","v":"2016-12-31"},{"$f":"DATE(YEAR(N18) + 1, MONTH(N18), DAY(N18))","v":"2017-12-31"},{"$f":"DATE(YEAR(O18) + 1, MONTH(O18), DAY(O18))","v":"2018-12-31"},{"$f":"DATE(YEAR(P18) + 1, MONTH(P18), DAY(P18))","v":"2019-12-31"},{"$f":"DATE(YEAR(Q18) + 1, MONTH(Q18), DAY(Q18))","v":"2020-12-31"},{"$f":"DATE(YEAR(R18) + 1, MONTH(R18), DAY(R18))","v":"2021-12-31"},{"$f":"DATE(YEAR(S18) + 1, MONTH(S18), DAY(S18))","v":"2022-12-31"},{"$f":"DATE(YEAR(T18) + 1, MONTH(T18), DAY(T18))","v":"2023-12-31"},{"$f":"DATE(YEAR(U18) + 1, MONTH(U18), DAY(U18))","v":"2024-12-31"},{"$f":"DATE(YEAR(V18) + 1, MONTH(V18), DAY(V18))","v":"2025-12-31"},{"$f":"DATE(YEAR(W18) + 1, MONTH(W18), DAY(W18))","v":"2026-12-31"},{"$f":"DATE(YEAR(X18) + 1, MONTH(X18), DAY(X18))","v":"2027-12-31"},{"$f":"DATE(YEAR(Y18) + 1, MONTH(Y18), DAY(Y18))","v":"2028-12-31"},{"$f":"DATE(YEAR(Z18) + 1, MONTH(Z18), DAY(Z18))","v":"2029-12-31"},{"$f":"DATE(YEAR(AA18) + 1, MONTH(AA18), DAY(AA18))","v":"2030-12-31"},{"$f":"DATE(YEAR(AB18) + 1, MONTH(AB18), DAY(AB18))","v":"2031-12-31"},{"$f":"DATE(YEAR(AC18) + 1, MONTH(AC18), DAY(AC18))","v":"2032-12-31"},{"$f":"DATE(YEAR(AD18) + 1, MONTH(AD18), DAY(AD18))","v":"2033-12-31"},{"$f":"DATE(YEAR(AE18) + 1, MONTH(AE18), DAY(AE18))","v":"2034-12-31"},{"$f":"DATE(YEAR(AF18) + 1, MONTH(AF18), DAY(AF18))","v":"2035-12-31"},{"$f":"DATE(YEAR(AG18) + 1, MONTH(AG18), DAY(AG18))","v":"2036-12-31"},{"$f":"DATE(YEAR(AH18) + 1, MONTH(AH18), DAY(AH18))","v":"2037-12-31"},{"$f":"DATE(YEAR(AI18) + 1, MONTH(AI18), DAY(AI18))","v":"2038-12-31"},{"$f":"DATE(YEAR(AJ18) + 1, MONTH(AJ18), DAY(AJ18))","v":"2039-12-31"},{"$f":"DATE(YEAR(AK18) + 1, MONTH(AK18), DAY(AK18))","v":"2040-12-31"},{"$f":"DATE(YEAR(AL18) + 1, MONTH(AL18), DAY(AL18))","v":"2041-12-31"},{"$f":"DATE(YEAR(AM18) + 1, MONTH(AM18), DAY(AM18))","v":"2042-12-31"},{"$f":"DATE(YEAR(AN18) + 1, MONTH(AN18), DAY(AN18))","v":"2043-12-31"},{"$f":"DATE(YEAR(AO18) + 1, MONTH(AO18), DAY(AO18))","v":"2044-12-31"},{"$f":"DATE(YEAR(AP18) + 1, MONTH(AP18), DAY(AP18))","v":"2045-12-31"},{"$f":"DATE(YEAR(AQ18) + 1, MONTH(AQ18), DAY(AQ18))","v":"2046-12-31"},{"$f":"DATE(YEAR(AR18) + 1, MONTH(AR18), DAY(AR18))","v":"2047-12-31"},{"$f":"DATE(YEAR(AS18) + 1, MONTH(AS18), DAY(AS18))","v":"2048-12-31"},{"$f":"DATE(YEAR(AT18) + 1, MONTH(AT18), DAY(AT18))","v":"2049-12-31"},{"$f":"DATE(YEAR(AU18) + 1, MONTH(AU18), DAY(AU18))","v":"2050-12-31"},{"$f":"DATE(YEAR(AV18) + 1, MONTH(AV18), DAY(AV18))","v":"2051-12-31"},{"$f":"DATE(YEAR(AW18) + 1, MONTH(AW18), DAY(AW18))","v":"2052-12-31"}]
[]
[null,null,null,null,"Development costs",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,0,0,0,1.0309226728309071,0.7844395920627365,1.4968659836666893,3.5591881498288243,2.924437434008937,1.5041461676019079,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Capex",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,0,0,0,0,0,0,0,0,6.6060539188691738,80.145479328253217,75.202203876975545,44.346262875902234,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Spares",null,"£m nominal prices",null,null,null,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,null,"Base year UK RPI inflation index value (CHAW)",null,"Jan 1987 = 100","UK RPI index 2020/21",294.16666666666703]
[]
[]
[]
[null,null,null,null,"12 month average UK RPI inflation index value (CHAW)",null,{"$f":"G24","v":"Jan 1987 = 100"},"UK RPI index t",null,null,250.10833333333301,256.0333333333333,258.54166666666669,263.05,272.47500000000002,281.58333333333331,288.8,293.14166666666699,305,{"$f":"S28*(1+$I$179)","v":318.05399999999997},{"$f":"T28*(1+$I$179)","v":331.66671119999995},{"$f":"U28*(1+$I$179)","v":345.86204643935991},360.66494202696452,376.1014015457186,392.19854153187532,408.98463910943957,426.48918166332356,444.7429186385138,463.77791555624219,483.62761034204931,504.32687206468898,525.91206218905768,548.42109845074935,571.89352146444139,596.37056418311943,621.89522433015691,648.51233993148765,676.26866808055524,705.21296707440297,735.39608206518733,766.8710343775773,799.69311464893758,833.91997995591203,869.61175509802501,906.83113821622044,945.64351093187463,986.11705319975886,1028.3228630767085,1072.3350816163916,1118.231023109573]
[]
[]
[]
[null,null,null,null,"Indexation factor",null,null,{"$f":"IF(I6=100%,\"CRPIt\",\"PPPIt\")","v":"CRPIt"},null,null,{"$f":"IF($I$6=100%,(K28/$I$24),($I$6*(K28/$I$24)+$I$7*(K29/$I$25)/(K30/$I$26)))","v":0.85022662889518197},{"$f":"IF($I$6=100%,(L28/$I$24),($I$6*(L28/$I$24)+$I$7*(L29/$I$25)/(L30/$I$26)))","v":0.87036827195467303},{"$f":"IF($I$6=100%,(M28/$I$24),($I$6*(M28/$I$24)+$I$7*(M29/$I$25)/(M30/$I$26)))","v":0.87889518413597634},{"$f":"IF($I$6=100%,(N28/$I$24),($I$6*(N28/$I$24)+$I$7*(N29/$I$25)/(N30/$I$26)))","v":0.89422096317280353},0.92626062322946068,0.9572237960339931,0.9817563739376759,0.99651558073654378,1.0368271954674209,1.0812033994334262,1.1274789049291769,1.1757350020601456,1.2260564601483199,1.278531676642668,1.333252832402974,1.3903160536298211,1.4498215807251775,1.5118739443802149,1.5765821491996883,1.6440598651854348,1.7144256274153713,1.7878030442687491,1.8643210145634517,1.9441139539867671,2.0273220312174005,2.1140914141535054,2.2045745266792753,2.2989303164211483,2.3973245339639733,2.499930024017631,2.6069270290455853,2.7185035058887363,2.8348554559407741,2.9561872694550391,3.0827120845877145,3.2146521618080683,3.3522392743334537,3.4957151152749253,3.6453317222086921,3.8013519199192238]
[]
[null,null,null,null,{"$f":"E20","v":"Development costs"},null,{"$f":"$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K20/K$32,K20/K$32/K$30)","v":0},{"$f":"IF($I$9=\"£\",L20/L$32,L20/L$32/L$30)","v":0},{"$f":"IF($I$9=\"£\",M20/M$32,M20/M$32/M$30)","v":0},{"$f":"IF($I$9=\"£\",N20/N$32,N20/N$32/N$30)","v":1.1528724054657247},{"$f":"IF($I$9=\"£\",O20/O$32,O20/O$32/O$30)","v":0.8468886319789164},1.563757597615691,3.6253272648014092,2.9346630304038288,1.4507202108291644,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,{"$f":"E21","v":"Capex"},null,{"$f":"$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K21/K$32,K21/K$32/K$30)","v":0},0,0,0,0,0,0,0,6.3714126594557952,74.126181410686613,66.699433176268073,37.717906499506995,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,{"$f":"E22","v":"Spares"},null,"£m 20/21 prices",null,null,null,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Ex-ante allowances for the operational period"]
[]
[null,null,null,null,"Operational Year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,null,null,null,"Replacement Capex",null,"£m 2020 prices",null,null,null,0,0,0,0,0,0,1.74,0,0,0,0,0,0,0,1.74,1.74,0,0,0,0,0,0,2.1749999999999998,0,0]
[null,null,null,null,"Decommissioning baseline",null,"£m 2020 prices",null,null,null,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999,0.15279999999999999]
[null,null,null,null,"Controllable Opex",null,"£m 2020 prices",null,null,null,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999,4.8102559999999999]
[null,null,null,null,"Non-controllable Opex baseline",null,"£m 2020 prices",null,null,null,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999,1.2275769999999999]
[]
[null,null,null,null,{"$f":"E24","v":"Base year UK RPI inflation index value (CHAW)"},null,{"$f":"G24","v":"Jan 1987 = 100"},{"$f":"H24","v":"UK RPI index 2020/21"},{"$f":"I24","v":294.16666666666703}]
[null,null,null,null,{"$f":"IF(E25=\"\",\"\",E25)","v":""},null,{"$f":"IF(G25=\"\",\"\",G25)","v":""},"",""]
[null,null,null,null,{"$f":"IF(E26=\"\",\"\",E26)","v":""},null,"","",""]
[]
[null,null,null,null,"2020 average UK RPI inflation index value (CHAW)",null,{"$f":"G24","v":"Jan 1987 = 100"},null,293.14166666666699]
[null,null,null,null,"2020 average Ireland CPI inflation index value",null,{"$f":"IF(G25=\"\",\"\",G25)","v":""}]
[null,null,null,null,"2020 average exchange rate (XUMAERS)",null,{"$f":"IF(G26=\"\",\"\",G26)","v":""}]
[]
[null,null,null,null,{"$f":"IF(E30=\"\",\"\",E30)","v":""},null,{"$f":"IF(G30=\"\",\"\",G30)","v":""},{"$f":"IF(H30=\"\",\"\",H30)","v":""}]
[]
[null,null,null,null,"Indexation conversion from 2020 to 2020/21 terms",null,null,null,{"$f":"I51/$I$47","v":0.99651558073654378}]
[]
[null,null,null,null,{"$f":"E42","v":"Replacement Capex"},null,{"$f":"$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K42/$I$57,K42/K$55/$I$57)","v":0},0,0,0,0,0,1.7460840890354494,0,0,0,0,0,0,0,1.7460840890354494,1.7460840890354494,0,0,0,0,0,0,2.1826051112943117,0,0]
[null,null,null,null,{"$f":"E43","v":"Decommissioning baseline"},null,"£m 20/21 prices",null,null,null,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348,0.15333428092219348]
[null,null,null,null,{"$f":"E44","v":"Controllable Opex"},null,"£m 20/21 prices",null,null,null,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754,4.8270755550501754]
[null,null,null,null,{"$f":"E45","v":"Non-controllable Opex baseline"},null,"£m 20/21 prices",null,null,null,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298,1.2318693492907298]
[]
[null,"Variables set at financial close"]
[]
[null,null,"Finance"]
[]
[null,null,null,null,"Cap return rate",null,"real annual %",null,8.1000000000000003E-2]
[null,null,null,null,"Floor return rate",null,"real annual %",null,-8.3999999999999995E-3]
[null,null,null,null,"Interest during construction (IDC) rate",null,"real annual %",null,5.21E-2]
[null,null,null,null,"Cost of debt (for tax)",null,"real annual %",null,{"$f":"I69","v":-8.3999999999999995E-3}]
[]
[null,null,null,null,"Pre-operational notional gearing",null,"%",null,0.3977]
[null,null,null,null,"Operational notional gearing",null,"%",null,0.5]
[]
[null,null,null,null,"Equity transaction costs",null,"%",null,0.05]
[null,null,null,null,"Debt transaction costs",null,"%",null,2.5000000000000001E-2]
[]
[null,null,"Actual cost of debt (inputs are not the exact project values, selected to generate the exact actual floor level determined in the project finance financial model)"]
[]
[null,null,null,null,"Project finance key input: senior debt amount or gearing",null,"1: Amount (£m)\n2: Gearing (%)",null,1]
[null,null,null,null,"Project finance senior debt amount (input if 1; empty if 2)",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,253.11449999999999]
[null,null,null,null,"Project finance actual gearing (input if 2; empty if 1)",null,"%"]
[]
[null,null,null,null,"Senior Debt tenor",null,"full years",null,22.591780821917808]
[null,null,null,null,"Senior Debt tail requirement",null,"full years",null,0]
[null,null,null,null,"DSCR sizing",null,"DSCRx",null,1.2]
[]
[null,null,null,null,"Fixed rate - Construction",null,"nominal %",null,1.3143521893981167E-2]
[null,null,null,null,"Fixed rate - Operation",null,"nominal %",null,1.3010779504157978E-2]
[]
[null,null,null,null,"Senior Debt construction margin",null,"nominal %",null,1.7704500000000001E-2]
[null,null,null,null,"of which: swap margin",null,"nominal %",null,1.7044999999999999E-3]
[null,null,null,null,"Senior Debt upfront fee",null,"nominal %",null,1.4E-2]
[null,null,null,null,"Senior Debt commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"Senior Debt drawdown year",null,"Year",null,null,null,1,2,3,4,5,6,7,8,9,10]
[null,null,null,null,"Senior Debt drawdown profile",null,"%",null,null,null,0.50574215483891483,0.49425784516108517,0,0,0,0,0,0,0,0]
[]
[null,null,null,null,"Debt Service Reserve Facility/Account amount",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,8.7884366946588557]
[null,null,null,null,"Debt Service Reserve Facility upfront fee",null,"nominal %",null,1.4E-2]
[null,null,null,null,"Debt Service Reserve Facility construction margin",null,"nominal %",null,1.6012036458399354E-2]
[null,null,null,null,"Debt Service Reserve Facility commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"Cap and Floor Liquidity Facility amount",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,23.221091736647139]
[null,null,null,null,"Cap and Floor Liquidity Facility average outstanding loan",null,"£m nominal prices",null,0]
[null,null,null,null,"Cap and Floor Liquidity Facility upfront fee",null,"nominal %",null,1.4E-2]
[null,null,null,null,"Cap and Floor Liquidity Facility construction margin",null,"nominal %",null,1.6038303717231035E-2]
[null,null,null,null,"Cap and Floor Liquidity Facility commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"Standby Debt Facility amount",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,0]
[null,null,null,null,"Standby Debt Facility upfront fee",null,"nominal %",null,1.4E-2]
[null,null,null,null,"Standby Debt Facility construction margin",null,"nominal %",null,1.6E-2]
[null,null,null,null,"Standby Debt Facility commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"VAT Facility amount",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,0.46442183473294274]
[null,null,null,null,"VAT Facility average outstanding loan",null,"£m nominal prices",null,0.19181378568180549]
[null,null,null,null,"VAT Facility upfront fee",null,"nominal %",null,1.2999999999999999E-2]
[null,null,null,null,"VAT Facility construction margin",null,"nominal %",null,1.2500000000000001E-2]
[null,null,null,null,"VAT Facility commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"Other Facilities amount",null,{"$f":"CONCATENATE($I$9,\"m nominal prices\")","v":"£m nominal prices"},null,12.5]
[null,null,null,null,"Other Facilities upfront fee",null,"nominal %",null,1.4E-2]
[null,null,null,null,"Other Facilities construction margin",null,"nominal %",null,1.6500000000000001E-2]
[null,null,null,null,"Other Facilities commitment fee",null,"% of applicable margin",null,0.35]
[]
[null,null,null,null,"Debt Service Reserve: Facility or Account",null,"1: DSRF\n2: DSRA",null,1]
[null,null,null,null,"Switch for transaction costs in taxes",null,"1: notional costs\n2: actual costs",null,2]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"$I$148","v":"2013-01-01"},{"$f":"+K131+1","v":"2014-01-01"},{"$f":"+L131+1","v":"2015-01-01"},{"$f":"+M131+1","v":"2016-01-01"},{"$f":"+N131+1","v":"2017-01-01"},{"$f":"+O131+1","v":"2018-01-01"},{"$f":"+P131+1","v":"2019-01-01"},{"$f":"+Q131+1","v":"2020-01-01"},{"$f":"+R131+1","v":"2021-01-01"},{"$f":"+S131+1","v":"2022-01-01"},{"$f":"+T131+1","v":"2023-01-01"},{"$f":"+U131+1","v":"2024-01-01"},{"$f":"+V131+1","v":"2025-01-01"},{"$f":"+W131+1","v":"2026-01-01"},{"$f":"+X131+1","v":"2027-01-01"},{"$f":"+Y131+1","v":"2028-01-01"},{"$f":"+Z131+1","v":"2029-01-01"},{"$f":"+AA131+1","v":"2030-01-01"},{"$f":"+AB131+1","v":"2031-01-01"},{"$f":"+AC131+1","v":"2032-01-01"},{"$f":"+AD131+1","v":"2033-01-01"},{"$f":"+AE131+1","v":"2034-01-01"},{"$f":"+AF131+1","v":"2035-01-01"},{"$f":"+AG131+1","v":"2036-01-01"},{"$f":"+AH131+1","v":"2037-01-01"},{"$f":"+AI131+1","v":"2038-01-01"},{"$f":"+AJ131+1","v":"2039-01-01"},{"$f":"+AK131+1","v":"2040-01-01"},{"$f":"+AL131+1","v":"2041-01-01"},{"$f":"+AM131+1","v":"2042-01-01"},{"$f":"+AN131+1","v":"2043-01-01"},{"$f":"+AO131+1","v":"2044-01-01"},{"$f":"+AP131+1","v":"2045-01-01"},{"$f":"+AQ131+1","v":"2046-01-01"},{"$f":"+AR131+1","v":"2047-01-01"},{"$f":"+AS131+1","v":"2048-01-01"},{"$f":"+AT131+1","v":"2049-01-01"},{"$f":"+AU131+1","v":"2050-01-01"},{"$f":"+AV131+1","v":"2051-01-01"},{"$f":"+AW131+1","v":"2052-01-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"EOMONTH(K130,11)","v":"2013-12-31"},{"$f":"DATE(YEAR(K131) + 1, MONTH(K131), DAY(K131))","v":"2014-12-31"},{"$f":"DATE(YEAR(L131) + 1, MONTH(L131), DAY(L131))","v":"2015-12-31"},{"$f":"DATE(YEAR(M131) + 1, MONTH(M131), DAY(M131))","v":"2016-12-31"},{"$f":"DATE(YEAR(N131) + 1, MONTH(N131), DAY(N131))","v":"2017-12-31"},{"$f":"DATE(YEAR(O131) + 1, MONTH(O131), DAY(O131))","v":"2018-12-31"},{"$f":"DATE(YEAR(P131) + 1, MONTH(P131), DAY(P131))","v":"2019-12-31"},{"$f":"DATE(YEAR(Q131) + 1, MONTH(Q131), DAY(Q131))","v":"2020-12-31"},{"$f":"DATE(YEAR(R131) + 1, MONTH(R131), DAY(R131))","v":"2021-12-31"},{"$f":"DATE(YEAR(S131) + 1, MONTH(S131), DAY(S131))","v":"2022-12-31"},{"$f":"DATE(YEAR(T131) + 1, MONTH(T131), DAY(T131))","v":"2023-12-31"},{"$f":"DATE(YEAR(U131) + 1, MONTH(U131), DAY(U131))","v":"2024-12-31"},{"$f":"DATE(YEAR(V131) + 1, MONTH(V131), DAY(V131))","v":"2025-12-31"},{"$f":"DATE(YEAR(W131) + 1, MONTH(W131), DAY(W131))","v":"2026-12-31"},{"$f":"DATE(YEAR(X131) + 1, MONTH(X131), DAY(X131))","v":"2027-12-31"},{"$f":"DATE(YEAR(Y131) + 1, MONTH(Y131), DAY(Y131))","v":"2028-12-31"},{"$f":"DATE(YEAR(Z131) + 1, MONTH(Z131), DAY(Z131))","v":"2029-12-31"},{"$f":"DATE(YEAR(AA131) + 1, MONTH(AA131), DAY(AA131))","v":"2030-12-31"},{"$f":"DATE(YEAR(AB131) + 1, MONTH(AB131), DAY(AB131))","v":"2031-12-31"},{"$f":"DATE(YEAR(AC131) + 1, MONTH(AC131), DAY(AC131))","v":"2032-12-31"},{"$f":"DATE(YEAR(AD131) + 1, MONTH(AD131), DAY(AD131))","v":"2033-12-31"},{"$f":"DATE(YEAR(AE131) + 1, MONTH(AE131), DAY(AE131))","v":"2034-12-31"},{"$f":"DATE(YEAR(AF131) + 1, MONTH(AF131), DAY(AF131))","v":"2035-12-31"},{"$f":"DATE(YEAR(AG131) + 1, MONTH(AG131), DAY(AG131))","v":"2036-12-31"},{"$f":"DATE(YEAR(AH131) + 1, MONTH(AH131), DAY(AH131))","v":"2037-12-31"},{"$f":"DATE(YEAR(AI131) + 1, MONTH(AI131), DAY(AI131))","v":"2038-12-31"},{"$f":"DATE(YEAR(AJ131) + 1, MONTH(AJ131), DAY(AJ131))","v":"2039-12-31"},{"$f":"DATE(YEAR(AK131) + 1, MONTH(AK131), DAY(AK131))","v":"2040-12-31"},{"$f":"DATE(YEAR(AL131) + 1, MONTH(AL131), DAY(AL131))","v":"2041-12-31"},{"$f":"DATE(YEAR(AM131) + 1, MONTH(AM131), DAY(AM131))","v":"2042-12-31"},{"$f":"DATE(YEAR(AN131) + 1, MONTH(AN131), DAY(AN131))","v":"2043-12-31"},{"$f":"DATE(YEAR(AO131) + 1, MONTH(AO131), DAY(AO131))","v":"2044-12-31"},{"$f":"DATE(YEAR(AP131) + 1, MONTH(AP131), DAY(AP131))","v":"2045-12-31"},{"$f":"DATE(YEAR(AQ131) + 1, MONTH(AQ131), DAY(AQ131))","v":"2046-12-31"},{"$f":"DATE(YEAR(AR131) + 1, MONTH(AR131), DAY(AR131))","v":"2047-12-31"},{"$f":"DATE(YEAR(AS131) + 1, MONTH(AS131), DAY(AS131))","v":"2048-12-31"},{"$f":"DATE(YEAR(AT131) + 1, MONTH(AT131), DAY(AT131))","v":"2049-12-31"},{"$f":"DATE(YEAR(AU131) + 1, MONTH(AU131), DAY(AU131))","v":"2050-12-31"},{"$f":"DATE(YEAR(AV131) + 1, MONTH(AV131), DAY(AV131))","v":"2051-12-31"},{"$f":"DATE(YEAR(AW131) + 1, MONTH(AW131), DAY(AW131))","v":"2052-12-31"}]
[]
[null,null,null,null,"Senior Debt repayment year",null,"Year",null,null,null,{"$f":"K171","v":0},{"$f":"L171","v":0},0,0,0,0,0,0,0,0,0,8.4699453551912565E-2,1.0846994535519126,2.0846994535519126,3.0846994535519126,4.084699453551913,5.084699453551913,6.084699453551913,7.084699453551913,8.084699453551913,9.084699453551913,10.084699453551913,11.084699453551913,12.084699453551913,13.084699453551913,14.084699453551913,15.084699453551913,16.084699453551913,17.084699453551913,18.084699453551913,19.084699453551913,20.084699453551913,21.084699453551913,22.084699453551913,22.580589864510817,0,0,0,0,0]
[null,null,null,null,"Senior Debt repayment profile",null,"%",null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,1.9431121328306773E-2,2.4375989173664295E-2,2.6046951464214492E-2,2.9582447236245708E-2,3.1383612779133763E-2,3.2017818622522634E-2,2.8014349840947063E-2,3.5801376475390639E-2,4.2356185642239044E-2,4.3990570739643263E-2,4.683001111051064E-2,4.6828414199576771E-2,5.2689369291696576E-2,5.2068479294291738E-2,4.5739928343171157E-2,4.5877875113697966E-2,5.616076474181074E-2,5.7879677840293797E-2,6.2078161420472094E-2,6.278318854400268E-2,6.8457160170738288E-2,6.978553203890249E-2,1.9821014588527457E-2,0]
[]
[null,null,null,null,"Senior Debt operation margin (including swap margin)",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,1.62045E-2,1.62045E-2,1.62045E-2,1.62045E-2,1.62045E-2,1.6289199453551912E-2,1.7204500000000001E-2,1.7204500000000001E-2,1.7204500000000001E-2,1.7204500000000001E-2,1.7289199453551913E-2,1.8204500000000002E-2,1.8204500000000002E-2,1.8204500000000002E-2,1.8204500000000002E-2,1.8289199453551914E-2,1.9204500000000003E-2,1.9204500000000003E-2,1.9204500000000003E-2,1.9204500000000003E-2,1.9289199453551915E-2,2.02045E-2,2.02045E-2,2.02045E-2,0]
[null,null,null,null,"Debt Service Reserve Facility operation margin",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,1.451203645839935E-2,1.451203645839935E-2,1.451203645839935E-2,1.451203645839935E-2,1.451203645839935E-2,1.4596735911951262E-2,1.551203645839935E-2,1.551203645839935E-2,1.551203645839935E-2,1.551203645839935E-2,1.5596735911951261E-2,1.651203645839935E-2,1.651203645839935E-2,1.651203645839935E-2,1.651203645839935E-2,1.6596735911951262E-2,1.7512036458399348E-2,1.7512036458399348E-2,1.7512036458399348E-2,1.7512036458399348E-2,1.7596735911951263E-2,1.8512036458399349E-2,1.8512036458399349E-2,1.8512036458399349E-2,0]
[null,null,null,null,"Cap and Floor Liquidity Facility operation margin",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,1.4538303717231034E-2,1.4538303717231034E-2,1.4538303717231034E-2,1.4538303717231034E-2,1.4538303717231034E-2,1.4623003170782946E-2,1.5538303717231033E-2,1.5538303717231033E-2,1.5538303717231033E-2,1.5538303717231033E-2,1.5623003170782947E-2,1.6538303717231036E-2,1.6538303717231036E-2,1.6538303717231036E-2,1.6538303717231036E-2,1.6623003170782948E-2,1.7538303717231033E-2,1.7538303717231033E-2,1.7538303717231033E-2,1.7538303717231033E-2,1.7623003170782945E-2,1.8538303717231034E-2,1.8538303717231034E-2,1.8538303717231034E-2,0]
[null,null,null,null,"Standby Debt Facility operation margin",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"VAT Facility operation margin",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,1.2500000000000001E-2,0]
[null,null,null,null,"Other facilities operation margin",null,"nominal %",null,null,null,null,null,null,null,null,null,null,null,null,null,null,1.4999999999999999E-2,1.4999999999999999E-2,1.4999999999999999E-2,1.4999999999999999E-2,1.4999999999999999E-2,1.5084699453551911E-2,1.6E-2,1.6E-2,1.6E-2,1.6E-2,1.6084699453551912E-2,1.7000000000000001E-2,1.7000000000000001E-2,1.7000000000000001E-2,1.7000000000000001E-2,1.7084699453551913E-2,1.7999999999999999E-2,1.7999999999999999E-2,1.7999999999999999E-2,1.7999999999999999E-2,1.8084699453551914E-2,1.9E-2,1.9E-2,1.9E-2,0]
[]
[null,null,"Model operation"]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"$I$148","v":"2013-01-01"},{"$f":"+K146+1","v":"2014-01-01"},{"$f":"+L146+1","v":"2015-01-01"},{"$f":"+M146+1","v":"2016-01-01"},{"$f":"+N146+1","v":"2017-01-01"},{"$f":"+O146+1","v":"2018-01-01"},{"$f":"+P146+1","v":"2019-01-01"},{"$f":"+Q146+1","v":"2020-01-01"},{"$f":"+R146+1","v":"2021-01-01"},{"$f":"+S146+1","v":"2022-01-01"},{"$f":"+T146+1","v":"2023-01-01"},{"$f":"+U146+1","v":"2024-01-01"},{"$f":"+V146+1","v":"2025-01-01"},{"$f":"+W146+1","v":"2026-01-01"},{"$f":"+X146+1","v":"2027-01-01"},{"$f":"+Y146+1","v":"2028-01-01"},{"$f":"+Z146+1","v":"2029-01-01"},{"$f":"+AA146+1","v":"2030-01-01"},{"$f":"+AB146+1","v":"2031-01-01"},{"$f":"+AC146+1","v":"2032-01-01"},{"$f":"+AD146+1","v":"2033-01-01"},{"$f":"+AE146+1","v":"2034-01-01"},{"$f":"+AF146+1","v":"2035-01-01"},{"$f":"+AG146+1","v":"2036-01-01"},{"$f":"+AH146+1","v":"2037-01-01"},{"$f":"+AI146+1","v":"2038-01-01"},{"$f":"+AJ146+1","v":"2039-01-01"},{"$f":"+AK146+1","v":"2040-01-01"},{"$f":"+AL146+1","v":"2041-01-01"},{"$f":"+AM146+1","v":"2042-01-01"},{"$f":"+AN146+1","v":"2043-01-01"},{"$f":"+AO146+1","v":"2044-01-01"},{"$f":"+AP146+1","v":"2045-01-01"},{"$f":"+AQ146+1","v":"2046-01-01"},{"$f":"+AR146+1","v":"2047-01-01"},{"$f":"+AS146+1","v":"2048-01-01"},{"$f":"+AT146+1","v":"2049-01-01"},{"$f":"+AU146+1","v":"2050-01-01"},{"$f":"+AV146+1","v":"2051-01-01"},{"$f":"+AW146+1","v":"2052-01-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"EOMONTH(K145,11)","v":"2013-12-31"},{"$f":"DATE(YEAR(K146) + 1, MONTH(K146), DAY(K146))","v":"2014-12-31"},{"$f":"DATE(YEAR(L146) + 1, MONTH(L146), DAY(L146))","v":"2015-12-31"},{"$f":"DATE(YEAR(M146) + 1, MONTH(M146), DAY(M146))","v":"2016-12-31"},{"$f":"DATE(YEAR(N146) + 1, MONTH(N146), DAY(N146))","v":"2017-12-31"},{"$f":"DATE(YEAR(O146) + 1, MONTH(O146), DAY(O146))","v":"2018-12-31"},{"$f":"DATE(YEAR(P146) + 1, MONTH(P146), DAY(P146))","v":"2019-12-31"},{"$f":"DATE(YEAR(Q146) + 1, MONTH(Q146), DAY(Q146))","v":"2020-12-31"},{"$f":"DATE(YEAR(R146) + 1, MONTH(R146), DAY(R146))","v":"2021-12-31"},{"$f":"DATE(YEAR(S146) + 1, MONTH(S146), DAY(S146))","v":"2022-12-31"},{"$f":"DATE(YEAR(T146) + 1, MONTH(T146), DAY(T146))","v":"2023-12-31"},{"$f":"DATE(YEAR(U146) + 1, MONTH(U146), DAY(U146))","v":"2024-12-31"},{"$f":"DATE(YEAR(V146) + 1, MONTH(V146), DAY(V146))","v":"2025-12-31"},{"$f":"DATE(YEAR(W146) + 1, MONTH(W146), DAY(W146))","v":"2026-12-31"},{"$f":"DATE(YEAR(X146) + 1, MONTH(X146), DAY(X146))","v":"2027-12-31"},{"$f":"DATE(YEAR(Y146) + 1, MONTH(Y146), DAY(Y146))","v":"2028-12-31"},{"$f":"DATE(YEAR(Z146) + 1, MONTH(Z146), DAY(Z146))","v":"2029-12-31"},{"$f":"DATE(YEAR(AA146) + 1, MONTH(AA146), DAY(AA146))","v":"2030-12-31"},{"$f":"DATE(YEAR(AB146) + 1, MONTH(AB146), DAY(AB146))","v":"2031-12-31"},{"$f":"DATE(YEAR(AC146) + 1, MONTH(AC146), DAY(AC146))","v":"2032-12-31"},{"$f":"DATE(YEAR(AD146) + 1, MONTH(AD146), DAY(AD146))","v":"2033-12-31"},{"$f":"DATE(YEAR(AE146) + 1, MONTH(AE146), DAY(AE146))","v":"2034-12-31"},{"$f":"DATE(YEAR(AF146) + 1, MONTH(AF146), DAY(AF146))","v":"2035-12-31"},{"$f":"DATE(YEAR(AG146) + 1, MONTH(AG146), DAY(AG146))","v":"2036-12-31"},{"$f":"DATE(YEAR(AH146) + 1, MONTH(AH146), DAY(AH146))","v":"2037-12-31"},{"$f":"DATE(YEAR(AI146) + 1, MONTH(AI146), DAY(AI146))","v":"2038-12-31"},{"$f":"DATE(YEAR(AJ146) + 1, MONTH(AJ146), DAY(AJ146))","v":"2039-12-31"},{"$f":"DATE(YEAR(AK146) + 1, MONTH(AK146), DAY(AK146))","v":"2040-12-31"},{"$f":"DATE(YEAR(AL146) + 1, MONTH(AL146), DAY(AL146))","v":"2041-12-31"},{"$f":"DATE(YEAR(AM146) + 1, MONTH(AM146), DAY(AM146))","v":"2042-12-31"},{"$f":"DATE(YEAR(AN146) + 1, MONTH(AN146), DAY(AN146))","v":"2043-12-31"},{"$f":"DATE(YEAR(AO146) + 1, MONTH(AO146), DAY(AO146))","v":"2044-12-31"},{"$f":"DATE(YEAR(AP146) + 1, MONTH(AP146), DAY(AP146))","v":"2045-12-31"},{"$f":"DATE(YEAR(AQ146) + 1, MONTH(AQ146), DAY(AQ146))","v":"2046-12-31"},{"$f":"DATE(YEAR(AR146) + 1, MONTH(AR146), DAY(AR146))","v":"2047-12-31"},{"$f":"DATE(YEAR(AS146) + 1, MONTH(AS146), DAY(AS146))","v":"2048-12-31"},{"$f":"DATE(YEAR(AT146) + 1, MONTH(AT146), DAY(AT146))","v":"2049-12-31"},{"$f":"DATE(YEAR(AU146) + 1, MONTH(AU146), DAY(AU146))","v":"2050-12-31"},{"$f":"DATE(YEAR(AV146) + 1, MONTH(AV146), DAY(AV146))","v":"2051-12-31"},{"$f":"DATE(YEAR(AW146) + 1, MONTH(AW146), DAY(AW146))","v":"2052-12-31"}]
[]
[null,null,null,null,"Model start date",null,"date",null,"2013-01-01"]
[null,null,null,null,"Regime start date",null,"date",null,"2022-05-01"]
[null,null,null,null,"End date for IDC",null,"date",null,"2024-11-30"]
[null,null,null,null,"Start of operations",null,"date",null,"2024-12-01"]
[null,null,null,null,"Regime end date",null,"date",null,{"$f":"DATE(YEAR($I$149)+I155,MONTH($I$149),DAY($I$149))-1","v":"2047-04-30"}]
[null,null,null,null,"Debt end date",null,"date",null,{"$f":"EOMONTH(I151-1,I85*12)","v":"2047-06-30"}]
[null,null,null,null,"Debt tail end date",null,"date",null,{"$f":"MIN(EOMONTH(I151-1,(I85+I86)*12),I152)","v":"2047-04-30"}]
[null,null,null,null,"Number of operational years",null,"full years",null,25]
[]
[null,null,null,null,"Debt tenor <= (Regime end date - Start of operations)",null,"check",null,{"$f":"I85<=ROUND((I152-I151)/365.25,0)","v":false}]
[]
[null,null,null,null,"Days in year",null,"days",null,null,null,{"$f":"K$146-K$145+1","v":365},365,{"$f":"M$146-M$145+1","v":365},{"$f":"N$146-N$145+1","v":366},365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366]
[null,null,null,null,"IDC flag",null,"flag",null,null,null,{"$f":"IF($I$150>=K$146,1,IF($I$150>=K$145,($I$150-K$145+1)/K$159,0))","v":1},{"$f":"IF($I$150>=L$146,1,IF($I$150>=L$145,($I$150-L$145+1)/L$159,0))","v":1},1,1,1,1,1,1,1,1,1,0.91530054644808745,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"IF(OR(K160=1,K162=1),0,IF($I$151<K145,0,IF($I$151<K146,($I$151-(MAX($I$150+1,K145)))/K159,MIN(1,(K146-$I$150)/K159))))","v":0},{"$f":"IF(OR(L160=1,L162=1),0,IF($I$151<L145,0,IF($I$151<L146,($I$151-(MAX($I$150+1,L145)))/L159,MIN(1,(L146-$I$150)/L159))))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"IF(OR($I$151>K$146,$I$152<K$145),0,IF($I$151>=K$145,(K$146-$I$151+1)/K$159,IF($I$152<=K$146,($I$152-K$145+1)/K$159,1)))","v":0},0,0,0,0,0,0,0,0,0,0,8.4699453551912565E-2,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,0.32876712328767121,0,0,0,0,0]
[null,null,null,null,"Regime flag",null,"flag",null,null,null,{"$f":"IF(OR($I$149>K$146,$I$152<K$145),0,IF($I$149>=K$145,(K$146-$I$149+1)/K$159,IF($I$152<=K$146,($I$152-K$145+1)/K$159,1)))","v":0},{"$f":"IF(OR($I$149>L$146,$I$152<L$145),0,IF($I$149>=L$145,(L$146-$I$149+1)/L$159,IF($I$152<=L$146,($I$152-L$145+1)/L$159,1)))","v":0},0,0,0,0,0,0,0,0.67123287671232879,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,0.32876712328767121,0,0,0,0,0]
[null,null,null,null,"Regime years",null,"count",null,null,null,{"$f":"ROUNDUP(SUM($K$163:K163)*(K163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:L163)*(L163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:M163)*(M163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:N163)*(N163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:O163)*(O163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:P163)*(P163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:Q163)*(Q163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:R163)*(R163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:S163)*(S163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:T163)*(T163<>0),0)","v":1},{"$f":"ROUNDUP(SUM($K$163:U163)*(U163<>0),0)","v":2},{"$f":"ROUNDUP(SUM($K$163:V163)*(V163<>0),0)","v":3},{"$f":"ROUNDUP(SUM($K$163:W163)*(W163<>0),0)","v":4},{"$f":"ROUNDUP(SUM($K$163:X163)*(X163<>0),0)","v":5},{"$f":"ROUNDUP(SUM($K$163:Y163)*(Y163<>0),0)","v":6},{"$f":"ROUNDUP(SUM($K$163:Z163)*(Z163<>0),0)","v":7},{"$f":"ROUNDUP(SUM($K$163:AA163)*(AA163<>0),0)","v":8},{"$f":"ROUNDUP(SUM($K$163:AB163)*(AB163<>0),0)","v":9},{"$f":"ROUNDUP(SUM($K$163:AC163)*(AC163<>0),0)","v":10},{"$f":"ROUNDUP(SUM($K$163:AD163)*(AD163<>0),0)","v":11},{"$f":"ROUNDUP(SUM($K$163:AE163)*(AE163<>0),0)","v":12},{"$f":"ROUNDUP(SUM($K$163:AF163)*(AF163<>0),0)","v":13},{"$f":"ROUNDUP(SUM($K$163:AG163)*(AG163<>0),0)","v":14},{"$f":"ROUNDUP(SUM($K$163:AH163)*(AH163<>0),0)","v":15},{"$f":"ROUNDUP(SUM($K$163:AI163)*(AI163<>0),0)","v":16},{"$f":"ROUNDUP(SUM($K$163:AJ163)*(AJ163<>0),0)","v":17},{"$f":"ROUNDUP(SUM($K$163:AK163)*(AK163<>0),0)","v":18},{"$f":"ROUNDUP(SUM($K$163:AL163)*(AL163<>0),0)","v":19},{"$f":"ROUNDUP(SUM($K$163:AM163)*(AM163<>0),0)","v":20},{"$f":"ROUNDUP(SUM($K$163:AN163)*(AN163<>0),0)","v":21},{"$f":"ROUNDUP(SUM($K$163:AO163)*(AO163<>0),0)","v":22},{"$f":"ROUNDUP(SUM($K$163:AP163)*(AP163<>0),0)","v":23},{"$f":"ROUNDUP(SUM($K$163:AQ163)*(AQ163<>0),0)","v":24},{"$f":"ROUNDUP(SUM($K$163:AR163)*(AR163<>0),0)","v":25},{"$f":"ROUNDUP(SUM($K$163:AS163)*(AS163<>0),0)","v":25},{"$f":"ROUNDUP(SUM($K$163:AT163)*(AT163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:AU163)*(AU163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:AV163)*(AV163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:AW163)*(AW163<>0),0)","v":0},{"$f":"ROUNDUP(SUM($K$163:AX163)*(AX163<>0),0)","v":0}]
[null,null,null,null,"Transfer construction to operations flag - Notional",null,"flag",null,null,null,{"$f":"IF(AND(SUM(K34:K36)<>0,SUM(L34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(L34:L36)<>0,SUM(M34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(M34:M36)<>0,SUM(N34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(N34:N36)<>0,SUM(O34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(O34:O36)<>0,SUM(P34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(P34:P36)<>0,SUM(Q34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Q34:Q36)<>0,SUM(R34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(R34:R36)<>0,SUM(S34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(S34:S36)<>0,SUM(T34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(T34:T36)<>0,SUM(U34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(U34:U36)<>0,SUM(V34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(V34:V36)<>0,SUM(W34:$AY36)=0),1,0)","v":1},{"$f":"IF(AND(SUM(W34:W36)<>0,SUM(X34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(X34:X36)<>0,SUM(Y34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Y34:Y36)<>0,SUM(Z34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Z34:Z36)<>0,SUM(AA34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AA34:AA36)<>0,SUM(AB34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AB34:AB36)<>0,SUM(AC34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AC34:AC36)<>0,SUM(AD34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AD34:AD36)<>0,SUM(AE34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AE34:AE36)<>0,SUM(AF34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AF34:AF36)<>0,SUM(AG34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AG34:AG36)<>0,SUM(AH34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AH34:AH36)<>0,SUM(AI34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AI34:AI36)<>0,SUM(AJ34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AJ34:AJ36)<>0,SUM(AK34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AK34:AK36)<>0,SUM(AL34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AL34:AL36)<>0,SUM(AM34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AM34:AM36)<>0,SUM(AN34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AN34:AN36)<>0,SUM(AO34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AO34:AO36)<>0,SUM(AP34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AP34:AP36)<>0,SUM(AQ34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AQ34:AQ36)<>0,SUM(AR34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AR34:AR36)<>0,SUM(AS34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AS34:AS36)<>0,SUM(AT34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AT34:AT36)<>0,SUM(AU34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AU34:AU36)<>0,SUM(AV34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AV34:AV36)<>0,SUM(AW34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AW34:AW36)<>0,SUM(AX34:$AY36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AX34:AX36)<>0,SUM(AY34:$AY36)=0),1,0)","v":0}]
[null,null,null,null,"Transfer construction to operations flag - ACOD",null,"flag","`",null,null,{"$f":"IF(AND($I$151<=K$146,$I$151>=K$145),1,0)","v":0},0,{"$f":"IF(AND($I$151<=M$146,$I$151>=M$145),1,0)","v":0},{"$f":"IF(AND($I$151<=N$146,$I$151>=N$145),1,0)","v":0},0,0,0,0,0,0,0,1,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Initial transaction costs flag",null,"flag",null,null,null,{"$f":"IF(AND(SUM($J35:K35)=0,L35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:L35)=0,M35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:M35)=0,N35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:N35)=0,O35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:O35)=0,P35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:P35)=0,Q35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Q35)=0,R35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:R35)=0,S35>0),1,0)","v":1},{"$f":"IF(AND(SUM($J35:S35)=0,T35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:T35)=0,U35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:U35)=0,V35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:V35)=0,W35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:W35)=0,X35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:X35)=0,Y35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Y35)=0,Z35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Z35)=0,AA35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AA35)=0,AB35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AB35)=0,AC35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AC35)=0,AD35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AD35)=0,AE35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AE35)=0,AF35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AF35)=0,AG35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AG35)=0,AH35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AH35)=0,AI35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AI35)=0,AJ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AJ35)=0,AK35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AK35)=0,AL35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AL35)=0,AM35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AM35)=0,AN35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AN35)=0,AO35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AO35)=0,AP35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AP35)=0,AQ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AQ35)=0,AR35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AR35)=0,AS35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AS35)=0,AT35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AT35)=0,AU35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AU35)=0,AV35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AV35)=0,AW35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AW35)=0,AX35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AX35)=0,AY35>0),1,0)","v":0}]
[null,null,null,null,"Financial close flag",null,"flag",null,null,null,{"$f":"IF(AND(SUM($J35:J35)=0,K35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:K35)=0,L35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:L35)=0,M35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:M35)=0,N35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:N35)=0,O35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:O35)=0,P35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:P35)=0,Q35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Q35)=0,R35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:R35)=0,S35>0),1,0)","v":1},{"$f":"IF(AND(SUM($J35:S35)=0,T35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:T35)=0,U35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:U35)=0,V35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:V35)=0,W35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:W35)=0,X35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:X35)=0,Y35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Y35)=0,Z35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Z35)=0,AA35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AA35)=0,AB35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AB35)=0,AC35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AC35)=0,AD35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AD35)=0,AE35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AE35)=0,AF35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AF35)=0,AG35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AG35)=0,AH35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AH35)=0,AI35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AI35)=0,AJ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AJ35)=0,AK35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AK35)=0,AL35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AL35)=0,AM35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AM35)=0,AN35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AN35)=0,AO35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AO35)=0,AP35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AP35)=0,AQ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AQ35)=0,AR35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AR35)=0,AS35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AS35)=0,AT35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AT35)=0,AU35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AU35)=0,AV35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AV35)=0,AW35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AW35)=0,AX35>0),1,0)","v":0}]
[null,null,null,null,"Debt drawdown flag",null,"flag",null,null,null,{"$f":"(SUM($J$168:K168)>=1)*(SUM($J$166:K166)<1)","v":0},{"$f":"(SUM($J$168:L168)>=1)*(SUM($J$166:L166)<1)","v":0},{"$f":"(SUM($J$168:M168)>=1)*(SUM($J$166:M166)<1)","v":0},{"$f":"(SUM($J$168:N168)>=1)*(SUM($J$166:N166)<1)","v":0},{"$f":"(SUM($J$168:O168)>=1)*(SUM($J$166:O166)<1)","v":0},{"$f":"(SUM($J$168:P168)>=1)*(SUM($J$166:P166)<1)","v":0},{"$f":"(SUM($J$168:Q168)>=1)*(SUM($J$166:Q166)<1)","v":0},{"$f":"(SUM($J$168:R168)>=1)*(SUM($J$166:R166)<1)","v":0},{"$f":"(SUM($J$168:S168)>=1)*(SUM($J$166:S166)<1)","v":1},{"$f":"(SUM($J$168:T168)>=1)*(SUM($J$166:T166)<1)","v":1},{"$f":"(SUM($J$168:U168)>=1)*(SUM($J$166:U166)<1)","v":1},{"$f":"(SUM($J$168:V168)>=1)*(SUM($J$166:V166)<1)","v":0},{"$f":"(SUM($J$168:W168)>=1)*(SUM($J$166:W166)<1)","v":0},{"$f":"(SUM($J$168:X168)>=1)*(SUM($J$166:X166)<1)","v":0},{"$f":"(SUM($J$168:Y168)>=1)*(SUM($J$166:Y166)<1)","v":0},{"$f":"(SUM($J$168:Z168)>=1)*(SUM($J$166:Z166)<1)","v":0},{"$f":"(SUM($J$168:AA168)>=1)*(SUM($J$166:AA166)<1)","v":0},{"$f":"(SUM($J$168:AB168)>=1)*(SUM($J$166:AB166)<1)","v":0},{"$f":"(SUM($J$168:AC168)>=1)*(SUM($J$166:AC166)<1)","v":0},{"$f":"(SUM($J$168:AD168)>=1)*(SUM($J$166:AD166)<1)","v":0},{"$f":"(SUM($J$168:AE168)>=1)*(SUM($J$166:AE166)<1)","v":0},{"$f":"(SUM($J$168:AF168)>=1)*(SUM($J$166:AF166)<1)","v":0},{"$f":"(SUM($J$168:AG168)>=1)*(SUM($J$166:AG166)<1)","v":0},{"$f":"(SUM($J$168:AH168)>=1)*(SUM($J$166:AH166)<1)","v":0},{"$f":"(SUM($J$168:AI168)>=1)*(SUM($J$166:AI166)<1)","v":0},{"$f":"(SUM($J$168:AJ168)>=1)*(SUM($J$166:AJ166)<1)","v":0},{"$f":"(SUM($J$168:AK168)>=1)*(SUM($J$166:AK166)<1)","v":0},{"$f":"(SUM($J$168:AL168)>=1)*(SUM($J$166:AL166)<1)","v":0},{"$f":"(SUM($J$168:AM168)>=1)*(SUM($J$166:AM166)<1)","v":0},{"$f":"(SUM($J$168:AN168)>=1)*(SUM($J$166:AN166)<1)","v":0},{"$f":"(SUM($J$168:AO168)>=1)*(SUM($J$166:AO166)<1)","v":0},{"$f":"(SUM($J$168:AP168)>=1)*(SUM($J$166:AP166)<1)","v":0},{"$f":"(SUM($J$168:AQ168)>=1)*(SUM($J$166:AQ166)<1)","v":0},{"$f":"(SUM($J$168:AR168)>=1)*(SUM($J$166:AR166)<1)","v":0},{"$f":"(SUM($J$168:AS168)>=1)*(SUM($J$166:AS166)<1)","v":0},{"$f":"(SUM($J$168:AT168)>=1)*(SUM($J$166:AT166)<1)","v":0},{"$f":"(SUM($J$168:AU168)>=1)*(SUM($J$166:AU166)<1)","v":0},{"$f":"(SUM($J$168:AV168)>=1)*(SUM($J$166:AV166)<1)","v":0},{"$f":"(SUM($J$168:AW168)>=1)*(SUM($J$166:AW166)<1)","v":0},{"$f":"(SUM($J$168:AX168)>=1)*(SUM($J$166:AX166)<1)","v":0}]
[null,null,null,null,"Debt repayment flag",null,"flag",null,null,null,{"$f":"IF(OR($I$151>K$146,$I$153<K$145),0,IF($I$151>=K$145,(K$146-$I$151+1)/K$159,IF($I$153<=K$146,($I$153-K$145+1)/K$159,1)))","v":0},{"$f":"IF(OR($I$151>L$146,$I$153<L$145),0,IF($I$151>=L$145,(L$146-$I$151+1)/L$159,IF($I$153<=L$146,($I$153-L$145+1)/L$159,1)))","v":0},0,0,0,0,0,0,0,0,0,8.4699453551912565E-2,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,0.49589041095890413,0,0,0,0,0]
[null,null,null,null,"Debt repayment years",null,"count",null,null,null,{"$f":"SUM($K$170:K170)*(K170<>0)","v":0},{"$f":"SUM($K$170:L170)*(L170<>0)","v":0},{"$f":"SUM($K$170:M170)*(M170<>0)","v":0},{"$f":"SUM($K$170:N170)*(N170<>0)","v":0},{"$f":"SUM($K$170:O170)*(O170<>0)","v":0},{"$f":"SUM($K$170:P170)*(P170<>0)","v":0},{"$f":"SUM($K$170:Q170)*(Q170<>0)","v":0},{"$f":"SUM($K$170:R170)*(R170<>0)","v":0},{"$f":"SUM($K$170:S170)*(S170<>0)","v":0},{"$f":"SUM($K$170:T170)*(T170<>0)","v":0},{"$f":"SUM($K$170:U170)*(U170<>0)","v":0},{"$f":"SUM($K$170:V170)*(V170<>0)","v":8.4699453551912565E-2},{"$f":"SUM($K$170:W170)*(W170<>0)","v":1.0846994535519126},{"$f":"SUM($K$170:X170)*(X170<>0)","v":2.0846994535519126},{"$f":"SUM($K$170:Y170)*(Y170<>0)","v":3.0846994535519126},{"$f":"SUM($K$170:Z170)*(Z170<>0)","v":4.084699453551913},{"$f":"SUM($K$170:AA170)*(AA170<>0)","v":5.084699453551913},{"$f":"SUM($K$170:AB170)*(AB170<>0)","v":6.084699453551913},{"$f":"SUM($K$170:AC170)*(AC170<>0)","v":7.084699453551913},{"$f":"SUM($K$170:AD170)*(AD170<>0)","v":8.084699453551913},{"$f":"SUM($K$170:AE170)*(AE170<>0)","v":9.084699453551913},{"$f":"SUM($K$170:AF170)*(AF170<>0)","v":10.084699453551913},{"$f":"SUM($K$170:AG170)*(AG170<>0)","v":11.084699453551913},{"$f":"SUM($K$170:AH170)*(AH170<>0)","v":12.084699453551913},{"$f":"SUM($K$170:AI170)*(AI170<>0)","v":13.084699453551913},{"$f":"SUM($K$170:AJ170)*(AJ170<>0)","v":14.084699453551913},{"$f":"SUM($K$170:AK170)*(AK170<>0)","v":15.084699453551913},{"$f":"SUM($K$170:AL170)*(AL170<>0)","v":16.084699453551913},{"$f":"SUM($K$170:AM170)*(AM170<>0)","v":17.084699453551913},{"$f":"SUM($K$170:AN170)*(AN170<>0)","v":18.084699453551913},{"$f":"SUM($K$170:AO170)*(AO170<>0)","v":19.084699453551913},{"$f":"SUM($K$170:AP170)*(AP170<>0)","v":20.084699453551913},{"$f":"SUM($K$170:AQ170)*(AQ170<>0)","v":21.084699453551913},{"$f":"SUM($K$170:AR170)*(AR170<>0)","v":22.084699453551913},{"$f":"SUM($K$170:AS170)*(AS170<>0)","v":22.580589864510817},{"$f":"SUM($K$170:AT170)*(AT170<>0)","v":0},{"$f":"SUM($K$170:AU170)*(AU170<>0)","v":0},{"$f":"SUM($K$170:AV170)*(AV170<>0)","v":0},{"$f":"SUM($K$170:AW170)*(AW170<>0)","v":0},{"$f":"SUM($K$170:AX170)*(AX170<>0)","v":0}]
[null,null,null,null,"Debt tail flag",null,"flag",null,null,null,{"$f":"IF(OR($I$151>K$146,$I$154<K$145),0,IF($I$151>=K$145,(K$146-$I$151+1)/K$159,IF($I$154<=K$146,($I$154-K$145+1)/K$159,1)))-K170","v":0},{"$f":"IF(OR($I$151>L$146,$I$154<L$145),0,IF($I$151>=L$145,(L$146-$I$151+1)/L$159,IF($I$154<=L$146,($I$154-L$145+1)/L$159,1)))-L170","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,-0.16712328767123291,0,0,0,0,0]
[]
[null,null,"Tax - Financial years"]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"K17","v":"2013-01-01"},{"$f":"+K177+1","v":"2014-01-01"},{"$f":"+L177+1","v":"2015-01-01"},{"$f":"+M177+1","v":"2016-01-01"},"2017-01-01","2018-01-01","2019-01-01","2020-01-01","2021-01-01","2022-01-01","2023-01-01","2024-01-01","2025-01-01","2026-01-01","2027-01-01","2028-01-01","2029-01-01","2030-01-01","2031-01-01","2032-01-01","2033-01-01","2034-01-01","2035-01-01","2036-01-01","2037-01-01","2038-01-01","2039-01-01","2040-01-01","2041-01-01","2042-01-01","2043-01-01","2044-01-01","2045-01-01","2046-01-01","2047-01-01","2048-01-01","2049-01-01","2050-01-01","2051-01-01","2052-01-01"]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"K18","v":"2013-12-31"},{"$f":"DATE(YEAR(K177) + 1, MONTH(K177), DAY(K177))","v":"2014-12-31"},"2015-12-31","2016-12-31","2017-12-31","2018-12-31","2019-12-31","2020-12-31","2021-12-31","2022-12-31","2023-12-31","2024-12-31","2025-12-31","2026-12-31","2027-12-31","2028-12-31","2029-12-31","2030-12-31","2031-12-31","2032-12-31","2033-12-31","2034-12-31","2035-12-31","2036-12-31","2037-12-31","2038-12-31","2039-12-31","2040-12-31","2041-12-31","2042-12-31","2043-12-31","2044-12-31","2045-12-31","2046-12-31","2047-12-31","2048-12-31","2049-12-31","2050-12-31","2051-12-31","2052-12-31"]
[]
[null,null,null,null,"Long-term expected UK RPI inflation",null,"%",null,4.2799999999999998E-2]
[null,null,null,null,{"$f":"E24","v":"Base year UK RPI inflation index value (CHAW)"},null,{"$f":"G24","v":"Jan 1987 = 100"},{"$f":"H24","v":"UK RPI index 2020/21"},{"$f":"I24","v":294.16666666666703}]
[]
[null,null,null,null,{"$f":"E28","v":"12 month average UK RPI inflation index value (CHAW)"},null,{"$f":"G28","v":"Jan 1987 = 100"},{"$f":"H28","v":"UK RPI index t"},null,null,{"$f":"K28","v":250.10833333333301},256.0333333333333,258.54166666666669,263.05,272.47500000000002,281.58333333333331,288.8,293.14166666666699,305,318.05399999999997,331.66671119999995,345.86204643935991,360.66494202696452,376.1014015457186,392.19854153187532,408.98463910943957,426.48918166332356,444.7429186385138,463.77791555624219,483.62761034204931,504.32687206468898,525.91206218905768,548.42109845074935,571.89352146444139,596.37056418311943,621.89522433015691,648.51233993148765,676.26866808055524,705.21296707440297,735.39608206518733,766.8710343775773,799.69311464893758,833.91997995591203,869.61175509802501,906.83113821622044,945.64351093187463,986.11705319975886,1028.3228630767085,1072.3350816163916,1118.231023109573]
[null,null,null,null,"UK RPI inflation uplift from 2019/20 term",null,"scalar",null,null,null,{"$f":"K182/$I$180","v":0.85022662889518197},{"$f":"L182/$I$180","v":0.87036827195467303},0.87889518413597634,0.89422096317280353,0.92626062322946068,0.9572237960339931,0.9817563739376759,0.99651558073654378,1.0368271954674209,1.0812033994334262,1.1274789049291769,1.1757350020601456,1.2260564601483199,1.278531676642668,1.333252832402974,1.3903160536298211,1.4498215807251775,1.5118739443802149,1.5765821491996883,1.6440598651854348,1.7144256274153713,1.7878030442687491,1.8643210145634517,1.9441139539867671,2.0273220312174005,2.1140914141535054,2.2045745266792753,2.2989303164211483,2.3973245339639733,2.499930024017631,2.6069270290455853,2.7185035058887363,2.8348554559407741,2.9561872694550391,3.0827120845877145,3.2146521618080683,3.3522392743334537,3.4957151152749253,3.6453317222086921,3.8013519199192238]
[]
[null,null,"Tax - Operational years"]
[]
[null,null,null,null,"Operational Year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,null,null,null,"Corporation tax rate",null,"%",null,null,null,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25,0.25]
[null,null,null,null,"Capital allowance rate (declining balance)",null,"%",null,null,null,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06,0.06]
[]
[null,null,null,null,{"$f":"E179","v":"Long-term expected UK RPI inflation"},null,"%",null,{"$f":"I179","v":4.2799999999999998E-2}]
[null,null,null,null,"Start of price base year",null,"date",null,"2020-04-01"]
[null,null,null,null,"End of price base year",null,"date",null,{"$f":"EOMONTH(I193,11)","v":"2021-03-31"}]
[null,null,null,null,"UK RPI uplift from 2020/21 term to start of regime",null,"scalar",null,{"$f":"(1+$I$192)^((I149-AVERAGE(I193,I194))/365.25)","v":1.0685693503755167}]
[]
[null,null,"Tax - Annuity"]
[]
[null,null,null,null,"Tax element of Cap and Floor annuity previously calculated and fixed",null,"choice",null,"No"]
[]
[null,"End of sheet"]

{"sheet":"Data Sources","index":3,"n_rows":135,"n_cols":12,"rows_kept":135,"cut":false,"hidden":false,"merged":[]}
["Data Sources",null,null,null,null,null,null,"Licence","Reference row in"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Inputs sheet",null,"Source","Link"]
[]
[null,"Indexation, currency and base year price term"]
[]
[null,null,null,null,{"$f":"Inputs!E6","v":"GB indexed portion of interconnector"},null,{"$f":"Inputs!G6","v":"choice %"},null,{"$f":"ROW(Inputs!E6)","v":6},null,"Project's licence"]
[null,null,null,null,{"$f":"Inputs!E9","v":"Currency of cost inputs"},null,{"$f":"Inputs!G9","v":"choice"},null,{"$f":"ROW(Inputs!E9)","v":9},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E11","v":"Base year price term"},null,{"$f":"Inputs!G11","v":"choice"},null,{"$f":"ROW(Inputs!E11)","v":11},null,"Project's licence"]
[]
[null,"Variables set after financial close"]
[]
[null,null,"Actual values"]
[]
[null,null,null,null,{"$f":"Inputs!E20","v":"Development costs"},null,{"$f":"Inputs!G20","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E20)","v":20},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E21","v":"Capex"},null,{"$f":"Inputs!G21","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E21)","v":21},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E22","v":"Spares"},null,{"$f":"Inputs!G22","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E22)","v":22},null,"Final Project Assessment decision"]
[]
[null,null,null,null,{"$f":"Inputs!E24","v":"Base year UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G24","v":"Jan 1987 = 100"},{"$f":"Inputs!H24","v":"UK RPI index 2020/21"},{"$f":"ROW(Inputs!E24)","v":24},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[null,null,null,null,{"$f":"Inputs!E25","v":0},null,{"$f":"Inputs!G25","v":0},null,{"$f":"ROW(Inputs!E25)","v":25}]
[null,null,null,null,{"$f":"Inputs!E26","v":0},null,{"$f":"Inputs!G26","v":0},null,{"$f":"ROW(Inputs!E26)","v":26},null,"Bank of England","XUMARES"]
[]
[null,null,null,null,{"$f":"Inputs!E28","v":"12 month average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G28","v":"Jan 1987 = 100"},{"$f":"Inputs!H28","v":"UK RPI index t"},{"$f":"ROW(Inputs!E28)","v":28},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[null,null,null,null,{"$f":"Inputs!E29","v":0},null,{"$f":"Inputs!G29","v":0},null,{"$f":"ROW(Inputs!E29)","v":29}]
[null,null,null,null,{"$f":"Inputs!E30","v":0},null,{"$f":"Inputs!G30","v":0},null,{"$f":"ROW(Inputs!E30)","v":30},null,"Bank of England","XUMAERS"]
[]
[null,null,"Ex-ante allowances for the operational period"]
[]
[null,null,null,null,{"$f":"Inputs!E42","v":"Replacement Capex"},null,{"$f":"Inputs!G42","v":"£m 2020 prices"},null,{"$f":"ROW(Inputs!E42)","v":42},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E43","v":"Decommissioning baseline"},null,{"$f":"Inputs!G43","v":"£m 2020 prices"},null,{"$f":"ROW(Inputs!E43)","v":43},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E44","v":"Controllable Opex"},null,{"$f":"Inputs!G44","v":"£m 2020 prices"},null,{"$f":"ROW(Inputs!E44)","v":44},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E45","v":"Non-controllable Opex baseline"},null,{"$f":"Inputs!G45","v":"£m 2020 prices"},null,{"$f":"ROW(Inputs!E45)","v":45},null,"Final Project Assessment decision"]
[]
[null,null,null,null,{"$f":"Inputs!E51","v":"2020 average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G51","v":"Jan 1987 = 100"},null,{"$f":"ROW(Inputs!E51)","v":51},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[null,null,null,null,{"$f":"Inputs!E52","v":"2020 average Ireland CPI inflation index value"},null,{"$f":"Inputs!G52","v":""},null,{"$f":"ROW(Inputs!E52)","v":52}]
[null,null,null,null,{"$f":"Inputs!E53","v":"2020 average exchange rate (XUMAERS)"},null,{"$f":"Inputs!G53","v":""},null,{"$f":"ROW(Inputs!E53)","v":53},null,"Bank of England","XUMAERS"]
[]
[null,null,null,null,{"$f":"Inputs!E55","v":""},null,{"$f":"Inputs!G55","v":""},{"$f":"Inputs!H55","v":""},{"$f":"ROW(Inputs!E55)","v":55},null,"Bank of England","XUMAERS"]
[]
[null,"Variables set at financial close"]
[]
[null,null,"Finance"]
[]
[null,null,null,null,{"$f":"Inputs!E68","v":"Cap return rate"},null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"ROW(Inputs!E68)","v":68},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E69","v":"Floor return rate"},null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"ROW(Inputs!E69)","v":69},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E70","v":"Interest during construction (IDC) rate"},null,{"$f":"Inputs!G70","v":"real annual %"},null,{"$f":"ROW(Inputs!E70)","v":70},null,"Ofgem's determination based on FID date"]
[]
[null,null,null,null,{"$f":"Inputs!E73","v":"Pre-operational notional gearing"},null,{"$f":"Inputs!G73","v":"%"},null,{"$f":"ROW(Inputs!E73)","v":73},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E74","v":"Operational notional gearing"},null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"ROW(Inputs!E74)","v":74},null,"Window 1 policy decision (fixed for Window 1 projects)"]
[]
[null,null,null,null,{"$f":"Inputs!E76","v":"Equity transaction costs"},null,{"$f":"Inputs!G76","v":"%"},null,{"$f":"ROW(Inputs!E76)","v":76},null,"Window 1 policy decision (fixed for Window 1 projects)"]
[null,null,null,null,{"$f":"Inputs!E77","v":"Debt transaction costs"},null,{"$f":"Inputs!G77","v":"%"},null,{"$f":"ROW(Inputs!E77)","v":77},null,"Window 1 policy decision (fixed for Window 1 projects)"]
[]
[null,null,"Actual cost of debt"]
[]
[null,null,null,null,{"$f":"Inputs!E81","v":"Project finance key input: senior debt amount or gearing"},null,{"$f":"Inputs!G81","v":"1: Amount (£m)\n2: Gearing (%)"},null,{"$f":"ROW(Inputs!E81)","v":81},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E82","v":"Project finance senior debt amount (input if 1; empty if 2)"},null,{"$f":"Inputs!G82","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E82)","v":82},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E83","v":"Project finance actual gearing (input if 2; empty if 1)"},null,{"$f":"Inputs!G83","v":"%"},null,{"$f":"ROW(Inputs!E83)","v":83},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E85","v":"Senior Debt tenor"},null,{"$f":"Inputs!G85","v":"full years"},null,{"$f":"ROW(Inputs!E85)","v":85},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E86","v":"Senior Debt tail requirement"},null,{"$f":"Inputs!G86","v":"full years"},null,{"$f":"ROW(Inputs!E86)","v":86},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E87","v":"DSCR sizing"},null,{"$f":"Inputs!G87","v":"DSCRx"},null,{"$f":"ROW(Inputs!E87)","v":87},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E89","v":"Fixed rate - Construction"},null,{"$f":"Inputs!G89","v":"nominal %"},null,{"$f":"ROW(Inputs!E89)","v":89},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E90","v":"Fixed rate - Operation"},null,{"$f":"Inputs!G90","v":"nominal %"},null,{"$f":"ROW(Inputs!E90)","v":90},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E92","v":"Senior Debt construction margin"},null,{"$f":"Inputs!G92","v":"nominal %"},null,{"$f":"ROW(Inputs!E92)","v":92},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E93","v":"of which: swap margin"},null,{"$f":"Inputs!G93","v":"nominal %"},null,{"$f":"ROW(Inputs!E93)","v":93},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E94","v":"Senior Debt upfront fee"},null,{"$f":"Inputs!G94","v":"nominal %"},null,{"$f":"ROW(Inputs!E94)","v":94},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E95","v":"Senior Debt commitment fee"},null,{"$f":"Inputs!G95","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E95)","v":95},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E97","v":"Senior Debt drawdown year"},null,{"$f":"Inputs!G97","v":"Year"},null,{"$f":"ROW(Inputs!E97)","v":97},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E98","v":"Senior Debt drawdown profile"},null,{"$f":"Inputs!G98","v":"%"},null,{"$f":"ROW(Inputs!E98)","v":98},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E100","v":"Debt Service Reserve Facility/Account amount"},null,{"$f":"Inputs!G100","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E100)","v":100},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E101","v":"Debt Service Reserve Facility upfront fee"},null,{"$f":"Inputs!G101","v":"nominal %"},null,{"$f":"ROW(Inputs!E101)","v":101},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E102","v":"Debt Service Reserve Facility construction margin"},null,{"$f":"Inputs!G102","v":"nominal %"},null,{"$f":"ROW(Inputs!E102)","v":102},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E103","v":"Debt Service Reserve Facility commitment fee"},null,{"$f":"Inputs!G103","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E103)","v":103},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E105","v":"Cap and Floor Liquidity Facility amount"},null,{"$f":"Inputs!G105","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E105)","v":105},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E107","v":"Cap and Floor Liquidity Facility upfront fee"},null,{"$f":"Inputs!G107","v":"nominal %"},null,{"$f":"ROW(Inputs!E107)","v":107},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E108","v":"Cap and Floor Liquidity Facility construction margin"},null,{"$f":"Inputs!G108","v":"nominal %"},null,{"$f":"ROW(Inputs!E108)","v":108},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E109","v":"Cap and Floor Liquidity Facility commitment fee"},null,{"$f":"Inputs!G109","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E109)","v":109},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E111","v":"Standby Debt Facility amount"},null,{"$f":"Inputs!G111","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E111)","v":111},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E112","v":"Standby Debt Facility upfront fee"},null,{"$f":"Inputs!G112","v":"nominal %"},null,{"$f":"ROW(Inputs!E112)","v":112},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E113","v":"Standby Debt Facility construction margin"},null,{"$f":"Inputs!G113","v":"nominal %"},null,{"$f":"ROW(Inputs!E113)","v":113},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E114","v":"Standby Debt Facility commitment fee"},null,{"$f":"Inputs!G114","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E114)","v":114},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E116","v":"VAT Facility amount"},null,{"$f":"Inputs!G116","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E116)","v":116},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E117","v":"VAT Facility average outstanding loan"},null,{"$f":"Inputs!G117","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E117)","v":117},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E118","v":"VAT Facility upfront fee"},null,{"$f":"Inputs!G118","v":"nominal %"},null,{"$f":"ROW(Inputs!E118)","v":118},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E119","v":"VAT Facility construction margin"},null,{"$f":"Inputs!G119","v":"nominal %"},null,{"$f":"ROW(Inputs!E119)","v":119},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E120","v":"VAT Facility commitment fee"},null,{"$f":"Inputs!G120","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E120)","v":120},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E122","v":"Other Facilities amount"},null,{"$f":"Inputs!G122","v":"£m nominal prices"},null,{"$f":"ROW(Inputs!E122)","v":122},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E123","v":"Other Facilities upfront fee"},null,{"$f":"Inputs!G123","v":"nominal %"},null,{"$f":"ROW(Inputs!E123)","v":123},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E124","v":"Other Facilities construction margin"},null,{"$f":"Inputs!G124","v":"nominal %"},null,{"$f":"ROW(Inputs!E124)","v":124},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E125","v":"Other Facilities commitment fee"},null,{"$f":"Inputs!G125","v":"% of applicable margin"},null,{"$f":"ROW(Inputs!E125)","v":125},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E127","v":"Debt Service Reserve: Facility or Account"},null,{"$f":"Inputs!G127","v":"1: DSRF\n2: DSRA"},null,{"$f":"ROW(Inputs!E127)","v":127},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E128","v":"Switch for transaction costs in taxes"},null,{"$f":"Inputs!G128","v":"1: notional costs\n2: actual costs"},null,{"$f":"ROW(Inputs!E128)","v":128},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E133","v":"Senior Debt repayment year"},null,{"$f":"Inputs!G133","v":"Year"},null,{"$f":"ROW(Inputs!E133)","v":133},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E134","v":"Senior Debt repayment profile"},null,{"$f":"Inputs!G134","v":"%"},null,{"$f":"ROW(Inputs!E134)","v":134},null,"Developer's Final Project Assessment submission"]
[]
[null,null,null,null,{"$f":"Inputs!E136","v":"Senior Debt operation margin (including swap margin)"},null,{"$f":"Inputs!G136","v":"nominal %"},null,{"$f":"ROW(Inputs!E136)","v":136},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E137","v":"Debt Service Reserve Facility operation margin"},null,{"$f":"Inputs!G137","v":"nominal %"},null,{"$f":"ROW(Inputs!E137)","v":137},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E138","v":"Cap and Floor Liquidity Facility operation margin"},null,{"$f":"Inputs!G138","v":"nominal %"},null,{"$f":"ROW(Inputs!E138)","v":138},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E139","v":"Standby Debt Facility operation margin"},null,{"$f":"Inputs!G139","v":"nominal %"},null,{"$f":"ROW(Inputs!E139)","v":139},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E140","v":"VAT Facility operation margin"},null,{"$f":"Inputs!G140","v":"nominal %"},null,{"$f":"ROW(Inputs!E140)","v":140},null,"Developer's Final Project Assessment submission"]
[null,null,null,null,{"$f":"Inputs!E141","v":"Other facilities operation margin"},null,{"$f":"Inputs!G141","v":"nominal %"},null,{"$f":"ROW(Inputs!E141)","v":141},null,"Developer's Final Project Assessment submission"]
[]
[null,null,"Model operation"]
[]
[null,null,null,null,{"$f":"Inputs!E149","v":"Regime start date"},null,{"$f":"Inputs!G149","v":"date"},null,{"$f":"ROW(Inputs!I149)","v":149},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E150","v":"End date for IDC"},null,{"$f":"Inputs!G150","v":"date"},null,{"$f":"ROW(Inputs!I150)","v":150},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E151","v":"Start of operations"},null,{"$f":"Inputs!G151","v":"date"},null,{"$f":"ROW(Inputs!I151)","v":151},null,"Final Project Assessment decision"]
[null,null,null,null,{"$f":"Inputs!E155","v":"Number of operational years"},null,{"$f":"Inputs!G155","v":"full years"},null,{"$f":"ROW(Inputs!I155)","v":155},null,"Project's licence"]
[]
[null,null,"Tax - Financial years"]
[]
[null,null,null,null,{"$f":"Inputs!E179","v":"Long-term expected UK RPI inflation"},null,{"$f":"Inputs!G179","v":"%"},null,{"$f":"ROW(Inputs!E179)","v":179},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E182","v":"12 month average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G182","v":"Jan 1987 = 100"},{"$f":"Inputs!H182","v":"UK RPI index t"},{"$f":"ROW(Inputs!E182)","v":182},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[]
[null,null,"Tax - Operational years"]
[]
[null,null,null,null,{"$f":"Inputs!E189","v":"Corporation tax rate"},null,{"$f":"Inputs!G189","v":"%"},null,{"$f":"ROW(Inputs!E189)","v":189},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E190","v":"Capital allowance rate (declining balance)"},null,{"$f":"Inputs!G190","v":"%"},null,{"$f":"ROW(Inputs!E190)","v":190},null,"Ofgem's determination based on FID date"]
[null,null,null,null,{"$f":"Inputs!E193","v":"Start of price base year"},null,{"$f":"Inputs!G193","v":"date"},null,{"$f":"ROW(Inputs!E193)","v":193},null,"Project's licence"]
[]
[null,null,"Tax - Annuity"]
[]
[null,null,null,null,{"$f":"Inputs!E199","v":"Tax element of Cap and Floor annuity previously calculated and fixed"},null,{"$f":"Inputs!G199","v":"choice"},null,{"$f":"ROW(Inputs!E199)","v":199},null,"N/a at Final Project Assessment"]
[]
[null,"End of sheet"]

{"sheet":"Pre Op RAV","index":4,"n_rows":59,"n_cols":50,"rows_kept":59,"cut":false,"hidden":false,"merged":[]}
["Pre Op RAV",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"Inputs!K17","v":"2013-01-01"},{"$f":"+K4+1","v":"2014-01-01"},{"$f":"+L4+1","v":"2015-01-01"},{"$f":"+M4+1","v":"2016-01-01"},"2017-01-01","2018-01-01","2019-01-01","2020-01-01","2021-01-01","2022-01-01","2023-01-01","2024-01-01","2025-01-01","2026-01-01","2027-01-01","2028-01-01","2029-01-01","2030-01-01","2031-01-01","2032-01-01","2033-01-01","2034-01-01","2035-01-01","2036-01-01","2037-01-01","2038-01-01","2039-01-01","2040-01-01","2041-01-01","2042-01-01","2043-01-01","2044-01-01","2045-01-01","2046-01-01","2047-01-01","2048-01-01","2049-01-01","2050-01-01","2051-01-01","2052-01-01"]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"Inputs!K18","v":"2013-12-31"},{"$f":"DATE(YEAR(K4) + 1, MONTH(K4), DAY(K4))","v":"2014-12-31"},"2015-12-31","2016-12-31","2017-12-31","2018-12-31","2019-12-31","2020-12-31","2021-12-31","2022-12-31","2023-12-31","2024-12-31","2025-12-31","2026-12-31","2027-12-31","2028-12-31","2029-12-31","2030-12-31","2031-12-31","2032-12-31","2033-12-31","2034-12-31","2035-12-31","2036-12-31","2037-12-31","2038-12-31","2039-12-31","2040-12-31","2041-12-31","2042-12-31","2043-12-31","2044-12-31","2045-12-31","2046-12-31","2047-12-31","2048-12-31","2049-12-31","2050-12-31","2051-12-31","2052-12-31"]
[]
[null,"Flags"]
[]
[null,null,null,null,"IDC flag",null,"flag",null,null,null,{"$f":"Inputs!K160","v":1},{"$f":"Inputs!L160","v":1},{"$f":"Inputs!M160","v":1},{"$f":"Inputs!N160","v":1},{"$f":"Inputs!O160","v":1},{"$f":"Inputs!P160","v":1},{"$f":"Inputs!Q160","v":1},{"$f":"Inputs!R160","v":1},{"$f":"Inputs!S160","v":1},{"$f":"Inputs!T160","v":1},{"$f":"Inputs!U160","v":1},{"$f":"Inputs!V160","v":0.91530054644808745},{"$f":"Inputs!W160","v":0},{"$f":"Inputs!X160","v":0},{"$f":"Inputs!Y160","v":0},{"$f":"Inputs!Z160","v":0},{"$f":"Inputs!AA160","v":0},{"$f":"Inputs!AB160","v":0},{"$f":"Inputs!AC160","v":0},{"$f":"Inputs!AD160","v":0},{"$f":"Inputs!AE160","v":0},{"$f":"Inputs!AF160","v":0},{"$f":"Inputs!AG160","v":0},{"$f":"Inputs!AH160","v":0},{"$f":"Inputs!AI160","v":0},{"$f":"Inputs!AJ160","v":0},{"$f":"Inputs!AK160","v":0},{"$f":"Inputs!AL160","v":0},{"$f":"Inputs!AM160","v":0},{"$f":"Inputs!AN160","v":0},{"$f":"Inputs!AO160","v":0},{"$f":"Inputs!AP160","v":0},{"$f":"Inputs!AQ160","v":0},{"$f":"Inputs!AR160","v":0},{"$f":"Inputs!AS160","v":0},{"$f":"Inputs!AT160","v":0},{"$f":"Inputs!AU160","v":0},{"$f":"Inputs!AV160","v":0},{"$f":"Inputs!AW160","v":0},{"$f":"Inputs!AX160","v":0}]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"Inputs!K161","v":0},{"$f":"Inputs!L161","v":0},{"$f":"Inputs!M161","v":0},{"$f":"Inputs!N161","v":0},{"$f":"Inputs!O161","v":0},{"$f":"Inputs!P161","v":0},{"$f":"Inputs!Q161","v":0},{"$f":"Inputs!R161","v":0},{"$f":"Inputs!S161","v":0},{"$f":"Inputs!T161","v":0},{"$f":"Inputs!U161","v":0},{"$f":"Inputs!V161","v":0},{"$f":"Inputs!W161","v":0},{"$f":"Inputs!X161","v":0},{"$f":"Inputs!Y161","v":0},{"$f":"Inputs!Z161","v":0},{"$f":"Inputs!AA161","v":0},{"$f":"Inputs!AB161","v":0},{"$f":"Inputs!AC161","v":0},{"$f":"Inputs!AD161","v":0},{"$f":"Inputs!AE161","v":0},{"$f":"Inputs!AF161","v":0},{"$f":"Inputs!AG161","v":0},{"$f":"Inputs!AH161","v":0},{"$f":"Inputs!AI161","v":0},{"$f":"Inputs!AJ161","v":0},{"$f":"Inputs!AK161","v":0},{"$f":"Inputs!AL161","v":0},{"$f":"Inputs!AM161","v":0},{"$f":"Inputs!AN161","v":0},{"$f":"Inputs!AO161","v":0},{"$f":"Inputs!AP161","v":0},{"$f":"Inputs!AQ161","v":0},{"$f":"Inputs!AR161","v":0},{"$f":"Inputs!AS161","v":0},{"$f":"Inputs!AT161","v":0},{"$f":"Inputs!AU161","v":0},{"$f":"Inputs!AV161","v":0},{"$f":"Inputs!AW161","v":0},{"$f":"Inputs!AX161","v":0}]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"Inputs!K162","v":0},{"$f":"Inputs!L162","v":0},{"$f":"Inputs!M162","v":0},{"$f":"Inputs!N162","v":0},{"$f":"Inputs!O162","v":0},{"$f":"Inputs!P162","v":0},{"$f":"Inputs!Q162","v":0},{"$f":"Inputs!R162","v":0},{"$f":"Inputs!S162","v":0},{"$f":"Inputs!T162","v":0},{"$f":"Inputs!U162","v":0},{"$f":"Inputs!V162","v":8.4699453551912565E-2},{"$f":"Inputs!W162","v":1},{"$f":"Inputs!X162","v":1},{"$f":"Inputs!Y162","v":1},{"$f":"Inputs!Z162","v":1},{"$f":"Inputs!AA162","v":1},{"$f":"Inputs!AB162","v":1},{"$f":"Inputs!AC162","v":1},{"$f":"Inputs!AD162","v":1},{"$f":"Inputs!AE162","v":1},{"$f":"Inputs!AF162","v":1},{"$f":"Inputs!AG162","v":1},{"$f":"Inputs!AH162","v":1},{"$f":"Inputs!AI162","v":1},{"$f":"Inputs!AJ162","v":1},{"$f":"Inputs!AK162","v":1},{"$f":"Inputs!AL162","v":1},{"$f":"Inputs!AM162","v":1},{"$f":"Inputs!AN162","v":1},{"$f":"Inputs!AO162","v":1},{"$f":"Inputs!AP162","v":1},{"$f":"Inputs!AQ162","v":1},{"$f":"Inputs!AR162","v":1},{"$f":"Inputs!AS162","v":0.32876712328767121},{"$f":"Inputs!AT162","v":0},{"$f":"Inputs!AU162","v":0},{"$f":"Inputs!AV162","v":0},{"$f":"Inputs!AW162","v":0},{"$f":"Inputs!AX162","v":0}]
[null,null,null,null,"Transfer construction to operations flag - Notional",null,"flag",null,null,null,{"$f":"Inputs!K165","v":0},{"$f":"Inputs!L165","v":0},{"$f":"Inputs!M165","v":0},{"$f":"Inputs!N165","v":0},{"$f":"Inputs!O165","v":0},{"$f":"Inputs!P165","v":0},{"$f":"Inputs!Q165","v":0},{"$f":"Inputs!R165","v":0},{"$f":"Inputs!S165","v":0},{"$f":"Inputs!T165","v":0},{"$f":"Inputs!U165","v":0},{"$f":"Inputs!V165","v":1},{"$f":"Inputs!W165","v":0},{"$f":"Inputs!X165","v":0},{"$f":"Inputs!Y165","v":0},{"$f":"Inputs!Z165","v":0},{"$f":"Inputs!AA165","v":0},{"$f":"Inputs!AB165","v":0},{"$f":"Inputs!AC165","v":0},{"$f":"Inputs!AD165","v":0},{"$f":"Inputs!AE165","v":0},{"$f":"Inputs!AF165","v":0},{"$f":"Inputs!AG165","v":0},{"$f":"Inputs!AH165","v":0},{"$f":"Inputs!AI165","v":0},{"$f":"Inputs!AJ165","v":0},{"$f":"Inputs!AK165","v":0},{"$f":"Inputs!AL165","v":0},{"$f":"Inputs!AM165","v":0},{"$f":"Inputs!AN165","v":0},{"$f":"Inputs!AO165","v":0},{"$f":"Inputs!AP165","v":0},{"$f":"Inputs!AQ165","v":0},{"$f":"Inputs!AR165","v":0},{"$f":"Inputs!AS165","v":0},{"$f":"Inputs!AT165","v":0},{"$f":"Inputs!AU165","v":0},{"$f":"Inputs!AV165","v":0},{"$f":"Inputs!AW165","v":0},{"$f":"Inputs!AX165","v":0}]
[null,null,null,null,"Transfer construction to operations flag - ACOD",null,"flag",null,null,null,{"$f":"Inputs!K166","v":0},{"$f":"Inputs!L166","v":0},{"$f":"Inputs!M166","v":0},{"$f":"Inputs!N166","v":0},{"$f":"Inputs!O166","v":0},{"$f":"Inputs!P166","v":0},{"$f":"Inputs!Q166","v":0},{"$f":"Inputs!R166","v":0},{"$f":"Inputs!S166","v":0},{"$f":"Inputs!T166","v":0},{"$f":"Inputs!U166","v":0},{"$f":"Inputs!V166","v":1},{"$f":"Inputs!W166","v":0},{"$f":"Inputs!X166","v":0},{"$f":"Inputs!Y166","v":0},{"$f":"Inputs!Z166","v":0},{"$f":"Inputs!AA166","v":0},{"$f":"Inputs!AB166","v":0},{"$f":"Inputs!AC166","v":0},{"$f":"Inputs!AD166","v":0},{"$f":"Inputs!AE166","v":0},{"$f":"Inputs!AF166","v":0},{"$f":"Inputs!AG166","v":0},{"$f":"Inputs!AH166","v":0},{"$f":"Inputs!AI166","v":0},{"$f":"Inputs!AJ166","v":0},{"$f":"Inputs!AK166","v":0},{"$f":"Inputs!AL166","v":0},{"$f":"Inputs!AM166","v":0},{"$f":"Inputs!AN166","v":0},{"$f":"Inputs!AO166","v":0},{"$f":"Inputs!AP166","v":0},{"$f":"Inputs!AQ166","v":0},{"$f":"Inputs!AR166","v":0},{"$f":"Inputs!AS166","v":0},{"$f":"Inputs!AT166","v":0},{"$f":"Inputs!AU166","v":0},{"$f":"Inputs!AV166","v":0},{"$f":"Inputs!AW166","v":0},{"$f":"Inputs!AX166","v":0}]
[null,null,null,null,"Financial close flag",null,"flag",null,null,null,{"$f":"Inputs!K168","v":0},{"$f":"Inputs!L168","v":0},{"$f":"Inputs!M168","v":0},{"$f":"Inputs!N168","v":0},{"$f":"Inputs!O168","v":0},{"$f":"Inputs!P168","v":0},{"$f":"Inputs!Q168","v":0},{"$f":"Inputs!R168","v":0},{"$f":"Inputs!S168","v":1},{"$f":"Inputs!T168","v":0},{"$f":"Inputs!U168","v":0},{"$f":"Inputs!V168","v":0},{"$f":"Inputs!W168","v":0},{"$f":"Inputs!X168","v":0},{"$f":"Inputs!Y168","v":0},{"$f":"Inputs!Z168","v":0},{"$f":"Inputs!AA168","v":0},{"$f":"Inputs!AB168","v":0},{"$f":"Inputs!AC168","v":0},{"$f":"Inputs!AD168","v":0},{"$f":"Inputs!AE168","v":0},{"$f":"Inputs!AF168","v":0},{"$f":"Inputs!AG168","v":0},{"$f":"Inputs!AH168","v":0},{"$f":"Inputs!AI168","v":0},{"$f":"Inputs!AJ168","v":0},{"$f":"Inputs!AK168","v":0},{"$f":"Inputs!AL168","v":0},{"$f":"Inputs!AM168","v":0},{"$f":"Inputs!AN168","v":0},{"$f":"Inputs!AO168","v":0},{"$f":"Inputs!AP168","v":0},{"$f":"Inputs!AQ168","v":0},{"$f":"Inputs!AR168","v":0},{"$f":"Inputs!AS168","v":0},{"$f":"Inputs!AT168","v":0},{"$f":"Inputs!AU168","v":0},{"$f":"Inputs!AV168","v":0},{"$f":"Inputs!AW168","v":0},{"$f":"Inputs!AX168","v":0}]
[]
[null,"RAV"]
[]
[null,null,"Pre-operational"]
[]
[null,null,null,null,"Opening pre-operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,null,{"$f":"K26","v":0},{"$f":"L26","v":0},0,1.1821422521226927,2.112121834419757,3.8256226368553317,7.7423069201247428,11.154851204019188,19.756745030230931,96.794214774782532,{"$f":"U26","v":170.23003352316832},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,{"$f":"Inputs!E34","v":"Development costs"},null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K34","v":0},{"$f":"Inputs!L34","v":0},{"$f":"Inputs!M34","v":0},{"$f":"Inputs!N34","v":1.1528724054657247},{"$f":"Inputs!O34","v":0.8468886319789164},{"$f":"Inputs!P34","v":1.563757597615691},{"$f":"Inputs!Q34","v":3.6253272648014092},{"$f":"Inputs!R34","v":2.9346630304038288},{"$f":"Inputs!S34","v":1.4507202108291644},{"$f":"Inputs!T34","v":0},{"$f":"Inputs!U34","v":0},{"$f":"Inputs!V34","v":0},{"$f":"Inputs!W34","v":0},{"$f":"Inputs!X34","v":0},{"$f":"Inputs!Y34","v":0},{"$f":"Inputs!Z34","v":0},{"$f":"Inputs!AA34","v":0},{"$f":"Inputs!AB34","v":0},{"$f":"Inputs!AC34","v":0},{"$f":"Inputs!AD34","v":0},{"$f":"Inputs!AE34","v":0},{"$f":"Inputs!AF34","v":0},{"$f":"Inputs!AG34","v":0},{"$f":"Inputs!AH34","v":0},{"$f":"Inputs!AI34","v":0},{"$f":"Inputs!AJ34","v":0},{"$f":"Inputs!AK34","v":0},{"$f":"Inputs!AL34","v":0},{"$f":"Inputs!AM34","v":0},{"$f":"Inputs!AN34","v":0},{"$f":"Inputs!AO34","v":0},{"$f":"Inputs!AP34","v":0},{"$f":"Inputs!AQ34","v":0},{"$f":"Inputs!AR34","v":0},{"$f":"Inputs!AS34","v":0},{"$f":"Inputs!AT34","v":0},{"$f":"Inputs!AU34","v":0},{"$f":"Inputs!AV34","v":0},{"$f":"Inputs!AW34","v":0},{"$f":"Inputs!AX34","v":0}]
[null,null,null,null,{"$f":"Inputs!E35","v":"Capex"},null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K35","v":0},{"$f":"Inputs!L35","v":0},{"$f":"Inputs!M35","v":0},{"$f":"Inputs!N35","v":0},{"$f":"Inputs!O35","v":0},{"$f":"Inputs!P35","v":0},{"$f":"Inputs!Q35","v":0},{"$f":"Inputs!R35","v":0},{"$f":"Inputs!S35","v":6.3714126594557952},{"$f":"Inputs!T35","v":74.126181410686613},{"$f":"Inputs!U35","v":66.699433176268073},{"$f":"Inputs!V35","v":37.717906499506995},{"$f":"Inputs!W35","v":0},{"$f":"Inputs!X35","v":0},{"$f":"Inputs!Y35","v":0},{"$f":"Inputs!Z35","v":0},{"$f":"Inputs!AA35","v":0},{"$f":"Inputs!AB35","v":0},{"$f":"Inputs!AC35","v":0},{"$f":"Inputs!AD35","v":0},{"$f":"Inputs!AE35","v":0},{"$f":"Inputs!AF35","v":0},{"$f":"Inputs!AG35","v":0},{"$f":"Inputs!AH35","v":0},{"$f":"Inputs!AI35","v":0},{"$f":"Inputs!AJ35","v":0},{"$f":"Inputs!AK35","v":0},{"$f":"Inputs!AL35","v":0},{"$f":"Inputs!AM35","v":0},{"$f":"Inputs!AN35","v":0},{"$f":"Inputs!AO35","v":0},{"$f":"Inputs!AP35","v":0},{"$f":"Inputs!AQ35","v":0},{"$f":"Inputs!AR35","v":0},{"$f":"Inputs!AS35","v":0},{"$f":"Inputs!AT35","v":0},{"$f":"Inputs!AU35","v":0},{"$f":"Inputs!AV35","v":0},{"$f":"Inputs!AW35","v":0},{"$f":"Inputs!AX35","v":0}]
[null,null,null,null,{"$f":"Inputs!E36","v":"Spares"},null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K36","v":0},{"$f":"Inputs!L36","v":0},{"$f":"Inputs!M36","v":0},{"$f":"Inputs!N36","v":0},{"$f":"Inputs!O36","v":0},{"$f":"Inputs!P36","v":0},{"$f":"Inputs!Q36","v":0},{"$f":"Inputs!R36","v":0},{"$f":"Inputs!S36","v":0},{"$f":"Inputs!T36","v":0},{"$f":"Inputs!U36","v":0},{"$f":"Inputs!V36","v":0},{"$f":"Inputs!W36","v":0},{"$f":"Inputs!X36","v":0},{"$f":"Inputs!Y36","v":0},{"$f":"Inputs!Z36","v":0},{"$f":"Inputs!AA36","v":0},{"$f":"Inputs!AB36","v":0},{"$f":"Inputs!AC36","v":0},{"$f":"Inputs!AD36","v":0},{"$f":"Inputs!AE36","v":0},{"$f":"Inputs!AF36","v":0},{"$f":"Inputs!AG36","v":0},{"$f":"Inputs!AH36","v":0},{"$f":"Inputs!AI36","v":0},{"$f":"Inputs!AJ36","v":0},{"$f":"Inputs!AK36","v":0},{"$f":"Inputs!AL36","v":0},{"$f":"Inputs!AM36","v":0},{"$f":"Inputs!AN36","v":0},{"$f":"Inputs!AO36","v":0},{"$f":"Inputs!AP36","v":0},{"$f":"Inputs!AQ36","v":0},{"$f":"Inputs!AR36","v":0},{"$f":"Inputs!AS36","v":0},{"$f":"Inputs!AT36","v":0},{"$f":"Inputs!AU36","v":0},{"$f":"Inputs!AV36","v":0},{"$f":"Inputs!AW36","v":0},{"$f":"Inputs!AX36","v":0}]
[null,null,null,null,{"$f":"Finance!E28","v":"Capitalised interest during construction"},null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Finance!K28","v":0},{"$f":"Finance!L28","v":0},{"$f":"Finance!M28","v":0},{"$f":"Finance!N28","v":2.9269846656968128E-2},{"$f":"Finance!O28","v":8.3090950318147561E-2},{"$f":"Finance!P28","v":0.14974320481988387},{"$f":"Finance!Q28","v":0.29135701846800149},{"$f":"Finance!R28","v":0.4778812534906165},{"$f":"Finance!S28","v":0.77976095592678174},{"$f":"Finance!T28","v":2.9112883338649915},{"$f":"Finance!U28","v":6.7363855721177002},{"$f":"Finance!V28","v":8.9748025522547579},{"$f":"Finance!W28","v":0},{"$f":"Finance!X28","v":0},{"$f":"Finance!Y28","v":0},{"$f":"Finance!Z28","v":0},{"$f":"Finance!AA28","v":0},{"$f":"Finance!AB28","v":0},{"$f":"Finance!AC28","v":0},{"$f":"Finance!AD28","v":0},{"$f":"Finance!AE28","v":0},{"$f":"Finance!AF28","v":0},{"$f":"Finance!AG28","v":0},{"$f":"Finance!AH28","v":0},{"$f":"Finance!AI28","v":0},{"$f":"Finance!AJ28","v":0},{"$f":"Finance!AK28","v":0},{"$f":"Finance!AL28","v":0},{"$f":"Finance!AM28","v":0},{"$f":"Finance!AN28","v":0},{"$f":"Finance!AO28","v":0},{"$f":"Finance!AP28","v":0},{"$f":"Finance!AQ28","v":0},{"$f":"Finance!AR28","v":0},{"$f":"Finance!AS28","v":0},{"$f":"Finance!AT28","v":0},{"$f":"Finance!AU28","v":0},{"$f":"Finance!AV28","v":0},{"$f":"Finance!AW28","v":0},{"$f":"Finance!AX28","v":0}]
[null,null,null,null,"Closing pre-operational RAV (after IDC)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K19:K23)","v":0},0,0,1.1821422521226927,2.112121834419757,3.8256226368553317,7.7423069201247428,11.154851204019188,19.756745030230931,96.794214774782532,170.23003352316832,{"$f":"SUM(V19:V23)","v":216.92274257493006},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Pre-operational RAV transfers",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"-K24*K11","v":0},{"$f":"-L24*L11","v":0},0,0,0,0,0,0,0,0,0,-216.92274257493006,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Closing pre-operational RAV (after IDC) - adjusted for RAV transfers",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K24:K25)","v":0},0,0,1.1821422521226927,2.112121834419757,3.8256226368553317,7.7423069201247428,11.154851204019188,19.756745030230931,96.794214774782532,{"$f":"SUM(U24:U25)","v":170.23003352316832},{"$f":"SUM(V24:V25)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"Actual cost of debt"]
[]
[null,null,"Development costs"]
[]
[null,null,null,null,"Opening development costs (before transfers)",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,null,{"$f":"K36","v":0},{"$f":"L36","v":0},0,1.0309226728309071,1.8153622648936436,3.3122282485603329,6.8714163983891572,9.7958538323980946,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Development costs",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"Inputs!K20","v":0},{"$f":"Inputs!L20","v":0},{"$f":"Inputs!M20","v":0},{"$f":"Inputs!N20","v":1.0309226728309071},{"$f":"Inputs!O20","v":0.7844395920627365},{"$f":"Inputs!P20","v":1.4968659836666893},{"$f":"Inputs!Q20","v":3.5591881498288243},{"$f":"Inputs!R20","v":2.924437434008937},{"$f":"Inputs!S20","v":1.5041461676019079},{"$f":"Inputs!T20","v":0},{"$f":"Inputs!U20","v":0},{"$f":"Inputs!V20","v":0},{"$f":"Inputs!W20","v":0},{"$f":"Inputs!X20","v":0},{"$f":"Inputs!Y20","v":0},{"$f":"Inputs!Z20","v":0},{"$f":"Inputs!AA20","v":0},{"$f":"Inputs!AB20","v":0},{"$f":"Inputs!AC20","v":0},{"$f":"Inputs!AD20","v":0},{"$f":"Inputs!AE20","v":0},{"$f":"Inputs!AF20","v":0},{"$f":"Inputs!AG20","v":0},{"$f":"Inputs!AH20","v":0},{"$f":"Inputs!AI20","v":0},{"$f":"Inputs!AJ20","v":0},{"$f":"Inputs!AK20","v":0},{"$f":"Inputs!AL20","v":0},{"$f":"Inputs!AM20","v":0},{"$f":"Inputs!AN20","v":0},{"$f":"Inputs!AO20","v":0},{"$f":"Inputs!AP20","v":0},{"$f":"Inputs!AQ20","v":0},{"$f":"Inputs!AR20","v":0},{"$f":"Inputs!AS20","v":0},{"$f":"Inputs!AT20","v":0},{"$f":"Inputs!AU20","v":0},{"$f":"Inputs!AV20","v":0},{"$f":"Inputs!AW20","v":0},{"$f":"Inputs!AX20","v":0}]
[null,null,null,null,"Closing development costs (before transfers)",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K32:K33)","v":0},0,0,1.0309226728309071,1.8153622648936436,3.3122282485603329,6.8714163983891572,9.7958538323980946,11.300000000000002,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Development costs transfers",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"-K34*K13","v":0},{"$f":"-L34*L13","v":0},{"$f":"-M34*M13","v":0},{"$f":"-N34*N13","v":0},{"$f":"-O34*O13","v":0},0,0,0,-11.300000000000002,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Closing development costs (after transfers)",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K34:K35)","v":0},0,0,1.0309226728309071,1.8153622648936436,3.3122282485603329,6.8714163983891572,9.7958538323980946,0,0,{"$f":"SUM(U34:U35)","v":0},{"$f":"SUM(V34:V35)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Pre-operational costs"]
[]
[null,null,null,null,"Opening eligible costs",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,null,{"$f":"K48","v":0},{"$f":"L48","v":0},0,0,0,0,0,0,26.986185899481182,115.19764749838563,198.46583364601241,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Development costs transfers",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"-K35","v":0},{"$f":"-L35","v":0},0,0,0,0,0,0,11.300000000000002,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Capex",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"Inputs!K21","v":0},{"$f":"Inputs!L21","v":0},{"$f":"Inputs!M21","v":0},{"$f":"Inputs!N21","v":0},{"$f":"Inputs!O21","v":0},{"$f":"Inputs!P21","v":0},{"$f":"Inputs!Q21","v":0},{"$f":"Inputs!R21","v":0},{"$f":"Inputs!S21","v":6.6060539188691738},{"$f":"Inputs!T21","v":80.145479328253217},{"$f":"Inputs!U21","v":75.202203876975545},{"$f":"Inputs!V21","v":44.346262875902234},{"$f":"Inputs!W21","v":0},{"$f":"Inputs!X21","v":0},{"$f":"Inputs!Y21","v":0},{"$f":"Inputs!Z21","v":0},{"$f":"Inputs!AA21","v":0},{"$f":"Inputs!AB21","v":0},{"$f":"Inputs!AC21","v":0},{"$f":"Inputs!AD21","v":0},{"$f":"Inputs!AE21","v":0},{"$f":"Inputs!AF21","v":0},{"$f":"Inputs!AG21","v":0},{"$f":"Inputs!AH21","v":0},{"$f":"Inputs!AI21","v":0},{"$f":"Inputs!AJ21","v":0},{"$f":"Inputs!AK21","v":0},{"$f":"Inputs!AL21","v":0},{"$f":"Inputs!AM21","v":0},{"$f":"Inputs!AN21","v":0},{"$f":"Inputs!AO21","v":0},{"$f":"Inputs!AP21","v":0},{"$f":"Inputs!AQ21","v":0},{"$f":"Inputs!AR21","v":0},{"$f":"Inputs!AS21","v":0},{"$f":"Inputs!AT21","v":0},{"$f":"Inputs!AU21","v":0},{"$f":"Inputs!AV21","v":0},{"$f":"Inputs!AW21","v":0},{"$f":"Inputs!AX21","v":0}]
[null,null,null,null,"Spares",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"Inputs!K22","v":0},{"$f":"Inputs!L22","v":0},{"$f":"Inputs!M22","v":0},{"$f":"Inputs!N22","v":0},{"$f":"Inputs!O22","v":0},{"$f":"Inputs!P22","v":0},{"$f":"Inputs!Q22","v":0},{"$f":"Inputs!R22","v":0},{"$f":"Inputs!S22","v":0},{"$f":"Inputs!T22","v":0},{"$f":"Inputs!U22","v":0},{"$f":"Inputs!V22","v":0},{"$f":"Inputs!W22","v":0},{"$f":"Inputs!X22","v":0},{"$f":"Inputs!Y22","v":0},{"$f":"Inputs!Z22","v":0},{"$f":"Inputs!AA22","v":0},{"$f":"Inputs!AB22","v":0},{"$f":"Inputs!AC22","v":0},{"$f":"Inputs!AD22","v":0},{"$f":"Inputs!AE22","v":0},{"$f":"Inputs!AF22","v":0},{"$f":"Inputs!AG22","v":0},{"$f":"Inputs!AH22","v":0},{"$f":"Inputs!AI22","v":0},{"$f":"Inputs!AJ22","v":0},{"$f":"Inputs!AK22","v":0},{"$f":"Inputs!AL22","v":0},{"$f":"Inputs!AM22","v":0},{"$f":"Inputs!AN22","v":0},{"$f":"Inputs!AO22","v":0},{"$f":"Inputs!AP22","v":0},{"$f":"Inputs!AQ22","v":0},{"$f":"Inputs!AR22","v":0},{"$f":"Inputs!AS22","v":0},{"$f":"Inputs!AT22","v":0},{"$f":"Inputs!AU22","v":0},{"$f":"Inputs!AV22","v":0},{"$f":"Inputs!AW22","v":0},{"$f":"Inputs!AX22","v":0}]
[null,null,null,null,"DSRA funding",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"Finance!K155","v":0},{"$f":"Finance!L155","v":0},{"$f":"Finance!M155","v":0},{"$f":"Finance!N155","v":0},{"$f":"Finance!O155","v":0},{"$f":"Finance!P155","v":0},{"$f":"Finance!Q155","v":0},{"$f":"Finance!R155","v":0},{"$f":"Finance!S155","v":0},{"$f":"Finance!T155","v":0},{"$f":"Finance!U155","v":0},{"$f":"Finance!V155","v":0},{"$f":"Finance!W155","v":0},{"$f":"Finance!X155","v":0},{"$f":"Finance!Y155","v":0},{"$f":"Finance!Z155","v":0},{"$f":"Finance!AA155","v":0},{"$f":"Finance!AB155","v":0},{"$f":"Finance!AC155","v":0},{"$f":"Finance!AD155","v":0},{"$f":"Finance!AE155","v":0},{"$f":"Finance!AF155","v":0},{"$f":"Finance!AG155","v":0},{"$f":"Finance!AH155","v":0},{"$f":"Finance!AI155","v":0},{"$f":"Finance!AJ155","v":0},{"$f":"Finance!AK155","v":0},{"$f":"Finance!AL155","v":0},{"$f":"Finance!AM155","v":0},{"$f":"Finance!AN155","v":0},{"$f":"Finance!AO155","v":0},{"$f":"Finance!AP155","v":0},{"$f":"Finance!AQ155","v":0},{"$f":"Finance!AR155","v":0},{"$f":"Finance!AS155","v":0},{"$f":"Finance!AT155","v":0},{"$f":"Finance!AU155","v":0},{"$f":"Finance!AV155","v":0},{"$f":"Finance!AW155","v":0},{"$f":"Finance!AX155","v":0}]
[null,null,null,null,"Financial expenses during construction",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"Finance!K114","v":0},{"$f":"Finance!L114","v":0},{"$f":"Finance!M114","v":0},{"$f":"Finance!N114","v":0},{"$f":"Finance!O114","v":0},{"$f":"Finance!P114","v":0},{"$f":"Finance!Q114","v":0},{"$f":"Finance!R114","v":0},{"$f":"Finance!S114","v":9.0801319806120055},{"$f":"Finance!T114","v":8.0659822706512294},{"$f":"Finance!U114","v":8.0659822706512294},{"$f":"Finance!V114","v":0},{"$f":"Finance!W114","v":0},{"$f":"Finance!X114","v":0},{"$f":"Finance!Y114","v":0},{"$f":"Finance!Z114","v":0},{"$f":"Finance!AA114","v":0},{"$f":"Finance!AB114","v":0},{"$f":"Finance!AC114","v":0},{"$f":"Finance!AD114","v":0},{"$f":"Finance!AE114","v":0},{"$f":"Finance!AF114","v":0},{"$f":"Finance!AG114","v":0},{"$f":"Finance!AH114","v":0},{"$f":"Finance!AI114","v":0},{"$f":"Finance!AJ114","v":0},{"$f":"Finance!AK114","v":0},{"$f":"Finance!AL114","v":0},{"$f":"Finance!AM114","v":0},{"$f":"Finance!AN114","v":0},{"$f":"Finance!AO114","v":0},{"$f":"Finance!AP114","v":0},{"$f":"Finance!AQ114","v":0},{"$f":"Finance!AR114","v":0},{"$f":"Finance!AS114","v":0},{"$f":"Finance!AT114","v":0},{"$f":"Finance!AU114","v":0},{"$f":"Finance!AV114","v":0},{"$f":"Finance!AW114","v":0},{"$f":"Finance!AX114","v":0}]
[null,null,null,null,"Closing eligible costs",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K40:K45)","v":0},{"$f":"SUM(L40:L45)","v":0},0,0,0,0,0,0,26.986185899481182,115.19764749838563,198.46583364601241,242.81209652191464,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Eligible costs transfer",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"-K46*K12","v":0},{"$f":"-L46*L12","v":0},0,0,0,0,0,0,0,0,0,-242.81209652191464,{"$f":"-W46*W12","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Closing eligible costs - adjusted for transfer",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K46:K47)","v":0},0,0,0,0,0,0,0,26.986185899481182,115.19764749838563,{"$f":"SUM(U46:U47)","v":198.46583364601241},{"$f":"SUM(V46:V47)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Eligible costs"]
[null,null,"Note: Due to the circularity of the interest calculation, \"Copy-PasteValues\" must be performed from Row 52 to Row 53 until the circularity check shows 'OK'"]
[]
[null,null,null,null,"Eligible costs - copy",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K41:K45)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(S41:S45)","v":26.986185899481182},88.211461598904449,83.268186147626778,44.346262875902234,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Eligible costs - paste",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,0,0,0,0,0,0,0,0,26.986185899481182,88.211461598904449,83.268186147626778,44.346262875902234,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,null,"Delta",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"ABS(K53-K54)","v":0},{"$f":"ABS(L53-L54)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Circularity check",null,null,null,{"$f":"IF(SUM(K56:AX56)<0.000001,\"OK\",\"Copy-Paste\")","v":"OK"}]
[]
[null,"End of sheet"]

{"sheet":"Finance","index":5,"n_rows":157,"n_cols":50,"rows_kept":157,"cut":false,"hidden":false,"merged":[]}
["Finance",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"Inputs!K17","v":"2013-01-01"},{"$f":"+K4+1","v":"2014-01-01"},"2015-01-01","2016-01-01","2017-01-01","2018-01-01","2019-01-01","2020-01-01","2021-01-01","2022-01-01","2023-01-01","2024-01-01","2025-01-01","2026-01-01","2027-01-01","2028-01-01","2029-01-01","2030-01-01","2031-01-01","2032-01-01","2033-01-01","2034-01-01","2035-01-01","2036-01-01","2037-01-01","2038-01-01","2039-01-01","2040-01-01","2041-01-01","2042-01-01","2043-01-01","2044-01-01","2045-01-01","2046-01-01","2047-01-01","2048-01-01",{"$f":"+AT4+1","v":"2049-01-01"},{"$f":"+AU4+1","v":"2050-01-01"},{"$f":"+AV4+1","v":"2051-01-01"},{"$f":"+AW4+1","v":"2052-01-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"Inputs!K18","v":"2013-12-31"},{"$f":"DATE(YEAR(K4) + 1, MONTH(K4), DAY(K4))","v":"2014-12-31"},"2015-12-31","2016-12-31","2017-12-31","2018-12-31","2019-12-31","2020-12-31","2021-12-31","2022-12-31","2023-12-31","2024-12-31","2025-12-31","2026-12-31","2027-12-31","2028-12-31","2029-12-31","2030-12-31","2031-12-31","2032-12-31","2033-12-31","2034-12-31","2035-12-31","2036-12-31","2037-12-31","2038-12-31","2039-12-31","2040-12-31","2041-12-31","2042-12-31","2043-12-31","2044-12-31","2045-12-31","2046-12-31","2047-12-31","2048-12-31",{"$f":"DATE(YEAR(AT4) + 1, MONTH(AT4), DAY(AT4))","v":"2049-12-31"},{"$f":"DATE(YEAR(AU4) + 1, MONTH(AU4), DAY(AU4))","v":"2050-12-31"},{"$f":"DATE(YEAR(AV4) + 1, MONTH(AV4), DAY(AV4))","v":"2051-12-31"},{"$f":"DATE(YEAR(AW4) + 1, MONTH(AW4), DAY(AW4))","v":"2052-12-31"}]
[]
[null,"Flags"]
[]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"Inputs!K161","v":0},{"$f":"Inputs!L161","v":0},{"$f":"Inputs!M161","v":0},{"$f":"Inputs!N161","v":0},{"$f":"Inputs!O161","v":0},{"$f":"Inputs!P161","v":0},{"$f":"Inputs!Q161","v":0},{"$f":"Inputs!R161","v":0},{"$f":"Inputs!S161","v":0},{"$f":"Inputs!T161","v":0},{"$f":"Inputs!U161","v":0},{"$f":"Inputs!V161","v":0},{"$f":"Inputs!W161","v":0},{"$f":"Inputs!X161","v":0},{"$f":"Inputs!Y161","v":0},{"$f":"Inputs!Z161","v":0},{"$f":"Inputs!AA161","v":0},{"$f":"Inputs!AB161","v":0},{"$f":"Inputs!AC161","v":0},{"$f":"Inputs!AD161","v":0},{"$f":"Inputs!AE161","v":0},{"$f":"Inputs!AF161","v":0},{"$f":"Inputs!AG161","v":0},{"$f":"Inputs!AH161","v":0},{"$f":"Inputs!AI161","v":0},{"$f":"Inputs!AJ161","v":0},{"$f":"Inputs!AK161","v":0},{"$f":"Inputs!AL161","v":0},{"$f":"Inputs!AM161","v":0},{"$f":"Inputs!AN161","v":0},{"$f":"Inputs!AO161","v":0},{"$f":"Inputs!AP161","v":0},{"$f":"Inputs!AQ161","v":0},{"$f":"Inputs!AR161","v":0},{"$f":"Inputs!AS161","v":0},{"$f":"Inputs!AT161","v":0},{"$f":"Inputs!AU161","v":0},{"$f":"Inputs!AV161","v":0},{"$f":"Inputs!AW161","v":0},{"$f":"Inputs!AX161","v":0}]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"Inputs!K162","v":0},{"$f":"Inputs!L162","v":0},{"$f":"Inputs!M162","v":0},{"$f":"Inputs!N162","v":0},{"$f":"Inputs!O162","v":0},{"$f":"Inputs!P162","v":0},{"$f":"Inputs!Q162","v":0},{"$f":"Inputs!R162","v":0},{"$f":"Inputs!S162","v":0},{"$f":"Inputs!T162","v":0},{"$f":"Inputs!U162","v":0},{"$f":"Inputs!V162","v":8.4699453551912565E-2},{"$f":"Inputs!W162","v":1},{"$f":"Inputs!X162","v":1},{"$f":"Inputs!Y162","v":1},{"$f":"Inputs!Z162","v":1},{"$f":"Inputs!AA162","v":1},{"$f":"Inputs!AB162","v":1},{"$f":"Inputs!AC162","v":1},{"$f":"Inputs!AD162","v":1},{"$f":"Inputs!AE162","v":1},{"$f":"Inputs!AF162","v":1},{"$f":"Inputs!AG162","v":1},{"$f":"Inputs!AH162","v":1},{"$f":"Inputs!AI162","v":1},{"$f":"Inputs!AJ162","v":1},{"$f":"Inputs!AK162","v":1},{"$f":"Inputs!AL162","v":1},{"$f":"Inputs!AM162","v":1},{"$f":"Inputs!AN162","v":1},{"$f":"Inputs!AO162","v":1},{"$f":"Inputs!AP162","v":1},{"$f":"Inputs!AQ162","v":1},{"$f":"Inputs!AR162","v":1},{"$f":"Inputs!AS162","v":0.32876712328767121},{"$f":"Inputs!AT162","v":0},{"$f":"Inputs!AU162","v":0},{"$f":"Inputs!AV162","v":0},{"$f":"Inputs!AW162","v":0},{"$f":"Inputs!AX162","v":0}]
[null,null,null,null,"Regime years",null,"count",null,null,null,{"$f":"Inputs!K164","v":0},{"$f":"Inputs!L164","v":0},{"$f":"Inputs!M164","v":0},{"$f":"Inputs!N164","v":0},{"$f":"Inputs!O164","v":0},{"$f":"Inputs!P164","v":0},{"$f":"Inputs!Q164","v":0},{"$f":"Inputs!R164","v":0},{"$f":"Inputs!S164","v":0},{"$f":"Inputs!T164","v":1},{"$f":"Inputs!U164","v":2},{"$f":"Inputs!V164","v":3},{"$f":"Inputs!W164","v":4},{"$f":"Inputs!X164","v":5},{"$f":"Inputs!Y164","v":6},{"$f":"Inputs!Z164","v":7},{"$f":"Inputs!AA164","v":8},{"$f":"Inputs!AB164","v":9},{"$f":"Inputs!AC164","v":10},{"$f":"Inputs!AD164","v":11},{"$f":"Inputs!AE164","v":12},{"$f":"Inputs!AF164","v":13},{"$f":"Inputs!AG164","v":14},{"$f":"Inputs!AH164","v":15},{"$f":"Inputs!AI164","v":16},{"$f":"Inputs!AJ164","v":17},{"$f":"Inputs!AK164","v":18},{"$f":"Inputs!AL164","v":19},{"$f":"Inputs!AM164","v":20},{"$f":"Inputs!AN164","v":21},{"$f":"Inputs!AO164","v":22},{"$f":"Inputs!AP164","v":23},{"$f":"Inputs!AQ164","v":24},{"$f":"Inputs!AR164","v":25},{"$f":"Inputs!AS164","v":25},{"$f":"Inputs!AT164","v":0},{"$f":"Inputs!AU164","v":0},{"$f":"Inputs!AV164","v":0},{"$f":"Inputs!AW164","v":0},{"$f":"Inputs!AX164","v":0}]
[null,null,null,null,"Transfer construction to operations flag - Notional",null,"flag",null,null,null,{"$f":"Inputs!K165","v":0},{"$f":"Inputs!L165","v":0},{"$f":"Inputs!M165","v":0},{"$f":"Inputs!N165","v":0},{"$f":"Inputs!O165","v":0},{"$f":"Inputs!P165","v":0},{"$f":"Inputs!Q165","v":0},{"$f":"Inputs!R165","v":0},{"$f":"Inputs!S165","v":0},{"$f":"Inputs!T165","v":0},{"$f":"Inputs!U165","v":0},{"$f":"Inputs!V165","v":1},{"$f":"Inputs!W165","v":0},{"$f":"Inputs!X165","v":0},{"$f":"Inputs!Y165","v":0},{"$f":"Inputs!Z165","v":0},{"$f":"Inputs!AA165","v":0},{"$f":"Inputs!AB165","v":0},{"$f":"Inputs!AC165","v":0},{"$f":"Inputs!AD165","v":0},{"$f":"Inputs!AE165","v":0},{"$f":"Inputs!AF165","v":0},{"$f":"Inputs!AG165","v":0},{"$f":"Inputs!AH165","v":0},{"$f":"Inputs!AI165","v":0},{"$f":"Inputs!AJ165","v":0},{"$f":"Inputs!AK165","v":0},{"$f":"Inputs!AL165","v":0},{"$f":"Inputs!AM165","v":0},{"$f":"Inputs!AN165","v":0},{"$f":"Inputs!AO165","v":0},{"$f":"Inputs!AP165","v":0},{"$f":"Inputs!AQ165","v":0},{"$f":"Inputs!AR165","v":0},{"$f":"Inputs!AS165","v":0},{"$f":"Inputs!AT165","v":0},{"$f":"Inputs!AU165","v":0},{"$f":"Inputs!AV165","v":0},{"$f":"Inputs!AW165","v":0},{"$f":"Inputs!AX165","v":0}]
[null,null,null,null,"Transfer construction to operations flag - ACOD",null,"flag",null,null,null,{"$f":"Inputs!K166","v":0},{"$f":"Inputs!L166","v":0},{"$f":"Inputs!M166","v":0},{"$f":"Inputs!N166","v":0},{"$f":"Inputs!O166","v":0},{"$f":"Inputs!P166","v":0},{"$f":"Inputs!Q166","v":0},{"$f":"Inputs!R166","v":0},{"$f":"Inputs!S166","v":0},{"$f":"Inputs!T166","v":0},{"$f":"Inputs!U166","v":0},{"$f":"Inputs!V166","v":1},{"$f":"Inputs!W166","v":0},{"$f":"Inputs!X166","v":0},{"$f":"Inputs!Y166","v":0},{"$f":"Inputs!Z166","v":0},{"$f":"Inputs!AA166","v":0},{"$f":"Inputs!AB166","v":0},{"$f":"Inputs!AC166","v":0},{"$f":"Inputs!AD166","v":0},{"$f":"Inputs!AE166","v":0},{"$f":"Inputs!AF166","v":0},{"$f":"Inputs!AG166","v":0},{"$f":"Inputs!AH166","v":0},{"$f":"Inputs!AI166","v":0},{"$f":"Inputs!AJ166","v":0},{"$f":"Inputs!AK166","v":0},{"$f":"Inputs!AL166","v":0},{"$f":"Inputs!AM166","v":0},{"$f":"Inputs!AN166","v":0},{"$f":"Inputs!AO166","v":0},{"$f":"Inputs!AP166","v":0},{"$f":"Inputs!AQ166","v":0},{"$f":"Inputs!AR166","v":0},{"$f":"Inputs!AS166","v":0},{"$f":"Inputs!AT166","v":0},{"$f":"Inputs!AU166","v":0},{"$f":"Inputs!AV166","v":0},{"$f":"Inputs!AW166","v":0},{"$f":"Inputs!AX166","v":0}]
[null,null,null,null,"Initial transaction costs flag",null,"flag",null,null,null,{"$f":"Inputs!K167","v":0},{"$f":"Inputs!L167","v":0},{"$f":"Inputs!M167","v":0},{"$f":"Inputs!N167","v":0},{"$f":"Inputs!O167","v":0},{"$f":"Inputs!P167","v":0},{"$f":"Inputs!Q167","v":0},{"$f":"Inputs!R167","v":1},{"$f":"Inputs!S167","v":0},{"$f":"Inputs!T167","v":0},{"$f":"Inputs!U167","v":0},{"$f":"Inputs!V167","v":0},{"$f":"Inputs!W167","v":0},{"$f":"Inputs!X167","v":0},{"$f":"Inputs!Y167","v":0},{"$f":"Inputs!Z167","v":0},{"$f":"Inputs!AA167","v":0},{"$f":"Inputs!AB167","v":0},{"$f":"Inputs!AC167","v":0},{"$f":"Inputs!AD167","v":0},{"$f":"Inputs!AE167","v":0},{"$f":"Inputs!AF167","v":0},{"$f":"Inputs!AG167","v":0},{"$f":"Inputs!AH167","v":0},{"$f":"Inputs!AI167","v":0},{"$f":"Inputs!AJ167","v":0},{"$f":"Inputs!AK167","v":0},{"$f":"Inputs!AL167","v":0},{"$f":"Inputs!AM167","v":0},{"$f":"Inputs!AN167","v":0},{"$f":"Inputs!AO167","v":0},{"$f":"Inputs!AP167","v":0},{"$f":"Inputs!AQ167","v":0},{"$f":"Inputs!AR167","v":0},{"$f":"Inputs!AS167","v":0},{"$f":"Inputs!AT167","v":0},{"$f":"Inputs!AU167","v":0},{"$f":"Inputs!AV167","v":0},{"$f":"Inputs!AW167","v":0},{"$f":"Inputs!AX167","v":0}]
[null,null,null,null,"Financial close flag",null,"flag",null,null,null,{"$f":"Inputs!K168","v":0},{"$f":"Inputs!L168","v":0},{"$f":"Inputs!M168","v":0},{"$f":"Inputs!N168","v":0},{"$f":"Inputs!O168","v":0},{"$f":"Inputs!P168","v":0},{"$f":"Inputs!Q168","v":0},{"$f":"Inputs!R168","v":0},{"$f":"Inputs!S168","v":1},{"$f":"Inputs!T168","v":0},{"$f":"Inputs!U168","v":0},{"$f":"Inputs!V168","v":0},{"$f":"Inputs!W168","v":0},{"$f":"Inputs!X168","v":0},{"$f":"Inputs!Y168","v":0},{"$f":"Inputs!Z168","v":0},{"$f":"Inputs!AA168","v":0},{"$f":"Inputs!AB168","v":0},{"$f":"Inputs!AC168","v":0},{"$f":"Inputs!AD168","v":0},{"$f":"Inputs!AE168","v":0},{"$f":"Inputs!AF168","v":0},{"$f":"Inputs!AG168","v":0},{"$f":"Inputs!AH168","v":0},{"$f":"Inputs!AI168","v":0},{"$f":"Inputs!AJ168","v":0},{"$f":"Inputs!AK168","v":0},{"$f":"Inputs!AL168","v":0},{"$f":"Inputs!AM168","v":0},{"$f":"Inputs!AN168","v":0},{"$f":"Inputs!AO168","v":0},{"$f":"Inputs!AP168","v":0},{"$f":"Inputs!AQ168","v":0},{"$f":"Inputs!AR168","v":0},{"$f":"Inputs!AS168","v":0},{"$f":"Inputs!AT168","v":0},{"$f":"Inputs!AU168","v":0},{"$f":"Inputs!AV168","v":0},{"$f":"Inputs!AW168","v":0},{"$f":"Inputs!AX168","v":0}]
[null,null,null,null,"Debt drawdown flag",null,"flag",null,null,null,{"$f":"Inputs!K169","v":0},{"$f":"Inputs!L169","v":0},{"$f":"Inputs!M169","v":0},{"$f":"Inputs!N169","v":0},{"$f":"Inputs!O169","v":0},{"$f":"Inputs!P169","v":0},{"$f":"Inputs!Q169","v":0},{"$f":"Inputs!R169","v":0},{"$f":"Inputs!S169","v":1},{"$f":"Inputs!T169","v":1},{"$f":"Inputs!U169","v":1},{"$f":"Inputs!V169","v":0},{"$f":"Inputs!W169","v":0},{"$f":"Inputs!X169","v":0},{"$f":"Inputs!Y169","v":0},{"$f":"Inputs!Z169","v":0},{"$f":"Inputs!AA169","v":0},{"$f":"Inputs!AB169","v":0},{"$f":"Inputs!AC169","v":0},{"$f":"Inputs!AD169","v":0},{"$f":"Inputs!AE169","v":0},{"$f":"Inputs!AF169","v":0},{"$f":"Inputs!AG169","v":0},{"$f":"Inputs!AH169","v":0},{"$f":"Inputs!AI169","v":0},{"$f":"Inputs!AJ169","v":0},{"$f":"Inputs!AK169","v":0},{"$f":"Inputs!AL169","v":0},{"$f":"Inputs!AM169","v":0},{"$f":"Inputs!AN169","v":0},{"$f":"Inputs!AO169","v":0},{"$f":"Inputs!AP169","v":0},{"$f":"Inputs!AQ169","v":0},{"$f":"Inputs!AR169","v":0},{"$f":"Inputs!AS169","v":0},{"$f":"Inputs!AT169","v":0},{"$f":"Inputs!AU169","v":0},{"$f":"Inputs!AV169","v":0},{"$f":"Inputs!AW169","v":0},{"$f":"Inputs!AX169","v":0}]
[null,null,null,null,"Debt repayment year",null,"count",null,null,null,{"$f":"Inputs!K171","v":0},{"$f":"Inputs!L171","v":0},{"$f":"Inputs!M171","v":0},{"$f":"Inputs!N171","v":0},{"$f":"Inputs!O171","v":0},{"$f":"Inputs!P171","v":0},{"$f":"Inputs!Q171","v":0},{"$f":"Inputs!R171","v":0},{"$f":"Inputs!S171","v":0},{"$f":"Inputs!T171","v":0},{"$f":"Inputs!U171","v":0},{"$f":"Inputs!V171","v":8.4699453551912565E-2},{"$f":"Inputs!W171","v":1.0846994535519126},{"$f":"Inputs!X171","v":2.0846994535519126},{"$f":"Inputs!Y171","v":3.0846994535519126},{"$f":"Inputs!Z171","v":4.084699453551913},{"$f":"Inputs!AA171","v":5.084699453551913},{"$f":"Inputs!AB171","v":6.084699453551913},{"$f":"Inputs!AC171","v":7.084699453551913},{"$f":"Inputs!AD171","v":8.084699453551913},{"$f":"Inputs!AE171","v":9.084699453551913},{"$f":"Inputs!AF171","v":10.084699453551913},{"$f":"Inputs!AG171","v":11.084699453551913},{"$f":"Inputs!AH171","v":12.084699453551913},{"$f":"Inputs!AI171","v":13.084699453551913},{"$f":"Inputs!AJ171","v":14.084699453551913},{"$f":"Inputs!AK171","v":15.084699453551913},{"$f":"Inputs!AL171","v":16.084699453551913},{"$f":"Inputs!AM171","v":17.084699453551913},{"$f":"Inputs!AN171","v":18.084699453551913},{"$f":"Inputs!AO171","v":19.084699453551913},{"$f":"Inputs!AP171","v":20.084699453551913},{"$f":"Inputs!AQ171","v":21.084699453551913},{"$f":"Inputs!AR171","v":22.084699453551913},{"$f":"Inputs!AS171","v":22.580589864510817},{"$f":"Inputs!AT171","v":0},{"$f":"Inputs!AU171","v":0},{"$f":"Inputs!AV171","v":0},{"$f":"Inputs!AW171","v":0},{"$f":"Inputs!AX171","v":0}]
[]
[null,"Pre-operational interest during construction"]
[]
[null,null,"Pre-operational interest during construction"]
[]
[null,null,null,null,"Interest during construction rate",null,{"$f":"Inputs!G70","v":"real annual %"},null,{"$f":"Inputs!I70","v":5.21E-2}]
[]
[null,null,null,null,"Opening pre-operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Pre Op RAV'!K19","v":0},{"$f":"'Pre Op RAV'!L19","v":0},{"$f":"'Pre Op RAV'!M19","v":0},{"$f":"'Pre Op RAV'!N19","v":0},{"$f":"'Pre Op RAV'!O19","v":1.1821422521226927},{"$f":"'Pre Op RAV'!P19","v":2.112121834419757},{"$f":"'Pre Op RAV'!Q19","v":3.8256226368553317},{"$f":"'Pre Op RAV'!R19","v":7.7423069201247428},{"$f":"'Pre Op RAV'!S19","v":11.154851204019188},{"$f":"'Pre Op RAV'!T19","v":19.756745030230931},{"$f":"'Pre Op RAV'!U19","v":96.794214774782532},{"$f":"'Pre Op RAV'!V19","v":170.23003352316832},{"$f":"'Pre Op RAV'!W19","v":0},{"$f":"'Pre Op RAV'!X19","v":0},{"$f":"'Pre Op RAV'!Y19","v":0},{"$f":"'Pre Op RAV'!Z19","v":0},{"$f":"'Pre Op RAV'!AA19","v":0},{"$f":"'Pre Op RAV'!AB19","v":0},{"$f":"'Pre Op RAV'!AC19","v":0},{"$f":"'Pre Op RAV'!AD19","v":0},{"$f":"'Pre Op RAV'!AE19","v":0},{"$f":"'Pre Op RAV'!AF19","v":0},{"$f":"'Pre Op RAV'!AG19","v":0},{"$f":"'Pre Op RAV'!AH19","v":0},{"$f":"'Pre Op RAV'!AI19","v":0},{"$f":"'Pre Op RAV'!AJ19","v":0},{"$f":"'Pre Op RAV'!AK19","v":0},{"$f":"'Pre Op RAV'!AL19","v":0},{"$f":"'Pre Op RAV'!AM19","v":0},{"$f":"'Pre Op RAV'!AN19","v":0},{"$f":"'Pre Op RAV'!AO19","v":0},{"$f":"'Pre Op RAV'!AP19","v":0},{"$f":"'Pre Op RAV'!AQ19","v":0},{"$f":"'Pre Op RAV'!AR19","v":0},{"$f":"'Pre Op RAV'!AS19","v":0},{"$f":"'Pre Op RAV'!AT19","v":0},{"$f":"'Pre Op RAV'!AU19","v":0},{"$f":"'Pre Op RAV'!AV19","v":0},{"$f":"'Pre Op RAV'!AW19","v":0},{"$f":"'Pre Op RAV'!AX19","v":0}]
[null,null,null,null,"Development costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K34","v":0},{"$f":"Inputs!L34","v":0},{"$f":"Inputs!M34","v":0},{"$f":"Inputs!N34","v":1.1528724054657247},{"$f":"Inputs!O34","v":0.8468886319789164},{"$f":"Inputs!P34","v":1.563757597615691},{"$f":"Inputs!Q34","v":3.6253272648014092},{"$f":"Inputs!R34","v":2.9346630304038288},{"$f":"Inputs!S34","v":1.4507202108291644},{"$f":"Inputs!T34","v":0},{"$f":"Inputs!U34","v":0},{"$f":"Inputs!V34","v":0},{"$f":"Inputs!W34","v":0},{"$f":"Inputs!X34","v":0},{"$f":"Inputs!Y34","v":0},{"$f":"Inputs!Z34","v":0},{"$f":"Inputs!AA34","v":0},{"$f":"Inputs!AB34","v":0},{"$f":"Inputs!AC34","v":0},{"$f":"Inputs!AD34","v":0},{"$f":"Inputs!AE34","v":0},{"$f":"Inputs!AF34","v":0},{"$f":"Inputs!AG34","v":0},{"$f":"Inputs!AH34","v":0},{"$f":"Inputs!AI34","v":0},{"$f":"Inputs!AJ34","v":0},{"$f":"Inputs!AK34","v":0},{"$f":"Inputs!AL34","v":0},{"$f":"Inputs!AM34","v":0},{"$f":"Inputs!AN34","v":0},{"$f":"Inputs!AO34","v":0},{"$f":"Inputs!AP34","v":0},{"$f":"Inputs!AQ34","v":0},{"$f":"Inputs!AR34","v":0},{"$f":"Inputs!AS34","v":0},{"$f":"Inputs!AT34","v":0},{"$f":"Inputs!AU34","v":0},{"$f":"Inputs!AV34","v":0},{"$f":"Inputs!AW34","v":0},{"$f":"Inputs!AX34","v":0}]
[null,null,null,null,"Capex",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K35","v":0},{"$f":"Inputs!L35","v":0},{"$f":"Inputs!M35","v":0},{"$f":"Inputs!N35","v":0},{"$f":"Inputs!O35","v":0},{"$f":"Inputs!P35","v":0},{"$f":"Inputs!Q35","v":0},{"$f":"Inputs!R35","v":0},{"$f":"Inputs!S35","v":6.3714126594557952},{"$f":"Inputs!T35","v":74.126181410686613},{"$f":"Inputs!U35","v":66.699433176268073},{"$f":"Inputs!V35","v":37.717906499506995},{"$f":"Inputs!W35","v":0},{"$f":"Inputs!X35","v":0},{"$f":"Inputs!Y35","v":0},{"$f":"Inputs!Z35","v":0},{"$f":"Inputs!AA35","v":0},{"$f":"Inputs!AB35","v":0},{"$f":"Inputs!AC35","v":0},{"$f":"Inputs!AD35","v":0},{"$f":"Inputs!AE35","v":0},{"$f":"Inputs!AF35","v":0},{"$f":"Inputs!AG35","v":0},{"$f":"Inputs!AH35","v":0},{"$f":"Inputs!AI35","v":0},{"$f":"Inputs!AJ35","v":0},{"$f":"Inputs!AK35","v":0},{"$f":"Inputs!AL35","v":0},{"$f":"Inputs!AM35","v":0},{"$f":"Inputs!AN35","v":0},{"$f":"Inputs!AO35","v":0},{"$f":"Inputs!AP35","v":0},{"$f":"Inputs!AQ35","v":0},{"$f":"Inputs!AR35","v":0},{"$f":"Inputs!AS35","v":0},{"$f":"Inputs!AT35","v":0},{"$f":"Inputs!AU35","v":0},{"$f":"Inputs!AV35","v":0},{"$f":"Inputs!AW35","v":0},{"$f":"Inputs!AX35","v":0}]
[null,null,null,null,"Spares",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K36","v":0},{"$f":"Inputs!L36","v":0},{"$f":"Inputs!M36","v":0},{"$f":"Inputs!N36","v":0},{"$f":"Inputs!O36","v":0},{"$f":"Inputs!P36","v":0},{"$f":"Inputs!Q36","v":0},{"$f":"Inputs!R36","v":0},{"$f":"Inputs!S36","v":0},{"$f":"Inputs!T36","v":0},{"$f":"Inputs!U36","v":0},{"$f":"Inputs!V36","v":0},{"$f":"Inputs!W36","v":0},{"$f":"Inputs!X36","v":0},{"$f":"Inputs!Y36","v":0},{"$f":"Inputs!Z36","v":0},{"$f":"Inputs!AA36","v":0},{"$f":"Inputs!AB36","v":0},{"$f":"Inputs!AC36","v":0},{"$f":"Inputs!AD36","v":0},{"$f":"Inputs!AE36","v":0},{"$f":"Inputs!AF36","v":0},{"$f":"Inputs!AG36","v":0},{"$f":"Inputs!AH36","v":0},{"$f":"Inputs!AI36","v":0},{"$f":"Inputs!AJ36","v":0},{"$f":"Inputs!AK36","v":0},{"$f":"Inputs!AL36","v":0},{"$f":"Inputs!AM36","v":0},{"$f":"Inputs!AN36","v":0},{"$f":"Inputs!AO36","v":0},{"$f":"Inputs!AP36","v":0},{"$f":"Inputs!AQ36","v":0},{"$f":"Inputs!AR36","v":0},{"$f":"Inputs!AS36","v":0},{"$f":"Inputs!AT36","v":0},{"$f":"Inputs!AU36","v":0},{"$f":"Inputs!AV36","v":0},{"$f":"Inputs!AW36","v":0},{"$f":"Inputs!AX36","v":0}]
[null,null,null,null,"Capitalised interest during construction",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"((1+$I22)^(1-K8-K9)-1)*(K24+(K25+K26+K27)/(2+$I22))","v":0},{"$f":"((1+$I22)^(1-L8-L9)-1)*(L24+(L25+L26+L27)/(2+$I22))","v":0},0,2.9269846656968128E-2,8.3090950318147561E-2,0.14974320481988387,0.29135701846800149,0.4778812534906165,0.77976095592678174,2.9112883338649915,6.7363855721177002,8.9748025522547579,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"Transaction costs"]
[]
[null,null,"Parameters"]
[]
[null,null,null,null,"Pre-operational notional gearing",null,{"$f":"Inputs!G73","v":"%"},null,{"$f":"Inputs!I73","v":0.3977}]
[null,null,null,null,"Operational notional gearing",null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"Inputs!I74","v":0.5}]
[]
[null,null,null,null,"Debt transaction costs",null,{"$f":"Inputs!G77","v":"%"},null,{"$f":"Inputs!I77","v":2.5000000000000001E-2}]
[null,null,null,null,"Equity transaction costs",null,{"$f":"Inputs!G76","v":"%"},null,{"$f":"Inputs!I76","v":0.05}]
[]
[null,null,"Allowance"]
[]
[null,null,null,null,"Transaction costs - opening",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"J50","v":0},{"$f":"K50","v":0},{"$f":"L50","v":0},{"$f":"M50","v":0},0,0,0,0,8.9099942522562099,9.3742049527987596,9.862601030839576,10.376442544546318,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"AT50","v":0},{"$f":"AU50","v":0},{"$f":"AV50","v":0},{"$f":"AW50","v":0}]
[null,null,null,null,"Initial debt transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"$I34*K$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*L$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*M$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*N$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*O$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*P$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*Q$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*R$13*$I37*'Op Rav'!$K$11","v":2.1567543680512422},{"$f":"$I34*S$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*T$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*U$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*V$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*W$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*X$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*Y$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*Z$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AA$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AB$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AC$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AD$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AE$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AF$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AG$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AH$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AI$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AJ$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AK$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AL$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AM$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AN$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AO$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AP$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AQ$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AR$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AS$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AT$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AU$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AV$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AW$13*$I37*'Op Rav'!$K$11","v":0},{"$f":"$I34*AX$13*$I37*'Op Rav'!$K$11","v":0}]
[null,null,null,null,"Initial equity transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"(1-$I34)*K$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*L$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*M$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*N$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*O$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*P$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*Q$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*R$13*$I38*'Op Rav'!$K$11","v":6.5326283926440194},{"$f":"(1-$I34)*S$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*T$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*U$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*V$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*W$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*X$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*Y$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*Z$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AA$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AB$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AC$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AD$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AE$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AF$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AG$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AH$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AI$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AJ$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AK$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AL$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AM$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AN$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AO$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AP$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AQ$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AR$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AS$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AT$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AU$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AV$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AW$13*$I38*'Op Rav'!$K$11","v":0},{"$f":"(1-$I34)*AX$13*$I38*'Op Rav'!$K$11","v":0}]
[null,null,null,null,"Final debt transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*K$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*L$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*M$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*N$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*O$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*P$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*Q$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*R$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*S$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*T$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*U$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*V$11","v":0.55477991413538363},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*W$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*X$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*Y$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*Z$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AA$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AB$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AC$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AD$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AE$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AF$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AG$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AH$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AI$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AJ$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AK$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AL$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AM$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AN$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AO$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AP$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AQ$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AR$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AS$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AT$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AU$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AV$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AW$11","v":0},{"$f":"($I35-$I34)*'Op Rav'!$K$11*$I37*AX$11","v":0}]
[null,null,null,null,"Final equity transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*K$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*L$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*M$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*N$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*O$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*P$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*Q$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*R$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*S$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*T$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*U$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*V$11","v":-1.1095598282707673},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*W$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*X$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*Y$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*Z$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AA$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AB$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AC$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AD$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AE$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AF$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AG$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AH$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AI$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AJ$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AK$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AL$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AM$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AN$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AO$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AP$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AQ$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AR$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AS$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AT$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AU$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AV$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AW$11","v":0},{"$f":"($I34-$I35)*'Op Rav'!$K$11*$I38*AX$11","v":0}]
[null,null,null,null,"Transaction costs - annual movement",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K43:K46)","v":0},{"$f":"SUM(L43:L46)","v":0},0,0,0,0,0,{"$f":"SUM(R43:R46)","v":8.6893827606952616},0,0,0,-0.55477991413538363,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"SUM(AU43:AU46)","v":0},0,0,0]
[null,null,null,null,"Capitalised IDC on transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"((1+$I22)^(1-K$9-K$8)-1)*(K42+(K43+K44+K45+K46)/(2+$I22))","v":0},{"$f":"((1+$I22)^(1-L$9-L$8)-1)*(L42+(L43+L44+L45+L46)/(2+$I22))","v":0},0,0,0,0,0,0.220611491560949,0.46421070054254887,0.4883960780408157,0.51384151370674225,0.48088712167136594,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Transfer to operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"-SUM(K42,K47,K48)*K$11","v":0},{"$f":"-SUM(L42,L47,L48)*L$11","v":0},0,0,0,0,0,0,0,0,0,-10.3025497520823,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Transaction costs - closing",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K49,K48,K47,K42)","v":0},{"$f":"SUM(L49,L48,L47,L42)","v":0},0,0,0,0,0,8.9099942522562099,9.3742049527987596,9.862601030839576,10.376442544546318,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"Actual cost of debt"]
[]
[null,null,"Debt balance and reserves"]
[]
[null,null,null,null,"Eligible costs",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"'Pre Op RAV'!K54","v":0},{"$f":"'Pre Op RAV'!L54","v":0},{"$f":"'Pre Op RAV'!M54","v":0},{"$f":"'Pre Op RAV'!N54","v":0},{"$f":"'Pre Op RAV'!O54","v":0},{"$f":"'Pre Op RAV'!P54","v":0},{"$f":"'Pre Op RAV'!Q54","v":0},{"$f":"'Pre Op RAV'!R54","v":0},{"$f":"'Pre Op RAV'!S54","v":26.986185899481182},{"$f":"'Pre Op RAV'!T54","v":88.211461598904449},{"$f":"'Pre Op RAV'!U54","v":83.268186147626778},{"$f":"'Pre Op RAV'!V54","v":44.346262875902234},{"$f":"'Pre Op RAV'!W54","v":0},{"$f":"'Pre Op RAV'!X54","v":0},{"$f":"'Pre Op RAV'!Y54","v":0},{"$f":"'Pre Op RAV'!Z54","v":0},{"$f":"'Pre Op RAV'!AA54","v":0},{"$f":"'Pre Op RAV'!AB54","v":0},{"$f":"'Pre Op RAV'!AC54","v":0},{"$f":"'Pre Op RAV'!AD54","v":0},{"$f":"'Pre Op RAV'!AE54","v":0},{"$f":"'Pre Op RAV'!AF54","v":0},{"$f":"'Pre Op RAV'!AG54","v":0},{"$f":"'Pre Op RAV'!AH54","v":0},{"$f":"'Pre Op RAV'!AI54","v":0},{"$f":"'Pre Op RAV'!AJ54","v":0},{"$f":"'Pre Op RAV'!AK54","v":0},{"$f":"'Pre Op RAV'!AL54","v":0},{"$f":"'Pre Op RAV'!AM54","v":0},{"$f":"'Pre Op RAV'!AN54","v":0},{"$f":"'Pre Op RAV'!AO54","v":0},{"$f":"'Pre Op RAV'!AP54","v":0},{"$f":"'Pre Op RAV'!AQ54","v":0},{"$f":"'Pre Op RAV'!AR54","v":0},{"$f":"'Pre Op RAV'!AS54","v":0},{"$f":"'Pre Op RAV'!AT54","v":0},{"$f":"'Pre Op RAV'!AU54","v":0},{"$f":"'Pre Op RAV'!AV54","v":0},{"$f":"'Pre Op RAV'!AW54","v":0},{"$f":"'Pre Op RAV'!AX54","v":0}]
[]
[null,null,null,null,"Project finance senior debt amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"IF(Inputs!I81=1,Inputs!I82,I59*SUM(K56:AX56))","v":253.11449999999999}]
[null,null,null,null,"Project finance actual gearing on eligible costs",null,"%",null,{"$f":"IF(Inputs!I81=2,Inputs!I83,Finance!I58/SUM(Finance!K56:AX56))","v":1.0424295314181578}]
[null,null,null,null,"Senior debt drawdown profile",null,"%",null,null,null,{"$f":"IF(Finance!K15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:K15)),0)","v":0},{"$f":"IF(Finance!L15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:L15)),0)","v":0},{"$f":"IF(Finance!M15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:M15)),0)","v":0},{"$f":"IF(Finance!N15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:N15)),0)","v":0},{"$f":"IF(Finance!O15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:O15)),0)","v":0},{"$f":"IF(Finance!P15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:P15)),0)","v":0},{"$f":"IF(Finance!Q15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:Q15)),0)","v":0},{"$f":"IF(Finance!R15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:R15)),0)","v":0},{"$f":"IF(Finance!S15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:S15)),0)","v":0.50574215483891483},{"$f":"IF(Finance!T15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:T15)),0)","v":0.49425784516108517},{"$f":"IF(Finance!U15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:U15)),0)","v":0},{"$f":"IF(Finance!V15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:V15)),0)","v":0},{"$f":"IF(Finance!W15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:W15)),0)","v":0},{"$f":"IF(Finance!X15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:X15)),0)","v":0},{"$f":"IF(Finance!Y15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:Y15)),0)","v":0},{"$f":"IF(Finance!Z15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:Z15)),0)","v":0},{"$f":"IF(Finance!AA15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AA15)),0)","v":0},{"$f":"IF(Finance!AB15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AB15)),0)","v":0},{"$f":"IF(Finance!AC15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AC15)),0)","v":0},{"$f":"IF(Finance!AD15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AD15)),0)","v":0},{"$f":"IF(Finance!AE15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AE15)),0)","v":0},{"$f":"IF(Finance!AF15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AF15)),0)","v":0},{"$f":"IF(Finance!AG15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AG15)),0)","v":0},{"$f":"IF(Finance!AH15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AH15)),0)","v":0},{"$f":"IF(Finance!AI15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AI15)),0)","v":0},{"$f":"IF(Finance!AJ15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AJ15)),0)","v":0},{"$f":"IF(Finance!AK15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AK15)),0)","v":0},{"$f":"IF(Finance!AL15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AL15)),0)","v":0},{"$f":"IF(Finance!AM15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AM15)),0)","v":0},{"$f":"IF(Finance!AN15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AN15)),0)","v":0},{"$f":"IF(Finance!AO15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AO15)),0)","v":0},{"$f":"IF(Finance!AP15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AP15)),0)","v":0},{"$f":"IF(Finance!AQ15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AQ15)),0)","v":0},{"$f":"IF(Finance!AR15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AR15)),0)","v":0},{"$f":"IF(Finance!AS15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AS15)),0)","v":0},{"$f":"IF(Finance!AT15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AT15)),0)","v":0},{"$f":"IF(Finance!AU15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AU15)),0)","v":0},{"$f":"IF(Finance!AV15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AV15)),0)","v":0},{"$f":"IF(Finance!AW15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AW15)),0)","v":0},{"$f":"IF(Finance!AX15>0,INDEX(Inputs!$K$98:$T$98,1,SUM(Finance!$K$15:AX15)),0)","v":0}]
[null,null,null,null,"Senior debt repayment profile",null,"%",null,null,null,{"$f":"SUMIF(Inputs!133:133,Finance!K16,Inputs!134:134)*(K16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!L16,Inputs!134:134)*(L16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!M16,Inputs!134:134)*(M16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!N16,Inputs!134:134)*(N16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!O16,Inputs!134:134)*(O16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!P16,Inputs!134:134)*(P16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!Q16,Inputs!134:134)*(Q16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!R16,Inputs!134:134)*(R16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!S16,Inputs!134:134)*(S16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!T16,Inputs!134:134)*(T16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!U16,Inputs!134:134)*(U16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!V16,Inputs!134:134)*(V16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!W16,Inputs!134:134)*(W16<>0)","v":1.9431121328306773E-2},{"$f":"SUMIF(Inputs!133:133,Finance!X16,Inputs!134:134)*(X16<>0)","v":2.4375989173664295E-2},{"$f":"SUMIF(Inputs!133:133,Finance!Y16,Inputs!134:134)*(Y16<>0)","v":2.6046951464214492E-2},{"$f":"SUMIF(Inputs!133:133,Finance!Z16,Inputs!134:134)*(Z16<>0)","v":2.9582447236245708E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AA16,Inputs!134:134)*(AA16<>0)","v":3.1383612779133763E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AB16,Inputs!134:134)*(AB16<>0)","v":3.2017818622522634E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AC16,Inputs!134:134)*(AC16<>0)","v":2.8014349840947063E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AD16,Inputs!134:134)*(AD16<>0)","v":3.5801376475390639E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AE16,Inputs!134:134)*(AE16<>0)","v":4.2356185642239044E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AF16,Inputs!134:134)*(AF16<>0)","v":4.3990570739643263E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AG16,Inputs!134:134)*(AG16<>0)","v":4.683001111051064E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AH16,Inputs!134:134)*(AH16<>0)","v":4.6828414199576771E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AI16,Inputs!134:134)*(AI16<>0)","v":5.2689369291696576E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AJ16,Inputs!134:134)*(AJ16<>0)","v":5.2068479294291738E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AK16,Inputs!134:134)*(AK16<>0)","v":4.5739928343171157E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AL16,Inputs!134:134)*(AL16<>0)","v":4.5877875113697966E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AM16,Inputs!134:134)*(AM16<>0)","v":5.616076474181074E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AN16,Inputs!134:134)*(AN16<>0)","v":5.7879677840293797E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AO16,Inputs!134:134)*(AO16<>0)","v":6.2078161420472094E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AP16,Inputs!134:134)*(AP16<>0)","v":6.278318854400268E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AQ16,Inputs!134:134)*(AQ16<>0)","v":6.8457160170738288E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AR16,Inputs!134:134)*(AR16<>0)","v":6.978553203890249E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AS16,Inputs!134:134)*(AS16<>0)","v":1.9821014588527457E-2},{"$f":"SUMIF(Inputs!133:133,Finance!AT16,Inputs!134:134)*(AT16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!AU16,Inputs!134:134)*(AU16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!AV16,Inputs!134:134)*(AV16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!AW16,Inputs!134:134)*(AW16<>0)","v":0},{"$f":"SUMIF(Inputs!133:133,Finance!AX16,Inputs!134:134)*(AX16<>0)","v":0}]
[]
[null,null,null,null,"Opening senior debt balance",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,null,{"$f":"K66","v":0},{"$f":"L66","v":0},0,0,0,0,0,0,128.0106726509745,253.11449999999999,253.11449999999999,253.11449999999999,248.19620144054628,242.02628512884883,235.4334240324599,227.94567769148119,220.00203023469714,211.89785608296665,204.80701793015027,195.74517042427001,185.02420567352749,173.88955435604805,162.03619950881671,150.18324886289793,136.8468054993148,123.66751839697979,112.09007930436219,100.47772388389609,86.262619996655033,71.61243427994799,{"$f":"AO66","v":55.899551491085909},40.008216114364942,22.680716246328604,5.0169861970678191,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14]
[null,null,null,null,"Senior debt drawdowns",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"K60*$I$58","v":0},{"$f":"L60*$I$58","v":0},0,0,0,0,0,0,128.0106726509745,125.10382734902549,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Senior debt repayments",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"-$I$58*K61","v":0},{"$f":"-$I$58*L61","v":0},0,0,0,0,0,0,0,0,0,{"$f":"-$I$58*V61","v":0},-4.9182985594537048,-6.1699163116974507,-6.5928610963889192,-7.4877463409787142,-7.9436474567840527,-8.1041741517305041,-7.0908381528163948,-9.0618475058802641,-10.720964750742514,-11.134651317479435,-11.853354847231346,-11.852950645918774,-13.336443363583133,-13.179287102335005,-11.577439092617595,-11.612355420466104,-14.215103887241055,-14.650185716707044,-15.712882788862084,-15.891335376720965,-17.327499868036337,-17.663730049260785,-5.0169861970678333,0,0,0,0,0]
[null,null,null,null,"Closing senior debt balance",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K63:K65)","v":0},{"$f":"SUM(L63:L65)","v":0},0,0,0,0,0,0,128.0106726509745,253.11449999999999,253.11449999999999,253.11449999999999,248.19620144054628,242.02628512884883,235.4334240324599,227.94567769148119,220.00203023469714,211.89785608296665,204.80701793015027,195.74517042427001,185.02420567352749,173.88955435604805,162.03619950881671,150.18324886289793,136.8468054993148,123.66751839697979,112.09007930436219,100.47772388389609,86.262619996655033,71.61243427994799,55.899551491085909,40.008216114364942,22.680716246328604,5.0169861970678191,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14,-1.4210854715202004E-14]
[]
[null,null,null,null,"Debt Service Reserve Facility amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I100*(Inputs!I127=1)","v":8.7884366946588557}]
[null,null,null,null,"Cap and Floor Liquidity Facility amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I105","v":23.221091736647139}]
[null,null,null,null,"Cap and Floor Liquidity Facility average outstanding loan",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I106","v":0}]
[null,null,null,null,"Standby Debt Facility amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I111","v":0}]
[null,null,null,null,"VAT Facility amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I116","v":0.46442183473294274}]
[null,null,null,null,"VAT Facility average outstanding loan",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I117","v":0.19181378568180549}]
[null,null,null,null,"Other facilities amount",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,{"$f":"Inputs!I122","v":12.5}]
[]
[null,null,"Financial expenses during construction"]
[]
[null,null,null,null,"Upfront fee - Senior Debt",null,"nominal %",null,{"$f":"Inputs!I94","v":1.4E-2}]
[null,null,null,null,"Upfront fee - Debt Service Reserve Facility",null,"nominal %",null,{"$f":"Inputs!I101","v":1.4E-2}]
[null,null,null,null,"Upfront fee - Cap and Floor Liquidity Facility",null,"nominal %",null,{"$f":"Inputs!I107","v":1.4E-2}]
[null,null,null,null,"Upfront fee - Standby Debt Facility",null,"nominal %",null,{"$f":"Inputs!I112","v":1.4E-2}]
[null,null,null,null,"Upfront fee - VAT Facility",null,"nominal %",null,{"$f":"Inputs!I118","v":1.2999999999999999E-2}]
[null,null,null,null,"Upfront fee - Other facilities",null,"nominal %",null,{"$f":"Inputs!I123","v":1.4E-2}]
[]
[null,null,null,null,"Fixed rate - Construction",null,"nominal %",null,{"$f":"Inputs!I89","v":1.3143521893981167E-2}]
[null,null,null,null,"Construction margin - Senior Debt",null,"nominal %",null,{"$f":"Inputs!I92","v":1.7704500000000001E-2}]
[null,null,null,null,"of which: swap margin",null,"nominal %",null,{"$f":"Inputs!I93","v":1.7044999999999999E-3}]
[null,null,null,null,"Construction margin - Debt Service Reserve Facility",null,"nominal %",null,{"$f":"Inputs!I102","v":1.6012036458399354E-2}]
[null,null,null,null,"Construction margin - Cap and Floor Liquidity Facility",null,"nominal %",null,{"$f":"Inputs!I108","v":1.6038303717231035E-2}]
[null,null,null,null,"Construction margin - Standby Debt Facility",null,"nominal %",null,{"$f":"Inputs!I113","v":1.6E-2}]
[null,null,null,null,"Construction margin - VAT Facility",null,"nominal %",null,{"$f":"Inputs!I119","v":1.2500000000000001E-2}]
[null,null,null,null,"Construction margin - Other facilities",null,"nominal %",null,{"$f":"Inputs!I124","v":1.6500000000000001E-2}]
[]
[null,null,null,null,"Total interest rate - Senior Debt",null,"nominal %",null,null,null,{"$f":"($I$85+$I86)*K$15","v":0},{"$f":"($I$85+$I86)*L$15","v":0},0,0,0,0,0,0,{"$f":"($I$85+$I86)*S$15","v":3.084802189398117E-2},{"$f":"($I$85+$I86)*T$15","v":3.084802189398117E-2},3.084802189398117E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Debt Service Reserve Facility ",null,"nominal %",null,null,null,{"$f":"($I$85+$I88)*K$15","v":0},0,0,0,0,0,0,0,{"$f":"($I$85+$I88)*S$15","v":2.9155558352380519E-2},2.9155558352380519E-2,2.9155558352380519E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Cap and Floor Liquidity Facility",null,"nominal %",null,null,null,{"$f":"($I$85+$I89)*K$15","v":0},{"$f":"($I$85+$I89)*L$15","v":0},0,0,0,0,0,0,{"$f":"($I$85+$I89)*S$15","v":2.91818256112122E-2},2.91818256112122E-2,2.91818256112122E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Standby Debt Facility",null,"nominal %",null,null,null,{"$f":"($I$85+$I90)*K$15","v":0},0,0,0,0,0,0,0,{"$f":"($I$85+$I90)*S$15","v":2.9143521893981165E-2},2.9143521893981165E-2,2.9143521893981165E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Total interest rate - VAT Facility",null,"nominal %",null,null,null,{"$f":"($I$85+$I91)*K$15","v":0},0,0,0,0,0,0,0,{"$f":"($I$85+$I91)*S$15","v":2.5643521893981169E-2},2.5643521893981169E-2,2.5643521893981169E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Other facilities",null,"nominal %",null,null,null,{"$f":"($I$85+$I92)*K$15","v":0},0,0,0,0,0,0,0,{"$f":"($I$85+$I92)*S$15","v":2.9643521893981166E-2},2.9643521893981166E-2,2.9643521893981166E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,null,"Commitment fee - Senior Debt",null,"% of applicable margin",null,{"$f":"Inputs!I95","v":0.35}]
[null,null,null,null,"Commitment fee - Debt Service Reserve Facility",null,"% of applicable margin",null,{"$f":"Inputs!I103","v":0.35}]
[null,null,null,null,"Commitment fee - Cap and Floor Liquidity Facility",null,"% of applicable margin",null,{"$f":"Inputs!I109","v":0.35}]
[null,null,null,null,"Commitment fee - Standby Debt Facility",null,"% of applicable margin",null,{"$f":"Inputs!I114","v":0.35}]
[null,null,null,null,"Commitment fee - VAT Facility",null,"% of applicable margin",null,{"$f":"Inputs!I120","v":0.35}]
[null,null,null,null,"Commitment fee - Other facilities",null,"% of applicable margin",null,{"$f":"Inputs!I125","v":0.35}]
[]
[null,null,null,null,"Upfront fee payable - Senior Debt",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"$I$58*$I$78*K14","v":0},{"$f":"$I$58*$I$78*L14","v":0},0,0,0,0,0,0,{"$f":"$I$58*$I$78*S14","v":3.5436030000000001},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Upfront fee payable - Ancillary Facilities",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"($I$68*$I$79+$I$69*$I$80+$I$71*$I$81+$I$72*$I$82+$I$74*$I$83)*K14","v":0},{"$f":"($I$68*$I$79+$I$69*$I$80+$I$71*$I$81+$I$72*$I$82+$I$74*$I$83)*L14","v":0},{"$f":"($I$68*$I$79+$I$69*$I$80+$I$71*$I$81+$I$72*$I$82+$I$74*$I$83)*M14","v":0},0,0,0,0,{"$f":"($I$68*$I$79+$I$69*$I$80+$I$71*$I$81+$I$72*$I$82+$I$74*$I$83)*R14","v":0},{"$f":"($I$68*$I$79+$I$69*$I$80+$I$71*$I$81+$I$72*$I$82+$I$74*$I$83)*S14","v":0.62917088188981218},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Interest payable - Senior Debt",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K63:K64)*K94*K15","v":0},{"$f":"SUM(L63:L64)*L94*L15","v":0},0,0,0,0,0,{"$f":"SUM(R63:R64)*R94*R15","v":0},{"$f":"SUM(S63:S64)*S94*S15","v":3.9488760326005181},7.8080816376840962,7.8080816376840962,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Interest payable - Ancillary Facilities",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"$I$73*K98*K15","v":0},{"$f":"$I$73*L98*L15","v":0},0,0,0,0,0,0,4.9187810126987905E-3,4.9187810126987905E-3,4.9187810126987905E-3,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Commitment fee payable - Senior Debt",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"($I$58-SUM(K63:K64))*(K94-$I$85-$I$87)*$I$101*K15","v":0},{"$f":"($I$58-SUM(L63:L64))*(L94-$I$85-$I$87)*$I$101*L15","v":0},0,0,0,0,0,0,{"$f":"($I$58-SUM(S63:S64))*(S94-$I$85-$I$87)*$I$101*S15","v":0.70058143315454291},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Commitment fee payable - Ancillary Facilities",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"($I$68*(K95-$I$85)*$I$102+$I$69*(K96-$I$85)*$I$103+$I$71*(K97-$I$85)*$I$104+($I$72-$I$73)*(K98-$I$85)*$I$105+$I$74*(K99-$I$85)*$I$106)*K15","v":0},{"$f":"($I$68*(L95-$I$85)*$I$102+$I$69*(L96-$I$85)*$I$103+$I$71*(L97-$I$85)*$I$104+($I$72-$I$73)*(L98-$I$85)*$I$105+$I$74*(L99-$I$85)*$I$106)*L15","v":0},{"$f":"($I$68*(M95-$I$85)*$I$102+$I$69*(M96-$I$85)*$I$103+$I$71*(M97-$I$85)*$I$104+($I$72-$I$73)*(M98-$I$85)*$I$105+$I$74*(M99-$I$85)*$I$106)*M15","v":0},0,0,0,0,0,{"$f":"($I$68*(S95-$I$85)*$I$102+$I$69*(S96-$I$85)*$I$103+$I$71*(S97-$I$85)*$I$104+($I$72-$I$73)*(S98-$I$85)*$I$105+$I$74*(S99-$I$85)*$I$106)*S15","v":0.25298185195443373},0.25298185195443373,{"$f":"($I$68*(U95-$I$85)*$I$102+$I$69*(U96-$I$85)*$I$103+$I$71*(U97-$I$85)*$I$104+($I$72-$I$73)*(U98-$I$85)*$I$105+$I$74*(U99-$I$85)*$I$106)*U15","v":0.25298185195443373},{"$f":"($I$68*(V95-$I$85)*$I$102+$I$69*(V96-$I$85)*$I$103+$I$71*(V97-$I$85)*$I$104+($I$72-$I$73)*(V98-$I$85)*$I$105+$I$74*(V99-$I$85)*$I$106)*V15","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Financial expenses during construction",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K108:K113)","v":0},{"$f":"SUM(L108:L113)","v":0},0,0,0,0,0,0,{"$f":"SUM(S108:S113)","v":9.0801319806120055},8.0659822706512294,8.0659822706512294,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Financial expenses during operation"]
[]
[null,null,null,null,"Fixed rate - Operation",null,"nominal %",null,{"$f":"Inputs!I90","v":1.3010779504157978E-2}]
[null,null,null,null,"Operation margin (including swap margin) - Senior Debt",null,"nominal %",null,null,null,{"$f":"SUMIF(Inputs!$133:$133,Finance!K$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!L$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!M$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!N$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!O$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!P$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Q$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!R$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!S$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!T$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!U$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!V$16,Inputs!136:136)","v":1.62045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!W$16,Inputs!136:136)","v":1.62045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!X$16,Inputs!136:136)","v":1.62045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Y$16,Inputs!136:136)","v":1.62045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Z$16,Inputs!136:136)","v":1.62045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AA$16,Inputs!136:136)","v":1.6289199453551912E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AB$16,Inputs!136:136)","v":1.7204500000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AC$16,Inputs!136:136)","v":1.7204500000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AD$16,Inputs!136:136)","v":1.7204500000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AE$16,Inputs!136:136)","v":1.7204500000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AF$16,Inputs!136:136)","v":1.7289199453551913E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AG$16,Inputs!136:136)","v":1.8204500000000002E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AH$16,Inputs!136:136)","v":1.8204500000000002E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AI$16,Inputs!136:136)","v":1.8204500000000002E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AJ$16,Inputs!136:136)","v":1.8204500000000002E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AK$16,Inputs!136:136)","v":1.8289199453551914E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AL$16,Inputs!136:136)","v":1.9204500000000003E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AM$16,Inputs!136:136)","v":1.9204500000000003E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AN$16,Inputs!136:136)","v":1.9204500000000003E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AO$16,Inputs!136:136)","v":1.9204500000000003E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AP$16,Inputs!136:136)","v":1.9289199453551915E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AQ$16,Inputs!136:136)","v":2.02045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AR$16,Inputs!136:136)","v":2.02045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AS$16,Inputs!136:136)","v":2.02045E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AT$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AU$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AV$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AW$16,Inputs!136:136)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AX$16,Inputs!136:136)","v":0}]
[null,null,null,null,"Operation margin - Debt Service Reserve Facility",null,"nominal %",null,null,null,{"$f":"SUMIF(Inputs!$133:$133,Finance!K$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!L$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!M$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!N$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!O$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!P$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Q$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!R$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!S$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!T$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!U$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!V$16,Inputs!137:137)","v":1.451203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!W$16,Inputs!137:137)","v":1.451203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!X$16,Inputs!137:137)","v":1.451203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Y$16,Inputs!137:137)","v":1.451203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Z$16,Inputs!137:137)","v":1.451203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AA$16,Inputs!137:137)","v":1.4596735911951262E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AB$16,Inputs!137:137)","v":1.551203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AC$16,Inputs!137:137)","v":1.551203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AD$16,Inputs!137:137)","v":1.551203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AE$16,Inputs!137:137)","v":1.551203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AF$16,Inputs!137:137)","v":1.5596735911951261E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AG$16,Inputs!137:137)","v":1.651203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AH$16,Inputs!137:137)","v":1.651203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AI$16,Inputs!137:137)","v":1.651203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AJ$16,Inputs!137:137)","v":1.651203645839935E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AK$16,Inputs!137:137)","v":1.6596735911951262E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AL$16,Inputs!137:137)","v":1.7512036458399348E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AM$16,Inputs!137:137)","v":1.7512036458399348E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AN$16,Inputs!137:137)","v":1.7512036458399348E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AO$16,Inputs!137:137)","v":1.7512036458399348E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AP$16,Inputs!137:137)","v":1.7596735911951263E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AQ$16,Inputs!137:137)","v":1.8512036458399349E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AR$16,Inputs!137:137)","v":1.8512036458399349E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AS$16,Inputs!137:137)","v":1.8512036458399349E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AT$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AU$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AV$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AW$16,Inputs!137:137)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AX$16,Inputs!137:137)","v":0}]
[null,null,null,null,"Operation margin - Cap and Floor Liquidity Facility",null,"nominal %",null,null,null,{"$f":"SUMIF(Inputs!$133:$133,Finance!K$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!L$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!M$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!N$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!O$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!P$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Q$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!R$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!S$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!T$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!U$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!V$16,Inputs!138:138)","v":1.4538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!W$16,Inputs!138:138)","v":1.4538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!X$16,Inputs!138:138)","v":1.4538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Y$16,Inputs!138:138)","v":1.4538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Z$16,Inputs!138:138)","v":1.4538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AA$16,Inputs!138:138)","v":1.4623003170782946E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AB$16,Inputs!138:138)","v":1.5538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AC$16,Inputs!138:138)","v":1.5538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AD$16,Inputs!138:138)","v":1.5538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AE$16,Inputs!138:138)","v":1.5538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AF$16,Inputs!138:138)","v":1.5623003170782947E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AG$16,Inputs!138:138)","v":1.6538303717231036E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AH$16,Inputs!138:138)","v":1.6538303717231036E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AI$16,Inputs!138:138)","v":1.6538303717231036E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AJ$16,Inputs!138:138)","v":1.6538303717231036E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AK$16,Inputs!138:138)","v":1.6623003170782948E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AL$16,Inputs!138:138)","v":1.7538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AM$16,Inputs!138:138)","v":1.7538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AN$16,Inputs!138:138)","v":1.7538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AO$16,Inputs!138:138)","v":1.7538303717231033E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AP$16,Inputs!138:138)","v":1.7623003170782945E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AQ$16,Inputs!138:138)","v":1.8538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AR$16,Inputs!138:138)","v":1.8538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AS$16,Inputs!138:138)","v":1.8538303717231034E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AT$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AU$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AV$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AW$16,Inputs!138:138)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AX$16,Inputs!138:138)","v":0}]
[null,null,null,null,"Operation margin - Standby Debt Facility",null,"nominal %",null,null,null,{"$f":"SUMIF(Inputs!$133:$133,Finance!K$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!L$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!M$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!N$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!O$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!P$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Q$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!R$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!S$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!T$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!U$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!V$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!W$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!X$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Y$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Z$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AA$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AB$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AC$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AD$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AE$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AF$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AG$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AH$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AI$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AJ$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AK$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AL$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AM$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AN$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AO$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AP$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AQ$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AR$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AS$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AT$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AU$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AV$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AW$16,Inputs!139:139)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AX$16,Inputs!139:139)","v":0}]
[null,null,null,null,"Operation margin - Other facilities",null,"nominal %",null,null,null,{"$f":"SUMIF(Inputs!$133:$133,Finance!K$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!L$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!M$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!N$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!O$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!P$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!Q$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!R$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!S$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!T$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!U$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!V$16,Inputs!141:141)","v":1.4999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!W$16,Inputs!141:141)","v":1.4999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!X$16,Inputs!141:141)","v":1.4999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Y$16,Inputs!141:141)","v":1.4999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!Z$16,Inputs!141:141)","v":1.4999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AA$16,Inputs!141:141)","v":1.5084699453551911E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AB$16,Inputs!141:141)","v":1.6E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AC$16,Inputs!141:141)","v":1.6E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AD$16,Inputs!141:141)","v":1.6E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AE$16,Inputs!141:141)","v":1.6E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AF$16,Inputs!141:141)","v":1.6084699453551912E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AG$16,Inputs!141:141)","v":1.7000000000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AH$16,Inputs!141:141)","v":1.7000000000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AI$16,Inputs!141:141)","v":1.7000000000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AJ$16,Inputs!141:141)","v":1.7000000000000001E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AK$16,Inputs!141:141)","v":1.7084699453551913E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AL$16,Inputs!141:141)","v":1.7999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AM$16,Inputs!141:141)","v":1.7999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AN$16,Inputs!141:141)","v":1.7999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AO$16,Inputs!141:141)","v":1.7999999999999999E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AP$16,Inputs!141:141)","v":1.8084699453551914E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AQ$16,Inputs!141:141)","v":1.9E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AR$16,Inputs!141:141)","v":1.9E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AS$16,Inputs!141:141)","v":1.9E-2},{"$f":"SUMIF(Inputs!$133:$133,Finance!AT$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AU$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AV$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AW$16,Inputs!141:141)","v":0},{"$f":"SUMIF(Inputs!$133:$133,Finance!AX$16,Inputs!141:141)","v":0}]
[]
[null,null,null,null,"Total interest rate - Senior Debt",null,"nominal %",null,null,null,{"$f":"($I$118+K119)*(K$16<>0)","v":0},{"$f":"($I$118+L119)*(L$16<>0)","v":0},0,0,0,0,0,0,0,0,0,2.9215279504157976E-2,2.9215279504157976E-2,2.9215279504157976E-2,2.9215279504157976E-2,2.9215279504157976E-2,2.9299978957709888E-2,3.0215279504157977E-2,3.0215279504157977E-2,3.0215279504157977E-2,3.0215279504157977E-2,3.0299978957709889E-2,3.1215279504157978E-2,3.1215279504157978E-2,3.1215279504157978E-2,3.1215279504157978E-2,3.129997895770989E-2,3.2215279504157979E-2,3.2215279504157979E-2,3.2215279504157979E-2,3.2215279504157979E-2,3.2299978957709891E-2,3.321527950415798E-2,3.321527950415798E-2,3.321527950415798E-2,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Debt Service Reserve Facility ",null,"nominal %",null,null,null,{"$f":"($I$118+K120)*(K$16<>0)","v":0},0,0,0,0,0,0,0,0,0,0,2.7522815962557328E-2,2.7522815962557328E-2,2.7522815962557328E-2,2.7522815962557328E-2,2.7522815962557328E-2,2.760751541610924E-2,2.8522815962557325E-2,2.8522815962557325E-2,2.8522815962557325E-2,2.8522815962557325E-2,2.8607515416109237E-2,2.9522815962557326E-2,2.9522815962557326E-2,2.9522815962557326E-2,2.9522815962557326E-2,2.9607515416109238E-2,3.0522815962557327E-2,3.0522815962557327E-2,3.0522815962557327E-2,3.0522815962557327E-2,3.0607515416109239E-2,3.1522815962557328E-2,3.1522815962557328E-2,3.1522815962557328E-2,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Cap and Floor Liquidity Facility",null,"nominal %",null,null,null,{"$f":"($I$118+K121)*(K$16<>0)","v":0},0,0,0,0,0,0,0,0,0,0,2.7549083221389013E-2,2.7549083221389013E-2,2.7549083221389013E-2,2.7549083221389013E-2,2.7549083221389013E-2,2.7633782674940925E-2,2.8549083221389011E-2,2.8549083221389011E-2,2.8549083221389011E-2,2.8549083221389011E-2,2.8633782674940926E-2,2.9549083221389015E-2,2.9549083221389015E-2,2.9549083221389015E-2,2.9549083221389015E-2,2.9633782674940927E-2,3.0549083221389009E-2,3.0549083221389009E-2,3.0549083221389009E-2,3.0549083221389009E-2,3.0633782674940921E-2,3.154908322138901E-2,3.154908322138901E-2,3.154908322138901E-2,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Standby Debt Facility",null,"nominal %",null,null,null,{"$f":"($I$118+K122)*(K$16<>0)","v":0},0,0,0,0,0,0,0,0,0,0,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,1.3010779504157978E-2,0,0,0,0,0]
[null,null,null,null,"Total interest rate - Other facilities",null,"nominal %",null,null,null,{"$f":"($I$118+K123)*(K$16<>0)","v":0},0,0,0,0,0,0,0,0,0,0,2.8010779504157979E-2,2.8010779504157979E-2,2.8010779504157979E-2,2.8010779504157979E-2,2.8010779504157979E-2,2.8095478957709891E-2,2.901077950415798E-2,2.901077950415798E-2,2.901077950415798E-2,2.901077950415798E-2,2.9095478957709892E-2,3.0010779504157981E-2,3.0010779504157981E-2,3.0010779504157981E-2,3.0010779504157981E-2,3.0095478957709892E-2,3.1010779504157975E-2,3.1010779504157975E-2,3.1010779504157975E-2,3.1010779504157975E-2,3.1095478957709893E-2,3.2010779504157975E-2,3.2010779504157975E-2,3.2010779504157975E-2,0,0,0,0,0]
[]
[null,null,null,null,"Commitment fee - Senior Debt",null,"% of applicable margin",null,{"$f":"Inputs!I95","v":0.35}]
[null,null,null,null,"Commitment fee - Debt Service Reserve Facility",null,"% of applicable margin",null,{"$f":"Inputs!I103","v":0.35}]
[null,null,null,null,"Commitment fee - Cap and Floor Liquidity Facility",null,"% of applicable margin",null,{"$f":"Inputs!I109","v":0.35}]
[null,null,null,null,"Commitment fee - Standby Debt Facility",null,"% of applicable margin",null,{"$f":"Inputs!I114","v":0.35}]
[null,null,null,null,"Commitment fee - Other facilities",null,"% of applicable margin",null,{"$f":"Inputs!I125","v":0.35}]
[]
[null,null,null,null,"Interest payable - Senior Debt",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K63:K64)*K125","v":0},{"$f":"SUM(L63:L64)*L125","v":0},0,0,0,0,0,0,0,0,0,{"$f":"SUM(V63:V64)*V125","v":7.3948108640551942},7.3948108640551942,7.2511213969558561,7.0708655673923513,6.8782532877292599,6.6788035598613193,6.6474228350235878,6.4025529478786787,6.1883012911725848,5.9144950359583559,5.6062295385748699,5.428011042077511,5.0580052574592189,4.6880120900978746,4.2717112829122543,3.870790723577668,3.6110132344332619,3.2369179588613224,2.7789744139532089,2.3070145863016687,1.8055543369074953,1.3288840807013889,0.75334632947630142,0.16664059880411022,0,0,0,0,0]
[null,null,null,null,"Interest payable - Ancillary Facilities",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"$I$70*K127","v":0},{"$f":"$I$70*L127","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Commitment fee payable - Ancillary Facilities",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"($I$68*(K126-$I$118)*$I$132+($I$69-$I$70)*(K127-$I$118)*$I$133+$I$74*(K129-$I$118)*$I$135)*(K$16<>0)","v":0},{"$f":"($I$68*(L126-$I$118)*$I$132+($I$69-$I$70)*(L127-$I$118)*$I$133+$I$74*(L129-$I$118)*$I$135)*(L$16<>0)","v":0},0,0,0,0,0,{"$f":"($I$68*(R126-$I$118)*$I$132+($I$69-$I$70)*(R127-$I$118)*$I$133+$I$74*(R129-$I$118)*$I$135)*(R$16<>0)","v":0},0,0,0,0.2284216893133994,0.2284216893133994,0.2284216893133994,0.2284216893133994,0.2284216893133994,0.2297411657709941,0.24400002426435646,0.24400002426435646,0.24400002426435646,0.24400002426435646,0.24531950072195116,0.25957835921531358,0.25957835921531358,0.25957835921531358,0.25957835921531358,0.26089783567290825,0.27515669416627059,0.27515669416627059,0.27515669416627059,0.27515669416627059,0.27647617062386531,0.29073502911722771,0.29073502911722771,0.29073502911722771,0,0,0,0,0]
[null,null,null,null,"Financial expenses during operation",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K137:K139)","v":0},{"$f":"SUM(L137:L139)","v":0},0,0,0,0,0,0,0,0,0,{"$f":"SUM(V137:V139)","v":7.6232325533685934},7.6232325533685934,7.4795430862692553,7.2992872567057505,7.1066749770426592,6.9085447256323134,6.8914228592879443,6.6465529721430352,6.4323013154369413,6.1584950602227124,5.8515490392968212,5.6875894012928248,5.3175836166745327,4.9475904493131884,4.5312896421275681,4.1316885592505761,3.8861699285995326,3.512074653027593,3.0541311081194795,2.5821712804679393,2.0820305075313605,1.6196191098186166,1.0440813585935291,0.4573756279213379,0,0,0,0,0]
[]
[null,null,"Debt service"]
[]
[null,null,null,null,"Principal repayment",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"-K65","v":0},{"$f":"-L65","v":0},0,0,0,0,0,0,0,0,0,0,4.9182985594537048,6.1699163116974507,6.5928610963889192,7.4877463409787142,7.9436474567840527,8.1041741517305041,7.0908381528163948,9.0618475058802641,10.720964750742514,11.134651317479435,11.853354847231346,11.852950645918774,13.336443363583133,13.179287102335005,11.577439092617595,11.612355420466104,14.215103887241055,14.650185716707044,15.712882788862084,15.891335376720965,17.327499868036337,17.663730049260785,5.0169861970678333,0,0,0,0,0]
[null,null,null,null,"Financial expenses during operation",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"K140","v":0},{"$f":"L140","v":0},0,0,0,0,0,0,0,0,0,7.6232325533685934,7.6232325533685934,7.4795430862692553,7.2992872567057505,7.1066749770426592,6.9085447256323134,6.8914228592879443,6.6465529721430352,6.4323013154369413,6.1584950602227124,5.8515490392968212,5.6875894012928248,5.3175836166745327,4.9475904493131884,4.5312896421275681,4.1316885592505761,3.8861699285995326,3.512074653027593,3.0541311081194795,2.5821712804679393,2.0820305075313605,1.6196191098186166,1.0440813585935291,0.4573756279213379,0,0,0,0,0]
[null,null,null,null,"Total debt service",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"SUM(K144:K145)","v":0},{"$f":"SUM(L144:L145)","v":0},0,0,0,0,0,0,0,0,0,7.6232325533685934,12.541531112822298,13.649459397966705,13.892148353094669,14.594421318021373,14.852192182416367,14.995597011018448,13.73739112495943,15.494148821317205,16.879459810965226,16.986200356776255,17.54094424852417,17.170534262593307,18.284033812896322,17.710576744462571,15.709127651868172,15.498525349065636,17.727178540268646,17.704316824826524,18.295054069330021,17.973365884252324,18.947118977854956,18.707811407854315,5.4743618249891712,0,0,0,0,0]
[]
[null,null,null,null,"DSCR sizing",null,{"$f":"Inputs!G87","v":"DSCRx"},null,{"$f":"Inputs!I87","v":1.2}]
[]
[null,null,null,null,"Total debt service including buffer",null,{"$f":"CONCATENATE(Inputs!$I$9,\"m nominal prices\")","v":"£m nominal prices"},null,null,null,{"$f":"K146*$I$148","v":0},{"$f":"L146*$I$148","v":0},0,0,0,0,0,0,0,0,0,9.1478790640423124,15.049837335386757,16.379351277560044,16.670578023713603,17.513305581625648,17.822630618899641,17.994716413222136,16.484869349951314,18.592978585580646,20.255351773158271,20.383440428131504,21.049133098229003,20.604641115111967,21.940840575475587,21.252692093355083,18.850953182241806,18.598230418878764,21.272614248322373,21.245180189791828,21.954064883196025,21.568039061102787,22.736542773425946,22.449373689425176,6.5692341899870055,0,0,0,0,0]
[null,null,null,null,"Total debt service including buffer",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K150/Inputs!K$32","v":0},{"$f":"L150/Inputs!L$32","v":0},{"$f":"M150/Inputs!M$32","v":0},{"$f":"N150/Inputs!N$32","v":0},{"$f":"O150/Inputs!O$32","v":0},{"$f":"P150/Inputs!P$32","v":0},{"$f":"Q150/Inputs!Q$32","v":0},{"$f":"R150/Inputs!R$32","v":0},{"$f":"S150/Inputs!S$32","v":0},{"$f":"T150/Inputs!T$32","v":0},{"$f":"U150/Inputs!U$32","v":0},{"$f":"V150/Inputs!V$32","v":7.7805619871937317},{"$f":"W150/Inputs!W$32","v":12.27499534039903},{"$f":"X150/Inputs!X$32","v":12.811064111114588},{"$f":"Y150/Inputs!Y$32","v":12.50368843669926},{"$f":"Z150/Inputs!Z$32","v":12.596636236704677},{"$f":"AA150/Inputs!AA$32","v":12.292982016438911},{"$f":"AB150/Inputs!AB$32","v":11.90225976187385},{"$f":"AC150/Inputs!AC$32","v":10.456080172111195},{"$f":"AD150/Inputs!AD$32","v":11.309185863182378},{"$f":"AE150/Inputs!AE$32","v":11.814657602671732},{"$f":"AF150/Inputs!AF$32","v":11.401390378809193},{"$f":"AG150/Inputs!AG$32","v":11.290508948727297},{"$f":"AH150/Inputs!AH$32","v":10.598473959233882},{"$f":"AI150/Inputs!AI$32","v":10.82257294974503},{"$f":"AJ150/Inputs!AJ$32","v":10.052872809128164},{"$f":"AK150/Inputs!AK$32","v":8.5508350723061177},{"$f":"AL150/Inputs!AL$32","v":8.0899496109266558},{"$f":"AM150/Inputs!AM$32","v":8.8734812274865984},{"$f":"AN150/Inputs!AN$32","v":8.4983099469515366},{"$f":"AO150/Inputs!AO$32","v":8.421434370272177},{"$f":"AP150/Inputs!AP$32","v":7.9337911517799347},{"$f":"AQ150/Inputs!AQ$32","v":8.0203534630941551},{"$f":"AR150/Inputs!AR$32","v":7.5940296209866389},{"$f":"AS150/Inputs!AS$32","v":2.1309918051803991},{"$f":"AT150/Inputs!AT$32","v":0},{"$f":"AU150/Inputs!AU$32","v":0},{"$f":"AV150/Inputs!AV$32","v":0},{"$f":"AW150/Inputs!AW$32","v":0},{"$f":"AX150/Inputs!AX$32","v":0}]
[]
[null,null,"DSRA calculation"]
[]
[null,null,null,null,"DSRA pre-funding ",null,null,null,null,null,{"$f":"Inputs!$I$100*Finance!K12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!L12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!M12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!N12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!O12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!P12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!Q12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!R12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!S12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!T12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!U12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!V12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!W12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!X12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!Y12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!Z12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AA12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AB12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AC12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AD12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AE12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AF12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AG12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AH12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AI12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AJ12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AK12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AL12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AM12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AN12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AO12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AP12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AQ12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AR12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AS12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AT12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AU12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AV12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AW12*(Inputs!$I$127=2)","v":0},{"$f":"Inputs!$I$100*Finance!AX12*(Inputs!$I$127=2)","v":0}]
[]
[null,"End of sheet"]

{"sheet":"Op Rav","index":6,"n_rows":43,"n_cols":35,"rows_kept":43,"cut":false,"hidden":false,"merged":[]}
["Op RAV",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"RAV"]
[]
[null,null,"Operational"]
[]
[null,null,null,null,"Opening operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"J15","v":0},218.13628063393188,209.04726894085138,199.95825724777089,190.86924555469039,181.7802338616099,172.69122216852941,165.34829456448438,156.16227819979079,146.9762618350972,137.79024547040362,128.60422910571003,119.41821274101646,110.23219637632289,101.04618001162932,93.606247735971195,85.99170705140952,76.43707293458624,66.88243881776296,57.32780470093968,47.7731705841164,38.21853646729312,28.66390235046984,21.291873344940871,10.645936672470436]
[null,null,null,null,"Transfers of transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"-SUM(Finance!K49:AX49)","v":10.3025497520823}]
[null,null,null,null,"Transfers of pre-operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"-SUM('Pre Op RAV'!K25:AX25)","v":216.92274257493006}]
[null,null,null,null,"Opening operational RAV (after transfers)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K9:K11)","v":227.22529232701237},{"$f":"SUM(L9:L11)","v":218.13628063393188},{"$f":"SUM(M9:M11)","v":209.04726894085138},199.95825724777089,190.86924555469039,181.7802338616099,172.69122216852941,165.34829456448438,156.16227819979079,146.9762618350972,137.79024547040362,128.60422910571003,119.41821274101646,110.23219637632289,101.04618001162932,93.606247735971195,85.99170705140952,76.43707293458624,66.88243881776296,57.32780470093968,47.7731705841164,38.21853646729312,28.66390235046984,21.291873344940871,10.645936672470436]
[null,null,null,null,"Replacement Capex",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K59","v":0},{"$f":"Inputs!L59","v":0},{"$f":"Inputs!M59","v":0},{"$f":"Inputs!N59","v":0},{"$f":"Inputs!O59","v":0},{"$f":"Inputs!P59","v":0},{"$f":"Inputs!Q59","v":1.7460840890354494},{"$f":"Inputs!R59","v":0},{"$f":"Inputs!S59","v":0},{"$f":"Inputs!T59","v":0},{"$f":"Inputs!U59","v":0},{"$f":"Inputs!V59","v":0},{"$f":"Inputs!W59","v":0},{"$f":"Inputs!X59","v":0},{"$f":"Inputs!Y59","v":1.7460840890354494},{"$f":"Inputs!Z59","v":1.7460840890354494},{"$f":"Inputs!AA59","v":0},{"$f":"Inputs!AB59","v":0},{"$f":"Inputs!AC59","v":0},{"$f":"Inputs!AD59","v":0},{"$f":"Inputs!AE59","v":0},{"$f":"Inputs!AF59","v":0},{"$f":"Inputs!AG59","v":2.1826051112943117},{"$f":"Inputs!AH59","v":0},{"$f":"Inputs!AI59","v":0}]
[null,null,null,null,"Depreciation (negative)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":" - K25","v":-9.0890116930804954},{"$f":" - L25","v":-9.0890116930804954},{"$f":" - M25","v":-9.0890116930804954},-9.0890116930804954,-9.0890116930804954,-9.0890116930804954,-9.0890116930804954,-9.1860163646935771,-9.1860163646935753,-9.1860163646935753,-9.1860163646935753,-9.1860163646935735,-9.1860163646935735,-9.1860163646935735,-9.1860163646935735,-9.3606247735971202,-9.55463411682328,-9.55463411682328,-9.55463411682328,-9.55463411682328,-9.55463411682328,-9.55463411682328,-9.55463411682328,-10.645936672470436,-10.645936672470436]
[null,null,null,null,"Closing operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K12:K14)","v":218.13628063393188},209.04726894085138,199.95825724777089,190.86924555469039,181.7802338616099,172.69122216852941,165.34829456448438,156.16227819979079,146.9762618350972,137.79024547040362,128.60422910571003,119.41821274101646,110.23219637632289,101.04618001162932,93.606247735971195,85.99170705140952,76.43707293458624,66.88243881776296,57.32780470093968,47.7731705841164,38.21853646729312,28.66390235046984,21.291873344940871,10.645936672470436,0]
[]
[null,null,null,null,"Average operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"AVERAGE(K12, K15)","v":222.68078648047214},{"$f":"AVERAGE(L12, L15)","v":213.59177478739161},204.50276309431115,195.41375140123063,186.32473970815016,177.23572801506964,169.01975836650689,160.75528638213757,151.56927001744401,142.3832536527504,133.19723728805684,124.01122092336325,114.82520455866967,105.63918819397611,97.326213873800256,89.798977393690365,{"$f":"AVERAGE(AA12, AA15)","v":81.21438999299788},71.6597558761746,62.10512175935132,52.55048764252804,42.99585352570476,33.44121940888148,24.977887847705354,15.968905008705654,5.3229683362352178]
[]
[null,"Operational RAV depreciation"]
[]
[null,null,null,null,"Number of operational years",null,"full years",null,{"$f":"Inputs!I155","v":25}]
[null,null,null,null,"Years remaining until end of operational period",null,"full years",null,null,null,{"$f":"I21","v":25},{"$f":"+K22-1","v":24},{"$f":"+L22-1","v":23},22,21,20,19,18,17,16,15,14,13,12,11,10,9,8,7,6,5,4,3,2,1]
[null,null,null,null,"Year is before end of operational period",null,"flag",null,null,null,{"$f":"K22 > 0","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"IF(K23, IF(K22=1,SUM(K12:K13),K12 / K22), 0)","v":9.0890116930804954},{"$f":"IF(L23, IF(L22=1,SUM(L12:L13),L12 / L22), 0)","v":9.0890116930804954},9.0890116930804954,9.0890116930804954,9.0890116930804954,9.0890116930804954,9.0890116930804954,9.1860163646935771,9.1860163646935753,9.1860163646935753,9.1860163646935753,9.1860163646935735,9.1860163646935735,9.1860163646935735,9.1860163646935735,9.3606247735971202,9.55463411682328,9.55463411682328,9.55463411682328,9.55463411682328,9.55463411682328,9.55463411682328,9.55463411682328,10.645936672470436,10.645936672470436]
[]
[null,null,null,null,"Depreciation equal to additions",null,"check",null,{"$f":"IF(ABS(SUM('Pre Op RAV'!K20:AX23,Finance!K43:AX46,Finance!K48:AX48,K13:AI13)-SUM(K25:AI25))<0.00000001,\"TRUE\",\"FALSE\")","v":"TRUE"}]
[]
[null,"Operational RAV return"]
[]
[null,null,null,null,"Cap return rate",null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"Inputs!I68","v":8.1000000000000003E-2}]
[null,null,null,null,"Floor return rate",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I69","v":-8.3999999999999995E-3}]
[]
[null,null,null,null,"Opening operational RAV (after transfers)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K12","v":227.22529232701237},218.13628063393188,209.04726894085138,199.95825724777089,190.86924555469039,181.7802338616099,172.69122216852941,165.34829456448438,156.16227819979079,146.9762618350972,137.79024547040362,128.60422910571003,119.41821274101646,110.23219637632289,101.04618001162932,93.606247735971195,85.99170705140952,76.43707293458624,66.88243881776296,57.32780470093968,47.7731705841164,38.21853646729312,28.66390235046984,21.291873344940871,10.645936672470436]
[null,null,null,null,"Closing operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K15","v":218.13628063393188},209.04726894085138,199.95825724777089,190.86924555469039,181.7802338616099,172.69122216852941,165.34829456448438,156.16227819979079,146.9762618350972,137.79024547040362,128.60422910571003,119.41821274101646,110.23219637632289,101.04618001162932,93.606247735971195,85.99170705140952,76.43707293458624,66.88243881776296,57.32780470093968,47.7731705841164,38.21853646729312,28.66390235046984,21.291873344940871,10.645936672470436,0]
[]
[null,null,null,null,"NPV neutral return base  (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"0.5 * K$34 + 0.5 * K$35 / (1 + $I31)","v":214.50824312647188},{"$f":"0.5 * L$34 + 0.5 * L$35 / (1 + $I31)","v":205.75975407314144},197.01126501981093,188.26277596648043,179.51428691314996,170.76579785981949,162.82493326950262,154.9046182349669,146.06275882010686,137.22089940524685,128.37903999038684,119.53718057552683,110.69532116066682,101.85346174580684,93.819226793960439,86.577271440330435,78.350651367789055,69.15398457911688,59.957317790444705,50.760651001772523,41.563984213100348,32.367317424428173,24.180181214523017,15.570051692114486,5.3229683362352178]
[null,null,null,null,"NPV neutral return base (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"0.5 * K$34 + 0.5 * K$35 / (1 + $I32)","v":223.60471989985746},214.47721098096923,205.34970206208104,196.22219314319284,187.09468422430461,177.96717530541639,169.72010410790546,161.4167240267918,152.19179956535385,142.9668751039159,133.74195064247795,124.51702618103999,115.29210171960206,106.06717725816412,97.722690518103491,90.163202050422825,81.53814524342674,71.943041720299846,62.347938197172965,52.752834674046085,43.15773115091919,33.562627627792303,25.068071256387032,16.013996713046492,5.3229683362352178]
[]
[null,null,null,null,"Return (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K37 * $I31","v":17.375167693244222},16.666540079924456,15.957912466604686,15.249284853284916,14.540657239965148,13.832029626645379,13.188819594829713,12.54727407703232,11.831083464428657,11.114892851824996,10.398702239221334,9.6825116266176732,8.9663210140140137,8.2501304014103543,7.5993573703107957,7.012758986666765,6.3464027607909133,5.6014727509084672,4.8565427410260211,4.1116127311435742,3.3666827212611281,2.621752711378682,1.9585946783763644,1.2611741870612734,0.43116043523505265]
[null,null,null,null,"Return (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K38 * $I32","v":-1.8782796471588026},-1.8016085722401414,-1.7249374973214806,-1.6482664224028198,-1.5715953474841586,-1.4949242725654976,-1.4256488745064058,-1.3559004818250511,-1.2784111163489722,-1.2009217508728935,-1.1234323853968147,-1.0459430199207358,-0.96845365444465725,-0.8909642889685786,-0.82087060035206927,-0.75737089722355166,-0.68492042004478459,-0.60432155045051872,-0.52372268085625284,-0.44312381126198708,-0.3625249416677212,-0.28192607207345532,-0.21057179855365105,-0.13451757238959053,-4.4712934024375824E-2]
[]
[null,"End of sheet"]

{"sheet":"Allowances Cap","index":7,"n_rows":36,"n_cols":35,"rows_kept":36,"cut":false,"hidden":false,"merged":[]}
["Allowances Cap",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[null,null,null,null,"Year",null,null,null,null,null,1,{"$f":"+K4+1","v":2},{"$f":"+L4+1","v":3},4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25]
[]
[" ","Unprofiled allowances except tax (cap)"]
[]
[null,null,null,null,"Controllable Opex",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K61","v":4.8270755550501754},{"$f":"Inputs!L61","v":4.8270755550501754},{"$f":"Inputs!M61","v":4.8270755550501754},{"$f":"Inputs!N61","v":4.8270755550501754},{"$f":"Inputs!O61","v":4.8270755550501754},{"$f":"Inputs!P61","v":4.8270755550501754},{"$f":"Inputs!Q61","v":4.8270755550501754},{"$f":"Inputs!R61","v":4.8270755550501754},{"$f":"Inputs!S61","v":4.8270755550501754},{"$f":"Inputs!T61","v":4.8270755550501754},{"$f":"Inputs!U61","v":4.8270755550501754},{"$f":"Inputs!V61","v":4.8270755550501754},{"$f":"Inputs!W61","v":4.8270755550501754},{"$f":"Inputs!X61","v":4.8270755550501754},{"$f":"Inputs!Y61","v":4.8270755550501754},{"$f":"Inputs!Z61","v":4.8270755550501754},{"$f":"Inputs!AA61","v":4.8270755550501754},{"$f":"Inputs!AB61","v":4.8270755550501754},{"$f":"Inputs!AC61","v":4.8270755550501754},{"$f":"Inputs!AD61","v":4.8270755550501754},{"$f":"Inputs!AE61","v":4.8270755550501754},{"$f":"Inputs!AF61","v":4.8270755550501754},{"$f":"Inputs!AG61","v":4.8270755550501754},{"$f":"Inputs!AH61","v":4.8270755550501754},{"$f":"Inputs!AI61","v":4.8270755550501754}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K62","v":1.2318693492907298},{"$f":"Inputs!L62","v":1.2318693492907298},{"$f":"Inputs!M62","v":1.2318693492907298},{"$f":"Inputs!N62","v":1.2318693492907298},{"$f":"Inputs!O62","v":1.2318693492907298},{"$f":"Inputs!P62","v":1.2318693492907298},{"$f":"Inputs!Q62","v":1.2318693492907298},{"$f":"Inputs!R62","v":1.2318693492907298},{"$f":"Inputs!S62","v":1.2318693492907298},{"$f":"Inputs!T62","v":1.2318693492907298},{"$f":"Inputs!U62","v":1.2318693492907298},{"$f":"Inputs!V62","v":1.2318693492907298},{"$f":"Inputs!W62","v":1.2318693492907298},{"$f":"Inputs!X62","v":1.2318693492907298},{"$f":"Inputs!Y62","v":1.2318693492907298},{"$f":"Inputs!Z62","v":1.2318693492907298},{"$f":"Inputs!AA62","v":1.2318693492907298},{"$f":"Inputs!AB62","v":1.2318693492907298},{"$f":"Inputs!AC62","v":1.2318693492907298},{"$f":"Inputs!AD62","v":1.2318693492907298},{"$f":"Inputs!AE62","v":1.2318693492907298},{"$f":"Inputs!AF62","v":1.2318693492907298},{"$f":"Inputs!AG62","v":1.2318693492907298},{"$f":"Inputs!AH62","v":1.2318693492907298},{"$f":"Inputs!AI62","v":1.2318693492907298}]
[null,null,null,null,"Decommissioning baseline",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K60","v":0.15333428092219348},{"$f":"Inputs!L60","v":0.15333428092219348},{"$f":"Inputs!M60","v":0.15333428092219348},{"$f":"Inputs!N60","v":0.15333428092219348},{"$f":"Inputs!O60","v":0.15333428092219348},{"$f":"Inputs!P60","v":0.15333428092219348},{"$f":"Inputs!Q60","v":0.15333428092219348},{"$f":"Inputs!R60","v":0.15333428092219348},{"$f":"Inputs!S60","v":0.15333428092219348},{"$f":"Inputs!T60","v":0.15333428092219348},{"$f":"Inputs!U60","v":0.15333428092219348},{"$f":"Inputs!V60","v":0.15333428092219348},{"$f":"Inputs!W60","v":0.15333428092219348},{"$f":"Inputs!X60","v":0.15333428092219348},{"$f":"Inputs!Y60","v":0.15333428092219348},{"$f":"Inputs!Z60","v":0.15333428092219348},{"$f":"Inputs!AA60","v":0.15333428092219348},{"$f":"Inputs!AB60","v":0.15333428092219348},{"$f":"Inputs!AC60","v":0.15333428092219348},{"$f":"Inputs!AD60","v":0.15333428092219348},{"$f":"Inputs!AE60","v":0.15333428092219348},{"$f":"Inputs!AF60","v":0.15333428092219348},{"$f":"Inputs!AG60","v":0.15333428092219348},{"$f":"Inputs!AH60","v":0.15333428092219348},{"$f":"Inputs!AI60","v":0.15333428092219348}]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Op Rav'!K25","v":9.0890116930804954},{"$f":"'Op Rav'!L25","v":9.0890116930804954},{"$f":"'Op Rav'!M25","v":9.0890116930804954},{"$f":"'Op Rav'!N25","v":9.0890116930804954},{"$f":"'Op Rav'!O25","v":9.0890116930804954},{"$f":"'Op Rav'!P25","v":9.0890116930804954},{"$f":"'Op Rav'!Q25","v":9.0890116930804954},{"$f":"'Op Rav'!R25","v":9.1860163646935771},{"$f":"'Op Rav'!S25","v":9.1860163646935753},{"$f":"'Op Rav'!T25","v":9.1860163646935753},{"$f":"'Op Rav'!U25","v":9.1860163646935753},{"$f":"'Op Rav'!V25","v":9.1860163646935735},{"$f":"'Op Rav'!W25","v":9.1860163646935735},{"$f":"'Op Rav'!X25","v":9.1860163646935735},{"$f":"'Op Rav'!Y25","v":9.1860163646935735},{"$f":"'Op Rav'!Z25","v":9.3606247735971202},{"$f":"'Op Rav'!AA25","v":9.55463411682328},{"$f":"'Op Rav'!AB25","v":9.55463411682328},{"$f":"'Op Rav'!AC25","v":9.55463411682328},{"$f":"'Op Rav'!AD25","v":9.55463411682328},{"$f":"'Op Rav'!AE25","v":9.55463411682328},{"$f":"'Op Rav'!AF25","v":9.55463411682328},{"$f":"'Op Rav'!AG25","v":9.55463411682328},{"$f":"'Op Rav'!AH25","v":10.645936672470436},{"$f":"'Op Rav'!AI25","v":10.645936672470436}]
[null,null,null,null,"Return (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Op Rav'!K40","v":17.375167693244222},{"$f":"'Op Rav'!L40","v":16.666540079924456},{"$f":"'Op Rav'!M40","v":15.957912466604686},{"$f":"'Op Rav'!N40","v":15.249284853284916},{"$f":"'Op Rav'!O40","v":14.540657239965148},{"$f":"'Op Rav'!P40","v":13.832029626645379},{"$f":"'Op Rav'!Q40","v":13.188819594829713},{"$f":"'Op Rav'!R40","v":12.54727407703232},{"$f":"'Op Rav'!S40","v":11.831083464428657},{"$f":"'Op Rav'!T40","v":11.114892851824996},{"$f":"'Op Rav'!U40","v":10.398702239221334},{"$f":"'Op Rav'!V40","v":9.6825116266176732},{"$f":"'Op Rav'!W40","v":8.9663210140140137},{"$f":"'Op Rav'!X40","v":8.2501304014103543},{"$f":"'Op Rav'!Y40","v":7.5993573703107957},{"$f":"'Op Rav'!Z40","v":7.012758986666765},{"$f":"'Op Rav'!AA40","v":6.3464027607909133},{"$f":"'Op Rav'!AB40","v":5.6014727509084672},{"$f":"'Op Rav'!AC40","v":4.8565427410260211},{"$f":"'Op Rav'!AD40","v":4.1116127311435742},{"$f":"'Op Rav'!AE40","v":3.3666827212611281},{"$f":"'Op Rav'!AF40","v":2.621752711378682},{"$f":"'Op Rav'!AG40","v":1.9585946783763644},{"$f":"'Op Rav'!AH40","v":1.2611741870612734},{"$f":"'Op Rav'!AI40","v":0.43116043523505265}]
[null,null,null,null,"Unprofiled allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K8:K12)","v":32.676458571587816},{"$f":"SUM(L8:L12)","v":31.967830958268049},31.259203344948279,30.550575731628509,29.841948118308743,29.133320504988973,28.490110473173306,27.945569626988995,27.22937901438533,26.513188401781669,25.796997789178008,25.080807176574346,24.364616563970685,23.648425951367024,22.997652920267466,22.585662945526984,22.113316062877292,21.368386052994843,20.623456043112398,19.878526033229953,19.133596023347508,18.388666013465059,17.725507980462741,18.119390044794805,17.289376292968587]
[]
[null,"Profiled allowances except tax (cap)"]
[]
[null,null,"Annuity parameters"]
[]
[null,null,null,null,"Cap return rate",null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"Inputs!I68","v":8.1000000000000003E-2}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G155","v":"full years"},null,{"$f":"Inputs!I155","v":25}]
[null,null,null,null,"Annuity factor (cap)",null,"scalar",null,{"$f":"I19 / (1 - (1 + I19)^(-I20))","v":9.4480276733656082E-2}]
[]
[null,null,null,null,"Year is within operational period",null,"flag",null,null,null,{"$f":"AND(K4 > 0, K4<= $I20)","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[null,null,null,null,"Discount factor to start of operational period (cap)",null,"scalar",null,null,null,{"$f":"(1 + $I19) ^ - K4","v":0.92506938020351526},0.85575335819011589,0.79163122866800739,0.73231381005366081,0.67744108238081491,0.62668000220241893,0.57972248122332926,0.53628351639530925,0.49609946012517048,0.45892642009728996,0.42453877899841808,0.39272782516042376,0.36330048580982777,0.33607815523573337,0.31089561076386063,0.28760000995731788,0.26604996295774092,0.24611467433648557,0.22767314924744272,0.21061345906331425,0.19483206203821857,0.18023317487346768,0.16672819137231054,0.15423514465523638,0.14267820967181905]
[]
[null,null,"Allowances except tax"]
[]
[null,null,null,null,"Discounted unprofiled allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K13 * K$24","v":30.227991278064582},{"$f":"L13 * L$24","v":27.356578696591832},24.745761551144493,22.372608513361779,20.216161633619198,18.257269358230268,16.516357533834789,14.986748347231609,13.508480228580209,12.16760263859465,10.951825943242522,9.8499308557239917,8.8516770342607263,7.9477193679642726,{"$f":"Y13 * Y$24","v":7.1498693507818372},{"$f":"Z13 * Z$24","v":6.4956368880261861},5.8832469194013211,5.2590733745291258,4.6954071857016038,4.186685128938703,3.7278379674350539,3.31424765729464,2.9553418867380095,2.7946467446235768,2.4668172558231496]
[null,null,null,null,"NPV of allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K28:AI28)","v":286.88552333973803}]
[]
[null,null,null,null,"Annuity factor (cap)",null,{"$f":"G$21","v":"scalar"},null,{"$f":"I$21","v":9.4480276733656082E-2}]
[]
[null,null,null,null,"Annuity of allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I29 * I31","v":27.105023636018199}]
[null,null,null,null,"Annuitised allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K$23 * $I33","v":27.105023636018199},27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,{"$f":"X$23 * $I33","v":27.105023636018199},{"$f":"Y$23 * $I33","v":27.105023636018199},27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199,27.105023636018199]
[]
[null,"End of sheet"]

{"sheet":"Allowances Floor","index":8,"n_rows":78,"n_cols":35,"rows_kept":78,"cut":false,"hidden":false,"merged":[]}
["Allowances Floor",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[null,null,null,null,"Year",null,null,null,null,null,1,{"$f":"+K4+1","v":2},{"$f":"+L4+1","v":3},4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25]
[]
[null,"Unprofiled allowances except tax (notional floor)"]
[]
[null,null,null,null,"Controllable Opex",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K61","v":4.8270755550501754},{"$f":"Inputs!L61","v":4.8270755550501754},{"$f":"Inputs!M61","v":4.8270755550501754},{"$f":"Inputs!N61","v":4.8270755550501754},{"$f":"Inputs!O61","v":4.8270755550501754},{"$f":"Inputs!P61","v":4.8270755550501754},{"$f":"Inputs!Q61","v":4.8270755550501754},{"$f":"Inputs!R61","v":4.8270755550501754},{"$f":"Inputs!S61","v":4.8270755550501754},{"$f":"Inputs!T61","v":4.8270755550501754},{"$f":"Inputs!U61","v":4.8270755550501754},{"$f":"Inputs!V61","v":4.8270755550501754},{"$f":"Inputs!W61","v":4.8270755550501754},{"$f":"Inputs!X61","v":4.8270755550501754},{"$f":"Inputs!Y61","v":4.8270755550501754},{"$f":"Inputs!Z61","v":4.8270755550501754},{"$f":"Inputs!AA61","v":4.8270755550501754},{"$f":"Inputs!AB61","v":4.8270755550501754},{"$f":"Inputs!AC61","v":4.8270755550501754},{"$f":"Inputs!AD61","v":4.8270755550501754},{"$f":"Inputs!AE61","v":4.8270755550501754},{"$f":"Inputs!AF61","v":4.8270755550501754},{"$f":"Inputs!AG61","v":4.8270755550501754},{"$f":"Inputs!AH61","v":4.8270755550501754},{"$f":"Inputs!AI61","v":4.8270755550501754}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K62","v":1.2318693492907298},{"$f":"Inputs!L62","v":1.2318693492907298},{"$f":"Inputs!M62","v":1.2318693492907298},{"$f":"Inputs!N62","v":1.2318693492907298},{"$f":"Inputs!O62","v":1.2318693492907298},{"$f":"Inputs!P62","v":1.2318693492907298},{"$f":"Inputs!Q62","v":1.2318693492907298},{"$f":"Inputs!R62","v":1.2318693492907298},{"$f":"Inputs!S62","v":1.2318693492907298},{"$f":"Inputs!T62","v":1.2318693492907298},{"$f":"Inputs!U62","v":1.2318693492907298},{"$f":"Inputs!V62","v":1.2318693492907298},{"$f":"Inputs!W62","v":1.2318693492907298},{"$f":"Inputs!X62","v":1.2318693492907298},{"$f":"Inputs!Y62","v":1.2318693492907298},{"$f":"Inputs!Z62","v":1.2318693492907298},{"$f":"Inputs!AA62","v":1.2318693492907298},{"$f":"Inputs!AB62","v":1.2318693492907298},{"$f":"Inputs!AC62","v":1.2318693492907298},{"$f":"Inputs!AD62","v":1.2318693492907298},{"$f":"Inputs!AE62","v":1.2318693492907298},{"$f":"Inputs!AF62","v":1.2318693492907298},{"$f":"Inputs!AG62","v":1.2318693492907298},{"$f":"Inputs!AH62","v":1.2318693492907298},{"$f":"Inputs!AI62","v":1.2318693492907298}]
[null,null,null,null,"Decommissioning baseline",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K60","v":0.15333428092219348},{"$f":"Inputs!L60","v":0.15333428092219348},{"$f":"Inputs!M60","v":0.15333428092219348},{"$f":"Inputs!N60","v":0.15333428092219348},{"$f":"Inputs!O60","v":0.15333428092219348},{"$f":"Inputs!P60","v":0.15333428092219348},{"$f":"Inputs!Q60","v":0.15333428092219348},{"$f":"Inputs!R60","v":0.15333428092219348},{"$f":"Inputs!S60","v":0.15333428092219348},{"$f":"Inputs!T60","v":0.15333428092219348},{"$f":"Inputs!U60","v":0.15333428092219348},{"$f":"Inputs!V60","v":0.15333428092219348},{"$f":"Inputs!W60","v":0.15333428092219348},{"$f":"Inputs!X60","v":0.15333428092219348},{"$f":"Inputs!Y60","v":0.15333428092219348},{"$f":"Inputs!Z60","v":0.15333428092219348},{"$f":"Inputs!AA60","v":0.15333428092219348},{"$f":"Inputs!AB60","v":0.15333428092219348},{"$f":"Inputs!AC60","v":0.15333428092219348},{"$f":"Inputs!AD60","v":0.15333428092219348},{"$f":"Inputs!AE60","v":0.15333428092219348},{"$f":"Inputs!AF60","v":0.15333428092219348},{"$f":"Inputs!AG60","v":0.15333428092219348},{"$f":"Inputs!AH60","v":0.15333428092219348},{"$f":"Inputs!AI60","v":0.15333428092219348}]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Op Rav'!K25","v":9.0890116930804954},{"$f":"'Op Rav'!L25","v":9.0890116930804954},{"$f":"'Op Rav'!M25","v":9.0890116930804954},{"$f":"'Op Rav'!N25","v":9.0890116930804954},{"$f":"'Op Rav'!O25","v":9.0890116930804954},{"$f":"'Op Rav'!P25","v":9.0890116930804954},{"$f":"'Op Rav'!Q25","v":9.0890116930804954},{"$f":"'Op Rav'!R25","v":9.1860163646935771},{"$f":"'Op Rav'!S25","v":9.1860163646935753},{"$f":"'Op Rav'!T25","v":9.1860163646935753},{"$f":"'Op Rav'!U25","v":9.1860163646935753},{"$f":"'Op Rav'!V25","v":9.1860163646935735},{"$f":"'Op Rav'!W25","v":9.1860163646935735},{"$f":"'Op Rav'!X25","v":9.1860163646935735},{"$f":"'Op Rav'!Y25","v":9.1860163646935735},{"$f":"'Op Rav'!Z25","v":9.3606247735971202},{"$f":"'Op Rav'!AA25","v":9.55463411682328},{"$f":"'Op Rav'!AB25","v":9.55463411682328},{"$f":"'Op Rav'!AC25","v":9.55463411682328},{"$f":"'Op Rav'!AD25","v":9.55463411682328},{"$f":"'Op Rav'!AE25","v":9.55463411682328},{"$f":"'Op Rav'!AF25","v":9.55463411682328},{"$f":"'Op Rav'!AG25","v":9.55463411682328},{"$f":"'Op Rav'!AH25","v":10.645936672470436},{"$f":"'Op Rav'!AI25","v":10.645936672470436}]
[null,null,null,null,"Return (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Op Rav'!K41","v":-1.8782796471588026},{"$f":"'Op Rav'!L41","v":-1.8016085722401414},{"$f":"'Op Rav'!M41","v":-1.7249374973214806},{"$f":"'Op Rav'!N41","v":-1.6482664224028198},{"$f":"'Op Rav'!O41","v":-1.5715953474841586},{"$f":"'Op Rav'!P41","v":-1.4949242725654976},{"$f":"'Op Rav'!Q41","v":-1.4256488745064058},{"$f":"'Op Rav'!R41","v":-1.3559004818250511},{"$f":"'Op Rav'!S41","v":-1.2784111163489722},{"$f":"'Op Rav'!T41","v":-1.2009217508728935},{"$f":"'Op Rav'!U41","v":-1.1234323853968147},{"$f":"'Op Rav'!V41","v":-1.0459430199207358},{"$f":"'Op Rav'!W41","v":-0.96845365444465725},{"$f":"'Op Rav'!X41","v":-0.8909642889685786},{"$f":"'Op Rav'!Y41","v":-0.82087060035206927},{"$f":"'Op Rav'!Z41","v":-0.75737089722355166},{"$f":"'Op Rav'!AA41","v":-0.68492042004478459},{"$f":"'Op Rav'!AB41","v":-0.60432155045051872},{"$f":"'Op Rav'!AC41","v":-0.52372268085625284},{"$f":"'Op Rav'!AD41","v":-0.44312381126198708},{"$f":"'Op Rav'!AE41","v":-0.3625249416677212},{"$f":"'Op Rav'!AF41","v":-0.28192607207345532},{"$f":"'Op Rav'!AG41","v":-0.21057179855365105},{"$f":"'Op Rav'!AH41","v":-0.13451757238959053},{"$f":"'Op Rav'!AI41","v":-4.4712934024375824E-2}]
[null,null,null,null,"Unprofiled allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K8:K12)","v":13.423011231184791},13.499682306103452,13.576353381022113,13.653024455940773,13.729695530859434,13.806366605778095,13.875642003837187,14.042395068131624,14.119884433607702,14.197373799083779,14.274863164559859,14.352352530035935,14.429841895512014,14.507331260988092,14.577424949604602,14.815533061636666,15.081992882041593,15.162591751635858,15.243190621230125,15.323789490824391,15.404388360418658,15.484987230012923,15.556341503532726,16.723698285343943,16.813502923709159]
[]
[null,"Profiled allowances except tax (notional floor)"]
[]
[null,null,"Annuity parameters"]
[]
[null,null,null,null,"Floor return rate",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I69","v":-8.3999999999999995E-3}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G155","v":"full years"},null,{"$f":"Inputs!I155","v":25}]
[null,null,null,null,"Annuity factor (floor)",null,"scalar",null,{"$f":"I19 / (1 - (1 + I19)^(-I20))","v":3.5779275382147847E-2}]
[]
[null,null,null,null,"Year is within operational period",null,"flag",null,null,null,{"$f":"AND(K4 > 0, K4<= $I20)","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[null,null,null,null,"Discount factor to start of operational period (floor)",null,"scalar",null,null,null,{"$f":"(1 + $I19) ^ - K4","v":1.008471157724889},1.017014075962978,1.0256293626088926,1.0343176307068298,1.0430794984941811,1.0519155894455232,1.0608265323169859,1.0698129611909901,1.0788755155213696,1.0880148401788721,1.0972315854970471,1.1065264073185228,1.1158999670416729,1.1253529316676811,1.1348859738480044,1.1444997719322352,1.1541950100163727,1.1639723779915012,1.1738325715928815,1.1837762924494568,1.1938042481337805,1.2039171522123642,1.2141157242964542,1.2244006900932376,1.2347727814574803]
[]
[null,null,"Allowances except tax"]
[]
[null,null,null,null,"Discounted unprofiled allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K13 * K$24","v":13.536719676467115},{"$f":"L13 * L$24","v":13.729366926335565},13.924306664730793,14.121563907251065,14.321163928806659,14.523132266218052,14.719649190602517,15.022736250051649,15.233597597410672,15.446953384969843,15.662830742803409,15.881257081629574,16.102260095618409,{"$f":"X13 * X$24","v":16.325867765227148},16.543715110128215,16.956374210097653,17.407560925554858,17.648837977665913,17.89295364619905,18.139938709724046,18.389824264570354,18.642641728001983,18.887198831964628,20.476507721486218,20.760855771151835]
[null,null,null,null,"NPV of allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K28:AI28)","v":410.29781437466715}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"G$21","v":"scalar"},null,{"$f":"I$21","v":3.5779275382147847E-2}]
[]
[null,null,null,null,"Annuity of allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I29 * I31","v":14.680158489204596}]
[null,null,null,null,"Annuitised allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K$23 * $I33","v":14.680158489204596},14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,{"$f":"X$23 * $I33","v":14.680158489204596},14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596,14.680158489204596]
[]
[null,"Unprofiled allowances except tax (actual floor during debt tenor and tail period)"]
[]
[null,null,null,null,"Controllable Opex",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K61*K56","v":0},{"$f":"Inputs!L61*L56","v":0},{"$f":"Inputs!M61*M56","v":4.8270755550501754},{"$f":"Inputs!N61*N56","v":4.8270755550501754},{"$f":"Inputs!O61*O56","v":4.8270755550501754},{"$f":"Inputs!P61*P56","v":4.8270755550501754},{"$f":"Inputs!Q61*Q56","v":4.8270755550501754},{"$f":"Inputs!R61*R56","v":4.8270755550501754},{"$f":"Inputs!S61*S56","v":4.8270755550501754},{"$f":"Inputs!T61*T56","v":4.8270755550501754},{"$f":"Inputs!U61*U56","v":4.8270755550501754},{"$f":"Inputs!V61*V56","v":4.8270755550501754},{"$f":"Inputs!W61*W56","v":4.8270755550501754},{"$f":"Inputs!X61*X56","v":4.8270755550501754},{"$f":"Inputs!Y61*Y56","v":4.8270755550501754},{"$f":"Inputs!Z61*Z56","v":4.8270755550501754},{"$f":"Inputs!AA61*AA56","v":4.8270755550501754},{"$f":"Inputs!AB61*AB56","v":4.8270755550501754},{"$f":"Inputs!AC61*AC56","v":4.8270755550501754},{"$f":"Inputs!AD61*AD56","v":4.8270755550501754},{"$f":"Inputs!AE61*AE56","v":4.8270755550501754},{"$f":"Inputs!AF61*AF56","v":4.8270755550501754},{"$f":"Inputs!AG61*AG56","v":4.8270755550501754},{"$f":"Inputs!AH61*AH56","v":4.8270755550501754},{"$f":"Inputs!AI61*AI56","v":4.8270755550501754}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K62*K56","v":0},{"$f":"Inputs!L62*L56","v":0},{"$f":"Inputs!M62*M56","v":1.2318693492907298},{"$f":"Inputs!N62*N56","v":1.2318693492907298},{"$f":"Inputs!O62*O56","v":1.2318693492907298},{"$f":"Inputs!P62*P56","v":1.2318693492907298},{"$f":"Inputs!Q62*Q56","v":1.2318693492907298},{"$f":"Inputs!R62*R56","v":1.2318693492907298},{"$f":"Inputs!S62*S56","v":1.2318693492907298},{"$f":"Inputs!T62*T56","v":1.2318693492907298},{"$f":"Inputs!U62*U56","v":1.2318693492907298},{"$f":"Inputs!V62*V56","v":1.2318693492907298},{"$f":"Inputs!W62*W56","v":1.2318693492907298},{"$f":"Inputs!X62*X56","v":1.2318693492907298},{"$f":"Inputs!Y62*Y56","v":1.2318693492907298},{"$f":"Inputs!Z62*Z56","v":1.2318693492907298},{"$f":"Inputs!AA62*AA56","v":1.2318693492907298},{"$f":"Inputs!AB62*AB56","v":1.2318693492907298},{"$f":"Inputs!AC62*AC56","v":1.2318693492907298},{"$f":"Inputs!AD62*AD56","v":1.2318693492907298},{"$f":"Inputs!AE62*AE56","v":1.2318693492907298},{"$f":"Inputs!AF62*AF56","v":1.2318693492907298},{"$f":"Inputs!AG62*AG56","v":1.2318693492907298},{"$f":"Inputs!AH62*AH56","v":1.2318693492907298},{"$f":"Inputs!AI62*AI56","v":1.2318693492907298}]
[null,null,null,null,"Decommissioning baseline",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"Inputs!K60*K56","v":0},{"$f":"Inputs!L60*L56","v":0},{"$f":"Inputs!M60*M56","v":0.15333428092219348},{"$f":"Inputs!N60*N56","v":0.15333428092219348},{"$f":"Inputs!O60*O56","v":0.15333428092219348},{"$f":"Inputs!P60*P56","v":0.15333428092219348},{"$f":"Inputs!Q60*Q56","v":0.15333428092219348},{"$f":"Inputs!R60*R56","v":0.15333428092219348},{"$f":"Inputs!S60*S56","v":0.15333428092219348},{"$f":"Inputs!T60*T56","v":0.15333428092219348},{"$f":"Inputs!U60*U56","v":0.15333428092219348},{"$f":"Inputs!V60*V56","v":0.15333428092219348},{"$f":"Inputs!W60*W56","v":0.15333428092219348},{"$f":"Inputs!X60*X56","v":0.15333428092219348},{"$f":"Inputs!Y60*Y56","v":0.15333428092219348},{"$f":"Inputs!Z60*Z56","v":0.15333428092219348},{"$f":"Inputs!AA60*AA56","v":0.15333428092219348},{"$f":"Inputs!AB60*AB56","v":0.15333428092219348},{"$f":"Inputs!AC60*AC56","v":0.15333428092219348},{"$f":"Inputs!AD60*AD56","v":0.15333428092219348},{"$f":"Inputs!AE60*AE56","v":0.15333428092219348},{"$f":"Inputs!AF60*AF56","v":0.15333428092219348},{"$f":"Inputs!AG60*AG56","v":0.15333428092219348},{"$f":"Inputs!AH60*AH56","v":0.15333428092219348},{"$f":"Inputs!AI60*AI56","v":0.15333428092219348}]
[null,null,null,null,"Total debt service including buffer",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!K4,Finance!151:151)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!L4,Finance!151:151)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!M4,Finance!151:151)","v":7.7805619871937317},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!N4,Finance!151:151)","v":12.27499534039903},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!O4,Finance!151:151)","v":12.811064111114588},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!P4,Finance!151:151)","v":12.50368843669926},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Q4,Finance!151:151)","v":12.596636236704677},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!R4,Finance!151:151)","v":12.292982016438911},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!S4,Finance!151:151)","v":11.90225976187385},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!T4,Finance!151:151)","v":10.456080172111195},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!U4,Finance!151:151)","v":11.309185863182378},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!V4,Finance!151:151)","v":11.814657602671732},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!W4,Finance!151:151)","v":11.401390378809193},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!X4,Finance!151:151)","v":11.290508948727297},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Y4,Finance!151:151)","v":10.598473959233882},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Z4,Finance!151:151)","v":10.82257294974503},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AA4,Finance!151:151)","v":10.052872809128164},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AB4,Finance!151:151)","v":8.5508350723061177},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AC4,Finance!151:151)","v":8.0899496109266558},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AD4,Finance!151:151)","v":8.8734812274865984},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AE4,Finance!151:151)","v":8.4983099469515366},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AF4,Finance!151:151)","v":8.421434370272177},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AG4,Finance!151:151)","v":7.9337911517799347},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AH4,Finance!151:151)","v":8.0203534630941551},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AI4,Finance!151:151)","v":9.7250214261670376}]
[null,null,null,null,"Unprofiled allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"SUM(K38:K41)","v":0},0,13.99284117245683,18.48727452566213,19.023343296377686,18.715967621962356,18.808915421967775,18.505261201702009,18.11453894713695,16.668359357374293,17.521465048445478,18.026936787934829,17.613669564072289,17.502788133990393,16.810753144496978,17.03485213500813,16.26515199439126,14.763114257569216,14.302228796189754,15.085760412749696,14.710589132214634,14.633713555535275,14.146070337043032,14.232632648357253,15.937300611430135]
[]
[null,"Profiled allowances except tax (actual floor during debt tenor and tail period)"]
[]
[null,null,"Annuity parameters during debt tenor"]
[]
[null,null,null,null,"Actual cost of debt",null,"nominal %",null,null,null,{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!K4,Finance!125:125)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!L4,Finance!125:125)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!M4,Finance!125:125)","v":2.9215279504157976E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!N4,Finance!125:125)","v":2.9215279504157976E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!O4,Finance!125:125)","v":2.9215279504157976E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!P4,Finance!125:125)","v":2.9215279504157976E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Q4,Finance!125:125)","v":2.9215279504157976E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!R4,Finance!125:125)","v":2.9299978957709888E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!S4,Finance!125:125)","v":3.0215279504157977E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!T4,Finance!125:125)","v":3.0215279504157977E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!U4,Finance!125:125)","v":3.0215279504157977E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!V4,Finance!125:125)","v":3.0215279504157977E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!W4,Finance!125:125)","v":3.0299978957709889E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!X4,Finance!125:125)","v":3.1215279504157978E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Y4,Finance!125:125)","v":3.1215279504157978E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Z4,Finance!125:125)","v":3.1215279504157978E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AA4,Finance!125:125)","v":3.1215279504157978E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AB4,Finance!125:125)","v":3.129997895770989E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AC4,Finance!125:125)","v":3.2215279504157979E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AD4,Finance!125:125)","v":3.2215279504157979E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AE4,Finance!125:125)","v":3.2215279504157979E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AF4,Finance!125:125)","v":3.2215279504157979E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AG4,Finance!125:125)","v":3.2299978957709891E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AH4,Finance!125:125)","v":3.321527950415798E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AI4,Finance!125:125)","v":6.6430559008315959E-2}]
[null,null,null,null,"Actual cost of debt",null,"real %",null,null,null,{"$f":"IF(K48=0,0,(1+K48)/(1+Inputs!$I$179)-1)","v":0},{"$f":"IF(L48=0,0,(1+L48)/(1+Inputs!$I$179)-1)","v":0},{"$f":"IF(M48=0,0,(1+M48)/(1+Inputs!$I$179)-1)","v":-1.3027158127965066E-2},{"$f":"IF(N48=0,0,(1+N48)/(1+Inputs!$I$179)-1)","v":-1.3027158127965066E-2},{"$f":"IF(O48=0,0,(1+O48)/(1+Inputs!$I$179)-1)","v":-1.3027158127965066E-2},{"$f":"IF(P48=0,0,(1+P48)/(1+Inputs!$I$179)-1)","v":-1.3027158127965066E-2},{"$f":"IF(Q48=0,0,(1+Q48)/(1+Inputs!$I$179)-1)","v":-1.3027158127965066E-2},{"$f":"IF(R48=0,0,(1+R48)/(1+Inputs!$I$179)-1)","v":-1.2945935023292998E-2},{"$f":"IF(S48=0,0,(1+S48)/(1+Inputs!$I$179)-1)","v":-1.2068201472805962E-2},{"$f":"IF(T48=0,0,(1+T48)/(1+Inputs!$I$179)-1)","v":-1.2068201472805962E-2},{"$f":"IF(U48=0,0,(1+U48)/(1+Inputs!$I$179)-1)","v":-1.2068201472805962E-2},{"$f":"IF(V48=0,0,(1+V48)/(1+Inputs!$I$179)-1)","v":-1.2068201472805962E-2},{"$f":"IF(W48=0,0,(1+W48)/(1+Inputs!$I$179)-1)","v":-1.1986978368134005E-2},{"$f":"IF(X48=0,0,(1+X48)/(1+Inputs!$I$179)-1)","v":-1.1109244817646635E-2},{"$f":"IF(Y48=0,0,(1+Y48)/(1+Inputs!$I$179)-1)","v":-1.1109244817646635E-2},{"$f":"IF(Z48=0,0,(1+Z48)/(1+Inputs!$I$179)-1)","v":-1.1109244817646635E-2},{"$f":"IF(AA48=0,0,(1+AA48)/(1+Inputs!$I$179)-1)","v":-1.1109244817646635E-2},{"$f":"IF(AB48=0,0,(1+AB48)/(1+Inputs!$I$179)-1)","v":-1.1028021712974678E-2},{"$f":"IF(AC48=0,0,(1+AC48)/(1+Inputs!$I$179)-1)","v":-1.0150288162487531E-2},{"$f":"IF(AD48=0,0,(1+AD48)/(1+Inputs!$I$179)-1)","v":-1.0150288162487531E-2},{"$f":"IF(AE48=0,0,(1+AE48)/(1+Inputs!$I$179)-1)","v":-1.0150288162487531E-2},{"$f":"IF(AF48=0,0,(1+AF48)/(1+Inputs!$I$179)-1)","v":-1.0150288162487531E-2},{"$f":"IF(AG48=0,0,(1+AG48)/(1+Inputs!$I$179)-1)","v":-1.0069065057815574E-2},{"$f":"IF(AH48=0,0,(1+AH48)/(1+Inputs!$I$179)-1)","v":-9.1913315073283153E-3},{"$f":"IF(AI48=0,0,(1+AI48)/(1+Inputs!$I$179)-1)","v":2.2660681826156548E-2}]
[null,null,null,null,"Cost of debt weighting",null,"%",null,null,null,{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!K4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!L4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":0},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!M4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":6.4128553750470205E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!N4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":6.4128553750470205E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!O4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":6.291980173487223E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!P4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":6.14034442613106E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Q4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.9783141214945185E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!R4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.8116419599382241E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!S4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.7972386143956819E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!T4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.5912478931404982E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!U4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.4110139990933767E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!V4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":5.1806812756483647E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!W4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":4.9224705459659693E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!X4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":4.7845435657113689E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Y4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":4.473285373326906E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!Z4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":4.1620377948970173E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AA4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":3.8118350626168605E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AB4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":3.4756805593582712E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AC4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":3.2691440987135029E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AD4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":2.9544457234591474E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AE4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":2.5692120705602357E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AF4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":2.1721875673232159E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AG4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":1.7514565425836862E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AH4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":1.3624644192888483E-2},{"$f":"SUMIF(Finance!10:10,'Allowances Floor'!AI4,Finance!140:140)/SUM(Finance!$K$140:$AX$140)","v":1.2630634627719732E-2}]
[]
[null,null,null,null,"Floor return rate",null,null,null,{"$f":"SUMPRODUCT(K49:AI49,K50:AI50)","v":-1.1490202032419634E-2}]
[null,null,null,null,"Debt tenor",null,{"$f":"Inputs!G85","v":"full years"},null,{"$f":"Inputs!I85","v":22.591780821917808}]
[null,null,null,null,"Annuity factor over debt tenor",null,"scalar",null,{"$f":"I52 / (1 - (1 + I52)^(-I53))","v":3.851370582182468E-2}]
[]
[null,null,null,null,"Year within debt tenor",null,"flag",null,null,null,{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!K4,Inputs!171:171)<>0)","v":false},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!L4,Inputs!171:171)<>0)","v":false},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!M4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!N4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!O4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!P4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!Q4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!R4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!S4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!T4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!U4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!V4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!W4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!X4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!Y4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!Z4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AA4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AB4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AC4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AD4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AE4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AF4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AG4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AH4,Inputs!171:171)<>0)","v":true},{"$f":"(SUMIF(Inputs!164:164,'Allowances Floor'!AI4,Inputs!171:171)<>0)","v":true}]
[null,null,null,null,"Discount factor to start of debt period (floor)",null,"scalar",null,null,null,{"$f":"(1 + $I52) ^ - K4","v":1.011623761399274},{"$f":"(1 + $I52) ^ - L4","v":1.0233826346276151},1.0352781901926869,1.0473120168573589,1.0594857218519012,1.0718009310886452,1.0842592893791394,1.0968624606538289,1.1096121281842894,1.1225099948080441,1.1355577831559931,1.1487572358824869,1.1621101158980744,1.1756182066049561,1.1892833121351745,1.203107257591572,1.2170918892915514,1.2312390750136679,1.2455507042470895,1.2600286884439555,1.2746749612746682,1.2894914788861536,1.3044802201631229,1.3196431869923717,1.3349824045301484]
[]
[null,null,"Allowances except tax during debt tenor"]
[]
[null,null,null,null,"Discounted unprofiled allowances except tax (floor) during debt period",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K42 * K$57 *K56","v":0},{"$f":"L42 * L$57 *L56","v":0},14.48648328467482,19.361944769666877,20.154960604399236,20.05979152344419,20.393741269415116,20.297726336740695,20.100112112209828,18.710399975704831,19.896636008057961,20.708574075936333,20.469023578494433,20.57659639666829,19.992748179174164,20.494754235627568,19.796184570467904,18.176923142810615,17.814151149397151,19.008490907056746,18.751219632433244,18.870048934323535,18.453268947708917,18.781996707369846,21.276015891966807]
[null,null,null,null,"NPV of allowances except tax (floor) during debt period",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K61:AI61)","v":446.63179223374902}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"G$21","v":"scalar"},null,{"$f":"I$54","v":3.851370582182468E-2}]
[]
[null,null,null,null,"Annuity of allowances except tax (floor) during debt tenor",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I62 * I64","v":17.20144545676493}]
[null,null,null,null,"Annuitised allowances except tax (floor) during debt tenor",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K$56 * $I66","v":0},{"$f":"L$56 * $I66","v":0},{"$f":"M$56 * $I66","v":17.20144545676493},17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493,17.20144545676493]
[]
[null,null,"Allowances except tax during debt tail period"]
[]
[null,null,null,null,"Debt tenor",null,{"$f":"Inputs!G85","v":"full years"},null,{"$f":"Inputs!I85","v":22.591780821917808}]
[null,null,null,null,"Debt tail requirement",null,{"$f":"Inputs!G86","v":"full years"},null,{"$f":"Inputs!I86","v":0}]
[]
[null,null,null,null,"Year within tail requirement period",null,"flag",null,null,null,{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!K4,Inputs!172:172)<>0),K56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!L4,Inputs!172:172)<>0),L56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!M4,Inputs!172:172)<>0),M56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!N4,Inputs!172:172)<>0),N56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!O4,Inputs!172:172)<>0),O56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!P4,Inputs!172:172)<>0),P56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!Q4,Inputs!172:172)<>0),Q56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!R4,Inputs!172:172)<>0),R56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!S4,Inputs!172:172)<>0),S56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!T4,Inputs!172:172)<>0),T56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!U4,Inputs!172:172)<>0),U56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!V4,Inputs!172:172)<>0),V56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!W4,Inputs!172:172)<>0),W56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!X4,Inputs!172:172)<>0),X56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!Y4,Inputs!172:172)<>0),Y56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!Z4,Inputs!172:172)<>0),Z56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AA4,Inputs!172:172)<>0),AA56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AB4,Inputs!172:172)<>0),AB56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AC4,Inputs!172:172)<>0),AC56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AD4,Inputs!172:172)<>0),AD56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AE4,Inputs!172:172)<>0),AE56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AF4,Inputs!172:172)<>0),AF56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AG4,Inputs!172:172)<>0),AG56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AH4,Inputs!172:172)<>0),AH56<>TRUE)","v":false},{"$f":"AND((SUMIF(Inputs!164:164,'Allowances Floor'!AI4,Inputs!172:172)<>0),AI56<>TRUE)","v":false}]
[]
[null,null,null,null,"Annuitised allowances except tax (floor) during tail period",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K$74 * $I66","v":0},{"$f":"L$74 * $I66","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"End of sheet"]

{"sheet":"Tax Deductions","index":9,"n_rows":76,"n_cols":35,"rows_kept":76,"cut":false,"hidden":false,"merged":[]}
["Tax Deductions",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[null,null,null,null,"Year",null,null,null,null,null,1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25]
[]
[null,"Tax deductions"]
[]
[null,null,"Inflation"]
[]
[null,null,null,null,{"$f":"Inputs!E195","v":"UK RPI uplift from 2020/21 term to start of regime"},null,"scalar",null,{"$f":"Inputs!I195","v":1.0685693503755167}]
[null,null,null,null,{"$f":"Inputs!E192","v":"Long-term expected UK RPI inflation"},null,"%",null,{"$f":"Inputs!I192","v":4.2799999999999998E-2}]
[null,null,null,null,"Forecast UK inflation uplift",null,"scalar",null,null,null,{"$f":"I10*(1+$I$11)^0.5","v":1.0911971536357694},{"$f":"K12*(1+$I$11)","v":1.1379003918113804},{"$f":"L12*(1+$I$11)","v":1.1866025285809074},1.2373891168041702,1.2903493710033886,1.3455763240823335,1.4031669907530573,1.4632225379572881,1.52584846258186,1.5911547767803635,1.659256201226563,1.7302723666390598,1.8043280239312114,1.8815532633554672,1.9620837430270812,2.0460609272286403,2.1336323349140258,2.224951798848346,2.320179735839055,2.4194834285329665,2.5230373192741773,2.6310233165391121,2.7436311144869858,2.8610585261870285,2.9835118311078332]
[]
[null,null,"Total tax deductions - Notional cost of debt"]
[]
[null,null,null,null,"Revenue pool additions",null,"£m nominal",null,null,null,{"$f":"K38","v":6.6115034336527447},6.8944757806130825,7.1895593440233228,7.49727248394752,7.8181557462604738,8.1527728122004213,8.5017114885625986,8.8655847402730767,9.2450317671567639,9.6407191267910743,10.053341905417732,10.483624938969609,10.932324086357507,11.40022755725361,11.888157296704064,12.396970429002998,12.927560763364324,13.480860364036317,14.057841187617068,14.659516790447078,15.286944109078213,15.941225316946763,16.623509760512082,17.334995978261997,18.07693380613161]
[null,null,null,null,"Capital allowances",null,"£m nominal",null,null,null,{"$f":"K53","v":12.378000000000009},11.635320000000007,10.937200800000008,10.280968752000007,9.6641106268800065,9.0842639892672068,8.6862110033199933,8.1650383431207949,7.6751360425335466,7.214627879981534,6.7817502071826414,6.3748451947516829,5.992354483066582,5.6328132140825877,5.5004022135409141,5.3847337465423228,5.0616497217497836,4.7579507384447961,4.4724736941381087,4.2041252724898222,3.9518777561404335,3.7147650907720071,3.8511749829648108,3.6201044839869221,56.714970249128449]
[null,null,null,null,"Interest payable",null,"£m nominal",null,null,null,{"$f":"K69","v":4.132616104279105},4.0251539923734017,3.9140338185966148,3.7991310607667823,3.6803169579070989,3.5574583659553025,3.4304176085613434,3.2990523228061295,3.163215299668471,3.0227543190614359,2.8775119792532666,2.727325520481704,2.5720266425640572,2.4114413162986326,2.2453895884461756,2.0736853800727921,1.8961362780283584,1.7125433193267632,1.5227007681863456,1.3263958854806839,1.1234086903413776,0.91351171364567541,0.69646974311270271,0.47203955972264178,0.23996966516349522]
[null,null,null,null,"Debt transaction costs",null,"£m nominal",null,null,null,{"$f":"SUMPRODUCT(Finance!K43:AX43,Inputs!K183:AX183)+SUMPRODUCT(Finance!K45:AX45,Inputs!K183:AX183)","v":2.8015134950735536}]
[null,null,null,null,"Total tax deductions",null,"£m nominal",null,null,null,{"$f":"SUM(K16:K19)","v":25.923633033005412},22.55494977298649,22.040793962619944,21.577372296714309,21.162583331047578,20.79449516742293,20.618340100443934,20.3296754062,{"$f":"SUM(S16:S19)","v":20.083383109358785},19.878101325834045,19.712604091853638,19.585795654202993,19.496705211988147,19.444482087634828,19.633949098691154,19.855389555618114,19.885346763142465,19.951354421807878,20.053015649941525,20.190037948417583,20.362230555560025,20.569502121364447,21.171154486589597,21.42714002197156,75.031873720423562]
[]
[null,null,"Total tax deductions - Actual cost of debt"]
[]
[null,null,null,null,"Year within debt tenor or tail period",null,"flag",null,null,null,{"$f":"OR('Allowances Floor'!K56,'Allowances Floor'!K74)","v":false},{"$f":"OR('Allowances Floor'!L56,'Allowances Floor'!L74)","v":false},{"$f":"OR('Allowances Floor'!M56,'Allowances Floor'!M74)","v":true},{"$f":"OR('Allowances Floor'!N56,'Allowances Floor'!N74)","v":true},{"$f":"OR('Allowances Floor'!O56,'Allowances Floor'!O74)","v":true},{"$f":"OR('Allowances Floor'!P56,'Allowances Floor'!P74)","v":true},{"$f":"OR('Allowances Floor'!Q56,'Allowances Floor'!Q74)","v":true},{"$f":"OR('Allowances Floor'!R56,'Allowances Floor'!R74)","v":true},{"$f":"OR('Allowances Floor'!S56,'Allowances Floor'!S74)","v":true},{"$f":"OR('Allowances Floor'!T56,'Allowances Floor'!T74)","v":true},{"$f":"OR('Allowances Floor'!U56,'Allowances Floor'!U74)","v":true},{"$f":"OR('Allowances Floor'!V56,'Allowances Floor'!V74)","v":true},{"$f":"OR('Allowances Floor'!W56,'Allowances Floor'!W74)","v":true},{"$f":"OR('Allowances Floor'!X56,'Allowances Floor'!X74)","v":true},{"$f":"OR('Allowances Floor'!Y56,'Allowances Floor'!Y74)","v":true},{"$f":"OR('Allowances Floor'!Z56,'Allowances Floor'!Z74)","v":true},{"$f":"OR('Allowances Floor'!AA56,'Allowances Floor'!AA74)","v":true},{"$f":"OR('Allowances Floor'!AB56,'Allowances Floor'!AB74)","v":true},{"$f":"OR('Allowances Floor'!AC56,'Allowances Floor'!AC74)","v":true},{"$f":"OR('Allowances Floor'!AD56,'Allowances Floor'!AD74)","v":true},{"$f":"OR('Allowances Floor'!AE56,'Allowances Floor'!AE74)","v":true},{"$f":"OR('Allowances Floor'!AF56,'Allowances Floor'!AF74)","v":true},{"$f":"OR('Allowances Floor'!AG56,'Allowances Floor'!AG74)","v":true},{"$f":"OR('Allowances Floor'!AH56,'Allowances Floor'!AH74)","v":true},{"$f":"OR('Allowances Floor'!AI56,'Allowances Floor'!AI74)","v":true}]
[]
[null,null,null,null,"Revenue pool additions",null,"£m nominal",null,null,null,{"$f":"K38*K$24","v":0},0,7.1895593440233228,7.49727248394752,7.8181557462604738,8.1527728122004213,8.5017114885625986,8.8655847402730767,9.2450317671567639,9.6407191267910743,10.053341905417732,10.483624938969609,10.932324086357507,11.40022755725361,11.888157296704064,12.396970429002998,12.927560763364324,13.480860364036317,14.057841187617068,14.659516790447078,15.286944109078213,15.941225316946763,16.623509760512082,17.334995978261997,18.07693380613161]
[null,null,null,null,"Capital allowances",null,"£m nominal",null,null,null,{"$f":"K53*K$24","v":0},0,10.937200800000008,10.280968752000007,{"$f":"O53*O$24","v":9.6641106268800065},9.0842639892672068,8.6862110033199933,8.1650383431207949,7.6751360425335466,7.214627879981534,6.7817502071826414,6.3748451947516829,5.992354483066582,5.6328132140825877,5.5004022135409141,5.3847337465423228,5.0616497217497836,4.7579507384447961,4.4724736941381087,4.2041252724898222,3.9518777561404335,3.7147650907720071,3.8511749829648108,3.6201044839869221,56.714970249128449]
[null,null,null,null,"Financial expenses during operation",null,"£m nominal",null,null,null,{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!K4,Finance!140:140)*K$24","v":0},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!L4,Finance!140:140)*L$24","v":0},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!M4,Finance!140:140)*M$24","v":7.6232325533685934},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!N4,Finance!140:140)*N$24","v":7.6232325533685934},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!O4,Finance!140:140)*O$24","v":7.4795430862692553},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!P4,Finance!140:140)*P$24","v":7.2992872567057505},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!Q4,Finance!140:140)*Q$24","v":7.1066749770426592},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!R4,Finance!140:140)*R$24","v":6.9085447256323134},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!S4,Finance!140:140)*S$24","v":6.8914228592879443},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!T4,Finance!140:140)*T$24","v":6.6465529721430352},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!U4,Finance!140:140)*U$24","v":6.4323013154369413},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!V4,Finance!140:140)*V$24","v":6.1584950602227124},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!W4,Finance!140:140)*W$24","v":5.8515490392968212},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!X4,Finance!140:140)*X$24","v":5.6875894012928248},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!Y4,Finance!140:140)*Y$24","v":5.3175836166745327},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!Z4,Finance!140:140)*Z$24","v":4.9475904493131884},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AA4,Finance!140:140)*AA$24","v":4.5312896421275681},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AB4,Finance!140:140)*AB$24","v":4.1316885592505761},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AC4,Finance!140:140)*AC$24","v":3.8861699285995326},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AD4,Finance!140:140)*AD$24","v":3.512074653027593},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AE4,Finance!140:140)*AE$24","v":3.0541311081194795},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AF4,Finance!140:140)*AF$24","v":2.5821712804679393},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AG4,Finance!140:140)*AG$24","v":2.0820305075313605},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AH4,Finance!140:140)*AH$24","v":1.6196191098186166},{"$f":"SUMIF(Finance!10:10,'Tax Deductions'!AI4,Finance!140:140)*AI$24","v":1.501456986514867}]
[null,null,null,null,"Debt transaction costs",null,"£m nominal",null,null,null,{"$f":"IF(Inputs!I128=1,'Tax Deductions'!K19,SUMPRODUCT(Finance!108:108,Finance!14:14)+SUMPRODUCT(Finance!109:109,Finance!14:14))","v":4.1727738818898121}]
[null,null,null,null,"Total tax deductions",null,"£m nominal",null,null,null,{"$f":"SUM(K26:K29)","v":4.1727738818898121},0,25.749992697391924,25.401473789316121,24.961809459409736,24.536324058173378,24.29459746892525,23.939167809026184,23.811590668978255,23.501899978915642,23.267393428037312,23.016965193944003,22.776227608720909,22.720630172629022,22.70614312691951,22.729294624858511,22.520500127241675,22.370499661731692,22.41648481035471,22.375716715964494,22.292952973338124,22.238161688186711,22.556715251008253,22.574719572067536,76.293361041774929]
[]
[null,"Tax pools"]
[]
[null,null,"Revenue pool"]
[]
[null,null,null,null,"Controllable Opex",null,"£m nominal",null,null,null,{"$f":"Inputs!K61* K$12","v":5.267291106055553},{"$f":"Inputs!L61* L$12","v":5.4927311653947308},{"$f":"Inputs!M61* M$12","v":5.7278200592736255},{"$f":"Inputs!N61* N$12","v":5.9729707578105362},{"$f":"Inputs!O61* O$12","v":6.2286139062448269},{"$f":"Inputs!P61* P$12","v":6.4951985814321045},{"$f":"Inputs!Q61* Q$12","v":6.7731930807173981},{"$f":"Inputs!R61* R$12","v":7.0630857445721027},{"$f":"Inputs!S61* S$12","v":7.3653858144397883},{"$f":"Inputs!T61* T$12","v":7.680624327297811},{"$f":"Inputs!U61* U$12","v":8.0093550485061566},{"$f":"Inputs!V61* V$12","v":8.3521554445822197},{"$f":"Inputs!W61* W$12","v":8.7096276976103386},{"$f":"Inputs!X61* X$12","v":9.0823997630680608},{"$f":"Inputs!Y61* Y$12","v":9.4711264729273736},{"$f":"Inputs!Z61* Z$12","v":9.8764906859686654},{"$f":"Inputs!AA61* AA$12","v":10.299204487328122},{"$f":"Inputs!AB61* AB$12","v":10.740010439385767},{"$f":"Inputs!AC61* AC$12","v":11.199682886191475},{"$f":"Inputs!AD61* AD$12","v":11.67902931372047},{"$f":"Inputs!AE61* AE$12","v":12.178891768347706},{"$f":"Inputs!AF61* AF$12","v":12.700148336032989},{"$f":"Inputs!AG61* AG$12","v":13.243714684815199},{"$f":"Inputs!AH61* AH$12","v":13.810545673325286},{"$f":"Inputs!AI61* AI$12","v":14.401637028143609}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,"£m nominal",null,null,null,{"$f":"Inputs!K62* K$12","v":1.3442123275971918},{"$f":"Inputs!L62* L$12","v":1.4017446152183515},{"$f":"Inputs!M62* M$12","v":1.4617392847496971},{"$f":"Inputs!N62* N$12","v":1.524301726136984},{"$f":"Inputs!O62* O$12","v":1.5895418400156469},{"$f":"Inputs!P62* P$12","v":1.6575742307683163},{"$f":"Inputs!Q62* Q$12","v":1.7285184078452001},{"$f":"Inputs!R62* R$12","v":1.8024989957009747},{"$f":"Inputs!S62* S$12","v":1.8796459527169764},{"$f":"Inputs!T62* T$12","v":1.9600947994932629},{"$f":"Inputs!U62* U$12","v":2.0439868569115744},{"$f":"Inputs!V62* V$12","v":2.1314694943873898},{"$f":"Inputs!W62* W$12","v":2.2226963887471696},{"$f":"Inputs!X62* X$12","v":2.3178277941855487},{"$f":"Inputs!Y62* Y$12","v":2.41703082377669},{"$f":"Inputs!Z62* Z$12","v":2.5204797430343322},{"$f":"Inputs!AA62* AA$12","v":2.6283562760362016},{"$f":"Inputs!AB62* AB$12","v":2.7408499246505507},{"$f":"Inputs!AC62* AC$12","v":2.8581583014255938},{"$f":"Inputs!AD62* AD$12","v":2.9804874767266094},{"$f":"Inputs!AE62* AE$12","v":3.1080523407305081},{"$f":"Inputs!AF62* AF$12","v":3.2410769809137738},{"$f":"Inputs!AG62* AG$12","v":3.3797950756968831},{"$f":"Inputs!AH62* AH$12","v":3.5244503049367091},{"$f":"Inputs!AI62* AI$12","v":3.6752967779880001}]
[null,null,null,null,"Revenue pool additions",null,"£m nominal",null,null,null,{"$f":"SUM(K36:K37)","v":6.6115034336527447},6.8944757806130825,7.1895593440233228,7.49727248394752,7.8181557462604738,8.1527728122004213,8.5017114885625986,8.8655847402730767,9.2450317671567639,9.6407191267910743,10.053341905417732,10.483624938969609,10.932324086357507,11.40022755725361,11.888157296704064,12.396970429002998,12.927560763364324,13.480860364036317,14.057841187617068,14.659516790447078,15.286944109078213,15.941225316946763,16.623509760512082,17.334995978261997,18.07693380613161]
[]
[null,null,"Capital allowance pool"]
[]
[null,null,null,null,"Capital allowance rate (declining balance)",null,{"$f":"Inputs!G190","v":"%"},null,null,null,{"$f":"Inputs!K190","v":0.06},{"$f":"Inputs!L190","v":0.06},{"$f":"Inputs!M190","v":0.06},{"$f":"Inputs!N190","v":0.06},{"$f":"Inputs!O190","v":0.06},{"$f":"Inputs!P190","v":0.06},{"$f":"Inputs!Q190","v":0.06},{"$f":"Inputs!R190","v":0.06},{"$f":"Inputs!S190","v":0.06},{"$f":"Inputs!T190","v":0.06},{"$f":"Inputs!U190","v":0.06},{"$f":"Inputs!V190","v":0.06},{"$f":"Inputs!W190","v":0.06},{"$f":"Inputs!X190","v":0.06},{"$f":"Inputs!Y190","v":0.06},{"$f":"Inputs!Z190","v":0.06},{"$f":"Inputs!AA190","v":0.06},{"$f":"Inputs!AB190","v":0.06},{"$f":"Inputs!AC190","v":0.06},{"$f":"Inputs!AD190","v":0.06},{"$f":"Inputs!AE190","v":0.06},{"$f":"Inputs!AF190","v":0.06},{"$f":"Inputs!AG190","v":0.06},{"$f":"Inputs!AH190","v":0.06},{"$f":"Inputs!AI190","v":0.06}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G155","v":"full years"},null,{"$f":"Inputs!I155","v":25}]
[]
[null,null,null,null,"Opening balance brought forward",null,"£m nominal",null,null,null,{"$f":"J51","v":0},193.92200000000014,182.28668000000013,171.34947920000013,161.06851044800013,151.40439982112011,142.32013583185289,136.08397238534658,127.91893404222579,120.24379799969223,113.0291701197107,106.24741991252806,99.872574717776374,93.880220234709796,88.247407020627207,86.172968012140998,84.360828695829724,79.299178974079936,74.541228235635145,70.068754541497043,65.864629269007224,61.912751512866791,58.197986422094786,60.33507473311537,56.714970249128449]
[null,null,null,null,"Capex",null,"£m nominal",null,null,null,{"$f":"SUMPRODUCT('Pre Op RAV'!K21:AX21,Inputs!K183:AX183)","v":206.30000000000015}]
[null,null,null,null,"Replacement Capex",null,"£m nominal",null,null,null,{"$f":"'Op Rav'!K13 * K$12","v":0},{"$f":"'Op Rav'!L13 * L$12","v":0},{"$f":"'Op Rav'!M13 * M$12","v":0},{"$f":"'Op Rav'!N13 * N$12","v":0},{"$f":"'Op Rav'!O13 * O$12","v":0},{"$f":"'Op Rav'!P13 * P$12","v":0},{"$f":"'Op Rav'!Q13 * Q$12","v":2.450047556813665},{"$f":"'Op Rav'!R13 * R$12","v":0},{"$f":"'Op Rav'!S13 * S$12","v":0},{"$f":"'Op Rav'!T13 * T$12","v":0},{"$f":"'Op Rav'!U13 * U$12","v":0},{"$f":"'Op Rav'!V13 * V$12","v":0},{"$f":"'Op Rav'!W13 * W$12","v":0},{"$f":"'Op Rav'!X13 * X$12","v":0},{"$f":"'Op Rav'!Y13 * Y$12","v":3.425963205054706},{"$f":"'Op Rav'!Z13 * Z$12","v":3.5725944302310473},{"$f":"'Op Rav'!AA13 * AA$12","v":0},{"$f":"'Op Rav'!AB13 * AB$12","v":0},{"$f":"'Op Rav'!AC13 * AC$12","v":0},{"$f":"'Op Rav'!AD13 * AD$12","v":0},{"$f":"'Op Rav'!AE13 * AE$12","v":0},{"$f":"'Op Rav'!AF13 * AF$12","v":0},{"$f":"'Op Rav'!AG13 * AG$12","v":5.9882632939854039},{"$f":"'Op Rav'!AH13 * AH$12","v":0},{"$f":"'Op Rav'!AI13 * AI$12","v":0}]
[null,null,null,null,"Tax book value pre-depreciation",null,"£m nominal",null,null,null,{"$f":"SUM(K45:K47)","v":206.30000000000015},193.92200000000014,182.28668000000013,171.34947920000013,161.06851044800013,151.40439982112011,144.77018338866657,136.08397238534658,127.91893404222579,120.24379799969223,113.0291701197107,106.24741991252806,99.872574717776374,93.880220234709796,91.673370225681907,89.745562442372048,84.360828695829724,79.299178974079936,74.541228235635145,70.068754541497043,65.864629269007224,61.912751512866791,64.186249716080184,60.33507473311537,56.714970249128449]
[null,null,null,null,"Capital allowance (reducing balance)",null,"£m nominal",null,null,null,{"$f":"-K48 * K42","v":-12.378000000000009},{"$f":"-L48 * L42","v":-11.635320000000007},{"$f":"-M48 * M42","v":-10.937200800000008},-10.280968752000007,-9.6641106268800065,-9.0842639892672068,-8.6862110033199933,-8.1650383431207949,-7.6751360425335466,-7.214627879981534,-6.7817502071826414,-6.3748451947516829,-5.992354483066582,-5.6328132140825877,-5.5004022135409141,-5.3847337465423228,-5.0616497217497836,-4.7579507384447961,-4.4724736941381087,-4.2041252724898222,-3.9518777561404335,-3.7147650907720071,-3.8511749829648108,-3.6201044839869221,-3.4028982149477067]
[null,null,null,null,"Write-back allowance",null,"£m nominal",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"-SUM(AI48:AI49)","v":-53.312072034180744}]
[null,null,null,null,"Closing balance carried forward",null,"£m nominal",null,null,null,{"$f":"SUM(K48:K50)","v":193.92200000000014},{"$f":"SUM(L48:L50)","v":182.28668000000013},171.34947920000013,161.06851044800013,151.40439982112011,142.32013583185289,136.08397238534658,127.91893404222579,120.24379799969223,113.0291701197107,106.24741991252806,99.872574717776374,93.880220234709796,88.247407020627207,86.172968012140998,84.360828695829724,79.299178974079936,74.541228235635145,70.068754541497043,65.864629269007224,61.912751512866791,58.197986422094786,60.33507473311537,56.714970249128449,{"$f":"SUM(AI48:AI50)","v":0}]
[]
[null,null,null,null,"Capital allowances",null,"£m nominal",null,null,null,{"$f":"-(K49 + K50)","v":12.378000000000009},11.635320000000007,10.937200800000008,10.280968752000007,9.6641106268800065,9.0842639892672068,8.6862110033199933,8.1650383431207949,7.6751360425335466,7.214627879981534,6.7817502071826414,{"$f":"-(V49 + V50)","v":6.3748451947516829},5.992354483066582,5.6328132140825877,5.5004022135409141,5.3847337465423228,5.0616497217497836,4.7579507384447961,4.4724736941381087,4.2041252724898222,3.9518777561404335,3.7147650907720071,3.8511749829648108,3.6201044839869221,56.714970249128449]
[]
[null,"Interest - Notional cost of debt"]
[]
[null,null,"Cost of debt"]
[]
[null,null,null,null,"Cost of debt (for tax)",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I71","v":-8.3999999999999995E-3}]
[null,null,null,null,"Expected UK RPI inflation",null,{"$f":"Inputs!G192","v":"%"},null,{"$f":"Inputs!I192","v":4.2799999999999998E-2}]
[null,null,null,null,"Cost of debt (for tax)",null,"nominal annual %",null,{"$f":"(1 + I59) * (1 + I$60) - 1","v":3.404048000000004E-2}]
[]
[null,null,"Net debt"]
[]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G155","v":"full years"},null,{"$f":"Inputs!I155","v":25}]
[null,null,null,null,"Operational notional gearing",null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"Inputs!I74","v":0.5}]
[]
[null,null,null,null,"Principal repayments",null,"£m nominal",null,null,null,{"$f":"K70 - K69","v":3.1568917919401525},{"$f":"L70 - L69","v":3.2643539038458558},3.3754740776226426,3.4903768354524751,3.6091909383121585,3.7320495302639549,3.8590902876579141,3.990455573413128,4.1262925965507868,4.2667535771578216,4.4119959169659904,4.562182375737553,4.7174812536552002,4.8780665799206249,5.0441183077730818,5.2158225161464653,5.3933716181908995,5.576964576892494,5.7668071280329123,5.9631120107385733,6.1660992058778801,6.3759961825735818,6.5930381531065549,6.8174683364966153,7.0495382310557622]
[null,null,null,null,"Net interest paid",null,"£m nominal",null,null,null,{"$f":"$I61 * K72","v":4.132616104279105},4.0251539923734017,3.9140338185966148,3.7991310607667823,3.6803169579070989,3.5574583659553025,3.4304176085613434,3.2990523228061295,3.163215299668471,3.0227543190614359,2.8775119792532666,2.727325520481704,2.5720266425640572,2.4114413162986326,2.2453895884461756,2.0736853800727921,1.8961362780283584,1.7125433193267632,1.5227007681863456,1.3263958854806839,1.1234086903413776,0.91351171364567541,0.69646974311270271,0.47203955972264178,0.23996966516349522]
[null,null,null,null,"Total",null,"£m nominal",null,null,null,{"$f":"$K$72*$I61/(1-(1+$I61)^(-$I65))","v":7.2895078962192574},{"$f":"$K$72*$I61/(1-(1+$I61)^(-$I65))","v":7.2895078962192574},7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574,7.2895078962192574]
[]
[null,null,null,null,"Opening net debt",null,"£m nominal",null,null,null,{"$f":"'Op Rav'!K12*I10*I66","v":121.40299150538124},{"$f":"K74","v":118.24609971344108},{"$f":"L74","v":114.98174580959522},111.60627173197258,108.1158948965201,104.50670395820795,100.774654427944,96.915564140286079,92.92510856687295,88.798815970322167,84.532062393164352,80.12006647619836,75.557884100460811,70.840402846805617,65.962336266884989,60.918217959111907,55.70239544296544,50.309023824774542,44.732059247882049,38.96525211984914,33.00214010911057,26.836040903232689,20.460044720659106,13.867006567552551,7.0495382310559354]
[null,null,null,null,"Less principal repayment",null,"£m nominal",null,null,null,{"$f":"IF(K3 = \"Year \"&$I65, -K72, -K68)","v":-3.1568917919401525},-3.2643539038458558,-3.3754740776226426,-3.4903768354524751,-3.6091909383121585,-3.7320495302639549,-3.8590902876579141,-3.990455573413128,-4.1262925965507868,-4.2667535771578216,-4.4119959169659904,-4.562182375737553,-4.7174812536552002,-4.8780665799206249,-5.0441183077730818,-5.2158225161464653,-5.3933716181908995,-5.576964576892494,-5.7668071280329123,-5.9631120107385733,-6.1660992058778801,-6.3759961825735818,-6.5930381531065549,-6.8174683364966153,-7.0495382310559354]
[null,null,null,null,"Closing net debt",null,"£m nominal",null,null,null,{"$f":"SUM(K72:K73)","v":118.24609971344108},{"$f":"SUM(L72:L73)","v":114.98174580959522},111.60627173197258,108.1158948965201,104.50670395820795,100.774654427944,96.915564140286079,92.92510856687295,88.798815970322167,84.532062393164352,80.12006647619836,75.557884100460811,70.840402846805617,{"$f":"SUM(X72:X73)","v":65.962336266884989},{"$f":"SUM(Y72:Y73)","v":60.918217959111907},55.70239544296544,50.309023824774542,44.732059247882049,38.96525211984914,33.00214010911057,26.836040903232689,20.460044720659106,13.867006567552551,7.0495382310559354,0]
[]
[null,"End of sheet"]

{"sheet":"Tax Cap","index":10,"n_rows":42,"n_cols":35,"rows_kept":42,"cut":false,"hidden":false,"merged":[]}
["Tax Cap",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"Unprofiled tax allowance (cap)"]
[]
[null,null,"Profits attributable to corporation tax"]
[]
[null,null,null,null,"Annuitised allowances except tax (cap)",null,"£m nominal prices",null,null,null,{"$f":"'Allowances Cap'!K34* 'Tax Deductions'!K$12","v":29.576924640853314},{"$f":"'Allowances Cap'!L34* 'Tax Deductions'!L$12","v":30.842817015481835},{"$f":"'Allowances Cap'!M34* 'Tax Deductions'!M$12","v":32.162889583744459},{"$f":"'Allowances Cap'!N34* 'Tax Deductions'!N$12","v":33.539461257928714},{"$f":"'Allowances Cap'!O34* 'Tax Deductions'!O$12","v":34.974950199768067},{"$f":"'Allowances Cap'!P34* 'Tax Deductions'!P$12","v":36.471878068318134},{"$f":"'Allowances Cap'!Q34* 'Tax Deductions'!Q$12","v":38.032874449642151},{"$f":"'Allowances Cap'!R34* 'Tax Deductions'!R$12","v":39.660681476086829},{"$f":"'Allowances Cap'!S34* 'Tax Deductions'!S$12","v":41.358158643263344},{"$f":"'Allowances Cap'!T34* 'Tax Deductions'!T$12","v":43.128287833195017},{"$f":"'Allowances Cap'!U34* 'Tax Deductions'!U$12","v":44.974178552455761},{"$f":"'Allowances Cap'!V34* 'Tax Deductions'!V$12","v":46.89907339450086},{"$f":"'Allowances Cap'!W34* 'Tax Deductions'!W$12","v":48.906353735785494},{"$f":"'Allowances Cap'!X34* 'Tax Deductions'!X$12","v":50.999545675677112},{"$f":"'Allowances Cap'!Y34* 'Tax Deductions'!Y$12","v":53.182326230596097},{"$f":"'Allowances Cap'!Z34* 'Tax Deductions'!Z$12","v":55.458529793265605},{"$f":"'Allowances Cap'!AA34* 'Tax Deductions'!AA$12","v":57.832154868417369},{"$f":"'Allowances Cap'!AB34* 'Tax Deductions'!AB$12","v":60.30737109678563},{"$f":"'Allowances Cap'!AC34* 'Tax Deductions'!AC$12","v":62.888526579728051},{"$f":"'Allowances Cap'!AD34* 'Tax Deductions'!AD$12","v":65.580155517340401},{"$f":"'Allowances Cap'!AE34* 'Tax Deductions'!AE$12","v":68.386986173482569},{"$f":"'Allowances Cap'!AF34* 'Tax Deductions'!AF$12","v":71.313949181707628},{"$f":"'Allowances Cap'!AG34* 'Tax Deductions'!AG$12","v":74.366186206684702},{"$f":"'Allowances Cap'!AH34* 'Tax Deductions'!AH$12","v":77.549058976330798},{"$f":"'Allowances Cap'!AI34* 'Tax Deductions'!AI$12","v":80.868158700517753}]
[null,null,null,null,"Less tax deductions",null,"£m nominal prices",null,null,null,{"$f":"-'Tax Deductions'!K20","v":-25.923633033005412},{"$f":"-'Tax Deductions'!L20","v":-22.55494977298649},{"$f":"-'Tax Deductions'!M20","v":-22.040793962619944},{"$f":"-'Tax Deductions'!N20","v":-21.577372296714309},{"$f":"-'Tax Deductions'!O20","v":-21.162583331047578},{"$f":"-'Tax Deductions'!P20","v":-20.79449516742293},{"$f":"-'Tax Deductions'!Q20","v":-20.618340100443934},{"$f":"-'Tax Deductions'!R20","v":-20.3296754062},{"$f":"-'Tax Deductions'!S20","v":-20.083383109358785},{"$f":"-'Tax Deductions'!T20","v":-19.878101325834045},{"$f":"-'Tax Deductions'!U20","v":-19.712604091853638},{"$f":"-'Tax Deductions'!V20","v":-19.585795654202993},{"$f":"-'Tax Deductions'!W20","v":-19.496705211988147},{"$f":"-'Tax Deductions'!X20","v":-19.444482087634828},{"$f":"-'Tax Deductions'!Y20","v":-19.633949098691154},{"$f":"-'Tax Deductions'!Z20","v":-19.855389555618114},{"$f":"-'Tax Deductions'!AA20","v":-19.885346763142465},{"$f":"-'Tax Deductions'!AB20","v":-19.951354421807878},{"$f":"-'Tax Deductions'!AC20","v":-20.053015649941525},{"$f":"-'Tax Deductions'!AD20","v":-20.190037948417583},{"$f":"-'Tax Deductions'!AE20","v":-20.362230555560025},{"$f":"-'Tax Deductions'!AF20","v":-20.569502121364447},{"$f":"-'Tax Deductions'!AG20","v":-21.171154486589597},{"$f":"-'Tax Deductions'!AH20","v":-21.42714002197156},{"$f":"-'Tax Deductions'!AI20","v":-75.031873720423562}]
[null,null,null,null,"Profits attributable to corporation tax",null,"£m nominal prices",null,null,null,{"$f":"SUM(K9:K10)","v":3.6532916078479012},{"$f":"SUM(L9:L10)","v":8.287867242495345},10.122095621124515,11.962088961214405,13.812366868720488,15.677382900895203,17.414534349198217,19.331006069886829,21.27477553390456,23.250186507360972,25.261574460602123,27.313277740297867,29.409648523797348,31.555063588042284,33.548377131904942,35.603140237647494,37.946808105274904,40.356016674977752,42.835510929786523,45.390117568922818,48.024755617922544,50.744447060343177,53.195031720095102,56.121918954359238,5.8362849800941916]
[]
[null,null,"Tax losses"]
[]
[null,null,null,null,"Taxable losses brought forward",null,"£m nominal prices",null,null,null,{"$f":"J18","v":0},{"$f":"K18","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"In-year taxable loss",null,"£m nominal prices",null,null,null,{"$f":"MIN(K11, 0)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Profits used to offset losses",null,"£m nominal prices",null,null,null,{"$f":"IF(K11 >= 0, MIN(K11, -K15), 0)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Taxable losses carried forward",null,"£m nominal prices",null,null,null,{"$f":"SUM(K15:K17)","v":0},{"$f":"SUM(L15:L17)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Tax allowance"]
[]
[null,null,null,null,"Profits attributable to corporation tax (after taxable losses)",null,"£m nominal prices",null,null,null,{"$f":"MAX(K11 - K17,0)","v":3.6532916078479012},8.287867242495345,10.122095621124515,11.962088961214405,13.812366868720488,15.677382900895203,17.414534349198217,19.331006069886829,21.27477553390456,23.250186507360972,25.261574460602123,27.313277740297867,29.409648523797348,{"$f":"MAX(X11 - X17,0)","v":31.555063588042284},{"$f":"MAX(Y11 - Y17,0)","v":33.548377131904942},35.603140237647494,37.946808105274904,40.356016674977752,42.835510929786523,45.390117568922818,48.024755617922544,50.744447060343177,53.195031720095102,56.121918954359238,5.8362849800941916]
[null,null,null,null,"Corporation tax rate",null,{"$f":"Inputs!G189","v":"%"},null,null,null,{"$f":"Inputs!K189","v":0.25},{"$f":"Inputs!L189","v":0.25},{"$f":"Inputs!M189","v":0.25},{"$f":"Inputs!N189","v":0.25},{"$f":"Inputs!O189","v":0.25},{"$f":"Inputs!P189","v":0.25},{"$f":"Inputs!Q189","v":0.25},{"$f":"Inputs!R189","v":0.25},{"$f":"Inputs!S189","v":0.25},{"$f":"Inputs!T189","v":0.25},{"$f":"Inputs!U189","v":0.25},{"$f":"Inputs!V189","v":0.25},{"$f":"Inputs!W189","v":0.25},{"$f":"Inputs!X189","v":0.25},{"$f":"Inputs!Y189","v":0.25},{"$f":"Inputs!Z189","v":0.25},{"$f":"Inputs!AA189","v":0.25},{"$f":"Inputs!AB189","v":0.25},{"$f":"Inputs!AC189","v":0.25},{"$f":"Inputs!AD189","v":0.25},{"$f":"Inputs!AE189","v":0.25},{"$f":"Inputs!AF189","v":0.25},{"$f":"Inputs!AG189","v":0.25},{"$f":"Inputs!AH189","v":0.25},{"$f":"Inputs!AI189","v":0.25}]
[null,null,null,null,"Corporation tax charge after losses",null,"£m nominal prices",null,null,null,{"$f":"K22 * K23","v":0.9133229019619753},2.0719668106238363,2.5305239052811288,2.9905222403036014,3.4530917171801221,3.9193457252238009,4.3536335872995542,4.8327515174717073,5.3186938834761399,5.812546626840243,6.3153936151505308,6.8283194350744667,7.3524121309493369,{"$f":"X22 * X23","v":7.888765897010571},{"$f":"Y22 * Y23","v":8.3870942829762356},8.9007850594118736,9.4867020263187261,10.089004168744438,10.708877732446631,11.347529392230705,12.006188904480636,12.686111765085794,13.298757930023775,14.030479738589809,1.4590712450235479]
[]
[null,null,null,null,"Grossing-up factor for tax on tax charge after losses",null,"scalar",null,null,null,{"$f":"1 / (1 - K23)","v":1.3333333333333333},1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,{"$f":"1 / (1 - X23)","v":1.3333333333333333},{"$f":"1 / (1 - Y23)","v":1.3333333333333333},1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333]
[]
[null,null,null,null,"Unprofiled tax allowance (cap)",null,"£m nominal prices",null,null,null,{"$f":"K24 * K26","v":1.2177638692826336},2.762622414165115,3.3740318737081716,3.9873629870714682,4.6041222895734961,5.2257943002984009,5.8048447830660717,6.4436686899622764,7.0915918446348529,7.7500621691203238,8.4205248202007077,9.1044259134326211,9.8032161745991147,{"$f":"X24 * X26","v":10.518354529347427},{"$f":"Y24 * Y26","v":11.182792377301647},{"$f":"Z24 * Z26","v":11.867713412549165},12.648936035091634,13.452005558325917,14.278503643262173,15.130039189640939,16.008251872640848,16.914815686781058,17.731677240031701,18.707306318119745,1.9454283266980639]
[]
[null,"Profiled tax allowance (cap)"]
[]
[null,null,null,null,"Unprofiled tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Tax Cap'!K28 / 'Tax Deductions'!K12","v":1.1159888616141964},{"$f":"'Tax Cap'!L28 / 'Tax Deductions'!L12","v":2.4278244686842942},{"$f":"'Tax Cap'!M28 / 'Tax Deductions'!M12","v":2.8434389717197677},{"$f":"'Tax Cap'!N28 / 'Tax Deductions'!N12","v":3.2224002400875409},{"$f":"'Tax Cap'!O28 / 'Tax Deductions'!O12","v":3.5681206912150345},{"$f":"'Tax Cap'!P28 / 'Tax Deductions'!P12","v":3.8836847875294835},{"$f":"'Tax Cap'!Q28 / 'Tax Deductions'!Q12","v":4.1369593365011417},{"$f":"'Tax Cap'!R28 / 'Tax Deductions'!R12","v":4.4037516664812122},{"$f":"'Tax Cap'!S28 / 'Tax Deductions'!S12","v":4.6476383589464065},{"$f":"'Tax Cap'!T28 / 'Tax Deductions'!T12","v":4.8707154591222466},{"$f":"'Tax Cap'!U28 / 'Tax Deductions'!U12","v":5.0748792223744887},{"$f":"'Tax Cap'!V28 / 'Tax Deductions'!V12","v":5.2618455273127713},{"$f":"'Tax Cap'!W28 / 'Tax Deductions'!W12","v":5.4331673867372441},{"$f":"'Tax Cap'!X28 / 'Tax Deductions'!X12","v":5.5902507434679389},{"$f":"'Tax Cap'!Y28 / 'Tax Deductions'!Y12","v":5.6994470378970457},{"$f":"'Tax Cap'!Z28 / 'Tax Deductions'!Z12","v":5.8002737135613112},{"$f":"'Tax Cap'!AA28 / 'Tax Deductions'!AA12","v":5.9283578656494811},{"$f":"'Tax Cap'!AB28 / 'Tax Deductions'!AB12","v":6.0459761713888769},{"$f":"'Tax Cap'!AC28 / 'Tax Deductions'!AC12","v":6.1540506637079933},{"$f":"'Tax Cap'!AD28 / 'Tax Deductions'!AD12","v":6.253417159717813},{"$f":"'Tax Cap'!AE28 / 'Tax Deductions'!AE12","v":6.3448335664119595},{"$f":"'Tax Cap'!AF28 / 'Tax Deductions'!AF12","v":6.4289873755398954},{"$f":"'Tax Cap'!AG28 / 'Tax Deductions'!AG12","v":6.4628503250325746},{"$f":"'Tax Cap'!AH28 / 'Tax Deductions'!AH12","v":6.5385961688281942},{"$f":"'Tax Cap'!AI28 / 'Tax Deductions'!AI12","v":0.65205986663565207}]
[null,null,null,null,"Discount factor to start of operational period (cap)",null,{"$f":"'Allowances Cap'!G24","v":"scalar"},null,null,null,{"$f":"'Allowances Cap'!K24","v":0.92506938020351526},{"$f":"'Allowances Cap'!L24","v":0.85575335819011589},{"$f":"'Allowances Cap'!M24","v":0.79163122866800739},{"$f":"'Allowances Cap'!N24","v":0.73231381005366081},{"$f":"'Allowances Cap'!O24","v":0.67744108238081491},{"$f":"'Allowances Cap'!P24","v":0.62668000220241893},{"$f":"'Allowances Cap'!Q24","v":0.57972248122332926},{"$f":"'Allowances Cap'!R24","v":0.53628351639530925},{"$f":"'Allowances Cap'!S24","v":0.49609946012517048},{"$f":"'Allowances Cap'!T24","v":0.45892642009728996},{"$f":"'Allowances Cap'!U24","v":0.42453877899841808},{"$f":"'Allowances Cap'!V24","v":0.39272782516042376},{"$f":"'Allowances Cap'!W24","v":0.36330048580982777},{"$f":"'Allowances Cap'!X24","v":0.33607815523573337},{"$f":"'Allowances Cap'!Y24","v":0.31089561076386063},{"$f":"'Allowances Cap'!Z24","v":0.28760000995731788},{"$f":"'Allowances Cap'!AA24","v":0.26604996295774092},{"$f":"'Allowances Cap'!AB24","v":0.24611467433648557},{"$f":"'Allowances Cap'!AC24","v":0.22767314924744272},{"$f":"'Allowances Cap'!AD24","v":0.21061345906331425},{"$f":"'Allowances Cap'!AE24","v":0.19483206203821857},{"$f":"'Allowances Cap'!AF24","v":0.18023317487346768},{"$f":"'Allowances Cap'!AG24","v":0.16672819137231054},{"$f":"'Allowances Cap'!AH24","v":0.15423514465523638},{"$f":"'Allowances Cap'!AI24","v":0.14267820967181905}]
[]
[null,null,null,null,"Discounted unprofiled tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K32 * K33","v":1.0323671245274713},2.0776189421727187,2.250955086825015,2.3598081973363385,2.4171915431220943,2.4338275912024776,2.3982883312764596,2.3616594290322475,2.3056908807303458,2.2353000089675006,2.154483028631307,2.0664731502716478,1.9738723510877532,{"$f":"X32 * X33","v":1.8787611571698919},{"$f":"Y32 * Y33","v":1.7719330678632783},1.6681587777754023,1.5772393905562765,1.4880034564675253,1.4011120952347138,1.3170538189740544,1.2361770070333464,1.1587168059149979,1.0775393458026306,1.0084813259413909,9.3034734370419925E-2]
[null,null,null,null,"NPV of tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K35:AI35)","v":43.743746648287306}]
[]
[null,null,null,null,"Annuity factor (cap)",null,{"$f":"'Allowances Cap'!G31","v":"scalar"},null,{"$f":"'Allowances Cap'!I31","v":9.4480276733656082E-2}]
[]
[null,null,null,null,"Annuity of tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I36 * I38","v":4.1329212886971254}]
[]
[null,"End of sheet"]

{"sheet":"Tax Floor","index":11,"n_rows":79,"n_cols":35,"rows_kept":79,"cut":false,"hidden":false,"merged":[]}
["Tax Floor",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"Unprofiled tax allowance (notional floor)"]
[]
[null,null,"Profits attributable to corporation tax"]
[]
[null,null,null,null,"Annuitised allowances except tax (floor)",null,"£m nominal prices",null,null,null,{"$f":"'Allowances Floor'!K34* 'Tax Deductions'!K$12","v":16.01894715834203},{"$f":"'Allowances Floor'!L34* 'Tax Deductions'!L$12","v":16.704558096719072},{"$f":"'Allowances Floor'!M34* 'Tax Deductions'!M$12","v":17.419513183258648},{"$f":"'Allowances Floor'!N34* 'Tax Deductions'!N$12","v":18.165068347502118},{"$f":"'Allowances Floor'!O34* 'Tax Deductions'!O$12","v":18.942533272775204},{"$f":"'Allowances Floor'!P34* 'Tax Deductions'!P$12","v":19.753273696849984},{"$f":"'Allowances Floor'!Q34* 'Tax Deductions'!Q$12","v":20.598713811075161},{"$f":"'Allowances Floor'!R34* 'Tax Deductions'!R$12","v":21.480338762189177},{"$f":"'Allowances Floor'!S34* 'Tax Deductions'!S$12","v":22.399697261210871},{"$f":"'Allowances Floor'!T34* 'Tax Deductions'!T$12","v":23.358404303990696},{"$f":"'Allowances Floor'!U34* 'Tax Deductions'!U$12","v":24.358144008201499},{"$f":"'Allowances Floor'!V34* 'Tax Deductions'!V$12","v":25.400672571752519},{"$f":"'Allowances Floor'!W34* 'Tax Deductions'!W$12","v":26.487821357823524},{"$f":"'Allowances Floor'!X34* 'Tax Deductions'!X$12","v":27.621500111938371},{"$f":"'Allowances Floor'!Y34* 'Tax Deductions'!Y$12","v":28.803700316729334},{"$f":"'Allowances Floor'!Z34* 'Tax Deductions'!Z$12","v":30.036498690285349},{"$f":"'Allowances Floor'!AA34* 'Tax Deductions'!AA$12","v":31.322060834229561},{"$f":"'Allowances Floor'!AB34* 'Tax Deductions'!AB$12","v":32.662645037934581},{"$f":"'Allowances Floor'!AC34* 'Tax Deductions'!AC$12","v":34.060606245558176},{"$f":"'Allowances Floor'!AD34* 'Tax Deductions'!AD$12","v":35.518400192868071},{"$f":"'Allowances Floor'!AE34* 'Tax Deductions'!AE$12","v":37.038587721122816},{"$f":"'Allowances Floor'!AF34* 'Tax Deductions'!AF$12","v":38.623839275586874},{"$f":"'Allowances Floor'!AG34* 'Tax Deductions'!AG$12","v":40.27693959658199},{"$f":"'Allowances Floor'!AH34* 'Tax Deductions'!AH$12","v":42.000792611315696},{"$f":"'Allowances Floor'!AI34* 'Tax Deductions'!AI$12","v":43.798426535080004}]
[null,null,null,null,"Less tax deductions",null,"£m nominal prices",null,null,null,{"$f":"-'Tax Deductions'!K20","v":-25.923633033005412},{"$f":"-'Tax Deductions'!L20","v":-22.55494977298649},{"$f":"-'Tax Deductions'!M20","v":-22.040793962619944},{"$f":"-'Tax Deductions'!N20","v":-21.577372296714309},{"$f":"-'Tax Deductions'!O20","v":-21.162583331047578},{"$f":"-'Tax Deductions'!P20","v":-20.79449516742293},{"$f":"-'Tax Deductions'!Q20","v":-20.618340100443934},{"$f":"-'Tax Deductions'!R20","v":-20.3296754062},{"$f":"-'Tax Deductions'!S20","v":-20.083383109358785},{"$f":"-'Tax Deductions'!T20","v":-19.878101325834045},{"$f":"-'Tax Deductions'!U20","v":-19.712604091853638},{"$f":"-'Tax Deductions'!V20","v":-19.585795654202993},{"$f":"-'Tax Deductions'!W20","v":-19.496705211988147},{"$f":"-'Tax Deductions'!X20","v":-19.444482087634828},{"$f":"-'Tax Deductions'!Y20","v":-19.633949098691154},{"$f":"-'Tax Deductions'!Z20","v":-19.855389555618114},{"$f":"-'Tax Deductions'!AA20","v":-19.885346763142465},{"$f":"-'Tax Deductions'!AB20","v":-19.951354421807878},{"$f":"-'Tax Deductions'!AC20","v":-20.053015649941525},{"$f":"-'Tax Deductions'!AD20","v":-20.190037948417583},{"$f":"-'Tax Deductions'!AE20","v":-20.362230555560025},{"$f":"-'Tax Deductions'!AF20","v":-20.569502121364447},{"$f":"-'Tax Deductions'!AG20","v":-21.171154486589597},{"$f":"-'Tax Deductions'!AH20","v":-21.42714002197156},{"$f":"-'Tax Deductions'!AI20","v":-75.031873720423562}]
[null,null,null,null,"Profits attributable to corporation tax",null,"£m nominal prices",null,null,null,{"$f":"SUM(K9:K10)","v":-9.9046858746633824},{"$f":"SUM(L9:L10)","v":-5.8503916762674173},-4.621280779361296,-3.4123039492121912,-2.2200500582723741,-1.0412214705729461,-1.9626289368773087E-2,1.1506633559891775,2.3163141518520867,3.4803029781566508,4.645539916347861,5.8148769175495261,6.9911161458353774,8.1770180243035426,9.1697512180381793,10.181109134667235,11.436714071087096,12.711290616126703,14.007590595616652,15.328362244450489,16.676357165562791,18.054337154222427,19.105785109992393,20.573652589344135,-31.233447185343557]
[]
[null,null,"Tax losses"]
[]
[null,null,null,null,"Taxable losses brought forward",null,"£m nominal prices",null,null,null,{"$f":"J18","v":0},{"$f":"K18","v":-9.9046858746633824},-15.7550775509308,-20.376358330292096,-23.788662279504287,-26.008712337776661,-27.049933808349607,-27.06956009771838,-25.918896741729203,-23.602582589877116,-20.122279611720465,-15.476739695372604,-9.6618627778230781,-2.6707466319877007,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"In-year taxable loss",null,"£m nominal prices",null,null,null,{"$f":"MIN(K11, 0)","v":-9.9046858746633824},-5.8503916762674173,-4.621280779361296,-3.4123039492121912,-2.2200500582723741,-1.0412214705729461,-1.9626289368773087E-2,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,-31.233447185343557]
[null,null,null,null,"Profits used to offset losses",null,"£m nominal prices",null,null,null,{"$f":"IF(K11 >= 0, MIN(K11, -K15), 0)","v":0},0,0,0,0,0,0,1.1506633559891775,2.3163141518520867,3.4803029781566508,4.645539916347861,5.8148769175495261,6.9911161458353774,2.6707466319877007,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Taxable losses carried forward",null,"£m nominal prices",null,null,null,{"$f":"SUM(K15:K17)","v":-9.9046858746633824},{"$f":"SUM(L15:L17)","v":-15.7550775509308},-20.376358330292096,-23.788662279504287,-26.008712337776661,-27.049933808349607,-27.06956009771838,-25.918896741729203,-23.602582589877116,-20.122279611720465,-15.476739695372604,-9.6618627778230781,-2.6707466319877007,0,0,0,0,0,0,0,0,0,0,0,-31.233447185343557]
[]
[null,null,"Tax allowance"]
[]
[null,null,null,null,"Profits attributable to corporation tax (after taxable losses)",null,"£m nominal prices",null,null,null,{"$f":"MAX(K11 - K17,0)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,5.506271392315842,9.1697512180381793,10.181109134667235,11.436714071087096,12.711290616126703,14.007590595616652,15.328362244450489,16.676357165562791,18.054337154222427,19.105785109992393,20.573652589344135,0]
[null,null,null,null,"Corporation tax rate",null,{"$f":"Inputs!G189","v":"%"},null,null,null,{"$f":"Inputs!K189","v":0.25},{"$f":"Inputs!L189","v":0.25},{"$f":"Inputs!M189","v":0.25},{"$f":"Inputs!N189","v":0.25},{"$f":"Inputs!O189","v":0.25},{"$f":"Inputs!P189","v":0.25},{"$f":"Inputs!Q189","v":0.25},{"$f":"Inputs!R189","v":0.25},{"$f":"Inputs!S189","v":0.25},{"$f":"Inputs!T189","v":0.25},{"$f":"Inputs!U189","v":0.25},{"$f":"Inputs!V189","v":0.25},{"$f":"Inputs!W189","v":0.25},{"$f":"Inputs!X189","v":0.25},{"$f":"Inputs!Y189","v":0.25},{"$f":"Inputs!Z189","v":0.25},{"$f":"Inputs!AA189","v":0.25},{"$f":"Inputs!AB189","v":0.25},{"$f":"Inputs!AC189","v":0.25},{"$f":"Inputs!AD189","v":0.25},{"$f":"Inputs!AE189","v":0.25},{"$f":"Inputs!AF189","v":0.25},{"$f":"Inputs!AG189","v":0.25},{"$f":"Inputs!AH189","v":0.25},{"$f":"Inputs!AI189","v":0.25}]
[null,null,null,null,"Corporation tax charge after losses",null,"£m nominal prices",null,null,null,{"$f":"K22 * K23","v":0},{"$f":"L22 * L23","v":0},0,0,0,0,0,0,0,0,0,0,0,1.3765678480789605,2.2924378045095448,2.5452772836668087,2.8591785177717739,3.1778226540316759,3.5018976489041629,3.8320905611126221,4.1690892913906978,4.5135842885556068,4.7764462774980982,5.1434131473360338,0]
[]
[null,null,null,null,"Grossing-up factor for tax on tax charge after losses",null,"scalar",null,null,null,{"$f":"1 / (1 - K23)","v":1.3333333333333333},1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,"£m nominal prices",null,null,null,{"$f":"K24 * K26","v":0},0,0,0,0,0,0,0,0,0,0,0,0,1.8354237974386138,3.0565837393460598,3.3937030448890781,3.8122380236956985,4.2370968720422342,4.6691968652055502,5.1094540814834959,5.5587857218542638,6.0181123847408085,6.3685950366641304,6.8578841964480448,0]
[]
[null,"Profiled tax allowance (notional floor)"]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Tax Floor'!K28 / 'Tax Deductions'!K$12","v":0},{"$f":"'Tax Floor'!L28 / 'Tax Deductions'!L$12","v":0},{"$f":"'Tax Floor'!M28 / 'Tax Deductions'!M$12","v":0},{"$f":"'Tax Floor'!N28 / 'Tax Deductions'!N$12","v":0},{"$f":"'Tax Floor'!O28 / 'Tax Deductions'!O$12","v":0},{"$f":"'Tax Floor'!P28 / 'Tax Deductions'!P$12","v":0},{"$f":"'Tax Floor'!Q28 / 'Tax Deductions'!Q$12","v":0},{"$f":"'Tax Floor'!R28 / 'Tax Deductions'!R$12","v":0},{"$f":"'Tax Floor'!S28 / 'Tax Deductions'!S$12","v":0},{"$f":"'Tax Floor'!T28 / 'Tax Deductions'!T$12","v":0},{"$f":"'Tax Floor'!U28 / 'Tax Deductions'!U$12","v":0},{"$f":"'Tax Floor'!V28 / 'Tax Deductions'!V$12","v":0},{"$f":"'Tax Floor'!W28 / 'Tax Deductions'!W$12","v":0},{"$f":"'Tax Floor'!X28 / 'Tax Deductions'!X$12","v":0.97548330583286891},{"$f":"'Tax Floor'!Y28 / 'Tax Deductions'!Y$12","v":1.5578253222925114},{"$f":"'Tax Floor'!Z28 / 'Tax Deductions'!Z$12","v":1.6586519979567762},{"$f":"'Tax Floor'!AA28 / 'Tax Deductions'!AA$12","v":1.7867361500449475},{"$f":"'Tax Floor'!AB28 / 'Tax Deductions'!AB$12","v":1.9043544557843417},{"$f":"'Tax Floor'!AC28 / 'Tax Deductions'!AC$12","v":2.0124289481034587},{"$f":"'Tax Floor'!AD28 / 'Tax Deductions'!AD$12","v":2.1117954441132794},{"$f":"'Tax Floor'!AE28 / 'Tax Deductions'!AE$12","v":2.203211850807425},{"$f":"'Tax Floor'!AF28 / 'Tax Deductions'!AF$12","v":2.2873656599353609},{"$f":"'Tax Floor'!AG28 / 'Tax Deductions'!AG$12","v":2.3212286094280401},{"$f":"'Tax Floor'!AH28 / 'Tax Deductions'!AH$12","v":2.3969744532236605},{"$f":"'Tax Floor'!AI28 / 'Tax Deductions'!AI$12","v":0}]
[null,null,null,null,"Discount factor to start of operational period (floor)",null,{"$f":"'Allowances Floor'!G24","v":"scalar"},null,null,null,{"$f":"'Allowances Floor'!K24","v":1.008471157724889},{"$f":"'Allowances Floor'!L24","v":1.017014075962978},{"$f":"'Allowances Floor'!M24","v":1.0256293626088926},{"$f":"'Allowances Floor'!N24","v":1.0343176307068298},{"$f":"'Allowances Floor'!O24","v":1.0430794984941811},{"$f":"'Allowances Floor'!P24","v":1.0519155894455232},{"$f":"'Allowances Floor'!Q24","v":1.0608265323169859},{"$f":"'Allowances Floor'!R24","v":1.0698129611909901},{"$f":"'Allowances Floor'!S24","v":1.0788755155213696},{"$f":"'Allowances Floor'!T24","v":1.0880148401788721},{"$f":"'Allowances Floor'!U24","v":1.0972315854970471},{"$f":"'Allowances Floor'!V24","v":1.1065264073185228},{"$f":"'Allowances Floor'!W24","v":1.1158999670416729},{"$f":"'Allowances Floor'!X24","v":1.1253529316676811},{"$f":"'Allowances Floor'!Y24","v":1.1348859738480044},{"$f":"'Allowances Floor'!Z24","v":1.1444997719322352},{"$f":"'Allowances Floor'!AA24","v":1.1541950100163727},{"$f":"'Allowances Floor'!AB24","v":1.1639723779915012},{"$f":"'Allowances Floor'!AC24","v":1.1738325715928815},{"$f":"'Allowances Floor'!AD24","v":1.1837762924494568},{"$f":"'Allowances Floor'!AE24","v":1.1938042481337805},{"$f":"'Allowances Floor'!AF24","v":1.2039171522123642},{"$f":"'Allowances Floor'!AG24","v":1.2141157242964542},{"$f":"'Allowances Floor'!AH24","v":1.2244006900932376},{"$f":"'Allowances Floor'!AI24","v":1.2347727814574803}]
[]
[null,null,null,null,"Discounted unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K32*K33","v":0},{"$f":"L32*L33","v":0},0,0,0,0,0,0,0,0,0,0,0,1.0977629980119001,1.7679541079750181,1.8983268333764767,2.0622419485977432,2.2166159844380116,2.3622546473002402,2.499893381244072,2.630203667032593,2.7537987513777349,2.8182401543933762,2.9348571746629109,0]
[null,null,null,null,"NPV of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K35:AI35)","v":25.042149648410074}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"'Allowances Floor'!G31","v":"scalar"},null,{"$f":"'Allowances Floor'!I31","v":3.5779275382147847E-2}]
[]
[null,null,null,null,"Annuity of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I36 * I38","v":0.89598996843142098}]
[]
[null,"Unprofiled tax allowance (actual floor)"]
[]
[null,null,"Profits attributable to corporation tax"]
[]
[null,null,null,null,"Annuitised allowances except tax (floor)",null,"£m nominal prices",null,null,null,{"$f":"('Allowances Floor'!K67+'Allowances Floor'!K76)* 'Tax Deductions'!K$12","v":0},{"$f":"('Allowances Floor'!L67+'Allowances Floor'!L76)* 'Tax Deductions'!L$12","v":0},{"$f":"('Allowances Floor'!M67+'Allowances Floor'!M76)* 'Tax Deductions'!M$12","v":20.411278674243828},{"$f":"('Allowances Floor'!N67+'Allowances Floor'!N76)* 'Tax Deductions'!N$12","v":21.284881401501462},{"$f":"('Allowances Floor'!O67+'Allowances Floor'!O76)* 'Tax Deductions'!O$12","v":22.195874325485725},{"$f":"('Allowances Floor'!P67+'Allowances Floor'!P76)* 'Tax Deductions'!P$12","v":23.14585774661651},{"$f":"('Allowances Floor'!Q67+'Allowances Floor'!Q76)* 'Tax Deductions'!Q$12","v":24.136500458171696},{"$f":"('Allowances Floor'!R67+'Allowances Floor'!R76)* 'Tax Deductions'!R$12","v":25.169542677781443},{"$f":"('Allowances Floor'!S67+'Allowances Floor'!S76)* 'Tax Deductions'!S$12","v":26.24679910439049},{"$f":"('Allowances Floor'!T67+'Allowances Floor'!T76)* 'Tax Deductions'!T$12","v":27.370162106058402},{"$f":"('Allowances Floor'!U67+'Allowances Floor'!U76)* 'Tax Deductions'!U$12","v":28.541605044197699},{"$f":"('Allowances Floor'!V67+'Allowances Floor'!V76)* 'Tax Deductions'!V$12","v":29.763185740089359},{"$f":"('Allowances Floor'!W67+'Allowances Floor'!W76)* 'Tax Deductions'!W$12","v":31.037050089765181},{"$f":"('Allowances Floor'!X67+'Allowances Floor'!X76)* 'Tax Deductions'!X$12","v":32.36543583360713},{"$f":"('Allowances Floor'!Y67+'Allowances Floor'!Y76)* 'Tax Deductions'!Y$12","v":33.750676487285517},{"$f":"('Allowances Floor'!Z67+'Allowances Floor'!Z76)* 'Tax Deductions'!Z$12","v":35.195205440941336},{"$f":"('Allowances Floor'!AA67+'Allowances Floor'!AA76)* 'Tax Deductions'!AA$12","v":36.701560233813616},{"$f":"('Allowances Floor'!AB67+'Allowances Floor'!AB76)* 'Tax Deductions'!AB$12","v":38.27238701182084},{"$f":"('Allowances Floor'!AC67+'Allowances Floor'!AC76)* 'Tax Deductions'!AC$12","v":39.910445175926768},{"$f":"('Allowances Floor'!AD67+'Allowances Floor'!AD76)* 'Tax Deductions'!AD$12","v":41.618612229456431},{"$f":"('Allowances Floor'!AE67+'Allowances Floor'!AE76)* 'Tax Deductions'!AE$12","v":43.399888832877167},{"$f":"('Allowances Floor'!AF67+'Allowances Floor'!AF76)* 'Tax Deductions'!AF$12","v":45.25740407492431},{"$f":"('Allowances Floor'!AG67+'Allowances Floor'!AG76)* 'Tax Deductions'!AG$12","v":47.194420969331063},{"$f":"('Allowances Floor'!AH67+'Allowances Floor'!AH76)* 'Tax Deductions'!AH$12","v":49.214342186818428},{"$f":"('Allowances Floor'!AI67+'Allowances Floor'!AI76)* 'Tax Deductions'!AI$12","v":51.320716032414254}]
[null,null,null,null,"Less tax deductions",null,"£m nominal prices",null,null,null,{"$f":"-'Tax Deductions'!K30","v":-4.1727738818898121},{"$f":"-'Tax Deductions'!L30","v":0},{"$f":"-'Tax Deductions'!M30","v":-25.749992697391924},{"$f":"-'Tax Deductions'!N30","v":-25.401473789316121},{"$f":"-'Tax Deductions'!O30","v":-24.961809459409736},{"$f":"-'Tax Deductions'!P30","v":-24.536324058173378},{"$f":"-'Tax Deductions'!Q30","v":-24.29459746892525},{"$f":"-'Tax Deductions'!R30","v":-23.939167809026184},{"$f":"-'Tax Deductions'!S30","v":-23.811590668978255},{"$f":"-'Tax Deductions'!T30","v":-23.501899978915642},{"$f":"-'Tax Deductions'!U30","v":-23.267393428037312},{"$f":"-'Tax Deductions'!V30","v":-23.016965193944003},{"$f":"-'Tax Deductions'!W30","v":-22.776227608720909},{"$f":"-'Tax Deductions'!X30","v":-22.720630172629022},{"$f":"-'Tax Deductions'!Y30","v":-22.70614312691951},{"$f":"-'Tax Deductions'!Z30","v":-22.729294624858511},{"$f":"-'Tax Deductions'!AA30","v":-22.520500127241675},{"$f":"-'Tax Deductions'!AB30","v":-22.370499661731692},{"$f":"-'Tax Deductions'!AC30","v":-22.41648481035471},{"$f":"-'Tax Deductions'!AD30","v":-22.375716715964494},{"$f":"-'Tax Deductions'!AE30","v":-22.292952973338124},{"$f":"-'Tax Deductions'!AF30","v":-22.238161688186711},{"$f":"-'Tax Deductions'!AG30","v":-22.556715251008253},{"$f":"-'Tax Deductions'!AH30","v":-22.574719572067536},{"$f":"-'Tax Deductions'!AI30","v":-76.293361041774929}]
[null,null,null,null,"Profits attributable to corporation tax",null,"£m nominal prices",null,null,null,{"$f":"SUM(K46:K47)","v":-4.1727738818898121},{"$f":"SUM(L46:L47)","v":0},-5.3387140231480963,-4.1165923878146593,-2.7659351339240104,-1.3904663115568674,-0.1580970107535542,1.2303748687552591,2.4352084354122354,3.86826212714276,5.274211616160386,6.7462205461453557,8.2608224810442721,9.6448056609781077,11.044533360366007,12.465910816082825,14.181060106571941,15.901887350089147,17.493960365572057,19.242895513491938,21.106935859539043,23.019242386737599,24.63770571832281,26.639622614750891,-24.972645009360676]
[]
[null,null,"Tax losses"]
[]
[null,null,null,null,"Taxable losses brought forward",null,"£m nominal prices",null,null,null,{"$f":"J55","v":0},{"$f":"K55","v":-4.1727738818898121},-4.1727738818898121,-9.5114879050379084,-13.628080292852568,-16.394015426776576,-17.784481738333444,-17.942578749086998,-16.712203880331739,-14.276995444919503,-10.408733317776743,-5.1345217016163573,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"In-year taxable loss",null,"£m nominal prices",null,null,null,{"$f":"MIN(K48, 0)","v":-4.1727738818898121},0,-5.3387140231480963,-4.1165923878146593,-2.7659351339240104,-1.3904663115568674,-0.1580970107535542,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,-24.972645009360676]
[null,null,null,null,"Profits used to offset losses",null,"£m nominal prices",null,null,null,{"$f":"IF(K48 >= 0, MIN(K48, -K52), 0)","v":0},0,0,0,0,0,0,1.2303748687552591,2.4352084354122354,3.86826212714276,5.274211616160386,5.1345217016163573,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Taxable losses carried forward",null,"£m nominal prices",null,null,null,{"$f":"SUM(K52:K54)","v":-4.1727738818898121},{"$f":"SUM(L52:L54)","v":-4.1727738818898121},-9.5114879050379084,-13.628080292852568,-16.394015426776576,-17.784481738333444,-17.942578749086998,-16.712203880331739,-14.276995444919503,-10.408733317776743,-5.1345217016163573,0,0,0,0,0,0,0,0,0,0,0,0,0,-24.972645009360676]
[]
[null,null,"Tax allowance"]
[]
[null,null,null,null,"Profits attributable to corporation tax (after taxable losses)",null,"£m nominal prices",null,null,null,{"$f":"MAX(K48 - K54,0)","v":0},0,0,0,{"$f":"MAX(O48 - O54,0)","v":0},0,0,0,0,0,0,1.6116988445289984,8.2608224810442721,9.6448056609781077,11.044533360366007,12.465910816082825,14.181060106571941,15.901887350089147,17.493960365572057,19.242895513491938,21.106935859539043,23.019242386737599,24.63770571832281,26.639622614750891,0]
[null,null,null,null,"Corporation tax rate",null,{"$f":"Inputs!G189","v":"%"},null,null,null,{"$f":"Inputs!K189","v":0.25},{"$f":"Inputs!L189","v":0.25},{"$f":"Inputs!M189","v":0.25},{"$f":"Inputs!N189","v":0.25},{"$f":"Inputs!O189","v":0.25},{"$f":"Inputs!P189","v":0.25},{"$f":"Inputs!Q189","v":0.25},{"$f":"Inputs!R189","v":0.25},{"$f":"Inputs!S189","v":0.25},{"$f":"Inputs!T189","v":0.25},{"$f":"Inputs!U189","v":0.25},{"$f":"Inputs!V189","v":0.25},{"$f":"Inputs!W189","v":0.25},{"$f":"Inputs!X189","v":0.25},{"$f":"Inputs!Y189","v":0.25},{"$f":"Inputs!Z189","v":0.25},{"$f":"Inputs!AA189","v":0.25},{"$f":"Inputs!AB189","v":0.25},{"$f":"Inputs!AC189","v":0.25},{"$f":"Inputs!AD189","v":0.25},{"$f":"Inputs!AE189","v":0.25},{"$f":"Inputs!AF189","v":0.25},{"$f":"Inputs!AG189","v":0.25},{"$f":"Inputs!AH189","v":0.25},{"$f":"Inputs!AI189","v":0.25}]
[null,null,null,null,"Corporation tax charge after losses",null,"£m nominal prices",null,null,null,{"$f":"K59 * K60","v":0},{"$f":"L59 * L60","v":0},0,0,0,0,0,0,0,0,0,0.40292471113224959,2.065205620261068,2.4112014152445269,2.7611333400915017,3.1164777040207063,3.5452650266429853,3.9754718375222868,4.3734900913930144,4.8107238783729844,5.2767339648847607,5.7548105966843996,6.1594264295807024,6.6599056536877228,0]
[]
[null,null,null,null,"Grossing-up factor for tax on tax charge after losses",null,"scalar",null,null,null,{"$f":"1 / (1 - K60)","v":1.3333333333333333},1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333,1.3333333333333333]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,"£m nominal prices",null,null,null,{"$f":"K61 * K63","v":0},0,0,0,0,0,0,0,0,0,0,0.53723294817633271,2.7536074936814239,3.2149352203260357,3.6815111201220021,4.1553036053609418,4.7270200355239798,5.3006291166963821,5.8313201218573525,6.414298504497312,7.0356452865130139,7.6730807955791995,8.2125685727742699,8.8798742049169626,0]
[]
[null,"Profiled tax allowance (actual floor)"]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"'Tax Floor'!K65 / 'Tax Deductions'!K$12","v":0},{"$f":"'Tax Floor'!L65 / 'Tax Deductions'!L$12","v":0},{"$f":"'Tax Floor'!M65 / 'Tax Deductions'!M$12","v":0},{"$f":"'Tax Floor'!N65 / 'Tax Deductions'!N$12","v":0},{"$f":"'Tax Floor'!O65 / 'Tax Deductions'!O$12","v":0},{"$f":"'Tax Floor'!P65 / 'Tax Deductions'!P$12","v":0},{"$f":"'Tax Floor'!Q65 / 'Tax Deductions'!Q$12","v":0},{"$f":"'Tax Floor'!R65 / 'Tax Deductions'!R$12","v":0},{"$f":"'Tax Floor'!S65 / 'Tax Deductions'!S$12","v":0},{"$f":"'Tax Floor'!T65 / 'Tax Deductions'!T$12","v":0},{"$f":"'Tax Floor'!U65 / 'Tax Deductions'!U$12","v":0},{"$f":"'Tax Floor'!V65 / 'Tax Deductions'!V$12","v":0.31049039361350511},{"$f":"'Tax Floor'!W65 / 'Tax Deductions'!W$12","v":1.5261124679990024},{"$f":"'Tax Floor'!X65 / 'Tax Deductions'!X$12","v":1.7086602239432129},{"$f":"'Tax Floor'!Y65 / 'Tax Deductions'!Y$12","v":1.8763272124370223},{"$f":"'Tax Floor'!Z65 / 'Tax Deductions'!Z$12","v":2.0308797016075371},{"$f":"'Tax Floor'!AA65 / 'Tax Deductions'!AA$12","v":2.2154801266238091},{"$f":"'Tax Floor'!AB65 / 'Tax Deductions'!AB$12","v":2.3823568310288938},{"$f":"'Tax Floor'!AC65 / 'Tax Deductions'!AC$12","v":2.5133053408677197},{"$f":"'Tax Floor'!AD65 / 'Tax Deductions'!AD$12","v":2.6511024745420837},{"$f":"'Tax Floor'!AE65 / 'Tax Deductions'!AE$12","v":2.7885617199419848},{"$f":"'Tax Floor'!AF65 / 'Tax Deductions'!AF$12","v":2.9163864673280382},{"$f":"'Tax Floor'!AG65 / 'Tax Deductions'!AG$12","v":2.9933209786877222},{"$f":"'Tax Floor'!AH65 / 'Tax Deductions'!AH$12","v":3.1037023967319155},{"$f":"'Tax Floor'!AI65 / 'Tax Deductions'!AI$12","v":0}]
[null,null,null,null,"Discount factor to start of operational period (floor)",null,{"$f":"'Allowances Floor'!G57","v":"scalar"},null,null,null,{"$f":"'Allowances Floor'!K57","v":1.011623761399274},{"$f":"'Allowances Floor'!L57","v":1.0233826346276151},{"$f":"'Allowances Floor'!M57","v":1.0352781901926869},{"$f":"'Allowances Floor'!N57","v":1.0473120168573589},{"$f":"'Allowances Floor'!O57","v":1.0594857218519012},{"$f":"'Allowances Floor'!P57","v":1.0718009310886452},{"$f":"'Allowances Floor'!Q57","v":1.0842592893791394},{"$f":"'Allowances Floor'!R57","v":1.0968624606538289},{"$f":"'Allowances Floor'!S57","v":1.1096121281842894},{"$f":"'Allowances Floor'!T57","v":1.1225099948080441},{"$f":"'Allowances Floor'!U57","v":1.1355577831559931},{"$f":"'Allowances Floor'!V57","v":1.1487572358824869},{"$f":"'Allowances Floor'!W57","v":1.1621101158980744},{"$f":"'Allowances Floor'!X57","v":1.1756182066049561},{"$f":"'Allowances Floor'!Y57","v":1.1892833121351745},{"$f":"'Allowances Floor'!Z57","v":1.203107257591572},{"$f":"'Allowances Floor'!AA57","v":1.2170918892915514},{"$f":"'Allowances Floor'!AB57","v":1.2312390750136679},{"$f":"'Allowances Floor'!AC57","v":1.2455507042470895},{"$f":"'Allowances Floor'!AD57","v":1.2600286884439555},{"$f":"'Allowances Floor'!AE57","v":1.2746749612746682},{"$f":"'Allowances Floor'!AF57","v":1.2894914788861536},{"$f":"'Allowances Floor'!AG57","v":1.3044802201631229},{"$f":"'Allowances Floor'!AH57","v":1.3196431869923717},{"$f":"'Allowances Floor'!AI57","v":1.3349824045301484}]
[]
[null,null,null,null,"Discounted unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,null,null,{"$f":"K69*K70","v":0},{"$f":"L69*L70","v":0},0,0,0,0,0,0,0,0,0,0.35667808633551551,1.7735107370598171,2.0087320681693428,2.2314846418564609,2.443366108299434,2.6964428930004574,2.9332508209885084,3.1304492373057595,3.3404651739277869,3.5545098023790715,3.7606554987583971,3.9047280092974543,4.0957797222991674,0]
[null,null,null,null,"NPV of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"SUM(K72:AI72)","v":36.230052799677175}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"'Allowances Floor'!G64","v":"scalar"},null,{"$f":"'Allowances Floor'!I64","v":3.851370582182468E-2}]
[]
[null,null,null,null,"Annuity of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I73 * I75","v":1.3953535954359424}]
[]
[null,"End of sheet"]

{"sheet":"Cap Floor Levels","index":12,"n_rows":40,"n_cols":9,"rows_kept":40,"cut":false,"hidden":false,"merged":[]}
["Cap Floor Levels",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant"]
[]
[null,"Cap and floor levels and adjustments"]
[]
[null,null,"Cap and Notional Floor levels at FPA (Preliminary) / PCR (Final) and PCA adjustments at PCR"]
[null,null,"Relevant stage: FPA for preliminary levels; PCR for final levels"]
[null,null,null,null,"Cap at relevant stage excluding tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"'Allowances Cap'!$I33","v":27.105023636018199}]
[null,null,null,null,"Floor at relevant stage excluding tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"'Allowances Floor'!$I33","v":14.680158489204596}]
[]
[null,null,null,null,"Cap at relevant stage - tax element (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"IF(Inputs!$I$199=\"No\",'Tax Cap'!I40,0)","v":4.1329212886971254}]
[null,null,null,null,"Floor at relevant stage - tax element (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"IF(Inputs!$I$199=\"No\",'Tax Floor'!I40,0)","v":0.89598996843142098}]
[]
[null,null,null,null,"Cap at relevant stage - tax element (previously calculated through the model and fixed)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"}]
[null,null,null,null,"Floor at relevant stage - tax element (previously calculated through the model and fixed)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"}]
[]
[null,null,null,null,"Cap at relevant stage including tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I8+IF(Inputs!$I$199=\"Yes\",I14,I11)","v":31.237944924715325}]
[null,null,null,null,"Floor at relevant stage including tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I9+IF(Inputs!$I$199=\"Yes\",I15,I12)","v":15.576148457636016}]
[]
[null,null,null,null,"Preliminary Cap including tax (hardcoded at FPA)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},"PCL"]
[null,null,null,null,"Preliminary Floor including tax (hardcoded at FPA)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},"PFL"]
[]
[null,null,null,null,"Cap PCA adjustment (at PCR)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},"PCAC",{"$f":"I17-I20","v":31.237944924715325}]
[null,null,null,null,"Floor PCA adjustment (at PCR)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},"PCAF",{"$f":"I18-I21","v":15.576148457636016}]
[]
[null,null,"Actual floor level at FPA (Preliminary) / PCR (Final) "]
[null,null,"Relevant stage: FPA for preliminary levels; PCR for final levels"]
[null,null,null,null,"Floor at relevant stage excluding tax during debt tenor and tail period (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"'Allowances Floor'!$I66","v":17.20144545676493}]
[]
[null,null,null,null,"Floor at relevant stage - tax element during debt tenor and tail period (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"IF(Inputs!$I$199=\"No\",'Tax Floor'!I77,0)","v":1.3953535954359424}]
[]
[null,null,null,null,"Floor at relevant stage - tax element during debt tenor and tail period (previously calculated through the model and fixed)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"}]
[]
[null,null,null,null,"Floor at relevant stage including tax during debt tenor and tail period (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I28+IF(Inputs!$I$199=\"Yes\",I32,I30)","v":18.596799052200872}]
[]
[null,null,null,null,"Preliminary Floor including tax during debt tenor and tail period (hardcoded at FPA)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"}]
[]
[null,null,null,null,"Floor adjustment during debt tenor and tail period (at PCR)",null,{"$f":"Inputs!$I$11","v":"£m 20/21 prices"},null,{"$f":"I34-I36","v":18.596799052200872}]
[]
[null,"End of sheet"]