{"text_format":"1","workbook":"xlsx","n_sheets":13,"sheets":["Cover","Version Control","Inputs","Data Sources","Pre Op RAV","Finance","Op Rav","Allowances Cap","Allowances Floor","Tax Deductions","Tax Cap","Tax Floor","Cap Floor Levels"],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":2,"defined_names":88,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Cover","index":0,"n_rows":41,"n_cols":7,"rows_kept":41,"cut":false,"hidden":false,"merged":[[4,2,4,6]]}
[]
["Cap and Floor Financial Model 1 (CFFM1)"]
[null,"Regime design model"]
[null,null,{"$f":"MID(CELL(\"filename\"),SEARCH(\"[\",CELL(\"filename\"))+1,SEARCH(\"]\",CELL(\"filename\"))-SEARCH(\"[\",CELL(\"filename\"))-1)","v":"IFA2CFFM1_PCR_decision.xlsm"}]
[null,null,"DISCLAIMER: In the event of any inconsistency between this model and the licence, licence conditions take precedence."]
[null,null,"For guidance on the use of the CFFM1, please refer to the CFFM1 Handbook (CFFM1H)"]
[]
[null,"Model key"]
[]
[null,null,null,null,"Sample",null,"Calculated value"]
[null,null,null,null,"Sample",null,"Formula changes in cells to the right"]
[null,null,null,null,"Sample",null,"Import from other sheet"]
[null,null,null,null,"Sample",null,"Export to other sheet"]
[null,null,null,null,"Sample",null,"Import from & export to other sheet"]
[null,null,null,null,"Sample",null,"Initial input"]
[null,null,null,null,"Sample",null,"Initial input for non-GB indexed portion (to be left empty if GB-indexed only)"]
[null,null,null,null,"Sample",null,"Updated input"]
[null,null,null,null,"Sample",null,"Notes and instructions"]
[null,null,null,null,"Sample",null,"Cell intentionally blank"]
[]
[null,"Contents"]
[]
[null,null,null,null,"Cover",null,"Model key and content directory"]
[null,null,null,null,"Version Control",null,"Version control and log of changes"]
[null,null,null,null,"Inputs",null,"Input data"]
[null,null,null,null,"Data Sources",null,"Sources of input data"]
[null,null,null,null,"Pre Op RAV",null,"Pre-operational RAV balances"]
[null,null,null,null,"Finance",null,"Interest during construction and transaction costs"]
[null,null,null,null,"Op RAV",null,"Operational RAV balances, return on RAV and RAV depreciation"]
[null,null,null,null,"Allowances Cap",null,"Cap allowances (excluding tax) and annuitisation"]
[null,null,null,null,"Allowances Floor",null,"Floor allowances (excluding tax) and annuitisation"]
[null,null,null,null,"Tax Deductions",null,"Tax calculations"]
[null,null,null,null,"Tax Cap",null,"Tax allowances at cap and annuitisation"]
[null,null,null,null,"Tax Floor",null,"Tax allowances at floor and annuitisation"]
[null,null,null,null,"Cap Floor Levels",null,"Cap and Floor values"]
[]
[null,"Checks"]
[]
[null,null,null,null,"Depreciation",null,{"$f":"'Op Rav'!I27","v":"TRUE"}]
[]
[null,"End of sheet"]

{"sheet":"Version Control","index":1,"n_rows":8,"n_cols":12,"rows_kept":8,"cut":false,"hidden":false,"merged":[]}
["Data Sources"]
[null,"Version number","File pathname","Based on version","Author or editor","Date","Description of changes","Rationale for changes","Location of changes","Impact of changes on outputs","Quality assurance performed? By?","Comments on QA performed"]
[]
[null,1.1000000000000001,"link","N/a","Andrew Stone & Neill Aitken (NGV)","2017-01-31","N/a","N/a","N/a","N/a","Internal (ORE) and external (BDO)","Comments reflected in version 1.1"]
[null,2.1,"link",1.1000000000000001,"Martin Namor","2019-03-20","CFFM split into CFFM1 (up to PCR) & CFFM2 (operations)","Simplification and standardisation","Throughout the model","No impact","Internal (ORE - Svitlana Voronkova)","Comments reflected in version 2.2"]
[null,2.2000000000000002,"link",2.1,"Martin Namor","2019-09-05","Minor changes","Reflecting comments from QA and tidying up","Throughout the model","No impact","Internal (ORE - Svitlana Voronkova)","Further comments reflected in version 2.2"]
[null,2.2999999999999998,null,2.2000000000000002,"Martin Namor","2020-08-14","Minor changes to three formulas","Allowing all construction costs to be transferred into the operational RAV; simplifying formulas used to calculate IDC","Inputs sheet and Finance sheet","Potential small impact if construction costs are incurred in the period after the period in which operations start","Internal (ORE - Svitlana Voronkova)","Comments reflected in version 2.3"]
[null,2.4,null,2.2999999999999998,"Vanessa Simpson & Neill Aitken (NGV) ","2022-06-28","All Nemo input parameters replaced with IFA2 input parameters to generate C + F levels for IFA2 Project.","Implementing the regime for IFA2","Multiple sheets","Medium","Internal (ORE - Rahmatullah Kawsary)","Comments reflected in version 2.4"]

{"sheet":"Inputs","index":2,"n_rows":125,"n_cols":50,"rows_kept":125,"cut":false,"hidden":false,"merged":[]}
["Inputs",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[]
[null,"Indexation, currency and base year price term"]
[]
[null,null,null,null,"GB indexed portion of interconnector",null,"choice %",null,1]
[null,null,null,null,"Non-GB indexed portion of interconnector",null,"%",null,{"$f":"100%-I6","v":0}]
[]
[null,null,null,null,"Currency of cost inputs",null,"choice",null,"£"]
[]
[null,null,null,null,"Base year price term",null,"choice",null,"£m 16/17 prices"]
[]
[null,"Variables set after financial close"]
[]
[null,null,"Actual values"]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"$I$84","v":"2009-04-01"},{"$f":"+K18+1","v":"2010-04-01"},{"$f":"+L18+1","v":"2011-04-01"},{"$f":"+M18+1","v":"2012-04-01"},{"$f":"+N18+1","v":"2013-04-01"},{"$f":"+O18+1","v":"2014-04-01"},{"$f":"+P18+1","v":"2015-04-01"},{"$f":"+Q18+1","v":"2016-04-01"},{"$f":"+R18+1","v":"2017-04-01"},{"$f":"+S18+1","v":"2018-04-01"},{"$f":"+T18+1","v":"2019-04-01"},{"$f":"+U18+1","v":"2020-04-01"},{"$f":"+V18+1","v":"2021-04-01"},{"$f":"+W18+1","v":"2022-04-01"},{"$f":"+X18+1","v":"2023-04-01"},{"$f":"+Y18+1","v":"2024-04-01"},{"$f":"+Z18+1","v":"2025-04-01"},{"$f":"+AA18+1","v":"2026-04-01"},{"$f":"+AB18+1","v":"2027-04-01"},{"$f":"+AC18+1","v":"2028-04-01"},{"$f":"+AD18+1","v":"2029-04-01"},{"$f":"+AE18+1","v":"2030-04-01"},{"$f":"+AF18+1","v":"2031-04-01"},{"$f":"+AG18+1","v":"2032-04-01"},{"$f":"+AH18+1","v":"2033-04-01"},{"$f":"+AI18+1","v":"2034-04-01"},{"$f":"+AJ18+1","v":"2035-04-01"},{"$f":"+AK18+1","v":"2036-04-01"},{"$f":"+AL18+1","v":"2037-04-01"},{"$f":"+AM18+1","v":"2038-04-01"},{"$f":"+AN18+1","v":"2039-04-01"},{"$f":"+AO18+1","v":"2040-04-01"},{"$f":"+AP18+1","v":"2041-04-01"},{"$f":"+AQ18+1","v":"2042-04-01"},{"$f":"+AR18+1","v":"2043-04-01"},{"$f":"+AS18+1","v":"2044-04-01"},{"$f":"+AT18+1","v":"2045-04-01"},{"$f":"+AU18+1","v":"2046-04-01"},{"$f":"+AV18+1","v":"2047-04-01"},{"$f":"+AW18+1","v":"2048-04-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"EOMONTH(K17,11)","v":"2010-03-31"},{"$f":"DATE(YEAR(K18) + 1, MONTH(K18), DAY(K18))","v":"2011-03-31"},{"$f":"DATE(YEAR(L18) + 1, MONTH(L18), DAY(L18))","v":"2012-03-31"},{"$f":"DATE(YEAR(M18) + 1, MONTH(M18), DAY(M18))","v":"2013-03-31"},{"$f":"DATE(YEAR(N18) + 1, MONTH(N18), DAY(N18))","v":"2014-03-31"},{"$f":"DATE(YEAR(O18) + 1, MONTH(O18), DAY(O18))","v":"2015-03-31"},{"$f":"DATE(YEAR(P18) + 1, MONTH(P18), DAY(P18))","v":"2016-03-31"},{"$f":"DATE(YEAR(Q18) + 1, MONTH(Q18), DAY(Q18))","v":"2017-03-31"},{"$f":"DATE(YEAR(R18) + 1, MONTH(R18), DAY(R18))","v":"2018-03-31"},{"$f":"DATE(YEAR(S18) + 1, MONTH(S18), DAY(S18))","v":"2019-03-31"},{"$f":"DATE(YEAR(T18) + 1, MONTH(T18), DAY(T18))","v":"2020-03-31"},{"$f":"DATE(YEAR(U18) + 1, MONTH(U18), DAY(U18))","v":"2021-03-31"},{"$f":"DATE(YEAR(V18) + 1, MONTH(V18), DAY(V18))","v":"2022-03-31"},{"$f":"DATE(YEAR(W18) + 1, MONTH(W18), DAY(W18))","v":"2023-03-31"},{"$f":"DATE(YEAR(X18) + 1, MONTH(X18), DAY(X18))","v":"2024-03-31"},{"$f":"DATE(YEAR(Y18) + 1, MONTH(Y18), DAY(Y18))","v":"2025-03-31"},{"$f":"DATE(YEAR(Z18) + 1, MONTH(Z18), DAY(Z18))","v":"2026-03-31"},{"$f":"DATE(YEAR(AA18) + 1, MONTH(AA18), DAY(AA18))","v":"2027-03-31"},{"$f":"DATE(YEAR(AB18) + 1, MONTH(AB18), DAY(AB18))","v":"2028-03-31"},{"$f":"DATE(YEAR(AC18) + 1, MONTH(AC18), DAY(AC18))","v":"2029-03-31"},{"$f":"DATE(YEAR(AD18) + 1, MONTH(AD18), DAY(AD18))","v":"2030-03-31"},{"$f":"DATE(YEAR(AE18) + 1, MONTH(AE18), DAY(AE18))","v":"2031-03-31"},{"$f":"DATE(YEAR(AF18) + 1, MONTH(AF18), DAY(AF18))","v":"2032-03-31"},{"$f":"DATE(YEAR(AG18) + 1, MONTH(AG18), DAY(AG18))","v":"2033-03-31"},{"$f":"DATE(YEAR(AH18) + 1, MONTH(AH18), DAY(AH18))","v":"2034-03-31"},{"$f":"DATE(YEAR(AI18) + 1, MONTH(AI18), DAY(AI18))","v":"2035-03-31"},{"$f":"DATE(YEAR(AJ18) + 1, MONTH(AJ18), DAY(AJ18))","v":"2036-03-31"},{"$f":"DATE(YEAR(AK18) + 1, MONTH(AK18), DAY(AK18))","v":"2037-03-31"},{"$f":"DATE(YEAR(AL18) + 1, MONTH(AL18), DAY(AL18))","v":"2038-03-31"},{"$f":"DATE(YEAR(AM18) + 1, MONTH(AM18), DAY(AM18))","v":"2039-03-31"},{"$f":"DATE(YEAR(AN18) + 1, MONTH(AN18), DAY(AN18))","v":"2040-03-31"},{"$f":"DATE(YEAR(AO18) + 1, MONTH(AO18), DAY(AO18))","v":"2041-03-31"},{"$f":"DATE(YEAR(AP18) + 1, MONTH(AP18), DAY(AP18))","v":"2042-03-31"},{"$f":"DATE(YEAR(AQ18) + 1, MONTH(AQ18), DAY(AQ18))","v":"2043-03-31"},{"$f":"DATE(YEAR(AR18) + 1, MONTH(AR18), DAY(AR18))","v":"2044-03-31"},{"$f":"DATE(YEAR(AS18) + 1, MONTH(AS18), DAY(AS18))","v":"2045-03-31"},{"$f":"DATE(YEAR(AT18) + 1, MONTH(AT18), DAY(AT18))","v":"2046-03-31"},{"$f":"DATE(YEAR(AU18) + 1, MONTH(AU18), DAY(AU18))","v":"2047-03-31"},{"$f":"DATE(YEAR(AV18) + 1, MONTH(AV18), DAY(AV18))","v":"2048-03-31"},{"$f":"DATE(YEAR(AW18) + 1, MONTH(AW18), DAY(AW18))","v":"2049-03-31"}]
[]
[null,null,null,null,"Development costs",null,{"$f":"CONCATENATE($I$9,\"m nominal\")","v":"£m nominal"},null,null,null,0,4.2914820000000006E-2,0.25841051999999998,0.70376327000000005,1.1280101900000001,1.88373799,3.8218000700000001,2.1858180343102038,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Capex",null,{"$f":"CONCATENATE($I$9,\"m nominal\")","v":"£m nominal"},null,null,null,0,0,0,0,0,0,0,1.57586067,56.9063338087714,122.21389563204501,117.04923724406007,36.618999013957392,11.843106274705663,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Spares",null,"£m nominal",null,null,null,0,0,0,0,0,0,0,0,0.19703424244839995,0.70869762715399998,2.4388806829314906,0.46020275837388985,1.4612415089732733,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,null,"Base year average UK RPI inflation index value (CHAW)",null,"Jan 1987 = 100","UK RPI index 2016/17",264.99166666666673]
[]
[]
[]
[null,null,null,null,"12-month average UK RPI inflation index value (CHAW)",null,{"$f":"G24","v":"Jan 1987 = 100"},"UK RPI index t",null,null,215.76666666666662,226.47499999999999,237.3416666666667,244.67499999999998,251.73333333333335,256.66666666666669,259.43333333333334,264.99166666666673,274.90833333333336,283.30833333333334,290.64166666666665,294.16666666666669,311.1583333333333,{"$f":"W28*(1+$I$103)","v":321.23986333333329},{"$f":"X28*(1+$I$103)","v":331.6480349053333},{"$f":"Y28*(1+$I$103)","v":342.39343123626611},{"$f":"Z28*(1+$I$103)","v":353.48697840832114},364.93995650875075,376.76401109963427,388.97116505926243,401.5738308071825,414.58482292533523,428.0173711881161,441.88513401461108,456.20221235668447,470.98316403704104,486.24301855184115,501.99729235292079,518.26200462515544,535.05369357501047,552.38943324684078,570.28685088403836,588.76414485268117,607.84010314590807,627.53412248783548,647.86622805644129,668.85709384546999,690.52806368606321,712.90117294949164,735.99917095305511]
[]
[]
[]
[null,null,null,null,"Indexation factor",null,null,{"$f":"IF(I6=100%,\"CRPIt\",\"PPPIt\")","v":"CRPIt"},null,null,{"$f":"IF($I$6=100%,(K28/$I$24),($I$6*(K28/$I$24)+$I$7*(K29/$I$25)/(K30/$I$26)))","v":0.81423944149187044},{"$f":"IF($I$6=100%,(L28/$I$24),($I$6*(L28/$I$24)+$I$7*(L29/$I$25)/(L30/$I$26)))","v":0.85464951728041738},{"$f":"IF($I$6=100%,(M28/$I$24),($I$6*(M28/$I$24)+$I$7*(M29/$I$25)/(M30/$I$26)))","v":0.89565709613509847},{"$f":"IF($I$6=100%,(N28/$I$24),($I$6*(N28/$I$24)+$I$7*(N29/$I$25)/(N30/$I$26)))","v":0.92333092235604863},0.9499669800937135,0.96858391773326191,{"$f":"IF($I$6=100%,(Q28/$I$24),($I$6*(Q28/$I$24)+$I$7*(Q29/$I$25)/(Q30/$I$26)))","v":0.97902449762571131},1,1.037422560457876,1.0691216704927826,1.0967954967137328,1.110097801817667,1.1742193150728006,1.2122640208811593,1.2515413751577089,1.2920913157128187,1.3339550743419142,1.3771752187505921,1.4217956958381113,1.4678618763832663,1.515420601178084,1.5645202286562538,1.6152106840647165,1.6675435102284133,1.7215719199598138,1.7773508501665118,1.8349370177119069,1.8943889770857725,1.9557671799433516,2.019134036573516,2.084553979358498,2.1520935282897131,2.2218213586062996,2.2938083706251438,2.3681277618333985,2.4448551013168003,2.5240684065994645,2.6058482229732873,2.6902777053976217,2.7774427030525044]
[]
[null,null,null,null,{"$f":"E20","v":"Development costs"},null,{"$f":"$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K20/K$32,K20/K$32/K$30)","v":0},{"$f":"IF($I$9=\"£\",L20/L$32,L20/L$32/L$30)","v":5.0213355454244421E-2},{"$f":"IF($I$9=\"£\",M20/M$32,M20/M$32/M$30)","v":0.28851501441241528},{"$f":"IF($I$9=\"£\",N20/N$32,N20/N$32/N$30)","v":0.76220047759715304},1.187420419485236,1.944837154026299,3.9036817559401911,2.1858180343102038,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,{"$f":"E21","v":"Capex"},null,{"$f":"$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K21/K$32,K21/K$32/K$30)","v":0},0,0,0,0,{"$f":"IF($I$9=\"£\",P21/P$32,P21/P$32/P$30)","v":0},0,1.57586067,54.853572669226772,114.31242954388328,106.71929051018915,32.987182709485303,10.08594060980116,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Spares",null,"£m 16/17 prices",null,null,null,{"$f":"IF($I$9=\"£\",K22/K$32,K22/K$32/K$30)","v":0},0,0,0,0,0,0,0,0.1899266990698921,0.66287836708739145,2.2236421376993003,0.4145605527912557,1.2444366143667782,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Ex-ante allowances for the operational period"]
[]
[null,null,null,null,"Operational Year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,null,null,null,"Replacement Capex",null,"£m 19/20 prices",null,null,null,0,0,0,0,0,0,2.6927209456896621,3.746453609488174,0,1.2400721199152915,0,0.75698153014861203,1.2747574877004189,4.300378786453444,0,0,25.7757780614217,0,0,1.2400721199152915,2.6927209456896621,0,0,0,0]
[null,null,null,null,"Decommissioning baseline",null,"£m 19/20 prices",null,null,null,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,28.747427544230945]
[null,null,null,null,"Controllable Opex",null,"£m 19/20 prices",null,null,null,15.840084485280682,11.903226737350177,16.272788449454247,15.961495606189811,17.027965934354022,16.984160377456536,16.791320854613431,18.100971695872676,18.474780111496148,19.497307881959738,19.146435810504407,19.179710071749117,19.213643003091111,19.248252509867296,20.11213769835604,19.596098673269957,19.634903630012719,19.674503636965607,19.714920416388328,20.597399181235456,20.13746478479597,20.182526810674819,20.22854061895077,20.275532350857169,20.499632393118592]
[null,null,null,null,"Non-controllable Opex baseline",null,"£m 19/20 prices",null,null,null,1.1642642677693742,1.149514665072112,1.138718554127788,1.1280240341819407,1.1174301474804942,1.1069359453149687,1.0965404879369025,1.0862428444730801,1.076042092841567,1.0659373196685384,1.0559276202058969,1.0460120982496695,1.0361898660591802,1.0264600442769873,1.0168217618495781,1.0072741559488176,0.99781637189414019,0.98844756307547676,0.97916689087691688,0.96997352460108877,0.96086664139426037,0.95184542617214707,0.94290907154642301,0.93405677775193086,0.9252877525745774]
[]
[null,null,null,null,{"$f":"E24","v":"Base year average UK RPI inflation index value (CHAW)"},null,{"$f":"G24","v":"Jan 1987 = 100"},{"$f":"H24","v":"UK RPI index 2016/17"},{"$f":"I24","v":264.99166666666673}]
[null,null,null,null,{"$f":"IF(E25=\"\",\"\",E25)","v":""},null,{"$f":"IF(G25=\"\",\"\",G25)","v":""},"",""]
[null,null,null,null,{"$f":"IF(E26=\"\",\"\",E26)","v":""},null,"","",""]
[]
[null,null,null,null,"2019/20 average UK RPI inflation index value (CHAW)",null,{"$f":"G24","v":"Jan 1987 = 100"},"UK RPI index 2019/20",290.64166666666665]
[null,null,null,null,null,null,{"$f":"IF(G25=\"\",\"\",G25)","v":""}]
[null,null,null,null,null,null,{"$f":"IF(G26=\"\",\"\",G26)","v":""}]
[]
[null,null,null,null,{"$f":"IF(E30=\"\",\"\",E30)","v":""},null,{"$f":"IF(G30=\"\",\"\",G30)","v":""},{"$f":"IF(H30=\"\",\"\",H30)","v":""}]
[]
[null,null,null,null,"Indexation conversion from 19/20 to 16/17 terms",null,null,null,{"$f":"IF($I$6=100%,(I51/$I$47),$I$6*(I51/$I$47)+$I$7*((I52/$I$48)/(I53/$I$49)))","v":1.0967954967137328}]
[]
[null,null,null,null,{"$f":"E42","v":"Replacement Capex"},null,{"$f":"$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"IF($I$9=\"£\",K42/$I$57,K42/K$55/$I$57)","v":0},0,0,0,0,0,2.4550802348821743,3.4158178263071504,0,1.1306320308852931,0,0.69017563658559289,1.1622563107889334,3.9208574427397171,0,0,23.500988232220344,0,0,1.1306320308852931,2.4550802348821743,0,0,0,0]
[null,null,null,null,{"$f":"E43","v":"Decommissioning baseline"},null,"£m 16/17 prices",null,null,null,{"$f":"IF($I$9=\"£\",K43/$I$57,K43/K$55/$I$57)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,26.210380723083983]
[null,null,null,null,"Controllable Opex",null,"£m 16/17 prices",null,null,null,{"$f":"IF($I$9=\"£\",K44/$I$57,K44/K$55/$I$57)","v":14.44214945515499},{"$f":"IF($I$9=\"£\",L44/$I$57,L44/L$55/$I$57)","v":10.852731227485117},14.836665994901963,14.55284567999627,15.525196798650219,15.485257213715073,15.309436357939406,16.503506579036483,16.844325279280508,17.776611902928519,17.456705345592507,17.487043053346056,17.517981301582545,17.549536415439125,18.337181141440603,17.866684110196161,17.902064412959103,17.938169600363263,17.975019477613689,18.779616841015756,18.360273036434535,18.401358203189748,18.443311154686921,18.486155725117051,18.690478265584147]
[null,null,null,null,"Non-controllable Opex baseline",null,"£m 16/17 prices",null,null,null,{"$f":"IF($I$9=\"£\",K45/$I$57,K45/K$55/$I$57)","v":1.0615144493734652},1.0480665434133698,1.0382232216850515,1.0284725252444746,1.0188135808622372,1.0092455235562319,0.9997674965136214,0.99037865101354716,0.98107814635057489,0.97186514975886296,0.96273883633705104,0.95369838897385817,0.94474299827438946,0.9358718624871385,0.92708418743168119,0.91837918642705685,0.90975608022082677,0.90121409691880305,0.89275247191544826,0.88437044782492846,0.87606727441282495,0.86784220852848915,0.85969451403803987,0.85162346175799697,0.84362832938954024]
[]
[null,"Variables set at financial close"]
[]
[null,null,"Finance"]
[]
[null,null,null,null,"Cap return rate",null,"real annual %",null,8.0999999999999989E-2]
[null,null,null,null,"Floor return rate",null,"real annual %",null,-2.0999999999999999E-3]
[null,null,null,null,"Interest during construction (IDC) rate",null,"real annual %",null,6.7500000000000004E-2]
[null,null,null,null,"Cost of debt (for tax)",null,"real annual %",null,{"$f":"I69","v":-2.0999999999999999E-3}]
[]
[null,null,null,null,"Pre-operational notional gearing",null,"%",null,0.40610000000000002]
[null,null,null,null,"Operational notional gearing",null,"%",null,0.5]
[]
[null,null,null,null,"Equity transaction costs",null,"%",null,0.05]
[null,null,null,null,"Debt transaction costs",null,"%",null,2.5000000000000001E-2]
[]
[null,null,"Model operation"]
[null,null,"Note: changes in these variables may require structural changes to the model."]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"$I$84","v":"2009-04-01"},{"$f":"+K82+1","v":"2010-04-01"},{"$f":"+L82+1","v":"2011-04-01"},{"$f":"+M82+1","v":"2012-04-01"},{"$f":"+N82+1","v":"2013-04-01"},{"$f":"+O82+1","v":"2014-04-01"},{"$f":"+P82+1","v":"2015-04-01"},{"$f":"+Q82+1","v":"2016-04-01"},{"$f":"+R82+1","v":"2017-04-01"},{"$f":"+S82+1","v":"2018-04-01"},{"$f":"+T82+1","v":"2019-04-01"},{"$f":"+U82+1","v":"2020-04-01"},{"$f":"+V82+1","v":"2021-04-01"},{"$f":"+W82+1","v":"2022-04-01"},{"$f":"+X82+1","v":"2023-04-01"},{"$f":"+Y82+1","v":"2024-04-01"},{"$f":"+Z82+1","v":"2025-04-01"},{"$f":"+AA82+1","v":"2026-04-01"},{"$f":"+AB82+1","v":"2027-04-01"},{"$f":"+AC82+1","v":"2028-04-01"},{"$f":"+AD82+1","v":"2029-04-01"},{"$f":"+AE82+1","v":"2030-04-01"},{"$f":"+AF82+1","v":"2031-04-01"},{"$f":"+AG82+1","v":"2032-04-01"},{"$f":"+AH82+1","v":"2033-04-01"},{"$f":"+AI82+1","v":"2034-04-01"},{"$f":"+AJ82+1","v":"2035-04-01"},{"$f":"+AK82+1","v":"2036-04-01"},{"$f":"+AL82+1","v":"2037-04-01"},{"$f":"+AM82+1","v":"2038-04-01"},{"$f":"+AN82+1","v":"2039-04-01"},{"$f":"+AO82+1","v":"2040-04-01"},{"$f":"+AP82+1","v":"2041-04-01"},{"$f":"+AQ82+1","v":"2042-04-01"},{"$f":"+AR82+1","v":"2043-04-01"},{"$f":"+AS82+1","v":"2044-04-01"},{"$f":"+AT82+1","v":"2045-04-01"},{"$f":"+AU82+1","v":"2046-04-01"},{"$f":"+AV82+1","v":"2047-04-01"},{"$f":"+AW82+1","v":"2048-04-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"EOMONTH(K81,11)","v":"2010-03-31"},{"$f":"DATE(YEAR(K82) + 1, MONTH(K82), DAY(K82))","v":"2011-03-31"},{"$f":"DATE(YEAR(L82) + 1, MONTH(L82), DAY(L82))","v":"2012-03-31"},{"$f":"DATE(YEAR(M82) + 1, MONTH(M82), DAY(M82))","v":"2013-03-31"},{"$f":"DATE(YEAR(N82) + 1, MONTH(N82), DAY(N82))","v":"2014-03-31"},{"$f":"DATE(YEAR(O82) + 1, MONTH(O82), DAY(O82))","v":"2015-03-31"},{"$f":"DATE(YEAR(P82) + 1, MONTH(P82), DAY(P82))","v":"2016-03-31"},{"$f":"DATE(YEAR(Q82) + 1, MONTH(Q82), DAY(Q82))","v":"2017-03-31"},{"$f":"DATE(YEAR(R82) + 1, MONTH(R82), DAY(R82))","v":"2018-03-31"},{"$f":"DATE(YEAR(S82) + 1, MONTH(S82), DAY(S82))","v":"2019-03-31"},{"$f":"DATE(YEAR(T82) + 1, MONTH(T82), DAY(T82))","v":"2020-03-31"},{"$f":"DATE(YEAR(U82) + 1, MONTH(U82), DAY(U82))","v":"2021-03-31"},{"$f":"DATE(YEAR(V82) + 1, MONTH(V82), DAY(V82))","v":"2022-03-31"},{"$f":"DATE(YEAR(W82) + 1, MONTH(W82), DAY(W82))","v":"2023-03-31"},{"$f":"DATE(YEAR(X82) + 1, MONTH(X82), DAY(X82))","v":"2024-03-31"},{"$f":"DATE(YEAR(Y82) + 1, MONTH(Y82), DAY(Y82))","v":"2025-03-31"},{"$f":"DATE(YEAR(Z82) + 1, MONTH(Z82), DAY(Z82))","v":"2026-03-31"},{"$f":"DATE(YEAR(AA82) + 1, MONTH(AA82), DAY(AA82))","v":"2027-03-31"},{"$f":"DATE(YEAR(AB82) + 1, MONTH(AB82), DAY(AB82))","v":"2028-03-31"},{"$f":"DATE(YEAR(AC82) + 1, MONTH(AC82), DAY(AC82))","v":"2029-03-31"},{"$f":"DATE(YEAR(AD82) + 1, MONTH(AD82), DAY(AD82))","v":"2030-03-31"},{"$f":"DATE(YEAR(AE82) + 1, MONTH(AE82), DAY(AE82))","v":"2031-03-31"},{"$f":"DATE(YEAR(AF82) + 1, MONTH(AF82), DAY(AF82))","v":"2032-03-31"},{"$f":"DATE(YEAR(AG82) + 1, MONTH(AG82), DAY(AG82))","v":"2033-03-31"},{"$f":"DATE(YEAR(AH82) + 1, MONTH(AH82), DAY(AH82))","v":"2034-03-31"},{"$f":"DATE(YEAR(AI82) + 1, MONTH(AI82), DAY(AI82))","v":"2035-03-31"},{"$f":"DATE(YEAR(AJ82) + 1, MONTH(AJ82), DAY(AJ82))","v":"2036-03-31"},{"$f":"DATE(YEAR(AK82) + 1, MONTH(AK82), DAY(AK82))","v":"2037-03-31"},{"$f":"DATE(YEAR(AL82) + 1, MONTH(AL82), DAY(AL82))","v":"2038-03-31"},{"$f":"DATE(YEAR(AM82) + 1, MONTH(AM82), DAY(AM82))","v":"2039-03-31"},{"$f":"DATE(YEAR(AN82) + 1, MONTH(AN82), DAY(AN82))","v":"2040-03-31"},{"$f":"DATE(YEAR(AO82) + 1, MONTH(AO82), DAY(AO82))","v":"2041-03-31"},{"$f":"DATE(YEAR(AP82) + 1, MONTH(AP82), DAY(AP82))","v":"2042-03-31"},{"$f":"DATE(YEAR(AQ82) + 1, MONTH(AQ82), DAY(AQ82))","v":"2043-03-31"},{"$f":"DATE(YEAR(AR82) + 1, MONTH(AR82), DAY(AR82))","v":"2044-03-31"},{"$f":"DATE(YEAR(AS82) + 1, MONTH(AS82), DAY(AS82))","v":"2045-03-31"},{"$f":"DATE(YEAR(AT82) + 1, MONTH(AT82), DAY(AT82))","v":"2046-03-31"},{"$f":"DATE(YEAR(AU82) + 1, MONTH(AU82), DAY(AU82))","v":"2047-03-31"},{"$f":"DATE(YEAR(AV82) + 1, MONTH(AV82), DAY(AV82))","v":"2048-03-31"},{"$f":"DATE(YEAR(AW82) + 1, MONTH(AW82), DAY(AW82))","v":"2049-03-31"}]
[]
[null,null,null,null,"Model start date",null,"date",null,"2009-04-01"]
[null,null,null,null,"Regime start date",null,"date",null,"2021-01-01"]
[null,null,null,null,"End date for IDC",null,"date",null,"2021-01-21"]
[null,null,null,null,"Start of operations",null,"date",null,"2021-01-22"]
[null,null,null,null,"Regime end date",null,"date",null,{"$f":"DATE(YEAR($I$85)+I89,MONTH($I$85),DAY($I$85))-1","v":"2045-12-31"}]
[null,null,null,null,"Number of operational years",null,"full years",null,25]
[]
[null,null,null,null,"Days in year",null,"days",null,null,null,{"$f":"K$82-K$81+1","v":365},365,{"$f":"M$82-M$81+1","v":366},{"$f":"N$82-N$81+1","v":365},365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365,365,365,366,365]
[null,null,null,null,"IDC flag",null,"flag",null,null,null,{"$f":"IF($I$86>=K$82,1,IF($I$86>=K$81,($I$86-K$81+1)/K$91,0))","v":1},1,1,1,1,1,1,1,1,1,1,0.81095890410958904,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"IF(OR(K92=1,K94=1),0,IF($I$87<K81,0,IF($I$87<K82,($I$87-(MAX($I$86+1,K81)))/K91,MIN(1,(K82-$I$86)/K91))))","v":0},{"$f":"IF(OR(L92=1,L94=1),0,IF($I$87<L81,0,IF($I$87<L82,($I$87-(MAX($I$86+1,L81)))/L91,MIN(1,(L82-$I$86)/L91))))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"IF(OR($I$87>K$82,$I$88<K$81),0,IF($I$87>=K$81,(K$82-$I$87+1)/K$91,IF($I$88<=K$82,($I$88-K$81+1)/K$91,1)))","v":0},0,0,0,0,0,0,0,0,0,0,0.18904109589041096,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,1,0.75342465753424659,0,0,0]
[null,null,null,null,"Transfer construction to operations flag",null,"flag","`",null,null,{"$f":"IF(AND(SUM(K34:K36)<>0,SUM(L34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(L34:L36)<>0,SUM(M34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(M34:M36)<>0,SUM(N34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(N34:N36)<>0,SUM(O34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(O34:O36)<>0,SUM(P34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(P34:P36)<>0,SUM(Q34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Q34:Q36)<>0,SUM(R34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(R34:R36)<>0,SUM(S34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(S34:S36)<>0,SUM(T34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(T34:T36)<>0,SUM(U34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(U34:U36)<>0,SUM(V34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(V34:V36)<>0,SUM(W34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(W34:W36)<>0,SUM(X34:$AX36)=0),1,0)","v":1},{"$f":"IF(AND(SUM(X34:X36)<>0,SUM(Y34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Y34:Y36)<>0,SUM(Z34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(Z34:Z36)<>0,SUM(AA34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AA34:AA36)<>0,SUM(AB34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AB34:AB36)<>0,SUM(AC34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AC34:AC36)<>0,SUM(AD34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AD34:AD36)<>0,SUM(AE34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AE34:AE36)<>0,SUM(AF34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AF34:AF36)<>0,SUM(AG34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AG34:AG36)<>0,SUM(AH34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AH34:AH36)<>0,SUM(AI34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AI34:AI36)<>0,SUM(AJ34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AJ34:AJ36)<>0,SUM(AK34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AK34:AK36)<>0,SUM(AL34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AL34:AL36)<>0,SUM(AM34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AM34:AM36)<>0,SUM(AN34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AN34:AN36)<>0,SUM(AO34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AO34:AO36)<>0,SUM(AP34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AP34:AP36)<>0,SUM(AQ34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AQ34:AQ36)<>0,SUM(AR34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AR34:AR36)<>0,SUM(AS34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AS34:AS36)<>0,SUM(AT34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AT34:AT36)<>0,SUM(AU34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AU34:AU36)<>0,SUM(AV34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AV34:AV36)<>0,SUM(AW34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AW34:AW36)<>0,SUM(AX34:$AX36)=0),1,0)","v":0},{"$f":"IF(AND(SUM(AX34:AX36)<>0,SUM($AX34:AZ36)=0),1,0)","v":0}]
[null,null,null,null,"Initial transaction costs flag",null,"flag",null,null,null,{"$f":"IF(AND(SUM($J35:K35)=0,L35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:L35)=0,M35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:M35)=0,N35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:N35)=0,O35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:O35)=0,P35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:P35)=0,Q35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Q35)=0,R35>0),1,0)","v":1},{"$f":"IF(AND(SUM($J35:R35)=0,S35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:S35)=0,T35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:T35)=0,U35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:U35)=0,V35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:V35)=0,W35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:W35)=0,X35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:X35)=0,Y35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Y35)=0,Z35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:Z35)=0,AA35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AA35)=0,AB35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AB35)=0,AC35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AC35)=0,AD35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AD35)=0,AE35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AE35)=0,AF35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AF35)=0,AG35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AG35)=0,AH35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AH35)=0,AI35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AI35)=0,AJ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AJ35)=0,AK35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AK35)=0,AL35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AL35)=0,AM35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AM35)=0,AN35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AN35)=0,AO35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AO35)=0,AP35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AP35)=0,AQ35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AQ35)=0,AR35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AR35)=0,AS35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AS35)=0,AT35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AT35)=0,AU35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AU35)=0,AV35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AV35)=0,AW35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AW35)=0,AX35>0),1,0)","v":0},{"$f":"IF(AND(SUM($J35:AX35)=0,AZ35>0),1,0)","v":0}]
[]
[null,null,"Tax - Financial years"]
[]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"K17","v":"2009-04-01"},{"$f":"+K101+1","v":"2010-04-01"},{"$f":"+L101+1","v":"2011-04-01"},{"$f":"+M101+1","v":"2012-04-01"},"2013-04-01","2014-04-01","2015-04-01","2016-04-01","2017-04-01","2018-04-01","2019-04-01","2020-04-01","2021-04-01","2022-04-01","2023-04-01","2024-04-01","2025-04-01","2026-04-01","2027-04-01","2028-04-01","2029-04-01","2030-04-01","2031-04-01","2032-04-01","2033-04-01","2034-04-01","2035-04-01","2036-04-01","2037-04-01","2038-04-01","2039-04-01","2040-04-01","2041-04-01","2042-04-01","2043-04-01","2044-04-01","2045-04-01","2046-04-01","2047-04-01","2048-04-01"]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"K18","v":"2010-03-31"},{"$f":"DATE(YEAR(K101) + 1, MONTH(K101), DAY(K101))","v":"2011-03-31"},"2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","2019-03-31","2020-03-31","2021-03-31","2022-03-31","2023-03-31","2024-03-31","2025-03-31","2026-03-31","2027-03-31","2028-03-31","2029-03-31","2030-03-31","2031-03-31","2032-03-31","2033-03-31","2034-03-31","2035-03-31","2036-03-31","2037-03-31","2038-03-31","2039-03-31","2040-03-31","2041-03-31","2042-03-31","2043-03-31","2044-03-31","2045-03-31","2046-03-31","2047-03-31","2048-03-31","2049-03-31"]
[]
[null,null,null,null,"Long-term expected UK RPI inflation",null,"%",null,3.2399999999999998E-2]
[null,null,null,null,{"$f":"E24","v":"Base year average UK RPI inflation index value (CHAW)"},null,{"$f":"G24","v":"Jan 1987 = 100"},{"$f":"H24","v":"UK RPI index 2016/17"},{"$f":"I24","v":264.99166666666673}]
[]
[null,null,null,null,{"$f":"E28","v":"12-month average UK RPI inflation index value (CHAW)"},null,{"$f":"G28","v":"Jan 1987 = 100"},{"$f":"H28","v":"UK RPI index t"},null,null,{"$f":"K28","v":215.76666666666662},{"$f":"L28","v":226.47499999999999},{"$f":"M28","v":237.3416666666667},244.67499999999998,251.73333333333335,256.66666666666669,259.43333333333334,264.99166666666673,274.90833333333336,283.30833333333334,290.64166666666665,294.16666666666669,311.1583333333333,321.23986333333329,331.6480349053333,342.39343123626611,353.48697840832114,364.93995650875075,376.76401109963427,388.97116505926243,401.5738308071825,414.58482292533523,428.0173711881161,441.88513401461108,456.20221235668447,470.98316403704104,486.24301855184115,501.99729235292079,518.26200462515544,535.05369357501047,552.38943324684078,570.28685088403836,588.76414485268117,607.84010314590807,627.53412248783548,647.86622805644129,668.85709384546999,690.52806368606321,712.90117294949164,735.99917095305511]
[null,null,null,null,"UK RPI inflation uplift from 2016/17 term",null,"scalar",null,null,null,{"$f":"K106/$I$104","v":0.81423944149187044},{"$f":"L106/$I$104","v":0.85464951728041738},0.89565709613509847,0.92333092235604863,0.9499669800937135,0.96858391773326191,0.97902449762571131,1,1.037422560457876,1.0691216704927826,1.0967954967137328,1.110097801817667,1.1742193150728006,1.2122640208811593,1.2515413751577089,1.2920913157128187,1.3339550743419142,1.3771752187505921,1.4217956958381113,1.4678618763832663,1.515420601178084,1.5645202286562538,1.6152106840647165,1.6675435102284133,1.7215719199598138,1.7773508501665118,1.8349370177119069,1.8943889770857725,1.9557671799433516,2.019134036573516,2.084553979358498,2.1520935282897131,2.2218213586062996,2.2938083706251438,2.3681277618333985,2.4448551013168003,2.5240684065994645,2.6058482229732873,2.6902777053976217,2.7774427030525044]
[]
[null,null,"Tax - Operational years"]
[]
[null,null,null,null,"Operational Year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,null,null,null,"Corporation tax rate",null,"%",null,null,null,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19,0.19]
[null,null,null,null,"Capital allowance rate (declining balance)",null,"%",null,null,null,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08,0.08]
[]
[null,null,null,null,{"$f":"E103","v":"Long-term expected UK RPI inflation"},null,"%",null,{"$f":"I103","v":3.2399999999999998E-2}]
[null,null,null,null,"Start of price base year",null,"date",null,"2016-04-01"]
[null,null,null,null,"End of price base year",null,"date",null,{"$f":"EOMONTH(I117,11)","v":"2017-03-31"}]
[null,null,null,null,"UK RPI uplift from 2016/17 term to start of regime",null,"scalar",null,{"$f":"(1+$I$116)^((I85-AVERAGE(I117,I118))/365.25)","v":1.1452965748301245}]
[]
[null,null,"Tax - Annuity"]
[]
[null,null,null,null,"Tax element of Cap and Floor annuity previously calculated and fixed",null,"choice",null,"No"]
[]
[null,"End of sheet"]

{"sheet":"Data Sources","index":3,"n_rows":72,"n_cols":12,"rows_kept":72,"cut":false,"hidden":false,"merged":[]}
["Data Sources",null,null,null,null,null,null,"Licence","Reference row in"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Inputs sheet",null,"Source","Link"]
[]
[null,"Indexation, currency and base year price term"]
[]
[null,null,null,null,{"$f":"Inputs!E6","v":"GB indexed portion of interconnector"},null,{"$f":"Inputs!G6","v":"choice %"},null,{"$f":"ROW(Inputs!E6)","v":6},null,"IFA2 licence - Special conditions - Schedule 1"]
[null,null,null,null,{"$f":"Inputs!E9","v":"Currency of cost inputs"},null,{"$f":"Inputs!G9","v":"choice"},null,{"$f":"ROW(Inputs!E9)","v":9},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E11","v":"Base year price term"},null,{"$f":"Inputs!G11","v":"choice"},null,{"$f":"ROW(Inputs!E11)","v":11},null,"IFA2 licence - Special conditions - Schedule 1"]
[]
[null,"Variables set after financial close"]
[]
[null,null,"Actual values"]
[]
[null,null,null,null,{"$f":"Inputs!E20","v":"Development costs"},null,{"$f":"Inputs!G20","v":"£m nominal"},null,{"$f":"ROW(Inputs!E20)","v":20},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E21","v":"Capex"},null,{"$f":"Inputs!G21","v":"£m nominal"},null,{"$f":"ROW(Inputs!E21)","v":21},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E22","v":"Spares"},null,{"$f":"Inputs!G22","v":"£m nominal"},null,{"$f":"ROW(Inputs!E22)","v":22},null,"Post Construction Review (PCR) decision"]
[]
[null,null,null,null,{"$f":"Inputs!E24","v":"Base year average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G24","v":"Jan 1987 = 100"},{"$f":"Inputs!H24","v":"UK RPI index 2016/17"},{"$f":"ROW(Inputs!E24)","v":24},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[]
[]
[]
[null,null,null,null,{"$f":"Inputs!E28","v":"12-month average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G28","v":"Jan 1987 = 100"},{"$f":"Inputs!H28","v":"UK RPI index t"},{"$f":"ROW(Inputs!E28)","v":28},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[]
[null,null,"Ex-ante allowances for the operational period"]
[]
[null,null,null,null,{"$f":"Inputs!E42","v":"Replacement Capex"},null,{"$f":"Inputs!G42","v":"£m 19/20 prices"},null,{"$f":"ROW(Inputs!E42)","v":42},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E43","v":"Decommissioning baseline"},null,{"$f":"Inputs!G43","v":"£m 19/20 prices"},null,{"$f":"ROW(Inputs!E43)","v":43},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E44","v":"Controllable Opex"},null,{"$f":"Inputs!G44","v":"£m 19/20 prices"},null,{"$f":"ROW(Inputs!E44)","v":44},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E45","v":"Non-controllable Opex baseline"},null,{"$f":"Inputs!G45","v":"£m 19/20 prices"},null,{"$f":"ROW(Inputs!E45)","v":45},null,"Post Construction Review (PCR) decision"]
[]
[null,null,null,null,{"$f":"Inputs!E51","v":"2019/20 average UK RPI inflation index value (CHAW)"},null,{"$f":"Inputs!G51","v":"Jan 1987 = 100"},null,{"$f":"ROW(Inputs!E51)","v":51},null,"Office for National Statistics","RPI All Items Index: Jan 1987=100"]
[null,null,null,null,{"$f":"Inputs!E52","v":0},null,{"$f":"Inputs!G52","v":""},null,{"$f":"ROW(Inputs!E52)","v":52}]
[null,null,null,null,{"$f":"Inputs!E53","v":0},null,{"$f":"Inputs!G53","v":""},null,{"$f":"ROW(Inputs!E53)","v":53}]
[]
[null,null,null,null,{"$f":"Inputs!E55","v":""},null,{"$f":"Inputs!G55","v":""},{"$f":"Inputs!H55","v":""},{"$f":"ROW(Inputs!E55)","v":55}]
[]
[null,"Variables set at financial close"]
[]
[null,null,"Finance"]
[]
[null,null,null,null,{"$f":"Inputs!E68","v":"Cap return rate"},null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"ROW(Inputs!E68)","v":68},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E69","v":"Floor return rate"},null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"ROW(Inputs!E69)","v":69},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E70","v":"Interest during construction (IDC) rate"},null,{"$f":"Inputs!G70","v":"real annual %"},null,{"$f":"ROW(Inputs!E70)","v":70},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[]
[null,null,null,null,{"$f":"Inputs!E73","v":"Pre-operational notional gearing"},null,{"$f":"Inputs!G73","v":"%"},null,{"$f":"ROW(Inputs!E73)","v":73},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E74","v":"Operational notional gearing"},null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"ROW(Inputs!E74)","v":74},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[]
[null,null,null,null,{"$f":"Inputs!E76","v":"Equity transaction costs"},null,{"$f":"Inputs!G76","v":"%"},null,{"$f":"ROW(Inputs!E76)","v":76},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E77","v":"Debt transaction costs"},null,{"$f":"Inputs!G77","v":"%"},null,{"$f":"ROW(Inputs!E77)","v":77},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[]
[null,null,"Model operation"]
[]
[null,null,null,null,{"$f":"Inputs!E85","v":"Regime start date"},null,{"$f":"Inputs!G85","v":"date"},null,{"$f":"ROW(Inputs!I85)","v":85},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E86","v":"End date for IDC"},null,{"$f":"Inputs!G86","v":"date"},null,{"$f":"ROW(Inputs!I86)","v":86},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E87","v":"Start of operations"},null,{"$f":"Inputs!G87","v":"date"},null,{"$f":"ROW(Inputs!I87)","v":87},null,"Post Construction Review (PCR) decision"]
[null,null,null,null,{"$f":"Inputs!E89","v":"Number of operational years"},null,{"$f":"Inputs!G89","v":"full years"},null,{"$f":"ROW(Inputs!I89)","v":89},null,"IFA2 licence - Special conditions - Schedule 1"]
[]
[null,null,"Tax - Financial years"]
[]
[null,null,null,null,{"$f":"Inputs!E103","v":"Long-term expected UK RPI inflation"},null,{"$f":"Inputs!G103","v":"%"},null,{"$f":"ROW(Inputs!E103)","v":103},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[]
[null,null,"Tax - Operational years"]
[]
[null,null,null,null,{"$f":"Inputs!E113","v":"Corporation tax rate"},null,{"$f":"Inputs!G113","v":"%"},null,{"$f":"ROW(Inputs!E113)","v":113},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E114","v":"Capital allowance rate (declining balance)"},null,{"$f":"Inputs!G114","v":"%"},null,{"$f":"ROW(Inputs!E114)","v":114},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[null,null,null,null,{"$f":"Inputs!E117","v":"Start of price base year"},null,{"$f":"Inputs!G117","v":"date"},null,{"$f":"ROW(Inputs!E117)","v":117},null,"IFA2 licence - Special conditions - Schedule 1"]
[]
[null,null,"Tax - Annuity"]
[]
[null,null,null,null,{"$f":"Inputs!E123","v":"Tax element of Cap and Floor annuity previously calculated and fixed"},null,{"$f":"Inputs!G123","v":"choice"},null,{"$f":"ROW(Inputs!E123)","v":123},null,"IFA2 Cap and Floor Financial Model 1 Handbook (IFA2CFFM1H)"]
[]
[null,"End of sheet"]

{"sheet":"Pre Op RAV","index":4,"n_rows":26,"n_cols":50,"rows_kept":26,"cut":false,"hidden":false,"merged":[]}
["Pre Op RAV",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"Inputs!K17","v":"2009-04-01"},{"$f":"+K4+1","v":"2010-04-01"},{"$f":"+L4+1","v":"2011-04-01"},{"$f":"+M4+1","v":"2012-04-01"},"2013-04-01","2014-04-01","2015-04-01","2016-04-01","2017-04-01","2018-04-01","2019-04-01","2020-04-01","2021-04-01","2022-04-01","2023-04-01","2024-04-01","2025-04-01","2026-04-01","2027-04-01","2028-04-01","2029-04-01","2030-04-01","2031-04-01","2032-04-01","2033-04-01","2034-04-01","2035-04-01","2036-04-01","2037-04-01","2038-04-01","2039-04-01","2040-04-01","2041-04-01","2042-04-01","2043-04-01","2044-04-01","2045-04-01","2046-04-01","2047-04-01","2048-04-01"]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"Inputs!K18","v":"2010-03-31"},{"$f":"DATE(YEAR(K4) + 1, MONTH(K4), DAY(K4))","v":"2011-03-31"},"2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","2019-03-31","2020-03-31","2021-03-31","2022-03-31","2023-03-31","2024-03-31","2025-03-31","2026-03-31","2027-03-31","2028-03-31","2029-03-31","2030-03-31","2031-03-31","2032-03-31","2033-03-31","2034-03-31","2035-03-31","2036-03-31","2037-03-31","2038-03-31","2039-03-31","2040-03-31","2041-03-31","2042-03-31","2043-03-31","2044-03-31","2045-03-31","2046-03-31","2047-03-31","2048-03-31","2049-03-31"]
[]
[null,"Flags"]
[]
[null,null,null,null,"IDC flag",null,"flag",null,null,null,{"$f":"Inputs!K92","v":1},{"$f":"Inputs!L92","v":1},{"$f":"Inputs!M92","v":1},{"$f":"Inputs!N92","v":1},{"$f":"Inputs!O92","v":1},{"$f":"Inputs!P92","v":1},{"$f":"Inputs!Q92","v":1},{"$f":"Inputs!R92","v":1},{"$f":"Inputs!S92","v":1},{"$f":"Inputs!T92","v":1},{"$f":"Inputs!U92","v":1},{"$f":"Inputs!V92","v":0.81095890410958904},{"$f":"Inputs!W92","v":0},{"$f":"Inputs!X92","v":0},{"$f":"Inputs!Y92","v":0},{"$f":"Inputs!Z92","v":0},{"$f":"Inputs!AA92","v":0},{"$f":"Inputs!AB92","v":0},{"$f":"Inputs!AC92","v":0},{"$f":"Inputs!AD92","v":0},{"$f":"Inputs!AE92","v":0},{"$f":"Inputs!AF92","v":0},{"$f":"Inputs!AG92","v":0},{"$f":"Inputs!AH92","v":0},{"$f":"Inputs!AI92","v":0},{"$f":"Inputs!AJ92","v":0},{"$f":"Inputs!AK92","v":0},{"$f":"Inputs!AL92","v":0},{"$f":"Inputs!AM92","v":0},{"$f":"Inputs!AN92","v":0},{"$f":"Inputs!AO92","v":0},{"$f":"Inputs!AP92","v":0},{"$f":"Inputs!AQ92","v":0},{"$f":"Inputs!AR92","v":0},{"$f":"Inputs!AS92","v":0},{"$f":"Inputs!AT92","v":0},{"$f":"Inputs!AU92","v":0},{"$f":"Inputs!AV92","v":0},{"$f":"Inputs!AW92","v":0},{"$f":"Inputs!AX92","v":0}]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"Inputs!K93","v":0},{"$f":"Inputs!L93","v":0},{"$f":"Inputs!M93","v":0},{"$f":"Inputs!N93","v":0},{"$f":"Inputs!O93","v":0},{"$f":"Inputs!P93","v":0},{"$f":"Inputs!Q93","v":0},{"$f":"Inputs!R93","v":0},{"$f":"Inputs!S93","v":0},{"$f":"Inputs!T93","v":0},{"$f":"Inputs!U93","v":0},{"$f":"Inputs!V93","v":0},{"$f":"Inputs!W93","v":0},{"$f":"Inputs!X93","v":0},{"$f":"Inputs!Y93","v":0},{"$f":"Inputs!Z93","v":0},{"$f":"Inputs!AA93","v":0},{"$f":"Inputs!AB93","v":0},{"$f":"Inputs!AC93","v":0},{"$f":"Inputs!AD93","v":0},{"$f":"Inputs!AE93","v":0},{"$f":"Inputs!AF93","v":0},{"$f":"Inputs!AG93","v":0},{"$f":"Inputs!AH93","v":0},{"$f":"Inputs!AI93","v":0},{"$f":"Inputs!AJ93","v":0},{"$f":"Inputs!AK93","v":0},{"$f":"Inputs!AL93","v":0},{"$f":"Inputs!AM93","v":0},{"$f":"Inputs!AN93","v":0},{"$f":"Inputs!AO93","v":0},{"$f":"Inputs!AP93","v":0},{"$f":"Inputs!AQ93","v":0},{"$f":"Inputs!AR93","v":0},{"$f":"Inputs!AS93","v":0},{"$f":"Inputs!AT93","v":0},{"$f":"Inputs!AU93","v":0},{"$f":"Inputs!AV93","v":0},{"$f":"Inputs!AW93","v":0},{"$f":"Inputs!AX93","v":0}]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"Inputs!K94","v":0},{"$f":"Inputs!L94","v":0},{"$f":"Inputs!M94","v":0},{"$f":"Inputs!N94","v":0},{"$f":"Inputs!O94","v":0},{"$f":"Inputs!P94","v":0},{"$f":"Inputs!Q94","v":0},{"$f":"Inputs!R94","v":0},{"$f":"Inputs!S94","v":0},{"$f":"Inputs!T94","v":0},{"$f":"Inputs!U94","v":0},{"$f":"Inputs!V94","v":0.18904109589041096},{"$f":"Inputs!W94","v":1},{"$f":"Inputs!X94","v":1},{"$f":"Inputs!Y94","v":1},{"$f":"Inputs!Z94","v":1},{"$f":"Inputs!AA94","v":1},{"$f":"Inputs!AB94","v":1},{"$f":"Inputs!AC94","v":1},{"$f":"Inputs!AD94","v":1},{"$f":"Inputs!AE94","v":1},{"$f":"Inputs!AF94","v":1},{"$f":"Inputs!AG94","v":1},{"$f":"Inputs!AH94","v":1},{"$f":"Inputs!AI94","v":1},{"$f":"Inputs!AJ94","v":1},{"$f":"Inputs!AK94","v":1},{"$f":"Inputs!AL94","v":1},{"$f":"Inputs!AM94","v":1},{"$f":"Inputs!AN94","v":1},{"$f":"Inputs!AO94","v":1},{"$f":"Inputs!AP94","v":1},{"$f":"Inputs!AQ94","v":1},{"$f":"Inputs!AR94","v":1},{"$f":"Inputs!AS94","v":1},{"$f":"Inputs!AT94","v":1},{"$f":"Inputs!AU94","v":0.75342465753424659},{"$f":"Inputs!AV94","v":0},{"$f":"Inputs!AW94","v":0},{"$f":"Inputs!AX94","v":0}]
[null,null,null,null,"Transfer construction to operations flag",null,"flag",null,null,null,{"$f":"Inputs!K95","v":0},{"$f":"Inputs!L95","v":0},{"$f":"Inputs!M95","v":0},{"$f":"Inputs!N95","v":0},{"$f":"Inputs!O95","v":0},{"$f":"Inputs!P95","v":0},{"$f":"Inputs!Q95","v":0},{"$f":"Inputs!R95","v":0},{"$f":"Inputs!S95","v":0},{"$f":"Inputs!T95","v":0},{"$f":"Inputs!U95","v":0},{"$f":"Inputs!V95","v":0},{"$f":"Inputs!W95","v":1},{"$f":"Inputs!X95","v":0},{"$f":"Inputs!Y95","v":0},{"$f":"Inputs!Z95","v":0},{"$f":"Inputs!AA95","v":0},{"$f":"Inputs!AB95","v":0},{"$f":"Inputs!AC95","v":0},{"$f":"Inputs!AD95","v":0},{"$f":"Inputs!AE95","v":0},{"$f":"Inputs!AF95","v":0},{"$f":"Inputs!AG95","v":0},{"$f":"Inputs!AH95","v":0},{"$f":"Inputs!AI95","v":0},{"$f":"Inputs!AJ95","v":0},{"$f":"Inputs!AK95","v":0},{"$f":"Inputs!AL95","v":0},{"$f":"Inputs!AM95","v":0},{"$f":"Inputs!AN95","v":0},{"$f":"Inputs!AO95","v":0},{"$f":"Inputs!AP95","v":0},{"$f":"Inputs!AQ95","v":0},{"$f":"Inputs!AR95","v":0},{"$f":"Inputs!AS95","v":0},{"$f":"Inputs!AT95","v":0},{"$f":"Inputs!AU95","v":0},{"$f":"Inputs!AV95","v":0},{"$f":"Inputs!AW95","v":0},{"$f":"Inputs!AX95","v":0}]
[]
[null,"RAV"]
[]
[null,null,"Pre-operational"]
[]
[null,null,null,null,"Opening pre-operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,null,{"$f":"K24","v":0},{"$f":"L24","v":5.1852727397732445E-2},0.35328727538245136,1.1642190611115995,2.4689913184021601,4.6439806743996979,8.9885790187402055,13.479798566206394,71.23025142713432,194.76732962091927,{"$f":"U24","v":320.41383958350752},372.12479033008128,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,{"$f":"Inputs!E34","v":"Development costs"},null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K34","v":0},{"$f":"Inputs!L34","v":5.0213355454244421E-2},{"$f":"Inputs!M34","v":0.28851501441241528},{"$f":"Inputs!N34","v":0.76220047759715304},{"$f":"Inputs!O34","v":1.187420419485236},{"$f":"Inputs!P34","v":1.944837154026299},{"$f":"Inputs!Q34","v":3.9036817559401911},{"$f":"Inputs!R34","v":2.1858180343102038},{"$f":"Inputs!S34","v":0},{"$f":"Inputs!T34","v":0},{"$f":"Inputs!U34","v":0},{"$f":"Inputs!V34","v":0},{"$f":"Inputs!W34","v":0},{"$f":"Inputs!X34","v":0},{"$f":"Inputs!Y34","v":0},{"$f":"Inputs!Z34","v":0},{"$f":"Inputs!AA34","v":0},{"$f":"Inputs!AB34","v":0},{"$f":"Inputs!AC34","v":0},{"$f":"Inputs!AD34","v":0},{"$f":"Inputs!AE34","v":0},{"$f":"Inputs!AF34","v":0},{"$f":"Inputs!AG34","v":0},{"$f":"Inputs!AH34","v":0},{"$f":"Inputs!AI34","v":0},{"$f":"Inputs!AJ34","v":0},{"$f":"Inputs!AK34","v":0},{"$f":"Inputs!AL34","v":0},{"$f":"Inputs!AM34","v":0},{"$f":"Inputs!AN34","v":0},{"$f":"Inputs!AO34","v":0},{"$f":"Inputs!AP34","v":0},{"$f":"Inputs!AQ34","v":0},{"$f":"Inputs!AR34","v":0},{"$f":"Inputs!AS34","v":0},{"$f":"Inputs!AT34","v":0},{"$f":"Inputs!AU34","v":0},{"$f":"Inputs!AV34","v":0},{"$f":"Inputs!AW34","v":0},{"$f":"Inputs!AX34","v":0}]
[null,null,null,null,{"$f":"Inputs!E35","v":"Capex"},null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K35","v":0},{"$f":"Inputs!L35","v":0},{"$f":"Inputs!M35","v":0},{"$f":"Inputs!N35","v":0},{"$f":"Inputs!O35","v":0},{"$f":"Inputs!P35","v":0},{"$f":"Inputs!Q35","v":0},{"$f":"Inputs!R35","v":1.57586067},{"$f":"Inputs!S35","v":54.853572669226772},{"$f":"Inputs!T35","v":114.31242954388328},{"$f":"Inputs!U35","v":106.71929051018915},{"$f":"Inputs!V35","v":32.987182709485303},{"$f":"Inputs!W35","v":10.08594060980116},{"$f":"Inputs!X35","v":0},{"$f":"Inputs!Y35","v":0},{"$f":"Inputs!Z35","v":0},{"$f":"Inputs!AA35","v":0},{"$f":"Inputs!AB35","v":0},{"$f":"Inputs!AC35","v":0},{"$f":"Inputs!AD35","v":0},{"$f":"Inputs!AE35","v":0},{"$f":"Inputs!AF35","v":0},{"$f":"Inputs!AG35","v":0},{"$f":"Inputs!AH35","v":0},{"$f":"Inputs!AI35","v":0},{"$f":"Inputs!AJ35","v":0},{"$f":"Inputs!AK35","v":0},{"$f":"Inputs!AL35","v":0},{"$f":"Inputs!AM35","v":0},{"$f":"Inputs!AN35","v":0},{"$f":"Inputs!AO35","v":0},{"$f":"Inputs!AP35","v":0},{"$f":"Inputs!AQ35","v":0},{"$f":"Inputs!AR35","v":0},{"$f":"Inputs!AS35","v":0},{"$f":"Inputs!AT35","v":0},{"$f":"Inputs!AU35","v":0},{"$f":"Inputs!AV35","v":0},{"$f":"Inputs!AW35","v":0},{"$f":"Inputs!AX35","v":0}]
[null,null,null,null,{"$f":"Inputs!E36","v":"Spares"},null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K36","v":0},{"$f":"Inputs!L36","v":0},{"$f":"Inputs!M36","v":0},{"$f":"Inputs!N36","v":0},{"$f":"Inputs!O36","v":0},{"$f":"Inputs!P36","v":0},{"$f":"Inputs!Q36","v":0},{"$f":"Inputs!R36","v":0},{"$f":"Inputs!S36","v":0.1899266990698921},{"$f":"Inputs!T36","v":0.66287836708739145},{"$f":"Inputs!U36","v":2.2236421376993003},{"$f":"Inputs!V36","v":0.4145605527912557},{"$f":"Inputs!W36","v":1.2444366143667782},{"$f":"Inputs!X36","v":0},{"$f":"Inputs!Y36","v":0},{"$f":"Inputs!Z36","v":0},{"$f":"Inputs!AA36","v":0},{"$f":"Inputs!AB36","v":0},{"$f":"Inputs!AC36","v":0},{"$f":"Inputs!AD36","v":0},{"$f":"Inputs!AE36","v":0},{"$f":"Inputs!AF36","v":0},{"$f":"Inputs!AG36","v":0},{"$f":"Inputs!AH36","v":0},{"$f":"Inputs!AI36","v":0},{"$f":"Inputs!AJ36","v":0},{"$f":"Inputs!AK36","v":0},{"$f":"Inputs!AL36","v":0},{"$f":"Inputs!AM36","v":0},{"$f":"Inputs!AN36","v":0},{"$f":"Inputs!AO36","v":0},{"$f":"Inputs!AP36","v":0},{"$f":"Inputs!AQ36","v":0},{"$f":"Inputs!AR36","v":0},{"$f":"Inputs!AS36","v":0},{"$f":"Inputs!AT36","v":0},{"$f":"Inputs!AU36","v":0},{"$f":"Inputs!AV36","v":0},{"$f":"Inputs!AW36","v":0},{"$f":"Inputs!AX36","v":0}]
[null,null,null,null,{"$f":"Finance!E24","v":"Capitalised interest during construction"},null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Finance!K24","v":0},{"$f":"Finance!L24","v":1.6393719434880257E-3},{"$f":"Finance!M24","v":1.2919533572303646E-2},{"$f":"Finance!N24","v":4.8731308131995117E-2},{"$f":"Finance!O24","v":0.11735183780532464},{"$f":"Finance!P24","v":0.23015220197123862},{"$f":"Finance!Q24","v":0.4409165884003165},{"$f":"Finance!R24","v":0.72954084315598511},{"$f":"Finance!S24","v":2.7069534926312731},{"$f":"Finance!T24","v":8.5617702828142725},{"$f":"Finance!U24","v":16.703577314699796},{"$f":"Finance!V24","v":18.309207484297168},{"$f":"Finance!W24","v":0},{"$f":"Finance!X24","v":0},{"$f":"Finance!Y24","v":0},{"$f":"Finance!Z24","v":0},{"$f":"Finance!AA24","v":0},{"$f":"Finance!AB24","v":0},{"$f":"Finance!AC24","v":0},{"$f":"Finance!AD24","v":0},{"$f":"Finance!AE24","v":0},{"$f":"Finance!AF24","v":0},{"$f":"Finance!AG24","v":0},{"$f":"Finance!AH24","v":0},{"$f":"Finance!AI24","v":0},{"$f":"Finance!AJ24","v":0},{"$f":"Finance!AK24","v":0},{"$f":"Finance!AL24","v":0},{"$f":"Finance!AM24","v":0},{"$f":"Finance!AN24","v":0},{"$f":"Finance!AO24","v":0},{"$f":"Finance!AP24","v":0},{"$f":"Finance!AQ24","v":0},{"$f":"Finance!AR24","v":0},{"$f":"Finance!AS24","v":0},{"$f":"Finance!AT24","v":0},{"$f":"Finance!AU24","v":0},{"$f":"Finance!AV24","v":0},{"$f":"Finance!AW24","v":0},{"$f":"Finance!AX24","v":0}]
[null,null,null,null,"Closing pre-operational RAV (after IDC)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K17:K21)","v":0},5.1852727397732445E-2,0.35328727538245136,1.1642190611115995,2.4689913184021601,4.6439806743996979,8.9885790187402055,13.479798566206394,71.23025142713432,194.76732962091927,320.41383958350752,{"$f":"SUM(V17:V21)","v":372.12479033008128},383.45516755424927,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Pre-operational RAV transfers",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"-K22*K11","v":0},0,0,0,0,0,0,0,0,0,0,{"$f":"-V22*V11","v":0},{"$f":"-W22*W11","v":-383.45516755424927},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Closing pre-operational RAV (after IDC) - adjusted for RAV transfers",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K22:K23)","v":0},5.1852727397732445E-2,0.35328727538245136,1.1642190611115995,2.4689913184021601,4.6439806743996979,8.9885790187402055,13.479798566206394,71.23025142713432,194.76732962091927,{"$f":"SUM(U22:U23)","v":320.41383958350752},{"$f":"SUM(V22:V23)","v":372.12479033008128},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"End of sheet"]

{"sheet":"Finance","index":5,"n_rows":48,"n_cols":50,"rows_kept":48,"cut":false,"hidden":false,"merged":[]}
["Finance",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Year commencing",null,null,null,null,null,{"$f":"Inputs!K17","v":"2009-04-01"},{"$f":"+K4+1","v":"2010-04-01"},"2011-04-01","2012-04-01","2013-04-01","2014-04-01","2015-04-01","2016-04-01","2017-04-01","2018-04-01","2019-04-01","2020-04-01","2021-04-01","2022-04-01","2023-04-01","2024-04-01","2025-04-01","2026-04-01","2027-04-01","2028-04-01","2029-04-01","2030-04-01","2031-04-01","2032-04-01","2033-04-01","2034-04-01","2035-04-01","2036-04-01","2037-04-01","2038-04-01","2039-04-01","2040-04-01","2041-04-01","2042-04-01","2043-04-01","2044-04-01",{"$f":"+AT4+1","v":"2045-04-01"},{"$f":"+AU4+1","v":"2046-04-01"},{"$f":"+AV4+1","v":"2047-04-01"},{"$f":"+AW4+1","v":"2048-04-01"}]
[null,null,null,null,"Year ending",null,null,null,null,null,{"$f":"Inputs!K18","v":"2010-03-31"},{"$f":"DATE(YEAR(K4) + 1, MONTH(K4), DAY(K4))","v":"2011-03-31"},"2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","2019-03-31","2020-03-31","2021-03-31","2022-03-31","2023-03-31","2024-03-31","2025-03-31","2026-03-31","2027-03-31","2028-03-31","2029-03-31","2030-03-31","2031-03-31","2032-03-31","2033-03-31","2034-03-31","2035-03-31","2036-03-31","2037-03-31","2038-03-31","2039-03-31","2040-03-31","2041-03-31","2042-03-31","2043-03-31","2044-03-31","2045-03-31",{"$f":"DATE(YEAR(AT4) + 1, MONTH(AT4), DAY(AT4))","v":"2046-03-31"},{"$f":"DATE(YEAR(AU4) + 1, MONTH(AU4), DAY(AU4))","v":"2047-03-31"},{"$f":"DATE(YEAR(AV4) + 1, MONTH(AV4), DAY(AV4))","v":"2048-03-31"},{"$f":"DATE(YEAR(AW4) + 1, MONTH(AW4), DAY(AW4))","v":"2049-03-31"}]
[]
[null,"Flags"]
[]
[null,null,null,null,"IDC flag",null,"flag",null,null,null,{"$f":"Inputs!K92","v":1},{"$f":"Inputs!L92","v":1},{"$f":"Inputs!M92","v":1},{"$f":"Inputs!N92","v":1},{"$f":"Inputs!O92","v":1},{"$f":"Inputs!P92","v":1},{"$f":"Inputs!Q92","v":1},{"$f":"Inputs!R92","v":1},{"$f":"Inputs!S92","v":1},{"$f":"Inputs!T92","v":1},{"$f":"Inputs!U92","v":1},{"$f":"Inputs!V92","v":0.81095890410958904},{"$f":"Inputs!W92","v":0},{"$f":"Inputs!X92","v":0},{"$f":"Inputs!Y92","v":0},{"$f":"Inputs!Z92","v":0},{"$f":"Inputs!AA92","v":0},{"$f":"Inputs!AB92","v":0},{"$f":"Inputs!AC92","v":0},{"$f":"Inputs!AD92","v":0},{"$f":"Inputs!AE92","v":0},{"$f":"Inputs!AF92","v":0},{"$f":"Inputs!AG92","v":0},{"$f":"Inputs!AH92","v":0},{"$f":"Inputs!AI92","v":0},{"$f":"Inputs!AJ92","v":0},{"$f":"Inputs!AK92","v":0},{"$f":"Inputs!AL92","v":0},{"$f":"Inputs!AM92","v":0},{"$f":"Inputs!AN92","v":0},{"$f":"Inputs!AO92","v":0},{"$f":"Inputs!AP92","v":0},{"$f":"Inputs!AQ92","v":0},{"$f":"Inputs!AR92","v":0},{"$f":"Inputs!AS92","v":0},{"$f":"Inputs!AT92","v":0},{"$f":"Inputs!AU92","v":0},{"$f":"Inputs!AV92","v":0},{"$f":"Inputs!AW92","v":0},{"$f":"Inputs!AX92","v":0}]
[null,null,null,null,"Post-IDC and pre-operations flag",null,"flag",null,null,null,{"$f":"Inputs!K93","v":0},{"$f":"Inputs!L93","v":0},{"$f":"Inputs!M93","v":0},{"$f":"Inputs!N93","v":0},{"$f":"Inputs!O93","v":0},{"$f":"Inputs!P93","v":0},{"$f":"Inputs!Q93","v":0},{"$f":"Inputs!R93","v":0},{"$f":"Inputs!S93","v":0},{"$f":"Inputs!T93","v":0},{"$f":"Inputs!U93","v":0},{"$f":"Inputs!V93","v":0},{"$f":"Inputs!W93","v":0},{"$f":"Inputs!X93","v":0},{"$f":"Inputs!Y93","v":0},{"$f":"Inputs!Z93","v":0},{"$f":"Inputs!AA93","v":0},{"$f":"Inputs!AB93","v":0},{"$f":"Inputs!AC93","v":0},{"$f":"Inputs!AD93","v":0},{"$f":"Inputs!AE93","v":0},{"$f":"Inputs!AF93","v":0},{"$f":"Inputs!AG93","v":0},{"$f":"Inputs!AH93","v":0},{"$f":"Inputs!AI93","v":0},{"$f":"Inputs!AJ93","v":0},{"$f":"Inputs!AK93","v":0},{"$f":"Inputs!AL93","v":0},{"$f":"Inputs!AM93","v":0},{"$f":"Inputs!AN93","v":0},{"$f":"Inputs!AO93","v":0},{"$f":"Inputs!AP93","v":0},{"$f":"Inputs!AQ93","v":0},{"$f":"Inputs!AR93","v":0},{"$f":"Inputs!AS93","v":0},{"$f":"Inputs!AT93","v":0},{"$f":"Inputs!AU93","v":0},{"$f":"Inputs!AV93","v":0},{"$f":"Inputs!AW93","v":0},{"$f":"Inputs!AX93","v":0}]
[null,null,null,null,"Operations flag",null,"flag",null,null,null,{"$f":"Inputs!K94","v":0},{"$f":"Inputs!L94","v":0},{"$f":"Inputs!M94","v":0},{"$f":"Inputs!N94","v":0},{"$f":"Inputs!O94","v":0},{"$f":"Inputs!P94","v":0},{"$f":"Inputs!Q94","v":0},{"$f":"Inputs!R94","v":0},{"$f":"Inputs!S94","v":0},{"$f":"Inputs!T94","v":0},{"$f":"Inputs!U94","v":0},{"$f":"Inputs!V94","v":0.18904109589041096},{"$f":"Inputs!W94","v":1},{"$f":"Inputs!X94","v":1},{"$f":"Inputs!Y94","v":1},{"$f":"Inputs!Z94","v":1},{"$f":"Inputs!AA94","v":1},{"$f":"Inputs!AB94","v":1},{"$f":"Inputs!AC94","v":1},{"$f":"Inputs!AD94","v":1},{"$f":"Inputs!AE94","v":1},{"$f":"Inputs!AF94","v":1},{"$f":"Inputs!AG94","v":1},{"$f":"Inputs!AH94","v":1},{"$f":"Inputs!AI94","v":1},{"$f":"Inputs!AJ94","v":1},{"$f":"Inputs!AK94","v":1},{"$f":"Inputs!AL94","v":1},{"$f":"Inputs!AM94","v":1},{"$f":"Inputs!AN94","v":1},{"$f":"Inputs!AO94","v":1},{"$f":"Inputs!AP94","v":1},{"$f":"Inputs!AQ94","v":1},{"$f":"Inputs!AR94","v":1},{"$f":"Inputs!AS94","v":1},{"$f":"Inputs!AT94","v":1},{"$f":"Inputs!AU94","v":0.75342465753424659},{"$f":"Inputs!AV94","v":0},{"$f":"Inputs!AW94","v":0},{"$f":"Inputs!AX94","v":0}]
[null,null,null,null,"Transfer construction to operations flag",null,"flag",null,null,null,{"$f":"Inputs!K95","v":0},{"$f":"Inputs!L95","v":0},{"$f":"Inputs!M95","v":0},{"$f":"Inputs!N95","v":0},{"$f":"Inputs!O95","v":0},{"$f":"Inputs!P95","v":0},{"$f":"Inputs!Q95","v":0},{"$f":"Inputs!R95","v":0},{"$f":"Inputs!S95","v":0},{"$f":"Inputs!T95","v":0},{"$f":"Inputs!U95","v":0},{"$f":"Inputs!V95","v":0},{"$f":"Inputs!W95","v":1},{"$f":"Inputs!X95","v":0},{"$f":"Inputs!Y95","v":0},{"$f":"Inputs!Z95","v":0},{"$f":"Inputs!AA95","v":0},{"$f":"Inputs!AB95","v":0},{"$f":"Inputs!AC95","v":0},{"$f":"Inputs!AD95","v":0},{"$f":"Inputs!AE95","v":0},{"$f":"Inputs!AF95","v":0},{"$f":"Inputs!AG95","v":0},{"$f":"Inputs!AH95","v":0},{"$f":"Inputs!AI95","v":0},{"$f":"Inputs!AJ95","v":0},{"$f":"Inputs!AK95","v":0},{"$f":"Inputs!AL95","v":0},{"$f":"Inputs!AM95","v":0},{"$f":"Inputs!AN95","v":0},{"$f":"Inputs!AO95","v":0},{"$f":"Inputs!AP95","v":0},{"$f":"Inputs!AQ95","v":0},{"$f":"Inputs!AR95","v":0},{"$f":"Inputs!AS95","v":0},{"$f":"Inputs!AT95","v":0},{"$f":"Inputs!AU95","v":0},{"$f":"Inputs!AV95","v":0},{"$f":"Inputs!AW95","v":0},{"$f":"Inputs!AX95","v":0}]
[null,null,null,null,"Initial transaction costs flag",null,"flag",null,null,null,{"$f":"Inputs!K96","v":0},{"$f":"Inputs!L96","v":0},{"$f":"Inputs!M96","v":0},{"$f":"Inputs!N96","v":0},{"$f":"Inputs!O96","v":0},{"$f":"Inputs!P96","v":0},{"$f":"Inputs!Q96","v":1},{"$f":"Inputs!R96","v":0},{"$f":"Inputs!S96","v":0},{"$f":"Inputs!T96","v":0},{"$f":"Inputs!U96","v":0},{"$f":"Inputs!V96","v":0},{"$f":"Inputs!W96","v":0},{"$f":"Inputs!X96","v":0},{"$f":"Inputs!Y96","v":0},{"$f":"Inputs!Z96","v":0},{"$f":"Inputs!AA96","v":0},{"$f":"Inputs!AB96","v":0},{"$f":"Inputs!AC96","v":0},{"$f":"Inputs!AD96","v":0},{"$f":"Inputs!AE96","v":0},{"$f":"Inputs!AF96","v":0},{"$f":"Inputs!AG96","v":0},{"$f":"Inputs!AH96","v":0},{"$f":"Inputs!AI96","v":0},{"$f":"Inputs!AJ96","v":0},{"$f":"Inputs!AK96","v":0},{"$f":"Inputs!AL96","v":0},{"$f":"Inputs!AM96","v":0},{"$f":"Inputs!AN96","v":0},{"$f":"Inputs!AO96","v":0},{"$f":"Inputs!AP96","v":0},{"$f":"Inputs!AQ96","v":0},{"$f":"Inputs!AR96","v":0},{"$f":"Inputs!AS96","v":0},{"$f":"Inputs!AT96","v":0},{"$f":"Inputs!AU96","v":0},{"$f":"Inputs!AV96","v":0},{"$f":"Inputs!AW96","v":0},{"$f":"Inputs!AX96","v":0}]
[]
[null,"Pre-operational interest during construction"]
[]
[null,null,"Pre-operational interest during construction"]
[]
[null,null,null,null,"Interest during construction rate",null,{"$f":"Inputs!G70","v":"real annual %"},null,{"$f":"Inputs!I70","v":6.7500000000000004E-2}]
[]
[null,null,null,null,"Opening pre-operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Pre Op RAV'!K17","v":0},{"$f":"'Pre Op RAV'!L17","v":0},{"$f":"'Pre Op RAV'!M17","v":5.1852727397732445E-2},{"$f":"'Pre Op RAV'!N17","v":0.35328727538245136},{"$f":"'Pre Op RAV'!O17","v":1.1642190611115995},{"$f":"'Pre Op RAV'!P17","v":2.4689913184021601},{"$f":"'Pre Op RAV'!Q17","v":4.6439806743996979},{"$f":"'Pre Op RAV'!R17","v":8.9885790187402055},{"$f":"'Pre Op RAV'!S17","v":13.479798566206394},{"$f":"'Pre Op RAV'!T17","v":71.23025142713432},{"$f":"'Pre Op RAV'!U17","v":194.76732962091927},{"$f":"'Pre Op RAV'!V17","v":320.41383958350752},{"$f":"'Pre Op RAV'!W17","v":372.12479033008128},{"$f":"'Pre Op RAV'!X17","v":0},{"$f":"'Pre Op RAV'!Y17","v":0},{"$f":"'Pre Op RAV'!Z17","v":0},{"$f":"'Pre Op RAV'!AA17","v":0},{"$f":"'Pre Op RAV'!AB17","v":0},{"$f":"'Pre Op RAV'!AC17","v":0},{"$f":"'Pre Op RAV'!AD17","v":0},{"$f":"'Pre Op RAV'!AE17","v":0},{"$f":"'Pre Op RAV'!AF17","v":0},{"$f":"'Pre Op RAV'!AG17","v":0},{"$f":"'Pre Op RAV'!AH17","v":0},{"$f":"'Pre Op RAV'!AI17","v":0},{"$f":"'Pre Op RAV'!AJ17","v":0},{"$f":"'Pre Op RAV'!AK17","v":0},{"$f":"'Pre Op RAV'!AL17","v":0},{"$f":"'Pre Op RAV'!AM17","v":0},{"$f":"'Pre Op RAV'!AN17","v":0},{"$f":"'Pre Op RAV'!AO17","v":0},{"$f":"'Pre Op RAV'!AP17","v":0},{"$f":"'Pre Op RAV'!AQ17","v":0},{"$f":"'Pre Op RAV'!AR17","v":0},{"$f":"'Pre Op RAV'!AS17","v":0},{"$f":"'Pre Op RAV'!AT17","v":0},{"$f":"'Pre Op RAV'!AU17","v":0},{"$f":"'Pre Op RAV'!AV17","v":0},{"$f":"'Pre Op RAV'!AW17","v":0},{"$f":"'Pre Op RAV'!AX17","v":0}]
[null,null,null,null,"Development costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K34","v":0},{"$f":"Inputs!L34","v":5.0213355454244421E-2},{"$f":"Inputs!M34","v":0.28851501441241528},{"$f":"Inputs!N34","v":0.76220047759715304},{"$f":"Inputs!O34","v":1.187420419485236},{"$f":"Inputs!P34","v":1.944837154026299},{"$f":"Inputs!Q34","v":3.9036817559401911},{"$f":"Inputs!R34","v":2.1858180343102038},{"$f":"Inputs!S34","v":0},{"$f":"Inputs!T34","v":0},{"$f":"Inputs!U34","v":0},{"$f":"Inputs!V34","v":0},{"$f":"Inputs!W34","v":0},{"$f":"Inputs!X34","v":0},{"$f":"Inputs!Y34","v":0},{"$f":"Inputs!Z34","v":0},{"$f":"Inputs!AA34","v":0},{"$f":"Inputs!AB34","v":0},{"$f":"Inputs!AC34","v":0},{"$f":"Inputs!AD34","v":0},{"$f":"Inputs!AE34","v":0},{"$f":"Inputs!AF34","v":0},{"$f":"Inputs!AG34","v":0},{"$f":"Inputs!AH34","v":0},{"$f":"Inputs!AI34","v":0},{"$f":"Inputs!AJ34","v":0},{"$f":"Inputs!AK34","v":0},{"$f":"Inputs!AL34","v":0},{"$f":"Inputs!AM34","v":0},{"$f":"Inputs!AN34","v":0},{"$f":"Inputs!AO34","v":0},{"$f":"Inputs!AP34","v":0},{"$f":"Inputs!AQ34","v":0},{"$f":"Inputs!AR34","v":0},{"$f":"Inputs!AS34","v":0},{"$f":"Inputs!AT34","v":0},{"$f":"Inputs!AU34","v":0},{"$f":"Inputs!AV34","v":0},{"$f":"Inputs!AW34","v":0},{"$f":"Inputs!AX34","v":0}]
[null,null,null,null,"Capex",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K35","v":0},{"$f":"Inputs!L35","v":0},{"$f":"Inputs!M35","v":0},{"$f":"Inputs!N35","v":0},{"$f":"Inputs!O35","v":0},{"$f":"Inputs!P35","v":0},{"$f":"Inputs!Q35","v":0},{"$f":"Inputs!R35","v":1.57586067},{"$f":"Inputs!S35","v":54.853572669226772},{"$f":"Inputs!T35","v":114.31242954388328},{"$f":"Inputs!U35","v":106.71929051018915},{"$f":"Inputs!V35","v":32.987182709485303},{"$f":"Inputs!W35","v":10.08594060980116},{"$f":"Inputs!X35","v":0},{"$f":"Inputs!Y35","v":0},{"$f":"Inputs!Z35","v":0},{"$f":"Inputs!AA35","v":0},{"$f":"Inputs!AB35","v":0},{"$f":"Inputs!AC35","v":0},{"$f":"Inputs!AD35","v":0},{"$f":"Inputs!AE35","v":0},{"$f":"Inputs!AF35","v":0},{"$f":"Inputs!AG35","v":0},{"$f":"Inputs!AH35","v":0},{"$f":"Inputs!AI35","v":0},{"$f":"Inputs!AJ35","v":0},{"$f":"Inputs!AK35","v":0},{"$f":"Inputs!AL35","v":0},{"$f":"Inputs!AM35","v":0},{"$f":"Inputs!AN35","v":0},{"$f":"Inputs!AO35","v":0},{"$f":"Inputs!AP35","v":0},{"$f":"Inputs!AQ35","v":0},{"$f":"Inputs!AR35","v":0},{"$f":"Inputs!AS35","v":0},{"$f":"Inputs!AT35","v":0},{"$f":"Inputs!AU35","v":0},{"$f":"Inputs!AV35","v":0},{"$f":"Inputs!AW35","v":0},{"$f":"Inputs!AX35","v":0}]
[null,null,null,null,"Spares",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K36","v":0},{"$f":"Inputs!L36","v":0},{"$f":"Inputs!M36","v":0},{"$f":"Inputs!N36","v":0},{"$f":"Inputs!O36","v":0},{"$f":"Inputs!P36","v":0},{"$f":"Inputs!Q36","v":0},{"$f":"Inputs!R36","v":0},{"$f":"Inputs!S36","v":0.1899266990698921},{"$f":"Inputs!T36","v":0.66287836708739145},{"$f":"Inputs!U36","v":2.2236421376993003},{"$f":"Inputs!V36","v":0.4145605527912557},{"$f":"Inputs!W36","v":1.2444366143667782},{"$f":"Inputs!X36","v":0},{"$f":"Inputs!Y36","v":0},{"$f":"Inputs!Z36","v":0},{"$f":"Inputs!AA36","v":0},{"$f":"Inputs!AB36","v":0},{"$f":"Inputs!AC36","v":0},{"$f":"Inputs!AD36","v":0},{"$f":"Inputs!AE36","v":0},{"$f":"Inputs!AF36","v":0},{"$f":"Inputs!AG36","v":0},{"$f":"Inputs!AH36","v":0},{"$f":"Inputs!AI36","v":0},{"$f":"Inputs!AJ36","v":0},{"$f":"Inputs!AK36","v":0},{"$f":"Inputs!AL36","v":0},{"$f":"Inputs!AM36","v":0},{"$f":"Inputs!AN36","v":0},{"$f":"Inputs!AO36","v":0},{"$f":"Inputs!AP36","v":0},{"$f":"Inputs!AQ36","v":0},{"$f":"Inputs!AR36","v":0},{"$f":"Inputs!AS36","v":0},{"$f":"Inputs!AT36","v":0},{"$f":"Inputs!AU36","v":0},{"$f":"Inputs!AV36","v":0},{"$f":"Inputs!AW36","v":0},{"$f":"Inputs!AX36","v":0}]
[null,null,null,null,"Capitalised interest during construction",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"((1+$I18)^K8-1)*(K20+(K21+K22+K23)/(2+$I18))","v":0},{"$f":"((1+$I18)^L8-1)*(L20+(L21+L22+L23)/(2+$I18))","v":1.6393719434880257E-3},1.2919533572303646E-2,4.8731308131995117E-2,0.11735183780532464,0.23015220197123862,0.4409165884003165,0.72954084315598511,2.7069534926312731,8.5617702828142725,16.703577314699796,{"$f":"((1+$I18)^V8-1)*(V20+(V21+V22+V23)/(2+$I18))","v":18.309207484297168},{"$f":"((1+$I18)^W8-1)*(W20+(W21+W22+W23)/(2+$I18))","v":0},{"$f":"((1+$I18)^X8-1)*(X20+(X21+X22+X23)/(2+$I18))","v":0},{"$f":"((1+$I18)^Y8-1)*(Y20+(Y21+Y22+Y23)/(2+$I18))","v":0},{"$f":"((1+$I18)^Z8-1)*(Z20+(Z21+Z22+Z23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AA8-1)*(AA20+(AA21+AA22+AA23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AB8-1)*(AB20+(AB21+AB22+AB23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AC8-1)*(AC20+(AC21+AC22+AC23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AD8-1)*(AD20+(AD21+AD22+AD23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AE8-1)*(AE20+(AE21+AE22+AE23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AF8-1)*(AF20+(AF21+AF22+AF23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AG8-1)*(AG20+(AG21+AG22+AG23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AH8-1)*(AH20+(AH21+AH22+AH23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AI8-1)*(AI20+(AI21+AI22+AI23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AJ8-1)*(AJ20+(AJ21+AJ22+AJ23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AK8-1)*(AK20+(AK21+AK22+AK23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AL8-1)*(AL20+(AL21+AL22+AL23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AM8-1)*(AM20+(AM21+AM22+AM23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AN8-1)*(AN20+(AN21+AN22+AN23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AO8-1)*(AO20+(AO21+AO22+AO23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AP8-1)*(AP20+(AP21+AP22+AP23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AQ8-1)*(AQ20+(AQ21+AQ22+AQ23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AR8-1)*(AR20+(AR21+AR22+AR23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AS8-1)*(AS20+(AS21+AS22+AS23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AT8-1)*(AT20+(AT21+AT22+AT23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AU8-1)*(AU20+(AU21+AU22+AU23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AV8-1)*(AV20+(AV21+AV22+AV23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AW8-1)*(AW20+(AW21+AW22+AW23)/(2+$I18))","v":0},{"$f":"((1+$I18)^AX8-1)*(AX20+(AX21+AX22+AX23)/(2+$I18))","v":0}]
[]
[null,"Transaction costs"]
[]
[null,null,"Parameters"]
[]
[null,null,null,null,"Pre-operational notional gearing",null,{"$f":"Inputs!G73","v":"%"},null,{"$f":"Inputs!I73","v":0.40610000000000002}]
[null,null,null,null,"Operational notional gearing",null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"Inputs!I74","v":0.5}]
[]
[null,null,null,null,"Debt transaction costs",null,{"$f":"Inputs!G77","v":"%"},null,{"$f":"Inputs!I77","v":2.5000000000000001E-2}]
[null,null,null,null,"Equity transaction costs",null,{"$f":"Inputs!G76","v":"%"},null,{"$f":"Inputs!I76","v":0.05}]
[]
[null,null,"Allowance"]
[]
[null,null,null,null,"Transaction costs - opening",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"J46","v":0},0,0,0,0,0,0,15.778584328786852,16.843638770979965,17.980584388021111,19.194273834212535,20.489887318021879,21.604526772493443,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"AT46","v":0},{"$f":"AU46","v":0},{"$f":"AV46","v":0},{"$f":"AW46","v":0}]
[null,null,null,null,"Initial debt transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"$I30*K$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*L$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*M$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*N$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*O$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*P$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*Q$12*$I33*'Op Rav'!$K$11","v":3.8930285885945164},{"$f":"$I30*R$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*S$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*T$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*U$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*V$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*W$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*X$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*Y$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*Z$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AA$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AB$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AC$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AD$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AE$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AF$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AG$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AH$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AI$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AJ$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AK$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AL$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AM$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AN$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AO$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AP$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AQ$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AR$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AS$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AT$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AU$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AV$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AW$12*$I33*'Op Rav'!$K$11","v":0},{"$f":"$I30*AX$12*$I33*'Op Rav'!$K$11","v":0}]
[null,null,null,null,"Initial equity transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"(1-$I30)*K$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*L$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*M$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*N$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*O$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*P$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*Q$12*$I34*'Op Rav'!$K$11","v":11.386701200523431},{"$f":"(1-$I30)*R$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*S$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*T$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*U$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*V$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*W$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*X$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*Y$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*Z$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AA$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AB$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AC$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AD$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AE$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AF$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AG$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AH$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AI$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AJ$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AK$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AL$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AM$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AN$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AO$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AP$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AQ$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AR$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AS$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AT$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AU$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AV$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AW$12*$I34*'Op Rav'!$K$11","v":0},{"$f":"(1-$I30)*AX$12*$I34*'Op Rav'!$K$11","v":0}]
[null,null,null,null,"Final debt transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*K$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*L$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*M$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*N$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*O$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*P$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*Q$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*R$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*S$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*T$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*U$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*V$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*W$11","v":0.90016100583360004},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*X$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*Y$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*Z$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AA$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AB$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AC$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AD$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AE$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AF$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AG$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AH$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AI$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AJ$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AK$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AL$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AM$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AN$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AO$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AP$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AQ$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AR$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AS$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AT$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AU$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AV$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AW$11","v":0},{"$f":"($I31-$I30)*'Op Rav'!$K$11*$I33*AX$11","v":0}]
[null,null,null,null,"Final equity transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*K$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*L$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*M$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*N$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*O$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*P$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*Q$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*R$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*S$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*T$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*U$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*V$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*W$11","v":-1.8003220116672001},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*X$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*Y$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*Z$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AA$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AB$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AC$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AD$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AE$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AF$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AG$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AH$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AI$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AJ$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AK$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AL$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AM$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AN$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AO$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AP$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AQ$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AR$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AS$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AT$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AU$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AV$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AW$11","v":0},{"$f":"($I30-$I31)*'Op Rav'!$K$11*$I34*AX$11","v":0}]
[null,null,null,null,"Transaction costs - annual movement",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K39:K42)","v":0},0,0,0,0,0,15.279729789117948,{"$f":"SUM(R39:R42)","v":0},0,0,0,0,-0.90016100583360004,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"SUM(AU39:AU42)","v":0},0,0,0]
[null,null,null,null,"Capitalised IDC on transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"((1+$I18)^K8-1)*(K38+(K39+K40+K41+K42)/(2+$I18))","v":0},{"$f":"((1+$I18)^L8-1)*(L38+(L39+L40+L41+L42)/(2+$I18))","v":0},0,0,0,0,0.49885453966890442,1.065054442193111,1.1369456170411458,1.2136894461914232,1.295613483809344,1.1146394544715639,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Transfer to operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"-SUM(K38,K43,K44)*K$11","v":0},0,0,0,0,0,0,0,0,0,0,0,-20.704365766659844,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Transaction costs - closing",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K45,K44,K43,K38)","v":0},{"$f":"SUM(L45,L44,L43,L38)","v":0},0,0,0,0,15.778584328786852,16.843638770979965,17.980584388021111,19.194273834212535,20.489887318021879,21.604526772493443,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,"End of sheet"]

{"sheet":"Op Rav","index":6,"n_rows":43,"n_cols":35,"rows_kept":43,"cut":false,"hidden":false,"merged":[]}
["Op RAV",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"RAV"]
[]
[null,null,"Operational"]
[]
[null,null,null,null,"Opening operational RAV (before transfers)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"J15","v":0},387.99315198807278,371.82677065523643,355.66038932240008,339.49400798956373,323.32762665672738,307.16124532389102,293.44994422593686,280.56298737302529,264.05928223343557,248.68620912473114,232.10712851641574,216.21822354468591,200.74830881357593,187.94014052185099,170.85467320168271,153.76920588151444,160.18472679356651,140.16163594437069,120.13854509517488,101.24608627686436,83.451949256373666,62.58896194228025,41.725974628186833,20.862987314093417]
[null,null,null,null,"Transfers of transaction costs",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"-SUM(Finance!K45:AX45)","v":20.704365766659844}]
[null,null,null,null,"Transfers of pre-operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"-SUM('Pre Op RAV'!K23:AX23)","v":383.45516755424927}]
[null,null,null,null,"Opening operational RAV (after transfers)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K9:K11)","v":404.15953332090913},{"$f":"SUM(L9:L11)","v":387.99315198807278},{"$f":"SUM(M9:M11)","v":371.82677065523643},355.66038932240008,339.49400798956373,323.32762665672738,307.16124532389102,293.44994422593686,280.56298737302529,264.05928223343557,248.68620912473114,232.10712851641574,216.21822354468591,200.74830881357593,187.94014052185099,170.85467320168271,153.76920588151444,160.18472679356651,140.16163594437069,120.13854509517488,101.24608627686436,83.451949256373666,62.58896194228025,41.725974628186833,20.862987314093417]
[null,null,null,null,"Replacement Capex",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K59","v":0},{"$f":"Inputs!L59","v":0},{"$f":"Inputs!M59","v":0},{"$f":"Inputs!N59","v":0},{"$f":"Inputs!O59","v":0},{"$f":"Inputs!P59","v":0},{"$f":"Inputs!Q59","v":2.4550802348821743},{"$f":"Inputs!R59","v":3.4158178263071504},{"$f":"Inputs!S59","v":0},{"$f":"Inputs!T59","v":1.1306320308852931},{"$f":"Inputs!U59","v":0},{"$f":"Inputs!V59","v":0.69017563658559289},{"$f":"Inputs!W59","v":1.1622563107889334},{"$f":"Inputs!X59","v":3.9208574427397171},{"$f":"Inputs!Y59","v":0},{"$f":"Inputs!Z59","v":0},{"$f":"Inputs!AA59","v":23.500988232220344},{"$f":"Inputs!AB59","v":0},{"$f":"Inputs!AC59","v":0},{"$f":"Inputs!AD59","v":1.1306320308852931},{"$f":"Inputs!AE59","v":2.4550802348821743},{"$f":"Inputs!AF59","v":0},{"$f":"Inputs!AG59","v":0},{"$f":"Inputs!AH59","v":0},{"$f":"Inputs!AI59","v":0}]
[null,null,null,null,"Depreciation (negative)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":" - K25","v":-16.166381332836366},{"$f":" - L25","v":-16.166381332836366},{"$f":" - M25","v":-16.166381332836366},-16.166381332836366,-16.166381332836369,-16.166381332836369,-16.166381332836369,-16.302774679218714,-16.503705139589723,-16.503705139589723,-16.579080608315408,-16.579080608315412,-16.632171041898918,-16.72902573446466,-17.085467320168274,-17.08546732016827,-17.08546732016827,-20.023090849195814,-20.023090849195814,-20.023090849195814,-20.249217255372873,-20.862987314093417,-20.862987314093417,-20.862987314093417,-20.862987314093417]
[null,null,null,null,"Closing operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K12:K14)","v":387.99315198807278},371.82677065523643,355.66038932240008,339.49400798956373,323.32762665672738,307.16124532389102,293.44994422593686,280.56298737302529,264.05928223343557,248.68620912473114,232.10712851641574,216.21822354468591,200.74830881357593,187.94014052185099,170.85467320168271,153.76920588151444,160.18472679356651,140.16163594437069,120.13854509517488,101.24608627686436,83.451949256373666,62.58896194228025,41.725974628186833,20.862987314093417,0]
[]
[null,null,null,null,"Average operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"AVERAGE(K12, K15)","v":396.07634265449099},{"$f":"AVERAGE(L12, L15)","v":379.90996132165458},{"$f":"AVERAGE(M12, M15)","v":363.74357998881828},347.57719865598187,331.41081732314558,315.24443599030917,300.30559477491397,287.00646579948108,272.3111348032304,256.37274567908332,240.39666882057344,224.16267603055081,208.48326617913091,194.34422466771346,179.39740686176685,162.31193954159858,{"$f":"AVERAGE(AA12, AA15)","v":156.97696633754049},150.17318136896859,130.15009051977279,110.69231568601961,92.349017766619014,73.020455599326965,52.157468285233541,31.294480971140125,10.431493657046708]
[]
[null,"Operational RAV depreciation"]
[]
[null,null,null,null,"Number of operational years",null,"full years",null,{"$f":"Inputs!I89","v":25}]
[null,null,null,null,"Years remaining until end of operational period",null,"full years",null,null,null,{"$f":"I21","v":25},{"$f":"+K22-1","v":24},{"$f":"+L22-1","v":23},22,21,20,19,18,17,16,15,14,13,12,11,10,9,8,7,6,5,4,3,2,1]
[null,null,null,null,"Year is before end of operational period",null,"flag",null,null,null,{"$f":"K22 > 0","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"IF(K23, IF(K22=1,SUM(K12:K13),K12 / K22), 0)","v":16.166381332836366},{"$f":"IF(L23, IF(L22=1,SUM(L12:L13),L12 / L22), 0)","v":16.166381332836366},16.166381332836366,16.166381332836366,16.166381332836369,16.166381332836369,16.166381332836369,16.302774679218714,16.503705139589723,16.503705139589723,16.579080608315408,16.579080608315412,16.632171041898918,16.72902573446466,17.085467320168274,17.08546732016827,17.08546732016827,20.023090849195814,20.023090849195814,20.023090849195814,20.249217255372873,20.862987314093417,20.862987314093417,20.862987314093417,20.862987314093417]
[]
[null,null,null,null,"Depreciation equal to additions",null,"check",null,{"$f":"IF(ABS(SUM('Pre Op RAV'!K18:AX21,Finance!K39:AX42,Finance!K44:AX44,K13:AI13)-SUM(K25:AI25))<0.00000001,\"TRUE\",\"FALSE\")","v":"TRUE"}]
[]
[null,"Operational RAV return"]
[]
[null,null,null,null,"Cap return rate",null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"Inputs!I68","v":8.0999999999999989E-2}]
[null,null,null,null,"Floor return rate",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I69","v":-2.0999999999999999E-3}]
[]
[null,null,null,null,"Opening operational RAV (after transfers)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K12","v":404.15953332090913},387.99315198807278,371.82677065523643,355.66038932240008,339.49400798956373,323.32762665672738,307.16124532389102,293.44994422593686,280.56298737302529,264.05928223343557,248.68620912473114,232.10712851641574,216.21822354468591,200.74830881357593,187.94014052185099,170.85467320168271,153.76920588151444,160.18472679356651,140.16163594437069,120.13854509517488,101.24608627686436,83.451949256373666,62.58896194228025,41.725974628186833,20.862987314093417]
[null,null,null,null,"Closing operational RAV",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K15","v":387.99315198807278},371.82677065523643,355.66038932240008,339.49400798956373,323.32762665672738,307.16124532389102,293.44994422593686,280.56298737302529,264.05928223343557,248.68620912473114,232.10712851641574,216.21822354468591,200.74830881357593,187.94014052185099,170.85467320168271,153.76920588151444,160.18472679356651,140.16163594437069,120.13854509517488,101.24608627686436,83.451949256373666,62.58896194228025,41.725974628186833,20.862987314093417,0]
[]
[null,null,null,null,"NPV neutral return base  (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"0.5 * K$34 + 0.5 * K$35 / (1 + $I31)","v":381.54005897686193},{"$f":"0.5 * L$34 + 0.5 * L$35 / (1 + $I31)","v":365.97935613059349},350.41865328432505,334.85795043805649,319.29724759178805,303.73654474551961,289.31140167486728,276.49508653157403,262.41807196284731,247.05563978680618,231.70070332111476,216.06199327980173,200.96216857788224,187.3029890607431,172.99628358270289,156.550928590441,150.97559590725422,144.92198224246812,125.6490626970581,106.89909968767272,89.222464626116576,70.675540743950137,50.594191714982323,30.512842686014515,10.431493657046708]
[null,null,null,null,"NPV neutral return base (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"0.5 * K$34 + 0.5 * K$35 / (1 + $I32)","v":396.48459278936167},380.30120103423906,364.11780927911639,347.93441752399377,331.75102576887116,315.56763401374849,300.6143656351577,287.30167687949074,272.58898052559249,256.63441570572024,240.64089417876789,224.39018292976107,208.69449548492736,194.54197709535947,179.5771817959905,162.47373698239983,157.14551425129258,150.3206607935017,130.27650145508687,110.79884779403716,92.436826712123775,73.086312308455518,52.201372757985922,31.316433207516312,10.431493657046708]
[]
[null,null,null,null,"Return (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K37 * $I31","v":30.904744777125813},29.644327846578069,28.383910916030324,27.123493985482572,25.863077054934827,24.602660124387086,23.434223535664248,22.396102009057493,21.255863828990631,20.011506822731299,18.767756969010293,17.501021455663938,16.277935654808459,15.171542113920189,14.012698970198931,12.680625215825719,12.229023268487589,11.738680561639915,10.177574078461705,8.6588270747014882,7.2270196347154414,5.7247188002599607,4.0981295289135673,2.4715402575671752,0.84495098622078324]
[null,null,null,null,"Return (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K38 * $I32","v":-0.83261764485765943},-0.79863252217190195,-0.76464739948614435,-0.73066227680038687,-0.69667715411462938,-0.66269203142887179,-0.63129016783383107,-0.60333352144693053,-0.5724368591037442,-0.53893227298201252,-0.50534587777541251,-0.4712193841524982,-0.43825844051834745,-0.40853815190025489,-0.37711208177158001,-0.34119484766303959,-0.3300055799277144,-0.31567338766635356,-0.27358065305568241,-0.23267758036747802,-0.19411733609545992,-0.15348125584775657,-0.10962288279177043,-6.5764509735784252E-2,-2.1906136679798086E-2]
[]
[null,"End of sheet"]

{"sheet":"Allowances Cap","index":7,"n_rows":36,"n_cols":35,"rows_kept":36,"cut":false,"hidden":false,"merged":[]}
["Allowances Cap",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[null,null,null,null,"Year",null,null,null,null,null,1,{"$f":"+K4+1","v":2},{"$f":"+L4+1","v":3},4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25]
[]
[" ","Unprofiled allowances except tax (cap)"]
[]
[null,null,null,null,"Controllable Opex",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K61","v":14.44214945515499},{"$f":"Inputs!L61","v":10.852731227485117},{"$f":"Inputs!M61","v":14.836665994901963},{"$f":"Inputs!N61","v":14.55284567999627},{"$f":"Inputs!O61","v":15.525196798650219},{"$f":"Inputs!P61","v":15.485257213715073},{"$f":"Inputs!Q61","v":15.309436357939406},{"$f":"Inputs!R61","v":16.503506579036483},{"$f":"Inputs!S61","v":16.844325279280508},{"$f":"Inputs!T61","v":17.776611902928519},{"$f":"Inputs!U61","v":17.456705345592507},{"$f":"Inputs!V61","v":17.487043053346056},{"$f":"Inputs!W61","v":17.517981301582545},{"$f":"Inputs!X61","v":17.549536415439125},{"$f":"Inputs!Y61","v":18.337181141440603},{"$f":"Inputs!Z61","v":17.866684110196161},{"$f":"Inputs!AA61","v":17.902064412959103},{"$f":"Inputs!AB61","v":17.938169600363263},{"$f":"Inputs!AC61","v":17.975019477613689},{"$f":"Inputs!AD61","v":18.779616841015756},{"$f":"Inputs!AE61","v":18.360273036434535},{"$f":"Inputs!AF61","v":18.401358203189748},{"$f":"Inputs!AG61","v":18.443311154686921},{"$f":"Inputs!AH61","v":18.486155725117051},{"$f":"Inputs!AI61","v":18.690478265584147}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K62","v":1.0615144493734652},{"$f":"Inputs!L62","v":1.0480665434133698},{"$f":"Inputs!M62","v":1.0382232216850515},{"$f":"Inputs!N62","v":1.0284725252444746},{"$f":"Inputs!O62","v":1.0188135808622372},{"$f":"Inputs!P62","v":1.0092455235562319},{"$f":"Inputs!Q62","v":0.9997674965136214},{"$f":"Inputs!R62","v":0.99037865101354716},{"$f":"Inputs!S62","v":0.98107814635057489},{"$f":"Inputs!T62","v":0.97186514975886296},{"$f":"Inputs!U62","v":0.96273883633705104},{"$f":"Inputs!V62","v":0.95369838897385817},{"$f":"Inputs!W62","v":0.94474299827438946},{"$f":"Inputs!X62","v":0.9358718624871385},{"$f":"Inputs!Y62","v":0.92708418743168119},{"$f":"Inputs!Z62","v":0.91837918642705685},{"$f":"Inputs!AA62","v":0.90975608022082677},{"$f":"Inputs!AB62","v":0.90121409691880305},{"$f":"Inputs!AC62","v":0.89275247191544826},{"$f":"Inputs!AD62","v":0.88437044782492846},{"$f":"Inputs!AE62","v":0.87606727441282495},{"$f":"Inputs!AF62","v":0.86784220852848915},{"$f":"Inputs!AG62","v":0.85969451403803987},{"$f":"Inputs!AH62","v":0.85162346175799697},{"$f":"Inputs!AI62","v":0.84362832938954024}]
[null,null,null,null,"Decommissioning baseline",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K60","v":0},{"$f":"Inputs!L60","v":0},{"$f":"Inputs!M60","v":0},{"$f":"Inputs!N60","v":0},{"$f":"Inputs!O60","v":0},{"$f":"Inputs!P60","v":0},{"$f":"Inputs!Q60","v":0},{"$f":"Inputs!R60","v":0},{"$f":"Inputs!S60","v":0},{"$f":"Inputs!T60","v":0},{"$f":"Inputs!U60","v":0},{"$f":"Inputs!V60","v":0},{"$f":"Inputs!W60","v":0},{"$f":"Inputs!X60","v":0},{"$f":"Inputs!Y60","v":0},{"$f":"Inputs!Z60","v":0},{"$f":"Inputs!AA60","v":0},{"$f":"Inputs!AB60","v":0},{"$f":"Inputs!AC60","v":0},{"$f":"Inputs!AD60","v":0},{"$f":"Inputs!AE60","v":0},{"$f":"Inputs!AF60","v":0},{"$f":"Inputs!AG60","v":0},{"$f":"Inputs!AH60","v":0},{"$f":"Inputs!AI60","v":26.210380723083983}]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Op Rav'!K25","v":16.166381332836366},{"$f":"'Op Rav'!L25","v":16.166381332836366},{"$f":"'Op Rav'!M25","v":16.166381332836366},{"$f":"'Op Rav'!N25","v":16.166381332836366},{"$f":"'Op Rav'!O25","v":16.166381332836369},{"$f":"'Op Rav'!P25","v":16.166381332836369},{"$f":"'Op Rav'!Q25","v":16.166381332836369},{"$f":"'Op Rav'!R25","v":16.302774679218714},{"$f":"'Op Rav'!S25","v":16.503705139589723},{"$f":"'Op Rav'!T25","v":16.503705139589723},{"$f":"'Op Rav'!U25","v":16.579080608315408},{"$f":"'Op Rav'!V25","v":16.579080608315412},{"$f":"'Op Rav'!W25","v":16.632171041898918},{"$f":"'Op Rav'!X25","v":16.72902573446466},{"$f":"'Op Rav'!Y25","v":17.085467320168274},{"$f":"'Op Rav'!Z25","v":17.08546732016827},{"$f":"'Op Rav'!AA25","v":17.08546732016827},{"$f":"'Op Rav'!AB25","v":20.023090849195814},{"$f":"'Op Rav'!AC25","v":20.023090849195814},{"$f":"'Op Rav'!AD25","v":20.023090849195814},{"$f":"'Op Rav'!AE25","v":20.249217255372873},{"$f":"'Op Rav'!AF25","v":20.862987314093417},{"$f":"'Op Rav'!AG25","v":20.862987314093417},{"$f":"'Op Rav'!AH25","v":20.862987314093417},{"$f":"'Op Rav'!AI25","v":20.862987314093417}]
[null,null,null,null,"Return (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Op Rav'!K40","v":30.904744777125813},{"$f":"'Op Rav'!L40","v":29.644327846578069},{"$f":"'Op Rav'!M40","v":28.383910916030324},{"$f":"'Op Rav'!N40","v":27.123493985482572},{"$f":"'Op Rav'!O40","v":25.863077054934827},{"$f":"'Op Rav'!P40","v":24.602660124387086},{"$f":"'Op Rav'!Q40","v":23.434223535664248},{"$f":"'Op Rav'!R40","v":22.396102009057493},{"$f":"'Op Rav'!S40","v":21.255863828990631},{"$f":"'Op Rav'!T40","v":20.011506822731299},{"$f":"'Op Rav'!U40","v":18.767756969010293},{"$f":"'Op Rav'!V40","v":17.501021455663938},{"$f":"'Op Rav'!W40","v":16.277935654808459},{"$f":"'Op Rav'!X40","v":15.171542113920189},{"$f":"'Op Rav'!Y40","v":14.012698970198931},{"$f":"'Op Rav'!Z40","v":12.680625215825719},{"$f":"'Op Rav'!AA40","v":12.229023268487589},{"$f":"'Op Rav'!AB40","v":11.738680561639915},{"$f":"'Op Rav'!AC40","v":10.177574078461705},{"$f":"'Op Rav'!AD40","v":8.6588270747014882},{"$f":"'Op Rav'!AE40","v":7.2270196347154414},{"$f":"'Op Rav'!AF40","v":5.7247188002599607},{"$f":"'Op Rav'!AG40","v":4.0981295289135673},{"$f":"'Op Rav'!AH40","v":2.4715402575671752},{"$f":"'Op Rav'!AI40","v":0.84495098622078324}]
[null,null,null,null,"Unprofiled allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K8:K12)","v":62.574790014490631},{"$f":"SUM(L8:L12)","v":57.711506950312923},60.425181465453704,58.871193523559683,58.57346876728365,57.263544194494756,55.909808722953642,56.192761918326234,55.584972394211434,55.263689015008403,53.766281759255257,52.520843506299265,51.372830996564311,50.385976126311114,50.362431619239494,48.551155832617205,48.126311081835787,50.601155108117801,49.068436877186656,48.345905212737989,46.712577200935677,45.856906526071612,44.264122511731948,42.67230675853564,67.452425618371862]
[]
[null,"Profiled allowances except tax (cap)"]
[]
[null,null,"Annuity parameters"]
[]
[null,null,null,null,"Cap return rate",null,{"$f":"Inputs!G68","v":"real annual %"},null,{"$f":"Inputs!I68","v":8.0999999999999989E-2}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G89","v":"full years"},null,{"$f":"Inputs!I89","v":25}]
[null,null,null,null,"Annuity factor (cap)",null,"scalar",null,{"$f":"I19 / (1 - (1 + I19)^(-I20))","v":9.4480276733656054E-2}]
[]
[null,null,null,null,"Year is within operational period",null,"flag",null,null,null,{"$f":"AND(K4 > 0, K4<= $I20)","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[null,null,null,null,"Discount factor to start of operational period (cap)",null,"scalar",null,null,null,{"$f":"(1 + $I19) ^ - K4","v":0.92506938020351526},0.85575335819011589,0.79163122866800739,0.73231381005366081,0.67744108238081491,0.62668000220241893,0.57972248122332926,0.53628351639530925,0.49609946012517048,0.45892642009728996,0.42453877899841808,0.39272782516042376,0.36330048580982777,0.33607815523573337,0.31089561076386063,0.28760000995731788,0.26604996295774092,0.24611467433648557,0.22767314924744272,0.21061345906331425,0.19483206203821857,0.18023317487346768,0.16672819137231054,0.15423514465523638,0.14267820967181905]
[]
[null,null,"Allowances except tax"]
[]
[null,null,null,null,"Discounted unprofiled allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K13 * K$24","v":57.886022215069964},{"$f":"L13 * L$24","v":49.3868158789425},47.834460645984421,43.112188031644394,39.680074080507495,35.885918001924288,32.412173037592424,30.135251957524417,27.575674795840797,25.361966961027733,22.825871609359144,20.626396645819874,18.663774458477992,16.933625906282341,{"$f":"Y13 * Y$24","v":15.65745893781663},{"$f":"Z13 * Z$24","v":13.9633129009},12.804003280615127,12.453686810484406,11.171565552478439,10.182298328401863,9.1011077391777739,8.2649358530697263,7.3800770890634437,6.5815694056753653,9.6239913252508398]
[null,null,null,null,"NPV of allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"SUM(K28:AI28)","v":585.50422144893139}]
[]
[null,null,null,null,"Annuity factor (cap)",null,{"$f":"G$21","v":"scalar"},null,{"$f":"I$21","v":9.4480276733656054E-2}]
[]
[null,null,null,null,"Annuity of allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I29 * I31","v":55.318600871218877}]
[null,null,null,null,"Annuitised allowances except tax (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K$23 * $I33","v":55.318600871218877},55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,{"$f":"X$23 * $I33","v":55.318600871218877},{"$f":"Y$23 * $I33","v":55.318600871218877},55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877,55.318600871218877]
[]
[null,"End of sheet"]

{"sheet":"Allowances Floor","index":8,"n_rows":36,"n_cols":35,"rows_kept":36,"cut":false,"hidden":false,"merged":[]}
["Allowances Floor",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[null,null,null,null,"Year",null,null,null,null,null,1,{"$f":"+K4+1","v":2},{"$f":"+L4+1","v":3},4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25]
[]
[null,"Unprofiled allowances except tax (floor)"]
[]
[null,null,null,null,"Controllable Opex",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K61","v":14.44214945515499},{"$f":"Inputs!L61","v":10.852731227485117},{"$f":"Inputs!M61","v":14.836665994901963},{"$f":"Inputs!N61","v":14.55284567999627},{"$f":"Inputs!O61","v":15.525196798650219},{"$f":"Inputs!P61","v":15.485257213715073},{"$f":"Inputs!Q61","v":15.309436357939406},{"$f":"Inputs!R61","v":16.503506579036483},{"$f":"Inputs!S61","v":16.844325279280508},{"$f":"Inputs!T61","v":17.776611902928519},{"$f":"Inputs!U61","v":17.456705345592507},{"$f":"Inputs!V61","v":17.487043053346056},{"$f":"Inputs!W61","v":17.517981301582545},{"$f":"Inputs!X61","v":17.549536415439125},{"$f":"Inputs!Y61","v":18.337181141440603},{"$f":"Inputs!Z61","v":17.866684110196161},{"$f":"Inputs!AA61","v":17.902064412959103},{"$f":"Inputs!AB61","v":17.938169600363263},{"$f":"Inputs!AC61","v":17.975019477613689},{"$f":"Inputs!AD61","v":18.779616841015756},{"$f":"Inputs!AE61","v":18.360273036434535},{"$f":"Inputs!AF61","v":18.401358203189748},{"$f":"Inputs!AG61","v":18.443311154686921},{"$f":"Inputs!AH61","v":18.486155725117051},{"$f":"Inputs!AI61","v":18.690478265584147}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K62","v":1.0615144493734652},{"$f":"Inputs!L62","v":1.0480665434133698},{"$f":"Inputs!M62","v":1.0382232216850515},{"$f":"Inputs!N62","v":1.0284725252444746},{"$f":"Inputs!O62","v":1.0188135808622372},{"$f":"Inputs!P62","v":1.0092455235562319},{"$f":"Inputs!Q62","v":0.9997674965136214},{"$f":"Inputs!R62","v":0.99037865101354716},{"$f":"Inputs!S62","v":0.98107814635057489},{"$f":"Inputs!T62","v":0.97186514975886296},{"$f":"Inputs!U62","v":0.96273883633705104},{"$f":"Inputs!V62","v":0.95369838897385817},{"$f":"Inputs!W62","v":0.94474299827438946},{"$f":"Inputs!X62","v":0.9358718624871385},{"$f":"Inputs!Y62","v":0.92708418743168119},{"$f":"Inputs!Z62","v":0.91837918642705685},{"$f":"Inputs!AA62","v":0.90975608022082677},{"$f":"Inputs!AB62","v":0.90121409691880305},{"$f":"Inputs!AC62","v":0.89275247191544826},{"$f":"Inputs!AD62","v":0.88437044782492846},{"$f":"Inputs!AE62","v":0.87606727441282495},{"$f":"Inputs!AF62","v":0.86784220852848915},{"$f":"Inputs!AG62","v":0.85969451403803987},{"$f":"Inputs!AH62","v":0.85162346175799697},{"$f":"Inputs!AI62","v":0.84362832938954024}]
[null,null,null,null,"Decommissioning baseline",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"Inputs!K60","v":0},{"$f":"Inputs!L60","v":0},{"$f":"Inputs!M60","v":0},{"$f":"Inputs!N60","v":0},{"$f":"Inputs!O60","v":0},{"$f":"Inputs!P60","v":0},{"$f":"Inputs!Q60","v":0},{"$f":"Inputs!R60","v":0},{"$f":"Inputs!S60","v":0},{"$f":"Inputs!T60","v":0},{"$f":"Inputs!U60","v":0},{"$f":"Inputs!V60","v":0},{"$f":"Inputs!W60","v":0},{"$f":"Inputs!X60","v":0},{"$f":"Inputs!Y60","v":0},{"$f":"Inputs!Z60","v":0},{"$f":"Inputs!AA60","v":0},{"$f":"Inputs!AB60","v":0},{"$f":"Inputs!AC60","v":0},{"$f":"Inputs!AD60","v":0},{"$f":"Inputs!AE60","v":0},{"$f":"Inputs!AF60","v":0},{"$f":"Inputs!AG60","v":0},{"$f":"Inputs!AH60","v":0},{"$f":"Inputs!AI60","v":26.210380723083983}]
[null,null,null,null,"RAV depreciation",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Op Rav'!K25","v":16.166381332836366},{"$f":"'Op Rav'!L25","v":16.166381332836366},{"$f":"'Op Rav'!M25","v":16.166381332836366},{"$f":"'Op Rav'!N25","v":16.166381332836366},{"$f":"'Op Rav'!O25","v":16.166381332836369},{"$f":"'Op Rav'!P25","v":16.166381332836369},{"$f":"'Op Rav'!Q25","v":16.166381332836369},{"$f":"'Op Rav'!R25","v":16.302774679218714},{"$f":"'Op Rav'!S25","v":16.503705139589723},{"$f":"'Op Rav'!T25","v":16.503705139589723},{"$f":"'Op Rav'!U25","v":16.579080608315408},{"$f":"'Op Rav'!V25","v":16.579080608315412},{"$f":"'Op Rav'!W25","v":16.632171041898918},{"$f":"'Op Rav'!X25","v":16.72902573446466},{"$f":"'Op Rav'!Y25","v":17.085467320168274},{"$f":"'Op Rav'!Z25","v":17.08546732016827},{"$f":"'Op Rav'!AA25","v":17.08546732016827},{"$f":"'Op Rav'!AB25","v":20.023090849195814},{"$f":"'Op Rav'!AC25","v":20.023090849195814},{"$f":"'Op Rav'!AD25","v":20.023090849195814},{"$f":"'Op Rav'!AE25","v":20.249217255372873},{"$f":"'Op Rav'!AF25","v":20.862987314093417},{"$f":"'Op Rav'!AG25","v":20.862987314093417},{"$f":"'Op Rav'!AH25","v":20.862987314093417},{"$f":"'Op Rav'!AI25","v":20.862987314093417}]
[null,null,null,null,"Return (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Op Rav'!K41","v":-0.83261764485765943},{"$f":"'Op Rav'!L41","v":-0.79863252217190195},{"$f":"'Op Rav'!M41","v":-0.76464739948614435},{"$f":"'Op Rav'!N41","v":-0.73066227680038687},{"$f":"'Op Rav'!O41","v":-0.69667715411462938},{"$f":"'Op Rav'!P41","v":-0.66269203142887179},{"$f":"'Op Rav'!Q41","v":-0.63129016783383107},{"$f":"'Op Rav'!R41","v":-0.60333352144693053},{"$f":"'Op Rav'!S41","v":-0.5724368591037442},{"$f":"'Op Rav'!T41","v":-0.53893227298201252},{"$f":"'Op Rav'!U41","v":-0.50534587777541251},{"$f":"'Op Rav'!V41","v":-0.4712193841524982},{"$f":"'Op Rav'!W41","v":-0.43825844051834745},{"$f":"'Op Rav'!X41","v":-0.40853815190025489},{"$f":"'Op Rav'!Y41","v":-0.37711208177158001},{"$f":"'Op Rav'!Z41","v":-0.34119484766303959},{"$f":"'Op Rav'!AA41","v":-0.3300055799277144},{"$f":"'Op Rav'!AB41","v":-0.31567338766635356},{"$f":"'Op Rav'!AC41","v":-0.27358065305568241},{"$f":"'Op Rav'!AD41","v":-0.23267758036747802},{"$f":"'Op Rav'!AE41","v":-0.19411733609545992},{"$f":"'Op Rav'!AF41","v":-0.15348125584775657},{"$f":"'Op Rav'!AG41","v":-0.10962288279177043},{"$f":"'Op Rav'!AH41","v":-6.5764509735784252E-2},{"$f":"'Op Rav'!AI41","v":-2.1906136679798086E-2}]
[null,null,null,null,"Unprofiled allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"SUM(K8:K12)","v":30.837427592507161},27.268546581562948,31.276623149937237,31.017037261276723,32.013714558234192,31.998192038678798,31.844295019455565,33.193326387821813,33.756671706117061,34.713249919295095,34.493178912469553,34.548602666482829,34.656636901237505,34.805895860490672,35.972620567268983,35.529335769128444,35.567282233420485,38.546801158811533,38.617282145669272,39.454400557669018,39.291440230124778,39.978706469963896,40.056370100026612,40.135001991232677,66.585568495471279]
[]
[null,"Profiled allowances except tax (floor)"]
[]
[null,null,"Annuity parameters"]
[]
[null,null,null,null,"Floor return rate",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I69","v":-2.0999999999999999E-3}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G89","v":"full years"},null,{"$f":"Inputs!I89","v":25}]
[null,null,null,null,"Annuity factor (floor)",null,"scalar",null,{"$f":"I19 / (1 - (1 + I19)^(-I20))","v":3.8917182021590405E-2}]
[]
[null,null,null,null,"Year is within operational period",null,"flag",null,null,null,{"$f":"AND(K4 > 0, K4<= $I20)","v":true},true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true,true]
[null,null,null,null,"Discount factor to start of operational period (floor)",null,"scalar",null,null,null,{"$f":"(1 + $I19) ^ - K4","v":1.0021044192804891},1.0042132671414861,1.0063265529025816,1.0084442859029779,1.0105664755015311,1.0126931310767924,1.0148242620270491,1.016959877770367,1.0190999877446307,1.0212446014075867,1.0233937282368841,1.0255473777301174,1.0277055594048676,1.0298682827987451,1.0320355574694309,1.0342073929947198,1.0363837989725622,1.0385647850211064,1.0407503607787418,1.0429405359041406,1.0451353200763007,1.0473347229945895,1.0495387543787849,1.0517474239691202,1.0539607415263255]
[]
[null,null,"Allowances except tax"]
[]
[null,null,null,null,"Discounted unprofiled allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K13 * K$24","v":30.902322469693519},{"$f":"L13 * L$24","v":27.383436252871128},31.47449636090942,31.278953991774262,32.351986688826784,32.40434928444612,32.316363192890627,33.756281146151167,34.401423722003422,35.450719077392456,35.300102965974091,35.431228868851207,35.61681841367767,{"$f":"X13 * X$24","v":35.845488201115479},37.125023520777759,36.744701720624377,36.861355080201641,40.033350258752435,40.190950325399761,41.148593661391949,41.064871961170297,41.87108746640164,42.040712779717531,42.211884955274478,70.178575146438845]
[null,null,null,null,"NPV of allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"SUM(K28:AI28)","v":933.385077512728}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"G$21","v":"scalar"},null,{"$f":"I$21","v":3.8917182021590405E-2}]
[]
[null,null,null,null,"Annuity of allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I29 * I31","v":36.324716957799104}]
[null,null,null,null,"Annuitised allowances except tax (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K$23 * $I33","v":36.324716957799104},36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,{"$f":"X$23 * $I33","v":36.324716957799104},36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104,36.324716957799104]
[]
[null,"End of sheet"]

{"sheet":"Tax Deductions","index":9,"n_rows":65,"n_cols":35,"rows_kept":65,"cut":false,"hidden":false,"merged":[]}
["Tax Deductions",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"Tax deductions"]
[]
[null,null,"Inflation"]
[]
[null,null,null,null,{"$f":"Inputs!E119","v":"UK RPI uplift from 2016/17 term to start of regime"},null,"scalar",null,{"$f":"Inputs!I119","v":1.1452965748301245}]
[null,null,null,null,{"$f":"Inputs!E116","v":"Long-term expected UK RPI inflation"},null,"%",null,{"$f":"Inputs!I116","v":3.2399999999999998E-2}]
[null,null,null,null,"Forecast UK inflation uplift",null,"scalar",null,null,null,{"$f":"I9*(1+$I$10)^0.5","v":1.1637024799464446},{"$f":"K11*(1+$I$10)","v":1.2014064402967093},{"$f":"L11*(1+$I$10)","v":1.2403320089623227},1.280518766052702,1.3220075740728094,1.3648406194727685,1.4090614555436862,1.4547150467033017,1.5018478142164886,1.5505076833971028,1.6007441323391689,1.6526082422269579,1.7061527492751114,1.761432098351625,1.8185024983382176,1.8774219792843758,1.9382504514131895,2.0010497660389768,2.0658837784586397,2.1328184128806997,2.2019217294580344,2.2732639934924745,2.3469177468816307,2.4229578818805955,2.5014617172535267]
[]
[null,null,"Total tax deductions"]
[]
[null,null,null,null,"Revenue pool additions",null,"£m nominal",null,null,null,{"$f":"K27","v":18.041652133955942},14.297695086626163,19.690133234063683,19.95217036164938,21.871307027254641,22.512367333832643,22.980670521914281,25.44861806945443,26.771043172311149,29.069657722186054,29.484817195172582,30.475321300354128,31.500227823309316,32.560791491874156,35.032114629204557,35.267490715328641,36.462019562809893,37.698544339764794,38.978624006189186,41.939714160291437,42.356915725704319,43.803979479349429,45.302566572087329,46.85462449890543,48.863819828076316]
[null,null,null,null,"Capital allowances",null,"£m nominal",null,null,null,{"$f":"K42","v":27.696594611483164},25.480867042564515,23.442397679159352,21.567005864826605,19.84164539564048,18.254313763989241,17.07071737720927,16.102583314130637,14.814376649000188,13.769470809158772,12.66791314442607,11.745727288520431,10.964708049439988,10.640037337700997,9.7888343506849171,9.0057276026301221,11.929333478400283,10.974986800128262,10.096987856118,9.4821434527217487,9.1560435378440079,8.4235600548164875,7.7496752504311681,7.1297012303966749,81.991564149561754]
[null,null,null,null,"Interest payable",null,"£m nominal",null,null,null,{"$f":"K58","v":6.9969230536970075},6.8055961020579909,6.6084849616701025,6.4054147651704527,6.1962053586130335,5.9806711416449465,5.7586209028508488,5.5298576501195376,5.2941784358821842,5.0513741770671743,4.8012294696118403,4.5435223973665044,4.278024335221331,4.0044997462813061,3.7227059729094312,3.4323930214527283,3.1333033404601043,2.8251715921952982,2.5077244172422208,2.1806801919938485,1.8437487788095368,1.4966312686190935,1.1390197157452731,0.77059686470943345,0.39103586877799229]
[null,null,null,null,"Debt transaction costs",null,"£m nominal",null,null,null,{"$f":"SUMPRODUCT(Finance!K39:AX39,Inputs!K107:AX107)+SUMPRODUCT(Finance!K41:AX41,Inputs!K107:AX107)","v":4.8683567979164515}]
[null,null,null,null,"Total tax deductions",null,"£m nominal",null,null,null,{"$f":"SUM(K15:K18)","v":57.603526597052564},46.584158231248665,49.741015874893137,47.92459099164644,47.909157781508156,46.747352239466835,45.810008801974405,47.081059033704605,{"$f":"SUM(S15:S18)","v":46.879598257193521},47.890502708412001,46.953959809210488,46.764570986241061,46.74296020797064,47.205328575856456,48.543654952798903,47.70561133941149,51.524656381670276,51.498702732088354,51.583336279549407,53.602537805007039,53.356708042357859,53.724170802785004,54.191261538263767,54.754922594011539,131.24641984641607]
[]
[null,"Tax pools"]
[]
[null,null,"Revenue pool"]
[]
[null,null,null,null,"Controllable Opex",null,"£m nominal",null,null,null,{"$f":"Inputs!K61* K$11","v":16.806365136721055},{"$f":"Inputs!L61* L$11","v":13.038541191509831},{"$f":"Inputs!M61* M$11","v":18.402391739759729},{"$f":"Inputs!N61* N$11","v":18.635191992704218},{"$f":"Inputs!O61* O$11","v":20.524427756786523},{"$f":"Inputs!P61* P$11","v":21.134908048262037},{"$f":"Inputs!Q61* Q$11","v":21.57193667807153},{"$f":"Inputs!R61* R$11","v":24.007899343891303},{"$f":"Inputs!S61* S$11","v":25.297613102638973},{"$f":"Inputs!T61* T$11","v":27.56277334025906},{"$f":"Inputs!U61* U$11","v":27.943718651931007},{"$f":"Inputs!V61* V$11","v":28.89923148213736},{"$f":"Inputs!W61* W$11","v":29.888351959445053},{"$f":"Inputs!X61* X$11","v":30.912316753345191},{"$f":"Inputs!Y61* Y$11","v":33.346209718190188},{"$f":"Inputs!Z61* Z$11","v":33.543305445413182},{"$f":"Inputs!AA61* AA$11","v":34.698684429645979},{"$f":"Inputs!AB61* AB$11","v":35.895170081974392},{"$f":"Inputs!AC61* AC$11","v":37.134301156280209},{"$f":"Inputs!AD61* AD$11","v":40.053512585362881},{"$f":"Inputs!AE61* AE$11","v":40.427884157707645},{"$f":"Inputs!AF61* AF$11","v":41.83114503466863},{"$f":"Inputs!AG61* AG$11","v":43.284934260194674},{"$f":"Inputs!AH61* AH$11","v":44.791176719844451},{"$f":"Inputs!AI61* AI$11","v":46.753515858517837}]
[null,null,null,null,"Non-controllable Opex (baseline)",null,"£m nominal",null,null,null,{"$f":"Inputs!K62* K$11","v":1.2352869972348861},{"$f":"Inputs!L62* L$11","v":1.2591538951163332},{"$f":"Inputs!M62* M$11","v":1.2877414943039549},{"$f":"Inputs!N62* N$11","v":1.3169783689451611},{"$f":"Inputs!O62* O$11","v":1.3468792704681183},{"$f":"Inputs!P62* P$11","v":1.377459285570606},{"$f":"Inputs!Q62* Q$11","v":1.4087338438427506},{"$f":"Inputs!R62* R$11","v":1.4407187255631251},{"$f":"Inputs!S62* S$11","v":1.4734300696721752},{"$f":"Inputs!T62* T$11","v":1.506884381926993},{"$f":"Inputs!U62* U$11","v":1.5410985432415738},{"$f":"Inputs!V62* V$11","v":1.5760898182167693},{"$f":"Inputs!W62* W$11","v":1.6118758638642614},{"$f":"Inputs!X62* X$11","v":1.6484747385289638},{"$f":"Inputs!Y62* Y$11","v":1.6859049110143687},{"$f":"Inputs!Z62* Z$11","v":1.7241852699154598},{"$f":"Inputs!AA62* AA$11","v":1.7633351331639113},{"$f":"Inputs!AB62* AB$11","v":1.8033742577903986},{"$f":"Inputs!AC62* AC$11","v":1.8443228499089768},{"$f":"Inputs!AD62* AD$11","v":1.8862015749285577},{"$f":"Inputs!AE62* AE$11","v":1.9290315679966739},{"$f":"Inputs!AF62* AF$11","v":1.9728344446808022},{"$f":"Inputs!AG62* AG$11","v":2.0176323118926551},{"$f":"Inputs!AH62* AH$11","v":2.0634477790609767},{"$f":"Inputs!AI62* AI$11","v":2.1103039695584833}]
[null,null,null,null,"Revenue pool additions",null,"£m nominal",null,null,null,{"$f":"SUM(K25:K26)","v":18.041652133955942},14.297695086626163,19.690133234063683,19.95217036164938,21.871307027254641,22.512367333832643,22.980670521914281,25.44861806945443,26.771043172311149,29.069657722186054,29.484817195172582,30.475321300354128,31.500227823309316,32.560791491874156,35.032114629204557,35.267490715328641,36.462019562809893,37.698544339764794,38.978624006189186,41.939714160291437,42.356915725704319,43.803979479349429,45.302566572087329,46.85462449890543,48.863819828076316]
[]
[null,null,"Capital allowance pool"]
[]
[null,null,null,null,"Capital allowance rate (declining balance)",null,{"$f":"Inputs!G114","v":"%"},null,null,null,{"$f":"Inputs!K114","v":0.08},{"$f":"Inputs!L114","v":0.08},{"$f":"Inputs!M114","v":0.08},{"$f":"Inputs!N114","v":0.08},{"$f":"Inputs!O114","v":0.08},{"$f":"Inputs!P114","v":0.08},{"$f":"Inputs!Q114","v":0.08},{"$f":"Inputs!R114","v":0.08},{"$f":"Inputs!S114","v":0.08},{"$f":"Inputs!T114","v":0.08},{"$f":"Inputs!U114","v":0.08},{"$f":"Inputs!V114","v":0.08},{"$f":"Inputs!W114","v":0.08},{"$f":"Inputs!X114","v":0.08},{"$f":"Inputs!Y114","v":0.08},{"$f":"Inputs!Z114","v":0.08},{"$f":"Inputs!AA114","v":0.08},{"$f":"Inputs!AB114","v":0.08},{"$f":"Inputs!AC114","v":0.08},{"$f":"Inputs!AD114","v":0.08},{"$f":"Inputs!AE114","v":0.08},{"$f":"Inputs!AF114","v":0.08},{"$f":"Inputs!AG114","v":0.08},{"$f":"Inputs!AH114","v":0.08},{"$f":"Inputs!AI114","v":0.08}]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G89","v":"full years"},null,{"$f":"Inputs!I89","v":25}]
[]
[null,null,null,null,"Opening balance brought forward",null,"£m nominal",null,null,null,{"$f":"J40","v":0},318.51083803205643,293.02997098949191,269.58757331033257,248.02056744550598,228.17892204986549,209.92460828587625,196.3132498379066,185.17970811250234,170.36533146350214,158.34891430532588,145.6810011608998,135.07586381798495,126.09414256855985,122.36042938356145,112.57159503287653,103.56586743024641,137.18733500160326,126.212348201475,116.11536034535699,109.04464970630011,105.29450068520609,96.870940630389597,89.12126537995843,81.991564149561754]
[null,null,null,null,"Capex",null,"£m nominal",null,null,null,{"$f":"SUMPRODUCT('Pre Op RAV'!K19:AX19,Inputs!K107:AX107)","v":346.20743264353956}]
[null,null,null,null,"Replacement Capex",null,"£m nominal",null,null,null,{"$f":"'Op Rav'!K13 * K$11","v":0},{"$f":"'Op Rav'!L13 * L$11","v":0},{"$f":"'Op Rav'!M13 * M$11","v":0},{"$f":"'Op Rav'!N13 * N$11","v":0},{"$f":"'Op Rav'!O13 * O$11","v":0},{"$f":"'Op Rav'!P13 * P$11","v":0},{"$f":"'Op Rav'!Q13 * Q$11","v":3.4593589292396114},{"$f":"'Op Rav'!R13 * R$11","v":4.9690415887263768},{"$f":"'Op Rav'!S13 * S$11","v":0},{"$f":"'Op Rav'!T13 * T$11","v":1.7530536509825172},{"$f":"'Op Rav'!U13 * U$11","v":0},{"$f":"'Op Rav'!V13 * V$11","v":1.1405899456055884},{"$f":"'Op Rav'!W13 * W$11","v":1.9829868000148871},{"$f":"'Op Rav'!X13 * X$11","v":6.9063241527026058},{"$f":"'Op Rav'!Y13 * Y$11","v":0},{"$f":"'Op Rav'!Z13 * Z$11","v":0},{"$f":"'Op Rav'!AA13 * AA$11","v":45.550801049757133},{"$f":"'Op Rav'!AB13 * AB$11","v":0},{"$f":"'Op Rav'!AC13 * AC$11","v":0},{"$f":"'Op Rav'!AD13 * AD$11","v":2.4114328136648528},{"$f":"'Op Rav'!AE13 * AE$11","v":5.4058945167499948},{"$f":"'Op Rav'!AF13 * AF$11","v":0},{"$f":"'Op Rav'!AG13 * AG$11","v":0},{"$f":"'Op Rav'!AH13 * AH$11","v":0},{"$f":"'Op Rav'!AI13 * AI$11","v":0}]
[null,null,null,null,"Tax book value pre-depreciation",null,"£m nominal",null,null,null,{"$f":"SUM(K34:K36)","v":346.20743264353956},318.51083803205643,293.02997098949191,269.58757331033257,248.02056744550598,228.17892204986549,213.38396721511586,201.28229142663298,185.17970811250234,172.11838511448465,158.34891430532588,146.82159110650539,137.05885061799984,133.00046672126246,122.36042938356145,112.57159503287653,149.11666848000354,137.18733500160326,126.212348201475,118.52679315902185,114.4505442230501,105.29450068520609,96.870940630389597,89.12126537995843,81.991564149561754]
[null,null,null,null,"Capital allowance (reducing balance)",null,"£m nominal",null,null,null,{"$f":"-K37 * K31","v":-27.696594611483164},{"$f":"-L37 * L31","v":-25.480867042564515},{"$f":"-M37 * M31","v":-23.442397679159352},-21.567005864826605,-19.84164539564048,-18.254313763989241,-17.07071737720927,-16.102583314130637,-14.814376649000188,-13.769470809158772,-12.66791314442607,-11.745727288520431,-10.964708049439988,-10.640037337700997,-9.7888343506849171,-9.0057276026301221,-11.929333478400283,-10.974986800128262,-10.096987856118,-9.4821434527217487,-9.1560435378440079,-8.4235600548164875,-7.7496752504311681,-7.1297012303966749,-6.5593251319649406]
[null,null,null,null,"Write-back allowance",null,"£m nominal",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"-SUM(AI37:AI38)","v":-75.432239017596814}]
[null,null,null,null,"Closing balance carried forward",null,"£m nominal",null,null,null,{"$f":"SUM(K37:K39)","v":318.51083803205643},{"$f":"SUM(L37:L39)","v":293.02997098949191},269.58757331033257,248.02056744550598,228.17892204986549,209.92460828587625,196.3132498379066,185.17970811250234,170.36533146350214,158.34891430532588,145.6810011608998,135.07586381798495,126.09414256855985,122.36042938356145,112.57159503287653,103.56586743024641,137.18733500160326,126.212348201475,116.11536034535699,109.04464970630011,105.29450068520609,96.870940630389597,89.12126537995843,81.991564149561754,{"$f":"SUM(AI37:AI39)","v":0}]
[]
[null,null,null,null,"Capital allowances",null,"£m nominal",null,null,null,{"$f":"-(K38 + K39)","v":27.696594611483164},{"$f":"-(L38 + L39)","v":25.480867042564515},23.442397679159352,21.567005864826605,19.84164539564048,18.254313763989241,17.07071737720927,16.102583314130637,14.814376649000188,13.769470809158772,12.66791314442607,{"$f":"-(V38 + V39)","v":11.745727288520431},10.964708049439988,10.640037337700997,9.7888343506849171,9.0057276026301221,11.929333478400283,10.974986800128262,10.096987856118,9.4821434527217487,9.1560435378440079,8.4235600548164875,7.7496752504311681,7.1297012303966749,81.991564149561754]
[]
[null,"Interest"]
[]
[null,null,"Cost of debt"]
[]
[null,null,null,null,"Cost of debt (for tax)",null,{"$f":"Inputs!G69","v":"real annual %"},null,{"$f":"Inputs!I71","v":-2.0999999999999999E-3}]
[null,null,null,null,"Expected UK RPI inflation",null,{"$f":"Inputs!G116","v":"%"},null,{"$f":"Inputs!I116","v":3.2399999999999998E-2}]
[null,null,null,null,"Cost of debt (for tax)",null,"nominal annual %",null,{"$f":"(1 + I48) * (1 + I$49) - 1","v":3.0231960000000058E-2}]
[]
[null,null,"Net debt"]
[]
[null,null,null,null,"Number of operational years",null,{"$f":"Inputs!G89","v":"full years"},null,{"$f":"Inputs!I89","v":25}]
[null,null,null,null,"Operational notional gearing",null,{"$f":"Inputs!G74","v":"%"},null,{"$f":"Inputs!I74","v":0.5}]
[]
[null,null,null,null,"Principal repayments",null,"£m nominal",null,null,null,{"$f":"K59 - K58","v":6.3286320714573465},{"$f":"L59 - L58","v":6.5199590230963631},6.7170701634842516,6.9201403599839013,7.1293497665413206,7.3448839835094075,7.5669342223035052,7.7956974750348165,8.0313766892721699,8.2741809480871797,8.5243256555425138,8.7820327277878505,9.047530789933024,9.3210553788730479,9.6028491522449233,9.8931621037016253,10.19225178469425,10.500383532959056,10.817830707912133,11.144874933160505,11.481806346344817,11.82892385653526,12.186535409409082,12.55495826044492,12.934519256376362]
[null,null,null,null,"Net interest paid",null,"£m nominal",null,null,null,{"$f":"$I50 * K61","v":6.9969230536970075},6.8055961020579909,6.6084849616701025,6.4054147651704527,6.1962053586130335,5.9806711416449465,5.7586209028508488,5.5298576501195376,5.2941784358821842,5.0513741770671743,4.8012294696118403,4.5435223973665044,4.278024335221331,4.0044997462813061,3.7227059729094312,3.4323930214527283,3.1333033404601043,2.8251715921952982,2.5077244172422208,2.1806801919938485,1.8437487788095368,1.4966312686190935,1.1390197157452731,0.77059686470943345,0.39103586877799229]
[null,null,null,null,"Total",null,"£m nominal",null,null,null,{"$f":"$K$61*$I50/(1-(1+$I50)^(-$I54))","v":13.325555125154354},{"$f":"$K$61*$I50/(1-(1+$I50)^(-$I54))","v":13.325555125154354},13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354,13.325555125154354]
[]
[null,null,null,null,"Opening net debt",null,"£m nominal",null,null,null,{"$f":"'Op Rav'!K12*I9*I55","v":231.4412645986894},{"$f":"K63","v":225.11263252723205},{"$f":"L63","v":218.59267350413569},211.87560334065142,204.95546298066753,197.82611321412622,190.4812292306168,182.9142950083133,175.11859753327849,167.08722084400631,158.81303989591913,150.28871424037661,141.50668151258876,132.45915072265572,123.13809534378268,113.53524619153775,103.64208408783612,93.449832303141875,82.949448770182812,72.131618062270675,60.986743129110167,49.504936782765348,37.676012926230086,25.489477516821005,12.934519256376085]
[null,null,null,null,"Less principal repayment",null,"£m nominal",null,null,null,{"$f":"IF(K3 = \"Year \"&$I54, -K61, -K57)","v":-6.3286320714573465},-6.5199590230963631,-6.7170701634842516,-6.9201403599839013,-7.1293497665413206,-7.3448839835094075,-7.5669342223035052,-7.7956974750348165,-8.0313766892721699,-8.2741809480871797,-8.5243256555425138,-8.7820327277878505,-9.047530789933024,-9.3210553788730479,-9.6028491522449233,-9.8931621037016253,-10.19225178469425,-10.500383532959056,-10.817830707912133,-11.144874933160505,-11.481806346344817,-11.82892385653526,-12.186535409409082,-12.55495826044492,{"$f":"IF(AI3 = \"Year \"&$I54, -AI61, -AI57)","v":-12.934519256376085}]
[null,null,null,null,"Closing net debt",null,"£m nominal",null,null,null,{"$f":"SUM(K61:K62)","v":225.11263252723205},{"$f":"SUM(L61:L62)","v":218.59267350413569},211.87560334065142,204.95546298066753,197.82611321412622,190.4812292306168,182.9142950083133,175.11859753327849,167.08722084400631,158.81303989591913,150.28871424037661,141.50668151258876,132.45915072265572,{"$f":"SUM(X61:X62)","v":123.13809534378268},{"$f":"SUM(Y61:Y62)","v":113.53524619153775},103.64208408783612,93.449832303141875,82.949448770182812,72.131618062270675,60.986743129110167,49.504936782765348,37.676012926230086,25.489477516821005,12.934519256376085,0]
[]
[null,"End of sheet"]

{"sheet":"Tax Cap","index":10,"n_rows":42,"n_cols":35,"rows_kept":42,"cut":false,"hidden":false,"merged":[]}
["Tax Cap",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"Unprofiled tax allowance (cap)"]
[]
[null,null,"Profits attributable to corporation tax"]
[]
[null,null,null,null,"Annuitised allowances except tax (cap)",null,"£m nominal prices",null,null,null,{"$f":"'Allowances Cap'!K34* 'Tax Deductions'!K$11","v":64.374393021004963},{"$f":"'Allowances Cap'!L34* 'Tax Deductions'!L$11","v":66.460123354885511},{"$f":"'Allowances Cap'!M34* 'Tax Deductions'!M$11","v":68.613431351583799},{"$f":"'Allowances Cap'!N34* 'Tax Deductions'!N$11","v":70.836506527375121},{"$f":"'Allowances Cap'!O34* 'Tax Deductions'!O$11","v":73.131609338862063},{"$f":"'Allowances Cap'!P34* 'Tax Deductions'!P$11","v":75.501073481441196},{"$f":"'Allowances Cap'!Q34* 'Tax Deductions'!Q$11","v":77.947308262239901},{"$f":"'Allowances Cap'!R34* 'Tax Deductions'!R$11","v":80.472801049936479},{"$f":"'Allowances Cap'!S34* 'Tax Deductions'!S$11","v":83.080119803954418},{"$f":"'Allowances Cap'!T34* 'Tax Deductions'!T$11","v":85.771915685602536},{"$f":"'Allowances Cap'!U34* 'Tax Deductions'!U$11","v":88.55092575381606},{"$f":"'Allowances Cap'!V34* 'Tax Deductions'!V$11","v":91.419975748239693},{"$f":"'Allowances Cap'!W34* 'Tax Deductions'!W$11","v":94.381982962482653},{"$f":"'Allowances Cap'!X34* 'Tax Deductions'!X$11","v":97.439959210467094},{"$f":"'Allowances Cap'!Y34* 'Tax Deductions'!Y$11","v":100.59701388888622},{"$f":"'Allowances Cap'!Z34* 'Tax Deductions'!Z$11","v":103.85635713888614},{"$f":"'Allowances Cap'!AA34* 'Tax Deductions'!AA$11","v":107.22130311018604},{"$f":"'Allowances Cap'!AB34* 'Tax Deductions'!AB$11","v":110.69527333095607},{"$f":"'Allowances Cap'!AC34* 'Tax Deductions'!AC$11","v":114.28180018687905},{"$f":"'Allowances Cap'!AD34* 'Tax Deductions'!AD$11","v":117.98453051293394},{"$f":"'Allowances Cap'!AE34* 'Tax Deductions'!AE$11","v":121.80722930155299},{"$f":"'Allowances Cap'!AF34* 'Tax Deductions'!AF$11","v":125.7537835309233},{"$f":"'Allowances Cap'!AG34* 'Tax Deductions'!AG$11","v":129.82820611732521},{"$f":"'Allowances Cap'!AH34* 'Tax Deductions'!AH$11","v":134.03463999552656},{"$f":"'Allowances Cap'!AI34* 'Tax Deductions'!AI$11","v":138.37736233138162}]
[null,null,null,null,"Less tax deductions",null,"£m nominal prices",null,null,null,{"$f":"-'Tax Deductions'!K19","v":-57.603526597052564},{"$f":"-'Tax Deductions'!L19","v":-46.584158231248665},{"$f":"-'Tax Deductions'!M19","v":-49.741015874893137},{"$f":"-'Tax Deductions'!N19","v":-47.92459099164644},{"$f":"-'Tax Deductions'!O19","v":-47.909157781508156},{"$f":"-'Tax Deductions'!P19","v":-46.747352239466835},{"$f":"-'Tax Deductions'!Q19","v":-45.810008801974405},{"$f":"-'Tax Deductions'!R19","v":-47.081059033704605},{"$f":"-'Tax Deductions'!S19","v":-46.879598257193521},{"$f":"-'Tax Deductions'!T19","v":-47.890502708412001},{"$f":"-'Tax Deductions'!U19","v":-46.953959809210488},{"$f":"-'Tax Deductions'!V19","v":-46.764570986241061},{"$f":"-'Tax Deductions'!W19","v":-46.74296020797064},{"$f":"-'Tax Deductions'!X19","v":-47.205328575856456},{"$f":"-'Tax Deductions'!Y19","v":-48.543654952798903},{"$f":"-'Tax Deductions'!Z19","v":-47.70561133941149},{"$f":"-'Tax Deductions'!AA19","v":-51.524656381670276},{"$f":"-'Tax Deductions'!AB19","v":-51.498702732088354},{"$f":"-'Tax Deductions'!AC19","v":-51.583336279549407},{"$f":"-'Tax Deductions'!AD19","v":-53.602537805007039},{"$f":"-'Tax Deductions'!AE19","v":-53.356708042357859},{"$f":"-'Tax Deductions'!AF19","v":-53.724170802785004},{"$f":"-'Tax Deductions'!AG19","v":-54.191261538263767},{"$f":"-'Tax Deductions'!AH19","v":-54.754922594011539},{"$f":"-'Tax Deductions'!AI19","v":-131.24641984641607}]
[null,null,null,null,"Profits attributable to corporation tax",null,"£m nominal prices",null,null,null,{"$f":"SUM(K9:K10)","v":6.7708664239523983},{"$f":"SUM(L9:L10)","v":19.875965123636846},18.872415476690662,22.911915535728681,25.222451557353907,28.753721241974361,32.137299460265496,33.391742016231873,36.200521546760896,37.881412977190536,41.596965944605572,44.655404761998632,47.639022754512013,50.234630634610639,52.053358936087321,56.150745799474649,55.696646728515766,59.196570598867716,62.698463907329646,64.381992707926912,68.450521259195142,72.029612728138289,75.636944579061435,79.279717401515029,7.1309424849655443]
[]
[null,null,"Tax losses"]
[]
[null,null,null,null,"Taxable losses brought forward",null,"£m nominal prices",null,null,null,{"$f":"J18","v":0},{"$f":"K18","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"In-year taxable loss",null,"£m nominal prices",null,null,null,{"$f":"MIN(K11, 0)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Profits used to offset losses",null,"£m nominal prices",null,null,null,{"$f":"IF(K11 >= 0, MIN(K11, -K15), 0)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Taxable losses carried forward",null,"£m nominal prices",null,null,null,{"$f":"SUM(K15:K17)","v":0},{"$f":"SUM(L15:L17)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"Tax allowance"]
[]
[null,null,null,null,"Profits attributable to corporation tax (after taxable losses)",null,"£m nominal prices",null,null,null,{"$f":"MAX(K11 - K17,0)","v":6.7708664239523983},19.875965123636846,18.872415476690662,22.911915535728681,25.222451557353907,28.753721241974361,32.137299460265496,33.391742016231873,36.200521546760896,37.881412977190536,41.596965944605572,44.655404761998632,47.639022754512013,{"$f":"MAX(X11 - X17,0)","v":50.234630634610639},{"$f":"MAX(Y11 - Y17,0)","v":52.053358936087321},56.150745799474649,55.696646728515766,59.196570598867716,62.698463907329646,64.381992707926912,68.450521259195142,72.029612728138289,75.636944579061435,79.279717401515029,7.1309424849655443]
[null,null,null,null,"Corporation tax rate",null,{"$f":"Inputs!G113","v":"%"},null,null,null,{"$f":"Inputs!K113","v":0.19},{"$f":"Inputs!L113","v":0.19},{"$f":"Inputs!M113","v":0.19},{"$f":"Inputs!N113","v":0.19},{"$f":"Inputs!O113","v":0.19},{"$f":"Inputs!P113","v":0.19},{"$f":"Inputs!Q113","v":0.19},{"$f":"Inputs!R113","v":0.19},{"$f":"Inputs!S113","v":0.19},{"$f":"Inputs!T113","v":0.19},{"$f":"Inputs!U113","v":0.19},{"$f":"Inputs!V113","v":0.19},{"$f":"Inputs!W113","v":0.19},{"$f":"Inputs!X113","v":0.19},{"$f":"Inputs!Y113","v":0.19},{"$f":"Inputs!Z113","v":0.19},{"$f":"Inputs!AA113","v":0.19},{"$f":"Inputs!AB113","v":0.19},{"$f":"Inputs!AC113","v":0.19},{"$f":"Inputs!AD113","v":0.19},{"$f":"Inputs!AE113","v":0.19},{"$f":"Inputs!AF113","v":0.19},{"$f":"Inputs!AG113","v":0.19},{"$f":"Inputs!AH113","v":0.19},{"$f":"Inputs!AI113","v":0.19}]
[null,null,null,null,"Corporation tax charge after losses",null,"£m nominal prices",null,null,null,{"$f":"K22 * K23","v":1.2864646205509558},3.7764333734910007,3.585758940571226,4.3532639517884499,4.7922657958972419,5.4632070359751284,6.1060868974504441,6.344430983084056,6.8780990938845701,7.1974684656662022,7.9034235294750586,8.4845269047797398,9.0514143233572817,{"$f":"X22 * X23","v":9.5445798205760219},{"$f":"Y22 * Y23","v":9.8901381978565919},10.668641701900183,10.582362878417996,11.247348413784866,11.912708142392633,12.232578614506114,13.005599039247077,13.685626418346276,14.371019470021674,15.063146306287855,1.3548790721434534]
[]
[null,null,null,null,"Grossing-up factor for tax on tax charge after losses",null,"scalar",null,null,null,{"$f":"1 / (1 - K23)","v":1.2345679012345678},1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,{"$f":"1 / (1 - X23)","v":1.2345679012345678},{"$f":"1 / (1 - Y23)","v":1.2345679012345678},1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678]
[]
[null,null,null,null,"Unprofiled tax allowance (cap)",null,"£m nominal prices",null,null,null,{"$f":"K24 * K26","v":1.5882279266061181},4.6622634240629637,4.4268628895941058,5.3743999404795675,5.9163775257990636,6.7447000444137384,7.538378885741289,7.8326308433136491,8.4914803628204556,8.8857635378595088,9.7573129993519228,10.474724573802147,11.174585584391705,{"$f":"X24 * X26","v":11.783431877254348},{"$f":"Y24 * Y26","v":12.210047157847644},{"$f":"Z24 * Z26","v":13.171162594938497},13.064645528911106,13.885615325660329,14.707047089373621,15.10194890679767,16.056295110181576,16.895835084378117,17.741999345705768,18.596476921343029,1.6726902125227818]
[]
[null,"Profiled tax allowance (cap)"]
[]
[null,null,null,null,"Unprofiled tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Tax Cap'!K28 / 'Tax Deductions'!K11","v":1.3648058279288111},{"$f":"'Tax Cap'!L28 / 'Tax Deductions'!L11","v":3.8806712430403922},{"$f":"'Tax Cap'!M28 / 'Tax Deductions'!M11","v":3.5690950951896139},{"$f":"'Tax Cap'!N28 / 'Tax Deductions'!N11","v":4.1970489484090656},{"$f":"'Tax Cap'!O28 / 'Tax Deductions'!O11","v":4.4752977530771849},{"$f":"'Tax Cap'!P28 / 'Tax Deductions'!P11","v":4.9417492036683264},{"$f":"'Tax Cap'!Q28 / 'Tax Deductions'!Q11","v":5.3499291007379135},{"$f":"'Tax Cap'!R28 / 'Tax Deductions'!R11","v":5.3843059237368047},{"$f":"'Tax Cap'!S28 / 'Tax Deductions'!S11","v":5.6540218539056477},{"$f":"'Tax Cap'!T28 / 'Tax Deductions'!T11","v":5.7308735925713972},{"$f":"'Tax Cap'!U28 / 'Tax Deductions'!U11","v":6.0954857195656578},{"$f":"'Tax Cap'!V28 / 'Tax Deductions'!V11","v":6.3382986397835115},{"$f":"'Tax Cap'!W28 / 'Tax Deductions'!W11","v":6.5495809734148489},{"$f":"'Tax Cap'!X28 / 'Tax Deductions'!X11","v":6.689688400865105},{"$f":"'Tax Cap'!Y28 / 'Tax Deductions'!Y11","v":6.7143417009354778},{"$f":"'Tax Cap'!Z28 / 'Tax Deductions'!Z11","v":7.0155578981551079},{"$f":"'Tax Cap'!AA28 / 'Tax Deductions'!AA11","v":6.7404320836791749},{"$f":"'Tax Cap'!AB28 / 'Tax Deductions'!AB11","v":6.9391654127355986},{"$f":"'Tax Cap'!AC28 / 'Tax Deductions'!AC11","v":7.1190099088471372},{"$f":"'Tax Cap'!AD28 / 'Tax Deductions'!AD11","v":7.0807476227665171},{"$f":"'Tax Cap'!AE28 / 'Tax Deductions'!AE11","v":7.2919463464005867},{"$f":"'Tax Cap'!AF28 / 'Tax Deductions'!AF11","v":7.4324122199378202},{"$f":"'Tax Cap'!AG28 / 'Tax Deductions'!AG11","v":7.5597022389385868},{"$f":"'Tax Cap'!AH28 / 'Tax Deductions'!AH11","v":7.6751135710659755},{"$f":"'Tax Cap'!AI28 / 'Tax Deductions'!AI11","v":0.66868511358203298}]
[null,null,null,null,"Discount factor to start of operational period (cap)",null,{"$f":"'Allowances Cap'!G24","v":"scalar"},null,null,null,{"$f":"'Allowances Cap'!K24","v":0.92506938020351526},{"$f":"'Allowances Cap'!L24","v":0.85575335819011589},{"$f":"'Allowances Cap'!M24","v":0.79163122866800739},{"$f":"'Allowances Cap'!N24","v":0.73231381005366081},{"$f":"'Allowances Cap'!O24","v":0.67744108238081491},{"$f":"'Allowances Cap'!P24","v":0.62668000220241893},{"$f":"'Allowances Cap'!Q24","v":0.57972248122332926},{"$f":"'Allowances Cap'!R24","v":0.53628351639530925},{"$f":"'Allowances Cap'!S24","v":0.49609946012517048},{"$f":"'Allowances Cap'!T24","v":0.45892642009728996},{"$f":"'Allowances Cap'!U24","v":0.42453877899841808},{"$f":"'Allowances Cap'!V24","v":0.39272782516042376},{"$f":"'Allowances Cap'!W24","v":0.36330048580982777},{"$f":"'Allowances Cap'!X24","v":0.33607815523573337},{"$f":"'Allowances Cap'!Y24","v":0.31089561076386063},{"$f":"'Allowances Cap'!Z24","v":0.28760000995731788},{"$f":"'Allowances Cap'!AA24","v":0.26604996295774092},{"$f":"'Allowances Cap'!AB24","v":0.24611467433648557},{"$f":"'Allowances Cap'!AC24","v":0.22767314924744272},{"$f":"'Allowances Cap'!AD24","v":0.21061345906331425},{"$f":"'Allowances Cap'!AE24","v":0.19483206203821857},{"$f":"'Allowances Cap'!AF24","v":0.18023317487346768},{"$f":"'Allowances Cap'!AG24","v":0.16672819137231054},{"$f":"'Allowances Cap'!AH24","v":0.15423514465523638},{"$f":"'Allowances Cap'!AI24","v":0.14267820967181905}]
[]
[null,null,null,null,"Discounted unprofiled tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K32 * K33","v":1.2625400813402508},{"$f":"L32 * L33","v":3.3208974482636271},2.8254071354379127,3.0735569063911532,3.0317505538210372,3.096895401838669,3.1014741726486776,2.8875145141296672,2.8049571892585075,2.6300493018688864,2.5877700647866981,2.4892262400194505,2.3794659494924191,{"$f":"X32 * X33","v":2.2482581368646275},{"$f":"Y32 * Y33","v":2.0874593639895944},2.0176745213655489,1.7932917061820128,1.7078304357224263,1.620807405470978,1.4913007495851955,1.4207049429412804,1.3395672513677512,1.2604154816114372,1.1837722518787286,9.5406794840081438E-2]
[null,null,null,null,"NPV of tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"SUM(K35:AI35)","v":53.757994001116622}]
[]
[null,null,null,null,"Annuity factor (cap)",null,{"$f":"'Allowances Cap'!G31","v":"scalar"},null,{"$f":"'Allowances Cap'!I31","v":9.4480276733656054E-2}]
[]
[null,null,null,null,"Annuity of tax allowance (cap)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I36 * I38","v":5.0790701498717201}]
[]
[null,"End of sheet"]

{"sheet":"Tax Floor","index":11,"n_rows":42,"n_cols":35,"rows_kept":42,"cut":false,"hidden":false,"merged":[]}
["Tax Floor",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant",null,"Annual values"]
[null,null,null,null,"Project year",null,null,null,null,null,"Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10","Year 11","Year 12","Year 13","Year 14","Year 15","Year 16","Year 17","Year 18","Year 19","Year 20","Year 21","Year 22","Year 23","Year 24","Year 25"]
[]
[null,"Unprofiled tax allowance (floor)"]
[]
[null,null,"Profits attributable to corporation tax"]
[]
[null,null,null,null,"Annuitised allowances except tax (floor)",null,"£m nominal prices",null,null,null,{"$f":"'Allowances Floor'!K34* 'Tax Deductions'!K$11","v":42.271163207143488},{"$f":"'Allowances Floor'!L34* 'Tax Deductions'!L$11","v":43.640748895054934},{"$f":"'Allowances Floor'!M34* 'Tax Deductions'!M$11","v":45.054709159254713},{"$f":"'Allowances Floor'!N34* 'Tax Deductions'!N$11","v":46.514481736014567},{"$f":"'Allowances Floor'!O34* 'Tax Deductions'!O$11","v":48.021550944261435},{"$f":"'Allowances Floor'!P34* 'Tax Deductions'!P$11","v":49.577449194855511},{"$f":"'Allowances Floor'!Q34* 'Tax Deductions'!Q$11","v":51.183758548768829},{"$f":"'Allowances Floor'!R34* 'Tax Deductions'!R$11","v":52.842112325748936},{"$f":"'Allowances Floor'!S34* 'Tax Deductions'!S$11","v":54.5541967651032},{"$f":"'Allowances Floor'!T34* 'Tax Deductions'!T$11","v":56.321752740292546},{"$f":"'Allowances Floor'!U34* 'Tax Deductions'!U$11","v":58.146577529078023},{"$f":"'Allowances Floor'!V34* 'Tax Deductions'!V$11","v":60.030526641020145},{"$f":"'Allowances Floor'!W34* 'Tax Deductions'!W$11","v":61.975515704189206},{"$f":"'Allowances Floor'!X34* 'Tax Deductions'!X$11","v":63.983522413004934},{"$f":"'Allowances Floor'!Y34* 'Tax Deductions'!Y$11","v":66.056588539186293},{"$f":"'Allowances Floor'!Z34* 'Tax Deductions'!Z$11","v":68.196822007855928},{"$f":"'Allowances Floor'!AA34* 'Tax Deductions'!AA$11","v":70.406399040910458},{"$f":"'Allowances Floor'!AB34* 'Tax Deductions'!AB$11","v":72.687566369835949},{"$f":"'Allowances Floor'!AC34* 'Tax Deductions'!AC$11","v":75.042643520218633},{"$f":"'Allowances Floor'!AD34* 'Tax Deductions'!AD$11","v":77.47402517027372},{"$f":"'Allowances Floor'!AE34* 'Tax Deductions'!AE$11","v":79.984183585790589},{"$f":"'Allowances Floor'!AF34* 'Tax Deductions'!AF$11","v":82.575671133970204},{"$f":"'Allowances Floor'!AG34* 'Tax Deductions'!AG$11","v":85.251122878710831},{"$f":"'Allowances Floor'!AH34* 'Tax Deductions'!AH$11","v":88.013259259981069},{"$f":"'Allowances Floor'!AI34* 'Tax Deductions'!AI$11","v":90.864888860004456}]
[null,null,null,null,"Less tax deductions",null,"£m nominal prices",null,null,null,{"$f":"-'Tax Deductions'!K19","v":-57.603526597052564},{"$f":"-'Tax Deductions'!L19","v":-46.584158231248665},{"$f":"-'Tax Deductions'!M19","v":-49.741015874893137},{"$f":"-'Tax Deductions'!N19","v":-47.92459099164644},{"$f":"-'Tax Deductions'!O19","v":-47.909157781508156},{"$f":"-'Tax Deductions'!P19","v":-46.747352239466835},{"$f":"-'Tax Deductions'!Q19","v":-45.810008801974405},{"$f":"-'Tax Deductions'!R19","v":-47.081059033704605},{"$f":"-'Tax Deductions'!S19","v":-46.879598257193521},{"$f":"-'Tax Deductions'!T19","v":-47.890502708412001},{"$f":"-'Tax Deductions'!U19","v":-46.953959809210488},{"$f":"-'Tax Deductions'!V19","v":-46.764570986241061},{"$f":"-'Tax Deductions'!W19","v":-46.74296020797064},{"$f":"-'Tax Deductions'!X19","v":-47.205328575856456},{"$f":"-'Tax Deductions'!Y19","v":-48.543654952798903},{"$f":"-'Tax Deductions'!Z19","v":-47.70561133941149},{"$f":"-'Tax Deductions'!AA19","v":-51.524656381670276},{"$f":"-'Tax Deductions'!AB19","v":-51.498702732088354},{"$f":"-'Tax Deductions'!AC19","v":-51.583336279549407},{"$f":"-'Tax Deductions'!AD19","v":-53.602537805007039},{"$f":"-'Tax Deductions'!AE19","v":-53.356708042357859},{"$f":"-'Tax Deductions'!AF19","v":-53.724170802785004},{"$f":"-'Tax Deductions'!AG19","v":-54.191261538263767},{"$f":"-'Tax Deductions'!AH19","v":-54.754922594011539},{"$f":"-'Tax Deductions'!AI19","v":-131.24641984641607}]
[null,null,null,null,"Profits attributable to corporation tax",null,"£m nominal prices",null,null,null,{"$f":"SUM(K9:K10)","v":-15.332363389909077},{"$f":"SUM(L9:L10)","v":-2.9434093361937315},-4.6863067156384233,-1.4101092556318733,0.11239316275327838,2.8300969553886759,5.3737497467944237,5.7610532920443305,7.6745985079096783,8.4312500318805448,11.192617719867535,13.265955654779084,15.232555496218566,16.778193837148478,17.512933586387391,20.491210668444438,18.881742659240182,21.188863637747595,23.459307240669226,23.871487365266681,26.62747554343273,28.8515003311852,31.059861340447064,33.25833666596953,-40.381530986411619]
[]
[null,null,"Tax losses"]
[]
[null,null,null,null,"Taxable losses brought forward",null,"£m nominal prices",null,null,null,{"$f":"J18","v":0},{"$f":"K18","v":-15.332363389909077},-18.275772726102808,-22.962079441741231,-24.372188697373105,-24.259795534619826,-21.42969857923115,-16.055948832436727,-10.294895540392396,-2.6202970324827177,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"In-year taxable loss",null,"£m nominal prices",null,null,null,{"$f":"MIN(K11, 0)","v":-15.332363389909077},-2.9434093361937315,-4.6863067156384233,-1.4101092556318733,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,-40.381530986411619]
[null,null,null,null,"Profits used to offset losses",null,"£m nominal prices",null,null,null,{"$f":"IF(K11 >= 0, MIN(K11, -K15), 0)","v":0},0,0,0,0.11239316275327838,2.8300969553886759,5.3737497467944237,5.7610532920443305,7.6745985079096783,2.6202970324827177,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"Taxable losses carried forward",null,"£m nominal prices",null,null,null,{"$f":"SUM(K15:K17)","v":-15.332363389909077},{"$f":"SUM(L15:L17)","v":-18.275772726102808},-22.962079441741231,-24.372188697373105,-24.259795534619826,-21.42969857923115,-16.055948832436727,-10.294895540392396,-2.6202970324827177,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,-40.381530986411619]
[]
[null,null,"Tax allowance"]
[]
[null,null,null,null,"Profits attributable to corporation tax (after taxable losses)",null,"£m nominal prices",null,null,null,{"$f":"MAX(K11 - K17,0)","v":0},0,0,0,0,0,0,0,0,5.8109529993978271,11.192617719867535,13.265955654779084,15.232555496218566,16.778193837148478,17.512933586387391,20.491210668444438,18.881742659240182,21.188863637747595,23.459307240669226,23.871487365266681,26.62747554343273,28.8515003311852,31.059861340447064,33.25833666596953,0]
[null,null,null,null,"Corporation tax rate",null,{"$f":"Inputs!G113","v":"%"},null,null,null,{"$f":"Inputs!K113","v":0.19},{"$f":"Inputs!L113","v":0.19},{"$f":"Inputs!M113","v":0.19},{"$f":"Inputs!N113","v":0.19},{"$f":"Inputs!O113","v":0.19},{"$f":"Inputs!P113","v":0.19},{"$f":"Inputs!Q113","v":0.19},{"$f":"Inputs!R113","v":0.19},{"$f":"Inputs!S113","v":0.19},{"$f":"Inputs!T113","v":0.19},{"$f":"Inputs!U113","v":0.19},{"$f":"Inputs!V113","v":0.19},{"$f":"Inputs!W113","v":0.19},{"$f":"Inputs!X113","v":0.19},{"$f":"Inputs!Y113","v":0.19},{"$f":"Inputs!Z113","v":0.19},{"$f":"Inputs!AA113","v":0.19},{"$f":"Inputs!AB113","v":0.19},{"$f":"Inputs!AC113","v":0.19},{"$f":"Inputs!AD113","v":0.19},{"$f":"Inputs!AE113","v":0.19},{"$f":"Inputs!AF113","v":0.19},{"$f":"Inputs!AG113","v":0.19},{"$f":"Inputs!AH113","v":0.19},{"$f":"Inputs!AI113","v":0.19}]
[null,null,null,null,"Corporation tax charge after losses",null,"£m nominal prices",null,null,null,{"$f":"K22 * K23","v":0},{"$f":"L22 * L23","v":0},0,0,0,0,0,0,0,1.1040810698855872,2.1265973667748317,2.5205315744080261,2.8941855442815276,3.187856829058211,3.3274573814136041,3.8933300270044433,3.5875311052556347,4.0258840911720428,4.4572683757271525,4.5355825994006693,5.0592203532522184,5.4817850629251881,5.9013736546849422,6.3190839665342109,0]
[]
[null,null,null,null,"Grossing-up factor for tax on tax charge after losses",null,"scalar",null,null,null,{"$f":"1 / (1 - K23)","v":1.2345679012345678},1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678,1.2345679012345678]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,"£m nominal prices",null,null,null,{"$f":"K24 * K26","v":0},0,0,0,0,0,0,0,0,1.3630630492414655,2.6254288478701624,3.1117673758123776,3.5730685731870708,3.93562571488668,4.1079720758192639,4.8065802802523985,4.4290507472291782,4.9702272730519041,5.502800463860682,5.5994846906181097,6.2459510533977998,6.7676358801545531,7.2856464872653603,7.801338230289149,0]
[]
[null,"Profiled tax allowance (floor)"]
[]
[null,null,null,null,"Unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"'Tax Floor'!K28 / 'Tax Deductions'!K$11","v":0},{"$f":"'Tax Floor'!L28 / 'Tax Deductions'!L$11","v":0},{"$f":"'Tax Floor'!M28 / 'Tax Deductions'!M$11","v":0},{"$f":"'Tax Floor'!N28 / 'Tax Deductions'!N$11","v":0},{"$f":"'Tax Floor'!O28 / 'Tax Deductions'!O$11","v":0},{"$f":"'Tax Floor'!P28 / 'Tax Deductions'!P$11","v":0},{"$f":"'Tax Floor'!Q28 / 'Tax Deductions'!Q$11","v":0},{"$f":"'Tax Floor'!R28 / 'Tax Deductions'!R$11","v":0},{"$f":"'Tax Floor'!S28 / 'Tax Deductions'!S$11","v":0},{"$f":"'Tax Floor'!T28 / 'Tax Deductions'!T$11","v":0.87910757478805057},{"$f":"'Tax Floor'!U28 / 'Tax Deductions'!U$11","v":1.6401302337017603},{"$f":"'Tax Floor'!V28 / 'Tax Deductions'!V$11","v":1.882943153919614},{"$f":"'Tax Floor'!W28 / 'Tax Deductions'!W$11","v":2.0942254875509541},{"$f":"'Tax Floor'!X28 / 'Tax Deductions'!X$11","v":2.2343329150012075},{"$f":"'Tax Floor'!Y28 / 'Tax Deductions'!Y$11","v":2.2589862150715807},{"$f":"'Tax Floor'!Z28 / 'Tax Deductions'!Z$11","v":2.5602024122912108},{"$f":"'Tax Floor'!AA28 / 'Tax Deductions'!AA$11","v":2.2850765978152783},{"$f":"'Tax Floor'!AB28 / 'Tax Deductions'!AB$11","v":2.4838099268717002},{"$f":"'Tax Floor'!AC28 / 'Tax Deductions'!AC$11","v":2.6636544229832393},{"$f":"'Tax Floor'!AD28 / 'Tax Deductions'!AD$11","v":2.6253921369026179},{"$f":"'Tax Floor'!AE28 / 'Tax Deductions'!AE$11","v":2.8365908605366887},{"$f":"'Tax Floor'!AF28 / 'Tax Deductions'!AF$11","v":2.9770567340739245},{"$f":"'Tax Floor'!AG28 / 'Tax Deductions'!AG$11","v":3.1043467530746911},{"$f":"'Tax Floor'!AH28 / 'Tax Deductions'!AH$11","v":3.219758085202078},{"$f":"'Tax Floor'!AI28 / 'Tax Deductions'!AI$11","v":0}]
[null,null,null,null,"Discount factor to start of operational period (floor)",null,{"$f":"'Allowances Floor'!G24","v":"scalar"},null,null,null,{"$f":"'Allowances Floor'!K24","v":1.0021044192804891},{"$f":"'Allowances Floor'!L24","v":1.0042132671414861},{"$f":"'Allowances Floor'!M24","v":1.0063265529025816},{"$f":"'Allowances Floor'!N24","v":1.0084442859029779},{"$f":"'Allowances Floor'!O24","v":1.0105664755015311},{"$f":"'Allowances Floor'!P24","v":1.0126931310767924},{"$f":"'Allowances Floor'!Q24","v":1.0148242620270491},{"$f":"'Allowances Floor'!R24","v":1.016959877770367},{"$f":"'Allowances Floor'!S24","v":1.0190999877446307},{"$f":"'Allowances Floor'!T24","v":1.0212446014075867},{"$f":"'Allowances Floor'!U24","v":1.0233937282368841},{"$f":"'Allowances Floor'!V24","v":1.0255473777301174},{"$f":"'Allowances Floor'!W24","v":1.0277055594048676},{"$f":"'Allowances Floor'!X24","v":1.0298682827987451},{"$f":"'Allowances Floor'!Y24","v":1.0320355574694309},{"$f":"'Allowances Floor'!Z24","v":1.0342073929947198},{"$f":"'Allowances Floor'!AA24","v":1.0363837989725622},{"$f":"'Allowances Floor'!AB24","v":1.0385647850211064},{"$f":"'Allowances Floor'!AC24","v":1.0407503607787418},{"$f":"'Allowances Floor'!AD24","v":1.0429405359041406},{"$f":"'Allowances Floor'!AE24","v":1.0451353200763007},{"$f":"'Allowances Floor'!AF24","v":1.0473347229945895},{"$f":"'Allowances Floor'!AG24","v":1.0495387543787849},{"$f":"'Allowances Floor'!AH24","v":1.0517474239691202},{"$f":"'Allowances Floor'!AI24","v":1.0539607415263255}]
[]
[null,null,null,null,"Discounted unprofiled tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,null,null,{"$f":"K32*K33","v":0},{"$f":"L32*L33","v":0},0,0,0,0,0,0,0,0.89778386480881289,1.6784989946620765,1.931047413917137,2.1522471762034847,2.3010686023730078,2.3313540977871585,2.6477802623544857,2.3682163653870956,2.5795975227347974,2.7721993017096977,2.7381278822197332,2.9646212969525214,3.1179748899204909,3.2581322243818365,3.3863722719150329,0]
[null,null,null,null,"NPV of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"SUM(K35:AI35)","v":37.125022167327373}]
[]
[null,null,null,null,"Annuity factor (floor)",null,{"$f":"'Allowances Floor'!G31","v":"scalar"},null,{"$f":"'Allowances Floor'!I31","v":3.8917182021590405E-2}]
[]
[null,null,null,null,"Annuity of tax allowance (floor)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I36 * I38","v":1.444801245241458}]
[]
[null,"End of sheet"]

{"sheet":"Cap Floor Levels","index":12,"n_rows":26,"n_cols":9,"rows_kept":26,"cut":false,"hidden":false,"merged":[]}
["Cap Floor Levels",null,null,null,null,null,null,"Licence"]
[null,null,null,null,"Parameter",null,"Units","Terminology","Constant"]
[]
[null,"Cap and Floor levels and adjustments"]
[]
[null,null,"Cap and Floor levels at FPA (Preliminary) / PCR (Final) and PCA adjustments at PCR"]
[null,null,"Relevant stage: FPA for Preliminary levels; PCR for final levels"]
[null,null,null,null,"Cap at relevant stage excluding tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"'Allowances Cap'!$I33","v":55.318600871218877}]
[null,null,null,null,"Floor at relevant stage excluding tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"'Allowances Floor'!$I33","v":36.324716957799104}]
[]
[null,null,null,null,"Cap at relevant stage - tax element (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"IF(Inputs!$I$123=\"No\",'Tax Cap'!I40,0)","v":5.0790701498717201}]
[null,null,null,null,"Floor at relevant stage - tax element (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"IF(Inputs!$I$123=\"No\",'Tax Floor'!I40,0)","v":1.444801245241458}]
[]
[null,null,null,null,"Cap at relevant stage - tax element (previously calculated through the model and fixed)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"}]
[null,null,null,null,"Floor at relevant stage - tax element (previously calculated through the model and fixed)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"}]
[]
[null,null,null,null,"Cap at relevant stage including tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I8+IF(Inputs!$I$123=\"Yes\",I14,I11)","v":60.397671021090595}]
[null,null,null,null,"Floor at relevant stage including tax (calculated through the model)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},null,{"$f":"I9+IF(Inputs!$I$123=\"Yes\",I15,I12)","v":37.769518203040562}]
[]
[null,null,null,null,"Preliminary Cap including tax (hardcoded at FPA)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},"PCL",50.695857535181297]
[null,null,null,null,"Preliminary Floor including tax (hardcoded at FPA)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},"PFL",27.572136438684257]
[]
[null,null,null,null,"Cap PCA adjustment (at PCR)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},"PCAC",{"$f":"I17-I20","v":9.7018134859092982}]
[null,null,null,null,"Floor PCA adjustment (at PCR)",null,{"$f":"Inputs!$I$11","v":"£m 16/17 prices"},"PCAF",{"$f":"I18-I21","v":10.197381764356305}]
[]
[null,"End of sheet"]